{"id":97174,"date":"2020-11-04T09:55:21","date_gmt":"2020-11-04T12:55:21","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=97174"},"modified":"2021-02-18T14:27:21","modified_gmt":"2021-02-18T17:27:21","slug":"gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/","title":{"rendered":"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20 mas prev\u00ea retomada"},"content":{"rendered":"<p>A <a href=\"https:\/\/www.suno.com.br\/acoes\/goll4\/\"><strong>Gol<\/strong> (GOLL4)<\/a> teve preju\u00edzo l\u00edquido de R$ 1,71 bilh\u00e3o no terceiro trimestre de 2020, aprofundando as perdas de R$ 242 milh\u00f5es vistas no mesmo per\u00edodo do ano passado. No entanto, a empresa mostrou melhora nos resultados operacionais em rela\u00e7\u00e3o ao trimestre anterior e fez previs\u00f5es positivas para o final do ano, prevendo retomada da demanda por viagens daqui para frente.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4-800x450.webp\" width=\"800\" height=\"450\" alt=\"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20 mas prev\u00ea retomada\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Gol (GOLL4). Foto: Divulga\u00e7\u00e3o.<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<div class=\"hubspot-form-wrapper\">\n\t<div id=\"single-form-target\"><\/div>\n<\/div>\n\n<p>No terceiro trimestre, o <strong>Ebitda<\/strong> (lucro antes de juros, impostos, amortiza\u00e7\u00e3o e deprecia\u00e7\u00e3o) foi negativo em R$ 204 milh\u00f5es, revertando um Ebitda positivo de R$ 1,14 bilh\u00e3o um ano antes. A <strong>receita operacional l\u00edquida<\/strong> da empresa foi de R$ 974,9 milh\u00f5es, queda de 73,7% na compara\u00e7\u00e3o anual.<\/p>\n<p>A receita obtida com o<strong> transporte de passageiros<\/strong> recuou 74,9% no trimestre, para R$ 879 milh\u00f5es. J\u00e1 a receita com <strong>transporte de cargas<\/strong> e outros caiu 54,1% e somou R$ 95,9 milh\u00f5es.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e Video Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/a><\/p>\n<h2>Demanda cresceu ante o trimestre anterior<\/h2>\n<p>O n\u00famero de Passageiro-Quil\u00f4metro Transportado Pago (<strong>RPK<\/strong>) diminuiu 72% comparativamente ao terceiro trimestre,\u00a0totalizando 3,2 bilh\u00f5es de RPKs. No entanto, houve um aumento de 63% em RPK de julho a setembro.<\/p>\n<p>Ao mesmo tempo, o indicador Assento Quil\u00f4metro Ofertado (<strong>ASK)<\/strong> reduziu 70% em rela\u00e7\u00e3o ao ano anterior, entretanto cresceu 59% dentro do\u00a0trimestre.<\/p>\n<p>A companhia transportou 2,6 milh\u00f5es de clientes no trimestre, uma diminui\u00e7\u00e3o de 73% versus o terceiro trimestre de 2019. Na compara\u00e7\u00e3o com o trimestre anterior, houve evolu\u00e7\u00e3o de 300%. De acordo com o diretor-presidente da Gol, Paulo Kakinoff, este n\u00famero mostra uma recupera\u00e7\u00e3o consider\u00e1vel.<\/p>\n<p>&#8220;Os resultados promissores do terceiro trimestre refletem o retorno dos passageiros aos c\u00e9us no Brasil e a\u00a0nossa confian\u00e7a nos diferenciais competitivos da GOL\u201d, afirmou no release de resultados.<\/p>\n<h2>Indicadores de liquidez<\/h2>\n<p>A Gol terminou o terceiro trimestre com R$ 2,2 bilh\u00f5es em liquidez. Segundo a empresa, os principais vencimentos de d\u00edvida de capital de giro e financiamentos de investimentos de curto prazo (Capex) foram reprogramados com os bancos.<\/p>\n<p>A empresa pagou R$ 2,58 bilh\u00f5es em<strong> d\u00edvidas<\/strong> no trimestre. A rela\u00e7\u00e3o entre d\u00edvida e Ebitda ajustado ficou em 4 vezes. Um ano antes, era de 2,4 vezes.\u00a0A<a href=\"https:\/\/www.suno.com.br\/artigos\/divida-liquida\/\" target=\"_blank\" rel=\"noopener noreferrer\"> d\u00edvida l\u00edquida<\/a> era de R$ 14,14 bilh\u00f5es ao final do trimestre, aumento de 50,3% ante o mesmo trimestre de 2019.<\/p>\n<p>Para o quarto trimestre, a empresa prev\u00ea <strong>consumo l\u00edquido de caixa<\/strong> da ordem de R$\u00a03 milh\u00f5es por dia, decorrente de investimentos para\u00a0trazer aeronaves de volta \u00e0\u00a0opera\u00e7\u00e3o at\u00e9 o final\u00a0do ano.<\/p>\n<h2>Perspectivas da Gol<\/h2>\n<p>A empresa prev\u00ea aumento de 100% de capacidade no quarto trimestre em rela\u00e7\u00e3o ao terceiro trimestre.\u00a0Em outubro de 2020, a companhia operou aproximadamente 376<strong> voos<\/strong> di\u00e1rios (53% do mesmo per\u00edodo de 2019), atingindo picos de 500 voos di\u00e1rios, atendendo 95% do mercado.<\/p>\n<p>Ao final de dezembro de 2020, a Gol espera restabelecer o mercado dom\u00e9stico operado do per\u00edodo pr\u00e9-pandemia, o que representa cerca de 80% da capacidade total de 2019.<\/p>\n<p>A Gol espera terminar o m\u00eas de dezembro com uma m\u00e9dia de 94 aeronaves operando na malha, representando mais de 75% da frota operacional no mesmo per\u00edodo do ano passado, mantendo a consist\u00eancia de sua taxa de ocupa\u00e7\u00e3o de aproximadamente 80% no trimestre.<\/p>\n<p>Al\u00e9m disso, a Gol espera encerrar o quarto trimestre com R$2,4 bilh\u00f5es em liquidez e R$13,1 bilh\u00f5es em d\u00edvida l\u00edquida ajustada.<\/p>\n<p>No quarto trimestre, a companhia estima operar uma frota m\u00e9dia de 92\u00a0aeronaves, que representar\u00e1 78% da frota m\u00e9dia\u00a0operada no mesmo trimestre do ano passado. Espera-se que a receita do trimestre aumente cerca de 130% em rela\u00e7\u00e3o ao trimestre anterior.<\/p>\n<p>As despesas totais no quarto trimestre devem diminuir em cerca de 16%, decorrentes das iniciativas de redu\u00e7\u00e3o de custos, menores capacidade e consumo de combust\u00edvel, de acordo com a <strong>Gol.<\/strong><\/p>\n<div class=\"canvasWrapper\">\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n<\/div>\n<div class=\"page\" data-page-number=\"10\" data-loaded=\"true\">\n<div class=\"textLayer\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Gol (GOLL4) teve preju\u00edzo l\u00edquido de R$ 1,71 bilh\u00e3o no terceiro trimestre de 2020, aprofundando as perdas de R$ 242 milh\u00f5es vistas no mesmo per\u00edodo do ano passado. No entanto, a empresa mostrou melhora nos resultados operacionais em rela\u00e7\u00e3o ao trimestre anterior e fez previs\u00f5es positivas para o final do ano, prevendo retomada da [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":70120,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[489,1607],"suno_strategy":[],"class_list":["post-97174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-gol-linhas-aereas-goll11-goll4","tag-resultado-das-empresas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20<\/title>\n<meta name=\"description\" content=\"A Gol (GOLL4) teve preju\u00edzo l\u00edquido de R$ 1,71 bilh\u00e3o no terceiro trimestre, aprofundando as perdas de R$ 242 milh\u00f5es vistas um ano antes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20\" \/>\n<meta property=\"og:description\" content=\"A Gol (GOLL4) teve preju\u00edzo l\u00edquido de R$ 1,71 bilh\u00e3o no terceiro trimestre, aprofundando as perdas de R$ 242 milh\u00f5es vistas um ano antes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Natalia G\u00f3mez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalia G\u00f3mez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/\"},\"author\":{\"name\":\"Natalia G\u00f3mez\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164\"},\"headline\":\"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20 mas prev\u00ea retomada\",\"datePublished\":\"2020-11-04T12:55:21+00:00\",\"dateModified\":\"2021-02-18T17:27:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/\"},\"wordCount\":672,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4-jpg.webp\",\"keywords\":[\"Gol Linhas A\u00e9reas (GOLL11\/GOLL4)\",\"Resultado das empresas\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/\",\"name\":\"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4-jpg.webp\",\"datePublished\":\"2020-11-04T12:55:21+00:00\",\"dateModified\":\"2021-02-18T17:27:21+00:00\",\"description\":\"A Gol (GOLL4) teve preju\u00edzo l\u00edquido de R$ 1,71 bilh\u00e3o no terceiro trimestre, aprofundando as perdas de R$ 242 milh\u00f5es vistas um ano antes.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4-jpg.webp\",\"width\":1024,\"height\":683,\"caption\":\"Gol (GOLL4). Foto: Divulga\u00e7\u00e3o.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20 mas prev\u00ea retomada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164\",\"name\":\"Natalia G\u00f3mez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g\",\"caption\":\"Natalia G\u00f3mez\"},\"description\":\"Editora do Suno Not\u00edcias desde outubro de 2020, \u00e9 jornalista formada pela PUC-SP, com p\u00f3s-gradua\u00e7\u00e3o em jornalismo liter\u00e1rio. Atua no mercado financeiro desde 2003, quando iniciou a carreira no jornal econ\u00f4mico DCI, cobrindo o setor de alimentos no caderno de Ind\u00fastria. Foi trainee do jornal Valor Econ\u00f4mico, onde atuou no Caderno de Empresas por quase tr\u00eas anos. L\u00e1, cobriu o setor de ind\u00fastria, com foco em siderurgia, embalagens e aeroespacial. Fez coberturas setoriais em viagens para S\u00e3o Jos\u00e9 dos Campos e Franca (SP), al\u00e9m de coberturas internacionais na Alemanha e na Su\u00e9cia. Trabalhou por cinco anos na Ag\u00eancia Estado\/Broadcast, do Grupo Estado, onde foi rep\u00f3rter dos setores de minera\u00e7\u00e3o e siderurgia, alimentos e bebidas e finan\u00e7as. Foi premiada como o pr\u00eamio Destaque de Reportagem da AE em 2007 e 2008. Al\u00e9m de atuar no servi\u00e7o de not\u00edcias em tempo real, fez participa\u00e7\u00f5es no caderno de Economia do jornal Estado de S.Paulo e na R\u00e1dio Eldorado. Ainda no Grupo Estado, foi editora assistente da editoria Empresas e Setores, atuando com edi\u00e7\u00e3o e pauta, al\u00e9m de cobrir mercados diariamente com o cen\u00e1rio de bolsa e fazer reportagens especiais com foco em governan\u00e7a corporativa. Trabalhou tamb\u00e9m como correspondente de finan\u00e7as no servi\u00e7o da Thomson Reuters em portugu\u00eas por quase um ano. Atuou por cerca de oito anos como jornalista independente, contribuindo para ve\u00edculos como UOL Economia, Infomoney e Revista Voc\u00ea SA, al\u00e9m de ter trabalhado em projetos na \u00e1rea de conte\u00fado e comunica\u00e7\u00e3o de institui\u00e7\u00f5es financeiras como Anbima, Banco BS2, Banco Pine, Ita\u00fa BBA e EQI.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20","description":"A Gol (GOLL4) teve preju\u00edzo l\u00edquido de R$ 1,71 bilh\u00e3o no terceiro trimestre, aprofundando as perdas de R$ 242 milh\u00f5es vistas um ano antes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/","og_locale":"pt_BR","og_type":"article","og_title":"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20","og_description":"A Gol (GOLL4) teve preju\u00edzo l\u00edquido de R$ 1,71 bilh\u00e3o no terceiro trimestre, aprofundando as perdas de R$ 242 milh\u00f5es vistas um ano antes.","og_url":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1024,"height":683,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4.jpg","type":"image\/jpeg"}],"author":"Natalia G\u00f3mez","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Natalia G\u00f3mez","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/"},"author":{"name":"Natalia G\u00f3mez","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164"},"headline":"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20 mas prev\u00ea retomada","datePublished":"2020-11-04T12:55:21+00:00","dateModified":"2021-02-18T17:27:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/"},"wordCount":672,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4-jpg.webp","keywords":["Gol Linhas A\u00e9reas (GOLL11\/GOLL4)","Resultado das empresas"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/","url":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/","name":"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4-jpg.webp","datePublished":"2020-11-04T12:55:21+00:00","dateModified":"2021-02-18T17:27:21+00:00","description":"A Gol (GOLL4) teve preju\u00edzo l\u00edquido de R$ 1,71 bilh\u00e3o no terceiro trimestre, aprofundando as perdas de R$ 242 milh\u00f5es vistas um ano antes.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4-jpg.webp","width":1024,"height":683,"caption":"Gol (GOLL4). Foto: Divulga\u00e7\u00e3o."},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20 mas prev\u00ea retomada"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164","name":"Natalia G\u00f3mez","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g","caption":"Natalia G\u00f3mez"},"description":"Editora do Suno Not\u00edcias desde outubro de 2020, \u00e9 jornalista formada pela PUC-SP, com p\u00f3s-gradua\u00e7\u00e3o em jornalismo liter\u00e1rio. Atua no mercado financeiro desde 2003, quando iniciou a carreira no jornal econ\u00f4mico DCI, cobrindo o setor de alimentos no caderno de Ind\u00fastria. Foi trainee do jornal Valor Econ\u00f4mico, onde atuou no Caderno de Empresas por quase tr\u00eas anos. L\u00e1, cobriu o setor de ind\u00fastria, com foco em siderurgia, embalagens e aeroespacial. Fez coberturas setoriais em viagens para S\u00e3o Jos\u00e9 dos Campos e Franca (SP), al\u00e9m de coberturas internacionais na Alemanha e na Su\u00e9cia. Trabalhou por cinco anos na Ag\u00eancia Estado\/Broadcast, do Grupo Estado, onde foi rep\u00f3rter dos setores de minera\u00e7\u00e3o e siderurgia, alimentos e bebidas e finan\u00e7as. Foi premiada como o pr\u00eamio Destaque de Reportagem da AE em 2007 e 2008. Al\u00e9m de atuar no servi\u00e7o de not\u00edcias em tempo real, fez participa\u00e7\u00f5es no caderno de Economia do jornal Estado de S.Paulo e na R\u00e1dio Eldorado. Ainda no Grupo Estado, foi editora assistente da editoria Empresas e Setores, atuando com edi\u00e7\u00e3o e pauta, al\u00e9m de cobrir mercados diariamente com o cen\u00e1rio de bolsa e fazer reportagens especiais com foco em governan\u00e7a corporativa. Trabalhou tamb\u00e9m como correspondente de finan\u00e7as no servi\u00e7o da Thomson Reuters em portugu\u00eas por quase um ano. Atuou por cerca de oito anos como jornalista independente, contribuindo para ve\u00edculos como UOL Economia, Infomoney e Revista Voc\u00ea SA, al\u00e9m de ter trabalhado em projetos na \u00e1rea de conte\u00fado e comunica\u00e7\u00e3o de institui\u00e7\u00f5es financeiras como Anbima, Banco BS2, Banco Pine, Ita\u00fa BBA e EQI.","url":"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/06\/efaafa19-gol-goll4-400x200.webp\" alt=\"Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20 mas prev\u00ea retomada\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/gol-goll4-tem-prejuizo-de-r-171-bilhao-no-3t20\/\"><h2 class=\"content__title\">Gol (GOLL4) tem preju\u00edzo de R$ 1,71 bilh\u00e3o no 3T20 mas prev\u00ea retomada<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&#038;r=g\" alt=\"Natalia G\u00f3mez\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/\"><span itemprop=\"author\">Natalia G\u00f3mez<\/span><\/a><\/span><time datetime=\"2020-11-04T09:55:21-03:00\" itemprop=\"datePublished\">04\/11\/2020 09:55<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/97174"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=97174"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/97174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/70120"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=97174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=97174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=97174"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=97174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}