{"id":96852,"date":"2020-11-03T10:11:35","date_gmt":"2020-11-03T13:11:35","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=96852"},"modified":"2021-05-31T00:08:45","modified_gmt":"2021-05-31T03:08:45","slug":"telefonica-vivo-vivt4-vende-empresa-ciberseguranca","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/","title":{"rendered":"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi"},"content":{"rendered":"<p>O conselho de administra\u00e7\u00e3o da <strong>Telef\u00f4nica<\/strong> Brasil (<a href=\"https:\/\/www.suno.com.br\/acoes\/vivt4\/\" target=\"_blank\" rel=\"noopener noreferrer\">VIVT4<\/a>) aprovou a venda da CyberCo Brasil para a Telef\u00f4nica Cybersecurity Tech, controlada indireta da matriz Telef\u00f3nica, por R$ 116,4 milh\u00f5es.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo-800x450.webp\" width=\"800\" height=\"450\" alt=\"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Telef\u00f4nica (VIVT3) bate o martelo e define quando vai pagar JCP de R$ 396 milh\u00f5es. Foto: Divulga\u00e7\u00e3o<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<div class=\"hubspot-form-wrapper\">\n\t<div id=\"single-form-target\"><\/div>\n<\/div>\n\n<p>Al\u00e9m disso, a Telef\u00f4nica transferiu alguns ativos relacionados \u00e0s atividades de cybersecurity, contratos e empregados para a CyberCo Brasil, antes da venda.<\/p>\n<p>Segundo comunicado enviado \u00e0 Comiss\u00e3o de Valores Mobili\u00e1rios (CVM), a opera\u00e7\u00e3o permitir\u00e1 que a Telef\u00f4nica Brasil se fortale\u00e7a no mercado de <strong>ciberseguran\u00e7a<\/strong>, como distribuidor exclusivo da <strong>CyberCo<\/strong> Brasil, por meio da amplia\u00e7\u00e3o do seu portf\u00f3lio de produtos e servi\u00e7os.<\/p>\n<p><span class=\"s3\"><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">No Suno One voc\u00ea aprende a fazer seu dinheiro trabalhar para voc\u00ea. Cadastre-se gratuitamente agora!<\/a><\/span><\/p>\n<p>&#8220;Al\u00e9m disso, a companhia se beneficiar\u00e1 de maior competividade em fun\u00e7\u00e3o da escala global do parceiro dedicado a tais atividades&#8221;, afirmou em comunicado. A empresa disse que a continuidade da presta\u00e7\u00e3o de servi\u00e7os de cybersecurity aos clientes finais est\u00e1 assegurada pela transa\u00e7\u00e3o.<\/p>\n<div>A opera\u00e7\u00e3o n\u00e3o depende de autoriza\u00e7\u00f5es regulat\u00f3rias e n\u00e3o causa altera\u00e7\u00f5es na estrutura acion\u00e1ria da companhia ou dilui\u00e7\u00e3o aos acionistas, de acordo com o comunicado.<\/div>\n<h2>Parceria da Telef\u00f4nica em 5G<\/h2>\n<div>Em setembro deste ano, a empresa que fechou um acordo com a Rakuten Mobile, subsidi\u00e1ria da Rakuten, para uma parceria na \u00e1rea de redes abertas 5G.<\/div>\n<div><\/div>\n<div>A colabora\u00e7\u00e3o entre as duas empresas prev\u00ea o desenvolvimento de uma arquitetura de redes de acesso de r\u00e1dio aberto, a chamada\u00a0<strong>Open Radio Access Network (RAN).<\/strong> Trata-se de uma tecnologia de nuvem para as opera\u00e7\u00f5es de redes.<\/div>\n<div><\/div>\n<div>A Telef\u00f4nica e a japonesa de telecomunica\u00e7\u00f5es v\u00e3o realizar testes de laborat\u00f3rio e investiga\u00e7\u00e3o, bem como avaliar o papel da intelig\u00eancia artificial.\u00a0O an\u00fancio, previsto para mais cedo neste ano, foi atrasado por conta da pandemia do novo coronav\u00edrus.<\/div>\n<div><\/div>\n<div>A nova tecnologia em estudo pela <strong>Telef\u00f4nica<\/strong> promete cortar custos significativos para as operadoras de telecomunica\u00e7\u00f5es em vista da utiliza\u00e7\u00e3o de software em nuvem e de hardware comoditizado em vez do uso de um equipamento de propriedade de companhias como Nokia, Ericsson e Huawei.<\/div>\n<div><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O conselho de administra\u00e7\u00e3o da Telef\u00f4nica Brasil (VIVT4) aprovou a venda da CyberCo Brasil para a Telef\u00f4nica Cybersecurity Tech, controlada indireta da matriz Telef\u00f3nica, por R$ 116,4 milh\u00f5es. Telef\u00f4nica (VIVT3) bate o martelo e define quando vai pagar JCP de R$ 396 milh\u00f5es. Foto: Divulga\u00e7\u00e3o Al\u00e9m disso, a Telef\u00f4nica transferiu alguns ativos relacionados \u00e0s atividades [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":31991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[659,1141],"suno_strategy":[],"class_list":["post-96852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-telefonica-vivt3","tag-vivo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi<\/title>\n<meta name=\"description\" content=\"A Telef\u00f4nica Brasil (VIVT4) aprovou a venda da CyberCo Brasil para a Telef\u00f4nica Cybersecurity Tech por R$ 116,4 milh\u00f5es. Leia aqui.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi\" \/>\n<meta property=\"og:description\" content=\"A Telef\u00f4nica Brasil (VIVT4) aprovou a venda da CyberCo Brasil para a Telef\u00f4nica Cybersecurity Tech por R$ 116,4 milh\u00f5es. Leia aqui.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4288\" \/>\n\t<meta property=\"og:image:height\" content=\"2079\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Natalia G\u00f3mez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalia G\u00f3mez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/\"},\"author\":{\"name\":\"Natalia G\u00f3mez\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164\"},\"headline\":\"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi\",\"datePublished\":\"2020-11-03T13:11:35+00:00\",\"dateModified\":\"2021-05-31T03:08:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/\"},\"wordCount\":395,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo-scaled.webp\",\"keywords\":[\"Telef\u00f4nica (VIVT3)\",\"Vivo\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/\",\"name\":\"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo-scaled.webp\",\"datePublished\":\"2020-11-03T13:11:35+00:00\",\"dateModified\":\"2021-05-31T03:08:45+00:00\",\"description\":\"A Telef\u00f4nica Brasil (VIVT4) aprovou a venda da CyberCo Brasil para a Telef\u00f4nica Cybersecurity Tech por R$ 116,4 milh\u00f5es. Leia aqui.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo-scaled.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo-scaled.webp\",\"width\":2560,\"height\":1241,\"caption\":\"Telef\u00f4nica (VIVT3) bate o martelo e define quando vai pagar JCP de R$ 396 milh\u00f5es. Foto: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164\",\"name\":\"Natalia G\u00f3mez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g\",\"caption\":\"Natalia G\u00f3mez\"},\"description\":\"Editora do Suno Not\u00edcias desde outubro de 2020, \u00e9 jornalista formada pela PUC-SP, com p\u00f3s-gradua\u00e7\u00e3o em jornalismo liter\u00e1rio. Atua no mercado financeiro desde 2003, quando iniciou a carreira no jornal econ\u00f4mico DCI, cobrindo o setor de alimentos no caderno de Ind\u00fastria. Foi trainee do jornal Valor Econ\u00f4mico, onde atuou no Caderno de Empresas por quase tr\u00eas anos. L\u00e1, cobriu o setor de ind\u00fastria, com foco em siderurgia, embalagens e aeroespacial. Fez coberturas setoriais em viagens para S\u00e3o Jos\u00e9 dos Campos e Franca (SP), al\u00e9m de coberturas internacionais na Alemanha e na Su\u00e9cia. Trabalhou por cinco anos na Ag\u00eancia Estado\/Broadcast, do Grupo Estado, onde foi rep\u00f3rter dos setores de minera\u00e7\u00e3o e siderurgia, alimentos e bebidas e finan\u00e7as. Foi premiada como o pr\u00eamio Destaque de Reportagem da AE em 2007 e 2008. Al\u00e9m de atuar no servi\u00e7o de not\u00edcias em tempo real, fez participa\u00e7\u00f5es no caderno de Economia do jornal Estado de S.Paulo e na R\u00e1dio Eldorado. Ainda no Grupo Estado, foi editora assistente da editoria Empresas e Setores, atuando com edi\u00e7\u00e3o e pauta, al\u00e9m de cobrir mercados diariamente com o cen\u00e1rio de bolsa e fazer reportagens especiais com foco em governan\u00e7a corporativa. Trabalhou tamb\u00e9m como correspondente de finan\u00e7as no servi\u00e7o da Thomson Reuters em portugu\u00eas por quase um ano. Atuou por cerca de oito anos como jornalista independente, contribuindo para ve\u00edculos como UOL Economia, Infomoney e Revista Voc\u00ea SA, al\u00e9m de ter trabalhado em projetos na \u00e1rea de conte\u00fado e comunica\u00e7\u00e3o de institui\u00e7\u00f5es financeiras como Anbima, Banco BS2, Banco Pine, Ita\u00fa BBA e EQI.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi","description":"A Telef\u00f4nica Brasil (VIVT4) aprovou a venda da CyberCo Brasil para a Telef\u00f4nica Cybersecurity Tech por R$ 116,4 milh\u00f5es. Leia aqui.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/","og_locale":"pt_BR","og_type":"article","og_title":"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi","og_description":"A Telef\u00f4nica Brasil (VIVT4) aprovou a venda da CyberCo Brasil para a Telef\u00f4nica Cybersecurity Tech por R$ 116,4 milh\u00f5es. Leia aqui.","og_url":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":4288,"height":2079,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo.jpg","type":"image\/jpeg"}],"author":"Natalia G\u00f3mez","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Natalia G\u00f3mez","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/"},"author":{"name":"Natalia G\u00f3mez","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164"},"headline":"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi","datePublished":"2020-11-03T13:11:35+00:00","dateModified":"2021-05-31T03:08:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/"},"wordCount":395,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo-scaled.webp","keywords":["Telef\u00f4nica (VIVT3)","Vivo"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/","url":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/","name":"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo-scaled.webp","datePublished":"2020-11-03T13:11:35+00:00","dateModified":"2021-05-31T03:08:45+00:00","description":"A Telef\u00f4nica Brasil (VIVT4) aprovou a venda da CyberCo Brasil para a Telef\u00f4nica Cybersecurity Tech por R$ 116,4 milh\u00f5es. Leia aqui.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo-scaled.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo-scaled.webp","width":2560,"height":1241,"caption":"Telef\u00f4nica (VIVT3) bate o martelo e define quando vai pagar JCP de R$ 396 milh\u00f5es. Foto: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164","name":"Natalia G\u00f3mez","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g","caption":"Natalia G\u00f3mez"},"description":"Editora do Suno Not\u00edcias desde outubro de 2020, \u00e9 jornalista formada pela PUC-SP, com p\u00f3s-gradua\u00e7\u00e3o em jornalismo liter\u00e1rio. Atua no mercado financeiro desde 2003, quando iniciou a carreira no jornal econ\u00f4mico DCI, cobrindo o setor de alimentos no caderno de Ind\u00fastria. Foi trainee do jornal Valor Econ\u00f4mico, onde atuou no Caderno de Empresas por quase tr\u00eas anos. L\u00e1, cobriu o setor de ind\u00fastria, com foco em siderurgia, embalagens e aeroespacial. Fez coberturas setoriais em viagens para S\u00e3o Jos\u00e9 dos Campos e Franca (SP), al\u00e9m de coberturas internacionais na Alemanha e na Su\u00e9cia. Trabalhou por cinco anos na Ag\u00eancia Estado\/Broadcast, do Grupo Estado, onde foi rep\u00f3rter dos setores de minera\u00e7\u00e3o e siderurgia, alimentos e bebidas e finan\u00e7as. Foi premiada como o pr\u00eamio Destaque de Reportagem da AE em 2007 e 2008. Al\u00e9m de atuar no servi\u00e7o de not\u00edcias em tempo real, fez participa\u00e7\u00f5es no caderno de Economia do jornal Estado de S.Paulo e na R\u00e1dio Eldorado. Ainda no Grupo Estado, foi editora assistente da editoria Empresas e Setores, atuando com edi\u00e7\u00e3o e pauta, al\u00e9m de cobrir mercados diariamente com o cen\u00e1rio de bolsa e fazer reportagens especiais com foco em governan\u00e7a corporativa. Trabalhou tamb\u00e9m como correspondente de finan\u00e7as no servi\u00e7o da Thomson Reuters em portugu\u00eas por quase um ano. Atuou por cerca de oito anos como jornalista independente, contribuindo para ve\u00edculos como UOL Economia, Infomoney e Revista Voc\u00ea SA, al\u00e9m de ter trabalhado em projetos na \u00e1rea de conte\u00fado e comunica\u00e7\u00e3o de institui\u00e7\u00f5es financeiras como Anbima, Banco BS2, Banco Pine, Ita\u00fa BBA e EQI.","url":"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/3f0f8318-telefonica-vivo-400x200.webp\" alt=\"Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/telefonica-vivo-vivt4-vende-empresa-ciberseguranca\/\"><h2 class=\"content__title\">Telef\u00f4nica (VIVT4) vende empresa de ciberseguran\u00e7a por R$ 116,4 mi<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&#038;r=g\" alt=\"Natalia G\u00f3mez\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/\"><span itemprop=\"author\">Natalia G\u00f3mez<\/span><\/a><\/span><time datetime=\"2020-11-03T10:11:35-03:00\" itemprop=\"datePublished\">03\/11\/2020 10:11<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/96852"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=96852"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/96852\/revisions"}],"predecessor-version":[{"id":152737,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/96852\/revisions\/152737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/31991"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=96852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=96852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=96852"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=96852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}