{"id":88767,"date":"2020-10-01T11:36:58","date_gmt":"2020-10-01T14:36:58","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=88767"},"modified":"2021-05-10T22:41:10","modified_gmt":"2021-05-11T01:41:10","slug":"equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/","title":{"rendered":"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas"},"content":{"rendered":"<p>A <a href=\"https:\/\/www.suno.com.br\/acoes\/eqtl3\/\"><strong>Equatorial<\/strong> (EQTL3)<\/a> informou, na manh\u00e3 desta quinta-feira (1), que realizar\u00e1 o pagamento de juros a debenturistas da 3\u00aa emiss\u00e3o dos pap\u00e9is de <a href=\"https:\/\/www.suno.com.br\/artigos\/titulos-privados\/\">cr\u00e9dito privado<\/a> da empresa.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia-800x450.webp\" width=\"800\" height=\"450\" alt=\"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">A Equatorial (EQTL3) soma cerca de 1% de alta na bolsa no acumulado de 2022, em estabilidade<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<div class=\"hubspot-form-wrapper\">\n\t<div id=\"single-form-target\"><\/div>\n<\/div>\n\n<p>O pagamento total ser\u00e1 na ordem de R$ 8,54 milh\u00f5es, com o pre\u00e7o unit\u00e1rio de R$ 19,06682300 por papel. O c\u00f3digo das <a href=\"https:\/\/www.suno.com.br\/artigos\/debentures\/\"><strong>deb\u00eantures<\/strong><\/a> em quest\u00e3o \u00e9 EQTL13. Segundo a Equatorial, o pagamento ser\u00e1 realizado nesta quinta-feira.<\/p>\n<p>De acordo com o comunicado da empresa, informa\u00e7\u00f5es adicionais poder\u00e3o ser obtidas junto \u00e0 diretoria de <strong>Rela\u00e7\u00f5es com Investidores<\/strong> da companhia. A nota foi assinada por Leonardo da Silva Lucas Tavares de Lima, diretor da \u00e1rea.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">No Suno One voc\u00ea aprende a fazer seu dinheiro trabalhar para voc\u00ea. Cadastre-se gratuitamente agora!<\/a><\/p>\n<h2>Equatorial lucra R$ 406 milh\u00f5es no segundo trimestre<\/h2>\n<p>A Equatorial registrou um<a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\"> lucro l\u00edquido<\/a> de R$ 406 milh\u00f5es no segundo trimestre deste ano, um avan\u00e7o de 18,6% sobre o resultado de R$ 342 milh\u00f5es apurado no mesmo trimestre de 2019. As informa\u00e7\u00f5es foram reveladas ao mercado em meados de agosto.<\/p>\n<p>De acordo com as informa\u00e7\u00f5es enviadas \u00e0 <a href=\"https:\/\/www.suno.com.br\/artigos\/cvm\/\">Comiss\u00e3o de Valores Mobili\u00e1rios (CVM)<\/a>, a receita operacional l\u00edquida da companhia atingiu R$ 3,48 bilh\u00f5es no per\u00edodo entre abril e julho, recuo de 20,4% frente aos R$ 4,37 bilh\u00f5es apresentados na rela\u00e7\u00e3o anualizada.<\/p>\n<p>O <strong>Ebitda<\/strong> (lucro antes de juros, impostos, deprecia\u00e7\u00e3o e amortiza\u00e7\u00e3o) da empresa somou R$ 873 milh\u00f5es no per\u00edodo, equivalente a uma queda de 11,1% ante os R$ 982 milh\u00f5es apurados no segundo trimestre do ano passado. O lucro operacional, tamb\u00e9m descrito como Ebit, foi de R$ 712 milh\u00f5es, baixa de 10,8% na compara\u00e7\u00e3o de ano para ano.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Saiba mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-cvc-petrobras-guararapes-natura\/\">\n\t\t\tAgenda do Dia: CVC; Petrobras; Guararapes; Natura\t\t<\/a>\n\t<\/div>\n\n\n<p>\u201cA baixa do Ebitida no segundo trimestre \u00e9 fruto do impacto, principalmente das distribuidoras Equatorial Maranh\u00e3o e Par\u00e1\u201d, comentou a empresa. O volume total de <strong>energia el\u00e9trica<\/strong> distribu\u00edda atingiu 5.349 GWh, com crescimento consolidado de 3,2% em compara\u00e7\u00e3o ao mesmo trimestre do ano anterior.<\/p>\n<h2>\u00daltima cota\u00e7\u00e3o das a\u00e7\u00f5es<\/h2>\n<p>As a\u00e7\u00f5es da <strong>Equatorial<\/strong> encerraram o preg\u00e3o na \u00faltima quarta-feira (30) com uma queda de 1,99%, negociadas a R$ 21,18. Os pap\u00e9is da companhia tamb\u00e9m operam em baixa nesta quinta-feira, indo a R$ 20,94. Nos \u00faltimos 12 meses, entretanto, os pap\u00e9is da empresa apresentam uma valoriza\u00e7\u00e3o de 6,29%.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>A Equatorial (EQTL3) informou, na manh\u00e3 desta quinta-feira (1), que realizar\u00e1 o pagamento de juros a debenturistas da 3\u00aa emiss\u00e3o dos pap\u00e9is de cr\u00e9dito privado da empresa. A Equatorial (EQTL3) soma cerca de 1% de alta na bolsa no acumulado de 2022, em estabilidade O pagamento total ser\u00e1 na ordem de R$ 8,54 milh\u00f5es, com [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":44620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[1151,105039],"suno_strategy":[],"class_list":["post-88767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-debentures","tag-equatorial-eqtl3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Equatorial (EQTL3) anuncia pagamento de juros a debenturistas<\/title>\n<meta name=\"description\" content=\"A Equatorial (EQTL3) informou, nesta quinta, que realizar\u00e1 o pagamento de juros a debenturistas da 3\u00aa emiss\u00e3o dos pap\u00e9is da empresa. Confira.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas\" \/>\n<meta property=\"og:description\" content=\"A Equatorial (EQTL3) informou, nesta quinta, que realizar\u00e1 o pagamento de juros a debenturistas da 3\u00aa emiss\u00e3o dos pap\u00e9is da empresa. Confira.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jader Lazarini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jader Lazarini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/\"},\"author\":{\"name\":\"Jader Lazarini\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\"},\"headline\":\"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas\",\"datePublished\":\"2020-10-01T14:36:58+00:00\",\"dateModified\":\"2021-05-11T01:41:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/\"},\"wordCount\":405,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia-jpg.webp\",\"keywords\":[\"deb\u00eantures\",\"Equatorial (EQTL3)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/\",\"name\":\"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia-jpg.webp\",\"datePublished\":\"2020-10-01T14:36:58+00:00\",\"dateModified\":\"2021-05-11T01:41:10+00:00\",\"description\":\"A Equatorial (EQTL3) informou, nesta quinta, que realizar\u00e1 o pagamento de juros a debenturistas da 3\u00aa emiss\u00e3o dos pap\u00e9is da empresa. Confira.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia-jpg.webp\",\"width\":1920,\"height\":1080,\"caption\":\"A Equatorial (EQTL3) soma cerca de 1% de alta na bolsa no acumulado de 2022, em estabilidade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\",\"name\":\"Jader Lazarini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"caption\":\"Jader Lazarini\"},\"description\":\"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas","description":"A Equatorial (EQTL3) informou, nesta quinta, que realizar\u00e1 o pagamento de juros a debenturistas da 3\u00aa emiss\u00e3o dos pap\u00e9is da empresa. Confira.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/","og_locale":"pt_BR","og_type":"article","og_title":"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas","og_description":"A Equatorial (EQTL3) informou, nesta quinta, que realizar\u00e1 o pagamento de juros a debenturistas da 3\u00aa emiss\u00e3o dos pap\u00e9is da empresa. Confira.","og_url":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1920,"height":1080,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia.jpg","type":"image\/jpeg"}],"author":"Jader Lazarini","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Jader Lazarini","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/"},"author":{"name":"Jader Lazarini","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f"},"headline":"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas","datePublished":"2020-10-01T14:36:58+00:00","dateModified":"2021-05-11T01:41:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/"},"wordCount":405,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia-jpg.webp","keywords":["deb\u00eantures","Equatorial (EQTL3)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/","url":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/","name":"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia-jpg.webp","datePublished":"2020-10-01T14:36:58+00:00","dateModified":"2021-05-11T01:41:10+00:00","description":"A Equatorial (EQTL3) informou, nesta quinta, que realizar\u00e1 o pagamento de juros a debenturistas da 3\u00aa emiss\u00e3o dos pap\u00e9is da empresa. Confira.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia-jpg.webp","width":1920,"height":1080,"caption":"A Equatorial (EQTL3) soma cerca de 1% de alta na bolsa no acumulado de 2022, em estabilidade"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f","name":"Jader Lazarini","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","caption":"Jader Lazarini"},"description":"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).","url":"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/11\/169e54a9-equatorial-energia-400x200.webp\" alt=\"Equatorial (EQTL3) anuncia pagamento de juros a debenturistas\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/equatorial-eqtl3-anuncia-pagamento-de-juros-a-debenturistas\/\"><h2 class=\"content__title\">Equatorial (EQTL3) anuncia pagamento de juros a debenturistas<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/178e6598-foto-perfil-2-150x150.jpg\" alt=\"Jader Lazarini\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"><span itemprop=\"author\">Jader Lazarini<\/span><\/a><\/span><time datetime=\"2020-10-01T11:36:58-03:00\" itemprop=\"datePublished\">01\/10\/2020 11:36<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/88767"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=88767"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/88767\/revisions"}],"predecessor-version":[{"id":146770,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/88767\/revisions\/146770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/44620"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=88767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=88767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=88767"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=88767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}