{"id":85875,"date":"2020-09-18T20:09:18","date_gmt":"2020-09-18T23:09:18","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=85875"},"modified":"2020-09-18T20:09:18","modified_gmt":"2020-09-18T23:09:18","slug":"paulo-guedes-condenado-comparar-servidores-parasitas","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/","title":{"rendered":"Paulo Guedes \u00e9 condenado por comparar servidores a &#8216;parasitas&#8217;"},"content":{"rendered":"<p>A Justi\u00e7a Federal condenou nesta sexta-feira (18) o ministro da Economia, <strong><a href=\"https:\/\/www.suno.com.br\/tudo-sobre\/paulo-guedes\/\">Paulo Guedes<\/a><\/strong>, a pagar R$ 50 mil ao Sindicato dos Policiais Federais da Bahia (Sindipol-BA) por ter comparado servidores p\u00fablicos a parasitas.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia-800x450.webp\" width=\"800\" height=\"450\" alt=\"Paulo Guedes \u00e9 condenado por comparar servidores a &#8216;parasitas&#8217;\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Guedes afirmou que n\u00e3o tem imposto nenhum<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<div class=\"hubspot-form-wrapper\">\n\t<div id=\"single-form-target\"><\/div>\n<\/div>\n\n<p>O chefe do Minist\u00e9rio da Economia foi condenado pela ju\u00edza Cl\u00e1udia da Costa Tourinho Scarpa, da 4\u00aa Vara Federal C\u00edvel da Se\u00e7\u00e3o Judici\u00e1ria da Bahia, em a\u00e7\u00e3o de repara\u00e7\u00e3o por <strong>dano moral coletivo<\/strong> movida pela entidade ap\u00f3s Paulo Guedes fazer a compara\u00e7\u00e3o em palestra no dia 7 de fevereiro deste ano, no semin\u00e1rio Pacto Federativo, promovido pela FGV (Funda\u00e7\u00e3o Getulio Vargas).<\/p>\n<p>&#8220;O funcionalismo teve aumento de 50% acima da infla\u00e7\u00e3o, al\u00e9m de ter estabilidade na carreira e aposentadoria generosa. O hospedeiro est\u00e1 morrendo, o cara virou um parasita&#8221;, afirmou o ministro na ocasi\u00e3o.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e Video Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/a><\/p>\n<p>O economista pediu desculpas aos servidores p\u00fablicos tr\u00eas dias depois e afirmou que sua inten\u00e7\u00e3o &#8220;jamais foi ofender as pessoas que cumprem seus deveres&#8221;. &#8220;Me expressei mal e pe\u00e7o desculpas n\u00e3o s\u00f3 aos meus queridos familiares e amigos, mas a todos os exemplares funcion\u00e1rios p\u00fablicos a quem eu possa descuidadamente ter ofendido&#8221;, salientou.<\/p>\n<h2>Paulo Guedes violou direitos da personalidade, diz ju\u00edza<\/h2>\n<p>Dessa forma, a magistrada entendeu que o ministro violou &#8220;os direitos da personalidade dos integrantes da categoria profissional representada por este ente sindical, por meio dos seus pronunciamentos&#8221;.<\/p>\n<p>Em nota, o presidente do Sindipol-BA, Jos\u00e9 M\u00e1rio Lima, avaliou que a justi\u00e7a foi feita. &#8220;Qualquer cidad\u00e3o independentemente da sua estatura de poder ou financeira, tem que ter a devida reprimenda quando est\u00e1 errado. A lei \u00e9 para todos&#8221;, destacou o chefe da entidade.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Saiba mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-reforma-administrativa-economizara-r-300-bi-10-anos\/\">\n\t\t\tPaulo Guedes diz que reforma administrativa economizar\u00e1 R$ 300 bi em 10 anos\t\t<\/a>\n\t<\/div>\n\n\n<p>O Minist\u00e9rio da Economia n\u00e3o se manifestou sobre a decis\u00e3o, deixando o posicionamento a cargo da Advocacia-Geral da Uni\u00e3o. A AGU informou que ir\u00e1 encaminhar um recurso contra a condena\u00e7\u00e3o de <strong>Paulo Guedes<\/strong>.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>A Justi\u00e7a Federal condenou nesta sexta-feira (18) o ministro da Economia, Paulo Guedes, a pagar R$ 50 mil ao Sindicato dos Policiais Federais da Bahia (Sindipol-BA) por ter comparado servidores p\u00fablicos a parasitas. Guedes afirmou que n\u00e3o tem imposto nenhum O chefe do Minist\u00e9rio da Economia foi condenado pela ju\u00edza Cl\u00e1udia da Costa Tourinho Scarpa, [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":79813,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[62],"tags":[796],"suno_strategy":[],"class_list":["post-85875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-paulo-guedes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paulo Guedes \u00e9 condenado por comparar servidores a &#039;parasitas&#039;<\/title>\n<meta name=\"description\" content=\"A Justi\u00e7a Federal condenou o ministro Paulo Guedes a pagar R$ 50 mil por comparar servidores p\u00fablicos a parasitas. Clique para saber mais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paulo Guedes \u00e9 condenado por comparar servidores a &#039;parasitas&#039;\" \/>\n<meta property=\"og:description\" content=\"A Justi\u00e7a Federal condenou o ministro Paulo Guedes a pagar R$ 50 mil por comparar servidores p\u00fablicos a parasitas. Clique para saber mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arthur Guimar\u00e3es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Guimar\u00e3es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/\"},\"author\":{\"name\":\"Arthur Guimar\u00e3es\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c\"},\"headline\":\"Paulo Guedes \u00e9 condenado por comparar servidores a &#8216;parasitas&#8217;\",\"datePublished\":\"2020-09-18T23:09:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/\"},\"wordCount\":370,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia-jpg.webp\",\"keywords\":[\"Paulo Guedes\"],\"articleSection\":[\"Economia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/\",\"name\":\"Paulo Guedes \u00e9 condenado por comparar servidores a 'parasitas'\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia-jpg.webp\",\"datePublished\":\"2020-09-18T23:09:18+00:00\",\"description\":\"A Justi\u00e7a Federal condenou o ministro Paulo Guedes a pagar R$ 50 mil por comparar servidores p\u00fablicos a parasitas. Clique para saber mais\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia-jpg.webp\",\"width\":1170,\"height\":700,\"caption\":\"Guedes afirmou que n\u00e3o tem imposto nenhum\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Economia\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/economia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Paulo Guedes \u00e9 condenado por comparar servidores a &#8216;parasitas&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c\",\"name\":\"Arthur Guimar\u00e3es\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g\",\"caption\":\"Arthur Guimar\u00e3es\"},\"description\":\"Arthur Guimar\u00e3es escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal de not\u00edcias da Suno Research. Atualmente, \u00e9 estudante de jornalismo pela Faculdade C\u00e1sper L\u00edbero.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paulo Guedes \u00e9 condenado por comparar servidores a 'parasitas'","description":"A Justi\u00e7a Federal condenou o ministro Paulo Guedes a pagar R$ 50 mil por comparar servidores p\u00fablicos a parasitas. Clique para saber mais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/","og_locale":"pt_BR","og_type":"article","og_title":"Paulo Guedes \u00e9 condenado por comparar servidores a 'parasitas'","og_description":"A Justi\u00e7a Federal condenou o ministro Paulo Guedes a pagar R$ 50 mil por comparar servidores p\u00fablicos a parasitas. Clique para saber mais","og_url":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1170,"height":700,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia.jpg","type":"image\/jpeg"}],"author":"Arthur Guimar\u00e3es","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Arthur Guimar\u00e3es","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/"},"author":{"name":"Arthur Guimar\u00e3es","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c"},"headline":"Paulo Guedes \u00e9 condenado por comparar servidores a &#8216;parasitas&#8217;","datePublished":"2020-09-18T23:09:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/"},"wordCount":370,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia-jpg.webp","keywords":["Paulo Guedes"],"articleSection":["Economia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/","url":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/","name":"Paulo Guedes \u00e9 condenado por comparar servidores a 'parasitas'","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia-jpg.webp","datePublished":"2020-09-18T23:09:18+00:00","description":"A Justi\u00e7a Federal condenou o ministro Paulo Guedes a pagar R$ 50 mil por comparar servidores p\u00fablicos a parasitas. Clique para saber mais","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia-jpg.webp","width":1170,"height":700,"caption":"Guedes afirmou que n\u00e3o tem imposto nenhum"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Economia","item":"https:\/\/www.suno.com.br\/noticias\/economia\/"},{"@type":"ListItem","position":3,"name":"Paulo Guedes \u00e9 condenado por comparar servidores a &#8216;parasitas&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c","name":"Arthur Guimar\u00e3es","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g","caption":"Arthur Guimar\u00e3es"},"description":"Arthur Guimar\u00e3es escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal de not\u00edcias da Suno Research. Atualmente, \u00e9 estudante de jornalismo pela Faculdade C\u00e1sper L\u00edbero.","url":"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/9dfb2f8b-paulo_guedes_mudan\u00e7a_eixo_economia-400x200.webp\" alt=\"Paulo Guedes \u00e9 condenado por comparar servidores a &#8216;parasitas&#8217;\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/economia\/\">Economia<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/paulo-guedes-condenado-comparar-servidores-parasitas\/\"><h2 class=\"content__title\">Paulo Guedes \u00e9 condenado por comparar servidores a &#8216;parasitas&#8217;<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/02\/dfb40897-eu-150x150.webp\" alt=\"Arthur Guimar\u00e3es\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/\"><span itemprop=\"author\">Arthur Guimar\u00e3es<\/span><\/a><\/span><time datetime=\"2020-09-18T20:09:18-03:00\" itemprop=\"datePublished\">18\/09\/2020 20:09<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/85875"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=85875"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/85875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/79813"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=85875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=85875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=85875"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=85875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}