{"id":73891,"date":"2020-07-20T10:26:50","date_gmt":"2020-07-20T13:26:50","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=73891"},"modified":"2020-07-20T10:26:50","modified_gmt":"2020-07-20T13:26:50","slug":"ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/","title":{"rendered":"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria"},"content":{"rendered":"<p>O <a href=\"https:\/\/www.suno.com.br\/artigos\/ibovespa\/\"><strong>Ibovespa<\/strong> <\/a>inicia a semana est\u00e1vel com os assuntos nacionais no radar como a reforma tribut\u00e1ria e proje\u00e7\u00f5es de crescimento econ\u00f4mico do Brasil.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa-800x450.webp\" width=\"800\" height=\"450\" alt=\"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">Ibovespa<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n<p>Por volta das 10h20, nesta segunda-feira (20), o Ibovespa abriu em leve queda de 0,04%, a 102.856,33 pontos. O mercado est\u00e1 ansioso para a proposta do governo federal da reforma tribut\u00e1ria que dever\u00e1 ser entregue amanh\u00e3.<\/p>\n<p>Al\u00e9m disso, segue no radar dos investidores a diminui\u00e7\u00e3o, novamente, da proje\u00e7\u00e3o do PIB deste ano para retra\u00e7\u00e3o de 5,95%.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: o primeiro passo para alcan\u00e7ar a sua independ\u00eancia financeira. Acesse agora, \u00e9 gratuito!<\/a><\/p>\n<h2>Reforma tribut\u00e1ria<\/h2>\n<p>No Brasil, os investidores est\u00e3o atentos as declara\u00e7\u00f5es do ministro da Economia, <a href=\"https:\/\/www.suno.com.br\/tudo-sobre\/paulo-guedes\/\">Paulo Guedes<\/a>, sobre a reforma tribut\u00e1ria.<\/p>\n<p>Na \u00faltima quinta-feira (16), o ministro afirmou que a proposta da reforma tribut\u00e1ria do governo j\u00e1 est\u00e1 pronta na Casa Civil e deve ser levada para a casa do presidente do Senado Davi Alcolumbre, na pr\u00f3xima ter\u00e7a-feira (21).<\/p>\n<p>Guedes ainda salientou que n\u00e3o \u00e9 poss\u00edvel afirmar se haver\u00e1 um imposto cobrado sobre transa\u00e7\u00f5es na reforma , e destacou que &#8220;se eu for come\u00e7ar sobre o que nos desune, vai acabar a reforma tribut\u00e1ria antes de a gente come\u00e7ar&#8221;.<\/p>\n<p>Al\u00e9m disso, o economista afirmou que j\u00e1 enviou as propostas do executivo para a Casa Civil, que depois devem passar para o Congresso. &#8220;Vamos levar para o presidente do Senado para encaminhar \u00e0 comiss\u00e3o mista&#8221;, apontou o ministro.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/guedes-quer-tributacao-digital-afirma-bolsonaro\/\">Veja Tamb\u00e9m: Guedes n\u00e3o quer CPMF, mas uma tributa\u00e7\u00e3o digital, afirma Bolsonaro<\/a><\/p>\n<p>Segundo Guedes, o governo usa como t\u00e1tica o envio de propostas que possam ser utilizadas em textos que j\u00e1 est\u00e3o sendo discutidos no Congresso.<\/p>\n<h2>Boletim Focus<\/h2>\n<p>Os respons\u00e1veis pela elabora\u00e7\u00e3o do <a href=\"https:\/\/www.suno.com.br\/artigos\/relatorio-focus\/\">Boletim <\/a><a href=\"https:\/\/www.suno.com.br\/artigos\/relatorio-focus\/\">Focus<\/a> diminu\u00edram, novamente, suas previs\u00f5es para a queda do <a href=\"https:\/\/www.suno.com.br\/artigos\/pib-produto-interno-bruto\/\">Produto Interno Bruto (PIB)<\/a> deste ano. A estimativa divulgada nesta segunda-feira (20) \u00e9 de uma retra\u00e7\u00e3o de 5,95%, ante 6,10% na \u00faltima semana.<\/p>\n<p>H\u00e1 sete semanas, todavia, o Boletim Focus previa uma queda de 6,54%. Essa \u00e9 a terceira semana consecutiva de melhora nas previs\u00f5es. No primeiro trimestre de 2020, a economia brasileira caiu 1,5%, de acordo com o Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). O resultado do segundo trimestre ser\u00e1 divulgado em 1\u00ba de setembro.<\/p>\n<p>O relat\u00f3rio divulgado pelo <a href=\"https:\/\/www.suno.com.br\/artigos\/bacen\/\">Banco Central (BC)<\/a> semanalmente, no in\u00edcio do ano, previa um crescimento de 2,30% da economia do Brasil. Os especialistas, entretanto, n\u00e3o esperavam pelos dr\u00e1sticos efeitos da pandemia do <a href=\"https:\/\/www.suno.com.br\/noticias\/tags\/coronavirus\/\">novo coronav\u00edrus (Covid-19)<\/a>. Para o ano que vem, os economistas permanecem com a estimativa de um crescimento de 3,50% pela oitava semana consecutiva.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/boletim-focus-pib-inflacao-20072020\/\">Saiba Mais: Boletim Focus projeta queda do PIB menos intensa<\/a><\/p>\n<p>Ademais, o relat\u00f3rio\u00a0permanece com a estimativa de que a <a href=\"https:\/\/www.suno.com.br\/artigos\/taxa-selic\/\">taxa b\u00e1sica de juros da economia (Selic)<\/a> terminar\u00e1 o ano na casa dos 2%, ainda 0,25% abaixo do atual patamar. A taxa foi cortada em 0,75% pelo <a href=\"https:\/\/www.suno.com.br\/artigos\/copom\/\">Comit\u00ea de Pol\u00edtica Monet\u00e1ria (Copom)<\/a> na \u00faltima reuni\u00e3o, em 17 de junho, trazendo-a para o menor n\u00edvel na s\u00e9rie hist\u00f3rica. A pr\u00f3xima reuni\u00e3o ser\u00e1 no dia 4 de agosto.<\/p>\n<h2>PIB Brasil<\/h2>\n<p>Em reuni\u00e3o virtual do G-20, realizada na tarde do \u00faltimo s\u00e1bado (18), a delega\u00e7\u00e3o brasileira afirmou que o <a href=\"https:\/\/www.suno.com.br\/artigos\/pib-produto-interno-bruto\/\">Produto Interno Bruto (PIB)<\/a> do Pa\u00eds cair\u00e1 cerca de 5% neste ano, em meio \u00e0s medidas\u00a0para mitigar a crise causada pela pandemia do novo <a href=\"https:\/\/www.suno.com.br\/noticias\/?s=coronav%C3%ADrus\">coronav\u00edrus (Covid-19)<\/a>.<\/p>\n<p>A equipe brasileira disse que a perspectiva global sobre o desempenho econ\u00f4mico permanece altamente incerto, em raz\u00e3o dos efeitos da pandemia. No entanto, a delega\u00e7\u00e3o salientou que por mais que a atividade econ\u00f4mica mostre sinais de recupera\u00e7\u00e3o, a produ\u00e7\u00e3o deve permanecer baixa por um per\u00edodo prolongado. O <a href=\"https:\/\/www.suno.com.br\/artigos\/fmi\/\">Fundo Monet\u00e1rio Internacional (FMI)<\/a> projeta uma <a href=\"https:\/\/www.suno.com.br\/noticias\/pib-do-brasil-pandemia-fmi\/\">queda de at\u00e9 9% na economia brasileira<\/a>.<\/p>\n<p>O Secret\u00e1rio de Assuntos Econ\u00f4micos Internacionais, Erivaldo Gomes, que substituiu o ministro <a href=\"https:\/\/www.suno.com.br\/tudo-sobre\/paulo-guedes\/\">Paulo Guedes<\/a> que n\u00e3o p\u00f4de participar, disse que &#8220;a pandemia interrompeu a tend\u00eancia de recupera\u00e7\u00e3o observada no Brasil, apoiada por pol\u00edticas econ\u00f4micas s\u00f3lidas&#8221;. Gomes refor\u00e7ou que a crise atual demanda por um novo conjunto de a\u00e7\u00f5es.<\/p>\n<h2>\u00daltima cota\u00e7\u00e3o do Ibovespa<\/h2>\n<p>Na \u00faltima sess\u00e3o, sexta-feira (17), o <strong>Ibovespa<\/strong> encerrou em alta de 2,32%, a 102.888,250 pontos.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>O Ibovespa inicia a semana est\u00e1vel com os assuntos nacionais no radar como a reforma tribut\u00e1ria e proje\u00e7\u00f5es de crescimento econ\u00f4mico do Brasil. Ibovespa Por volta das 10h20, nesta segunda-feira (20), o Ibovespa abriu em leve queda de 0,04%, a 102.856,33 pontos. O mercado est\u00e1 ansioso para a proposta do governo federal da reforma tribut\u00e1ria [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":3936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[721,1286],"suno_strategy":[],"class_list":["post-73891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-ibovespa","tag-reforma-tributaria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria<\/title>\n<meta name=\"description\" content=\"Por volta das 10h20, nesta segunda-feira (20), o Ibovespa abriu em leve queda de 0,04%, a 102.856,33 pontos. Clique aqui e saiba mais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria\" \/>\n<meta property=\"og:description\" content=\"Por volta das 10h20, nesta segunda-feira (20), o Ibovespa abriu em leve queda de 0,04%, a 102.856,33 pontos. Clique aqui e saiba mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1359\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Poliana Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Poliana Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/\"},\"author\":{\"name\":\"Poliana Santos\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\"},\"headline\":\"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria\",\"datePublished\":\"2020-07-20T13:26:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/\"},\"wordCount\":731,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa-jpg.webp\",\"keywords\":[\"Ibovespa\",\"reforma tribut\u00e1ria\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/\",\"name\":\"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa-jpg.webp\",\"datePublished\":\"2020-07-20T13:26:50+00:00\",\"description\":\"Por volta das 10h20, nesta segunda-feira (20), o Ibovespa abriu em leve queda de 0,04%, a 102.856,33 pontos. Clique aqui e saiba mais\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa-jpg.webp\",\"width\":2560,\"height\":1359,\"caption\":\"Ibovespa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/mercado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\",\"name\":\"Poliana Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"caption\":\"Poliana Santos\"},\"description\":\"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria","description":"Por volta das 10h20, nesta segunda-feira (20), o Ibovespa abriu em leve queda de 0,04%, a 102.856,33 pontos. Clique aqui e saiba mais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/","og_locale":"pt_BR","og_type":"article","og_title":"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria","og_description":"Por volta das 10h20, nesta segunda-feira (20), o Ibovespa abriu em leve queda de 0,04%, a 102.856,33 pontos. Clique aqui e saiba mais","og_url":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":2560,"height":1359,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa.jpg","type":"image\/jpeg"}],"author":"Poliana Santos","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Poliana Santos","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/"},"author":{"name":"Poliana Santos","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda"},"headline":"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria","datePublished":"2020-07-20T13:26:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/"},"wordCount":731,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa-jpg.webp","keywords":["Ibovespa","reforma tribut\u00e1ria"],"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/","url":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/","name":"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa-jpg.webp","datePublished":"2020-07-20T13:26:50+00:00","description":"Por volta das 10h20, nesta segunda-feira (20), o Ibovespa abriu em leve queda de 0,04%, a 102.856,33 pontos. Clique aqui e saiba mais","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa-jpg.webp","width":2560,"height":1359,"caption":"Ibovespa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/www.suno.com.br\/noticias\/mercado\/"},{"@type":"ListItem","position":3,"name":"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda","name":"Poliana Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","caption":"Poliana Santos"},"description":"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.","url":"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/09\/de4d6372-dolar-ibovespa-400x200.webp\" alt=\"Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mercado\/\">Mercado<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-abre-estavel-atento-ao-desdobramento-da-reforma-tributaria-20072020\/\"><h2 class=\"content__title\">Ibovespa abre est\u00e1vel atento ao desdobramento da reforma tribut\u00e1ria<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2020-07-20T10:26:50-03:00\" itemprop=\"datePublished\">20\/07\/2020 10:26<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/73891"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=73891"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/73891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/3936"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=73891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=73891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=73891"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=73891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}