{"id":72336,"date":"2020-07-08T12:31:23","date_gmt":"2020-07-08T15:31:23","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=72336"},"modified":"2020-07-08T12:31:23","modified_gmt":"2020-07-08T15:31:23","slug":"brexit-acordo-reino-unido-uniao-europeia","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/","title":{"rendered":"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel"},"content":{"rendered":"<p>Mesmo ap\u00f3s a decis\u00e3o pela sa\u00edda do Reino Unido da <a href=\"https:\/\/www.suno.com.br\/artigos\/uniao-europeia\/\">Uni\u00e3o Europeia (UE)<\/a>, as negocia\u00e7\u00f5es entre as partes continuam. A primeira-ministra da Alemanha, Angela Merkel, disse, nesta quarta-feira (8), que o bloco europeu precisa se preparar para a possibilidade de que n\u00e3o haja um acordo com os brit\u00e2nicos ap\u00f3s a transi\u00e7\u00e3o do <strong>Brexit<\/strong>.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel-800x450.webp\" width=\"800\" height=\"450\" alt=\"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">Na \u00faltima quinta-feira (20), o jornal alem\u00e3o S\u00fcddeutsche Zeitung noticiou que a chanceler disse que o acordo entre UE e Mercosul levaria \u00e0 destrui\u00e7\u00e3o da Amaz\u00f4nia.<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n<p>As negocia\u00e7\u00f5es t\u00eam a data limite em dezembro deste ano, e a premi\u00ea alertou sobre as dificuldades encontradas para se chegar a um entendimento. \u201cO progresso das negocia\u00e7\u00f5es tem sido pequeno, para dizer de modo diplom\u00e1tico\u201d, disse <strong>Merkel<\/strong>, sobre o Brexit, no <strong>Parlamento Europeu<\/strong>.<\/p>\n<p>Embora recentemente as partes tenham se disposto a intensificar as negocia\u00e7\u00f5es, alguns entraves ainda pairam sobre os representantes. Direitos de pesca, influ\u00eancia de cortes europeias no Reino Unido e acesso brit\u00e2nico ao mercado da <a href=\"https:\/\/www.suno.com.br\/artigos\/zona-do-euro\/\">zona do euro<\/a> s\u00e3o os principais pontos de diverg\u00eancia. A nova rodada de conversas, que estava prevista para ser encerrada na pr\u00f3xima quinta-feira (9), foi finalizada um dia antes.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">No Suno One voc\u00ea aprende a fazer seu dinheiro trabalhar para voc\u00ea. Cadastre-se gratuitamente agora!<\/a><\/p>\n<p>A declara\u00e7\u00e3o de Merkel vem logo ap\u00f3s o primeiro-ministro brit\u00e2nico, <strong>Boris Johnson<\/strong>, pressionar a premi\u00ea alem\u00e3, por telefone, na \u00faltima ter\u00e7a-feira (7), afirmando que o Reino Unido est\u00e1 apto para deixar o bloco europeu sem as bases acertadas caso as negocia\u00e7\u00f5es n\u00e3o avancem.<\/p>\n<p>Em comunicado, o gabinete de Johnson disse que \u201co primeiro-ministro sublinhou o compromisso do Reino Unido para trabalhar duro para encontrar um acordo com o processo de negocia\u00e7\u00f5es intensificadas\u201d na conversa com a l\u00edder alem\u00e3. \u201cEle tamb\u00e9m notou que o Reino Unido estaria, da mesma forma, pronto para deixar o per\u00edodo de transi\u00e7\u00e3o em condi\u00e7\u00f5es como as da Austr\u00e1lia se um acordo n\u00e3o puder ser alcan\u00e7ado\u201d.<\/p>\n<p>A Austr\u00e1lia n\u00e3o possui um acordo comercial coletivo com a UE, apenas acordos espec\u00edficos para determinadas mercadorias. Grande parte do com\u00e9rcio entre o pa\u00eds da Oceania e o bloco europeu \u00e9 regido pelas regras globais da <a href=\"https:\/\/www.suno.com.br\/artigos\/omc-organizacao-mundial-do-comercio\/\">Organiza\u00e7\u00e3o Mundial do Com\u00e9rcio (OMC)<\/a>.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/brexit-novas-negociacoes-nao-avancam\/\">Veja tamb\u00e9m: Brexit: novas negocia\u00e7\u00f5es entre Reino Unido e UE n\u00e3o avan\u00e7am<\/a><\/p>\n<p>Embora j\u00e1 se considere avisada, Merkel continua defendendo um acordo com os brit\u00e2nicos. A <strong>Alemanha<\/strong>, principal economia da zona do euro, ter\u00e1 uma participa\u00e7\u00e3o fundamental nesse processo &#8212; recentemente, o pa\u00eds assumiu a presid\u00eancia rotativa da UE.<\/p>\n<p>O acordo inicial para o <strong>Brexit<\/strong> foi acertado <a href=\"https:\/\/www.suno.com.br\/noticias\/brexit-oficial-nesta-sexta\/\">em 31 de janeiro deste ano, ap\u00f3s consecutivas posterga\u00e7\u00f5es<\/a>. A menos de cinco meses para o final do prazo estipulado, no entanto, o Reino Unido n\u00e3o considera solicitar um adiamento. Todavia, por parte da comitiva europeia, a possibilidade j\u00e1 \u00e9 palp\u00e1vel ap\u00f3s as infrut\u00edferas negocia\u00e7\u00f5es.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Mesmo ap\u00f3s a decis\u00e3o pela sa\u00edda do Reino Unido da Uni\u00e3o Europeia (UE), as negocia\u00e7\u00f5es entre as partes continuam. A primeira-ministra da Alemanha, Angela Merkel, disse, nesta quarta-feira (8), que o bloco europeu precisa se preparar para a possibilidade de que n\u00e3o haja um acordo com os brit\u00e2nicos ap\u00f3s a transi\u00e7\u00e3o do Brexit. Na \u00faltima [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":72344,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[753,730,731],"suno_strategy":[],"class_list":["post-72336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-brexit","tag-reino-unido","tag-uniao-europeia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel<\/title>\n<meta name=\"description\" content=\"Mesmo ap\u00f3s a decis\u00e3o pela sa\u00edda do Reino Unido da UE no Brexit, as negocia\u00e7\u00f5es entre as partes continuam. Clique e saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel\" \/>\n<meta property=\"og:description\" content=\"Mesmo ap\u00f3s a decis\u00e3o pela sa\u00edda do Reino Unido da UE no Brexit, as negocia\u00e7\u00f5es entre as partes continuam. Clique e saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jader Lazarini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jader Lazarini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/\"},\"author\":{\"name\":\"Jader Lazarini\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\"},\"headline\":\"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel\",\"datePublished\":\"2020-07-08T15:31:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/\"},\"wordCount\":498,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel.jpg\",\"keywords\":[\"Brexit\",\"Reino Unido\",\"Uni\u00e3o Europeia\"],\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/\",\"name\":\"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel.jpg\",\"datePublished\":\"2020-07-08T15:31:23+00:00\",\"description\":\"Mesmo ap\u00f3s a decis\u00e3o pela sa\u00edda do Reino Unido da UE no Brexit, as negocia\u00e7\u00f5es entre as partes continuam. Clique e saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Na \u00faltima quinta-feira (20), o jornal alem\u00e3o S\u00fcddeutsche Zeitung noticiou que a chanceler disse que o acordo entre UE e Mercosul levaria \u00e0 destrui\u00e7\u00e3o da Amaz\u00f4nia.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\",\"name\":\"Jader Lazarini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"caption\":\"Jader Lazarini\"},\"description\":\"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel","description":"Mesmo ap\u00f3s a decis\u00e3o pela sa\u00edda do Reino Unido da UE no Brexit, as negocia\u00e7\u00f5es entre as partes continuam. Clique e saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/","og_locale":"pt_BR","og_type":"article","og_title":"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel","og_description":"Mesmo ap\u00f3s a decis\u00e3o pela sa\u00edda do Reino Unido da UE no Brexit, as negocia\u00e7\u00f5es entre as partes continuam. Clique e saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1920,"height":1080,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel.jpg","type":"image\/jpeg"}],"author":"Jader Lazarini","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Jader Lazarini","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/"},"author":{"name":"Jader Lazarini","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f"},"headline":"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel","datePublished":"2020-07-08T15:31:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/"},"wordCount":498,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel.jpg","keywords":["Brexit","Reino Unido","Uni\u00e3o Europeia"],"articleSection":["Internacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/","url":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/","name":"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel.jpg","datePublished":"2020-07-08T15:31:23+00:00","description":"Mesmo ap\u00f3s a decis\u00e3o pela sa\u00edda do Reino Unido da UE no Brexit, as negocia\u00e7\u00f5es entre as partes continuam. Clique e saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel.jpg","width":1920,"height":1080,"caption":"Na \u00faltima quinta-feira (20), o jornal alem\u00e3o S\u00fcddeutsche Zeitung noticiou que a chanceler disse que o acordo entre UE e Mercosul levaria \u00e0 destrui\u00e7\u00e3o da Amaz\u00f4nia."},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Internacional","item":"https:\/\/www.suno.com.br\/noticias\/internacional\/"},{"@type":"ListItem","position":3,"name":"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f","name":"Jader Lazarini","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","caption":"Jader Lazarini"},"description":"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).","url":"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/07\/b3c3b560-merkel-400x200.webp\" alt=\"Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/internacional\/\">Internacional<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/brexit-acordo-reino-unido-uniao-europeia\/\"><h2 class=\"content__title\">Brexit: Reino Unido e UE podem n\u00e3o entrar em acordo, diz Merkel<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/178e6598-foto-perfil-2-150x150.jpg\" alt=\"Jader Lazarini\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"><span itemprop=\"author\">Jader Lazarini<\/span><\/a><\/span><time datetime=\"2020-07-08T12:31:23-03:00\" itemprop=\"datePublished\">08\/07\/2020 12:31<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/72336"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=72336"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/72336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/72344"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=72336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=72336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=72336"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=72336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}