{"id":70955,"date":"2020-06-29T19:09:49","date_gmt":"2020-06-29T22:09:49","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=70955"},"modified":"2021-05-11T20:21:59","modified_gmt":"2021-05-11T23:21:59","slug":"xp-sec-follow-on-us1bi","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/","title":{"rendered":"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC"},"content":{"rendered":"<p>A <strong>XP<\/strong> Inc anunciou nesta segunda-feira (29) que protocolou na <a href=\"https:\/\/www.suno.com.br\/artigos\/sec\/\">Securities and Exchange Commission (SEC)<\/a>, nos Estados Unidos, um prospecto preliminar para a realiza\u00e7\u00e3o de um <a href=\"https:\/\/www.suno.com.br\/artigos\/follow-on\/\">follow-on<\/a> de cerca de US$ 1,012 bilh\u00e3o (equivalente a R$ 5,48 bilh\u00f5es).<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp-800x450.webp\" width=\"800\" height=\"450\" alt=\"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">XP perde maior escrit\u00f3rio de agentes aut\u00f4nomos para rival BTG<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n<p>O documento indica que a oferta subsequente de a\u00e7\u00f5es seria uma venda secund\u00e1ria de 19.535.420 de a\u00e7\u00f5es classe A, ofertadas pela XP Controle Participa\u00e7\u00f5es e pela General Atlantic. Conforme o prospecto, o pre\u00e7o teto por a\u00e7\u00e3o ser\u00e1 de US$ 45,05.<\/p>\n<p>Segundo a empresa, a oferta ainda poder\u00e1 ter um lote adicional de 2.930.313 a\u00e7\u00f5es classe A, elevando a um total de 22.465.733. Ao valor de US$ 45,05, o follow-on alcan\u00e7aria o patamar de US$ 1,012 bilh\u00e3o.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: o primeiro passo para alcan\u00e7ar a sua independ\u00eancia financeira. Acesse agora, \u00e9 gratuito!<\/a><\/p>\n<p>Considerando o valor de fechamento das a\u00e7\u00f5es da XP, negociadas na <a href=\"https:\/\/www.suno.com.br\/artigos\/nasdaq\/\">bolsa de valores norte-americana Nasdaq<\/a>, na \u00faltima sexta-feira (26), de US$ 43,88, o valor de chegaria a US$ 985,8 milh\u00f5es.<\/p>\n<p><iframe loading=\"lazy\" title=\"?Resultados da Taurus (TASA4), Ita\u00fa (ITUB4) n\u00e3o quer vender XP, TikTok proibido\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/HKgPnFcKmyc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&#8220;Ap\u00f3s a oferta, nossos principais acionistas, XP Controle Participa\u00e7\u00f5es S.A., ou XP Controle, ITB Holding Brasil Participa\u00e7\u00f5es Ltda., ou Ita\u00fa, e General Atlantic (XP) Bermuda, L.P., ou GA Bermuda, v\u00e3o deter 79,49% do capital, assumindo n\u00e3o exercer op\u00e7\u00e3o de subscri\u00e7\u00e3o para adquirir as a\u00e7\u00f5es do lote adicional&#8221;, informou o documento.<\/p>\n<p>A opera\u00e7\u00e3o ser\u00e1 coordenada pela XP Investimentos e os bancos estadunidenses<\/p>\n<ul>\n<li>Morgan Stanley;<\/li>\n<li>Goldman Sachs;<\/li>\n<li>J.P.Morgan.<\/li>\n<\/ul>\n<p>Com isso, ap\u00f3s a oferta subsequente de a\u00e7\u00f5es, XP Controle manter\u00e1 aproximadamente 53,57% do poder de voto.<\/p>\n<h2>XP divulga pr\u00e9via operacional do 2T20<\/h2>\n<p>A XP Inc. tamb\u00e9m reportou nesta segunda-feira sua pr\u00e9via operacional do segundo trimestre deste ano. O per\u00edodo ainda n\u00e3o terminou e, por essa raz\u00e3o, os n\u00fameros ainda n\u00e3o foram auditados.<\/p>\n<p>O <a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\">lucro l\u00edquido<\/a> da empresa deve ficar na faixa de R$ 420 milh\u00f5es e R$ 520 milh\u00f5es. O meio-termo entre os dois valores, R$ 470 milh\u00f5es, representaria um crescimento de 106% na compara\u00e7\u00e3o com o mesmo per\u00edodo do ano anterior.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/itau-itub4-nao-tem-intencao-de-vender-participacao-na-xp-diz-jornal\/\">Saiba mais: Ita\u00fa (ITUB4) n\u00e3o tem inten\u00e7\u00e3o de vender participa\u00e7\u00e3o na XP, diz jornal<\/a><\/p>\n<p>Segundo a pr\u00e9via, estima-se que a <a href=\"https:\/\/www.suno.com.br\/artigos\/receita-bruta\/\">receita bruta<\/a> fique entre R$ 1,850 bilh\u00e3o e R$ 1,980 bilh\u00e3o. A m\u00e9dia dos dois valores, R$ 1,915 bilh\u00e3o, significaria um aumento de 55%.<\/p>\n<p>Ao mesmo tempo, as proje\u00e7\u00f5es apontam para uma <a href=\"https:\/\/www.suno.com.br\/artigos\/margem-liquida\/\">margem l\u00edquida<\/a> entre 24% e 28%, ante 20% no mesmo intervalo do ano passado.<\/p>\n<p>Enquanto, as entradas l\u00edquidas de recursos da <strong>XP<\/strong> deve registrar algo entre R$ 10 bilh\u00f5es e R$ 12 bilh\u00f5es em junho. Os valores de maio (R$ 8,3 bilh\u00f5es) e abril (R$ 6,9 bilh\u00f5es) j\u00e1 foram informados.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>A XP Inc anunciou nesta segunda-feira (29) que protocolou na Securities and Exchange Commission (SEC), nos Estados Unidos, um prospecto preliminar para a realiza\u00e7\u00e3o de um follow-on de cerca de US$ 1,012 bilh\u00e3o (equivalente a R$ 5,48 bilh\u00f5es). XP perde maior escrit\u00f3rio de agentes aut\u00f4nomos para rival BTG O documento indica que a oferta subsequente [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":37448,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[793,1436,1374,888],"suno_strategy":[],"class_list":["post-70955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-estados-unidos-eua","tag-follow-on-oferta-subsequente-de-acoes","tag-sec","tag-xp-investimentos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC<\/title>\n<meta name=\"description\" content=\"A XP protocolou na SEC um prospecto preliminar para a realiza\u00e7\u00e3o de um follow-on de cerca de US$ 1,012 bilh\u00e3o. Clique para saber mais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC\" \/>\n<meta property=\"og:description\" content=\"A XP protocolou na SEC um prospecto preliminar para a realiza\u00e7\u00e3o de um follow-on de cerca de US$ 1,012 bilh\u00e3o. Clique para saber mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arthur Guimar\u00e3es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Guimar\u00e3es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/\"},\"author\":{\"name\":\"Arthur Guimar\u00e3es\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c\"},\"headline\":\"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC\",\"datePublished\":\"2020-06-29T22:09:49+00:00\",\"dateModified\":\"2021-05-11T23:21:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/\"},\"wordCount\":478,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp-jpg.webp\",\"keywords\":[\"Estados Unidos (EUA)\",\"Follow-on (Oferta Subsequente de A\u00e7\u00f5es)\",\"SEC\",\"XP Investimentos\"],\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/\",\"name\":\"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp-jpg.webp\",\"datePublished\":\"2020-06-29T22:09:49+00:00\",\"dateModified\":\"2021-05-11T23:21:59+00:00\",\"description\":\"A XP protocolou na SEC um prospecto preliminar para a realiza\u00e7\u00e3o de um follow-on de cerca de US$ 1,012 bilh\u00e3o. Clique para saber mais\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp-jpg.webp\",\"width\":900,\"height\":900,\"caption\":\"XP perde maior escrit\u00f3rio de agentes aut\u00f4nomos para rival BTG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c\",\"name\":\"Arthur Guimar\u00e3es\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g\",\"caption\":\"Arthur Guimar\u00e3es\"},\"description\":\"Arthur Guimar\u00e3es escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal de not\u00edcias da Suno Research. Atualmente, \u00e9 estudante de jornalismo pela Faculdade C\u00e1sper L\u00edbero.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC","description":"A XP protocolou na SEC um prospecto preliminar para a realiza\u00e7\u00e3o de um follow-on de cerca de US$ 1,012 bilh\u00e3o. Clique para saber mais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/","og_locale":"pt_BR","og_type":"article","og_title":"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC","og_description":"A XP protocolou na SEC um prospecto preliminar para a realiza\u00e7\u00e3o de um follow-on de cerca de US$ 1,012 bilh\u00e3o. Clique para saber mais","og_url":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":900,"height":900,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp.jpg","type":"image\/jpeg"}],"author":"Arthur Guimar\u00e3es","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Arthur Guimar\u00e3es","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/"},"author":{"name":"Arthur Guimar\u00e3es","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c"},"headline":"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC","datePublished":"2020-06-29T22:09:49+00:00","dateModified":"2021-05-11T23:21:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/"},"wordCount":478,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp-jpg.webp","keywords":["Estados Unidos (EUA)","Follow-on (Oferta Subsequente de A\u00e7\u00f5es)","SEC","XP Investimentos"],"articleSection":["Internacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/","url":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/","name":"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp-jpg.webp","datePublished":"2020-06-29T22:09:49+00:00","dateModified":"2021-05-11T23:21:59+00:00","description":"A XP protocolou na SEC um prospecto preliminar para a realiza\u00e7\u00e3o de um follow-on de cerca de US$ 1,012 bilh\u00e3o. Clique para saber mais","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp-jpg.webp","width":900,"height":900,"caption":"XP perde maior escrit\u00f3rio de agentes aut\u00f4nomos para rival BTG"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Internacional","item":"https:\/\/www.suno.com.br\/noticias\/internacional\/"},{"@type":"ListItem","position":3,"name":"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c","name":"Arthur Guimar\u00e3es","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g","caption":"Arthur Guimar\u00e3es"},"description":"Arthur Guimar\u00e3es escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal de not\u00edcias da Suno Research. Atualmente, \u00e9 estudante de jornalismo pela Faculdade C\u00e1sper L\u00edbero.","url":"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/09\/6ea86ad5-xp-400x200.webp\" alt=\"XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/internacional\/\">Internacional<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/xp-sec-follow-on-us1bi\/\"><h2 class=\"content__title\">XP anuncia follow-on de quase US$ 1,012 bilh\u00e3o na SEC<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/02\/dfb40897-eu-150x150.webp\" alt=\"Arthur Guimar\u00e3es\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/\"><span itemprop=\"author\">Arthur Guimar\u00e3es<\/span><\/a><\/span><time datetime=\"2020-06-29T19:09:49-03:00\" itemprop=\"datePublished\">29\/06\/2020 19:09<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/70955"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=70955"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/70955\/revisions"}],"predecessor-version":[{"id":146099,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/70955\/revisions\/146099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/37448"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=70955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=70955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=70955"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=70955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}