{"id":640278,"date":"2026-02-01T10:00:00","date_gmt":"2026-02-01T13:00:00","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=640278"},"modified":"2026-02-02T08:54:33","modified_gmt":"2026-02-02T11:54:33","slug":"o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/","title":{"rendered":"Bradesco (BBDC4) e Santander (SANB11): Veja quem vai pagar dividendos na semana"},"content":{"rendered":"<p>Esta semana traz os <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" rel=\"noopener\">dividendos<\/a> que os investidores tanto esperam receber das empresas em que investem, caso do <strong>Bradesco (BBDC4)<\/strong>.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Bradesco (BBDC4) e Santander (SANB11): Veja quem vai pagar dividendos na semana\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Carrefour (CRFB3). Foto: Divulga\u00e7\u00e3o <\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"89005\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>Esta empresa far\u00e1 uma distribui\u00e7\u00e3o de R$ 0,0172 por a\u00e7\u00e3o em 2 de fevereiro, conforme os detalhes abaixo.<\/p>\n\n\n\n<p>De segunda-feira a sexta-feira, cinco empresas far\u00e3o o pagamento de dividendos aos seus acionistas, entre as quais est\u00e1 tamb\u00e9m o <a class=\"suno-keyword\" target=\"_blank\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/analitica\/acoes\/SANB11\/\" rel=\"noopener\">Santander (<\/a><a class=\"suno-keyword\" target=\"_blank\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/analitica\/acoes\/sanb11\/\" rel=\"noopener\">SANB11<\/a>).<\/p>\n\n\n\n<p>O Santander pagar\u00e1 R$ 0,5359 por a\u00e7\u00e3o em dividendos para seus acionistas em 5 de fevereiro.<\/p>\n\n\n\n<p>Lembrando que para ter direito a receber dividendos e <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/entenda-o-jcp\/\" rel=\"noopener\">juros sobre capital pr\u00f3prio<\/a>, o investidor precisava ter os pap\u00e9is em carteira no dia da data de corte e que n\u00e3o \u00e9 preciso fazer nenhuma a\u00e7\u00e3o.<\/p>\n\n\n\n<p>Muitos n\u00e3o sabem <strong>como receber dividendos<\/strong>, mas o&nbsp;dinheiro ficar\u00e1 dispon\u00edvel automaticamente na conta da corretora. Acompanhe abaixo os detalhes de cada pagamento.<\/p>\n\n\n\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:513,&quot;3&quot;:{&quot;1&quot;:0},&quot;12&quot;:0}\">\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Agenda de dividendos da semana<\/h2>\n\n\n\n<p><strong>Segunda-feira, 2\/2:<\/strong> <a class=\"suno-keyword\" target=\"_blank\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/analitica\/acoes\/bees3\/\" rel=\"noopener\">Banco Banestes (BEES3)<\/a> e <a class=\"suno-keyword\" target=\"_blank\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/analitica\/acoes\/BBDC4\/\" rel=\"noopener\">Bradesco (BBDC4)<\/a>.<\/p>\n\n\n\n<p><strong>Quarta-feira, 4\/2:<\/strong> <a class=\"suno-keyword\" target=\"_blank\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/analitica\/acoes\/MTRE3\/\" rel=\"noopener\">Mitre (MTRE3)<\/a>.<\/p>\n\n\n\n<p><strong>Quinta-feira, 5\/2:<\/strong> Santander (SANB11).<\/p>\n\n\n\n<p><strong>Sexta-feira, 3\/2:<\/strong> Banese (BGIP4).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Proventos da semana<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Segunda-feira, 2\/02<\/h3>\n\n\n\n<p><strong>Banco Banestes (BEES3)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tipo:<\/strong> JCP<\/li>\n\n\n\n<li><strong>Valor por a\u00e7\u00e3o:<\/strong> R$ 0,0287<\/li>\n\n\n\n<li><strong>Data de corte:<\/strong> 02\/01\/2026<\/li>\n\n\n\n<li><strong>Data de pagamento:<\/strong> 02\/02\/2026<\/li>\n<\/ul>\n\n\n\n<p><strong>Bradesco (BBDC4)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tipo:<\/strong> JCP<\/li>\n\n\n\n<li><strong>Valor por a\u00e7\u00e3o:<\/strong> R$ 0,0172<\/li>\n\n\n\n<li><strong>Data de corte:<\/strong> 02\/01\/2026<\/li>\n\n\n\n<li><strong>Data de pagamento:<\/strong> 02\/02\/2026<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Quarta-feira, 4\/02<\/h3>\n\n\n\n<p><strong>Mitre (MTRE3)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tipo:<\/strong> Dividendo<\/li>\n\n\n\n<li><strong>Valor por a\u00e7\u00e3o:<\/strong> R$ 0,0425<\/li>\n\n\n\n<li><strong>Data de corte:<\/strong> 26\/01\/2026<\/li>\n\n\n\n<li><strong>Data de pagamento:<\/strong> 04\/02\/2026<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Quinta-feira, 5\/02<\/h3>\n\n\n\n<p><strong>Santander (SANB11)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tipo:<\/strong> JCP<\/li>\n\n\n\n<li><strong>Valor por a\u00e7\u00e3o:<\/strong> R$ 0,1661 e R$ 0,5358<\/li>\n\n\n\n<li><strong>Data de corte:<\/strong> 02\/01\/2026 e 20\/01\/2026<\/li>\n\n\n\n<li><strong>Data de pagamento:<\/strong> 05\/02\/2026<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Sexta-feira, 3\/02<\/h3>\n\n\n\n<p><strong>Banese (BGIP4)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tipo:<\/strong> Dividendo, JCP, JCP e JCP<\/li>\n\n\n\n<li><strong>Valor por a\u00e7\u00e3o:<\/strong> R$ 0,8478, R$ 0,8578, R$ 0,8478 e R$ 0,9723<\/li>\n\n\n\n<li><strong>Data de corte:<\/strong> 19\/11\/2025, 19\/11\/2025, 19\/11\/2025 e 21\/01\/2026<\/li>\n\n\n\n<li><strong>Data de pagamento:<\/strong> 03\/02\/2026, 03\/02\/2026, 03\/02\/2026 e 06\/02\/2026<\/li>\n<\/ul>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Data de corte para dividendos<\/h2>\n\n\n\n<p>Para garantir mais fluxo de proventos no futuro, confira as empresas que marcaram a data de corte nesta semana para o pagamento de proventos, como a Banco Banestes (BEES3) e a Banco Banestes (BEES3). Veja a lista completa:<\/p>\n\n\n\n<p><strong>Segunda-feira (2\/02)<\/strong>:<\/p>\n\n\n\n<p><strong>Banco Banestes (BEES3)<\/strong><\/p>\n\n\n\n<p><strong>Valor por a\u00e7\u00e3o:<\/strong> R$ 0,02<\/p>\n\n\n\n<p><strong>Data de pagamento<\/strong>: 02\/03\/2026<\/p>\n\n\n\n<p>Vale destacar que esta mat\u00e9ria de agenda de <strong>dividendos<\/strong> n\u00e3o \u00e9 uma recomenda\u00e7\u00e3o de compra ou venda de ativos.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile-1.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop-1.jpg\"\n\t\t\t\t\tdata-promo-id=\"171998\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop-1.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Esta semana traz os dividendos que os investidores tanto esperam receber das empresas em que investem, caso do Bradesco (BBDC4). Carrefour (CRFB3). Foto: Divulga\u00e7\u00e3o Esta empresa far\u00e1 uma distribui\u00e7\u00e3o de R$ 0,0172 por a\u00e7\u00e3o em 2 de fevereiro, conforme os detalhes abaixo. De segunda-feira a sexta-feira, cinco empresas far\u00e3o o pagamento de dividendos aos seus [&hellip;]<\/p>\n","protected":false},"author":43,"featured_media":424228,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[295,1957],"suno_strategy":[],"class_list":["post-640278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-dividendos","tag-juros-sobre-capital-proprio-jcp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bradesco (BBDC4) e Santander: Veja quem vai pagar dividendos<\/title>\n<meta name=\"description\" content=\"Confira as empresas t\u00eam data de corte e quais pagam dividendos na semana. Bradesco (BBDC4) e o Santander (SANB11) s\u00e3o os destaques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bradesco (BBDC4) e Santander: Veja quem vai pagar dividendos\" \/>\n<meta property=\"og:description\" content=\"Confira as empresas t\u00eam data de corte e quais pagam dividendos na semana. Bradesco (BBDC4) e o Santander (SANB11) s\u00e3o os destaques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sunonoticias\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Suno Not\u00edcias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Suno Not\u00edcias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Suno Not\u00edcias\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea\"},\"headline\":\"Bradesco (BBDC4) e Santander (SANB11): Veja quem vai pagar dividendos na semana\",\"datePublished\":\"2026-02-01T13:00:00+00:00\",\"dateModified\":\"2026-02-02T11:54:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/\"},\"wordCount\":358,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel.jpg\",\"keywords\":[\"dividendos\",\"juros sobre capital pr\u00f3prio (JCP)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/\",\"name\":\"Bradesco (BBDC4) e Santander: Veja quem vai pagar dividendos\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel.jpg\",\"datePublished\":\"2026-02-01T13:00:00+00:00\",\"dateModified\":\"2026-02-02T11:54:33+00:00\",\"description\":\"Confira as empresas t\u00eam data de corte e quais pagam dividendos na semana. Bradesco (BBDC4) e o Santander (SANB11) s\u00e3o os destaques.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Carrefour (CRFB3). Foto: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bradesco (BBDC4) e Santander (SANB11): Veja quem vai pagar dividendos na semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea\",\"name\":\"Reda\u00e7\u00e3o Suno Not\u00edcias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g\",\"caption\":\"Reda\u00e7\u00e3o Suno Not\u00edcias\"},\"description\":\"O Suno Not\u00edcias \u00e9 um portal de informa\u00e7\u00f5es sobre Mercado Financeiro, Pol\u00edtica, Neg\u00f3cios, Economia e Finan\u00e7as Pessoais.\",\"sameAs\":[\"https:\/\/www.suno.com.br\/noticias\",\"https:\/\/www.facebook.com\/sunonoticias\/\",\"https:\/\/www.instagram.com\/sunonoticias\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/sunoresearch\",\"https:\/\/www.youtube.com\/sunonoticias\"],\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bradesco (BBDC4) e Santander: Veja quem vai pagar dividendos","description":"Confira as empresas t\u00eam data de corte e quais pagam dividendos na semana. Bradesco (BBDC4) e o Santander (SANB11) s\u00e3o os destaques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/","og_locale":"pt_BR","og_type":"article","og_title":"Bradesco (BBDC4) e Santander: Veja quem vai pagar dividendos","og_description":"Confira as empresas t\u00eam data de corte e quais pagam dividendos na semana. Bradesco (BBDC4) e o Santander (SANB11) s\u00e3o os destaques.","og_url":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","article_author":"https:\/\/www.facebook.com\/sunonoticias\/","og_image":[{"width":1200,"height":800,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Suno Not\u00edcias","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Suno Not\u00edcias","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/"},"author":{"name":"Reda\u00e7\u00e3o Suno Not\u00edcias","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea"},"headline":"Bradesco (BBDC4) e Santander (SANB11): Veja quem vai pagar dividendos na semana","datePublished":"2026-02-01T13:00:00+00:00","dateModified":"2026-02-02T11:54:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/"},"wordCount":358,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel.jpg","keywords":["dividendos","juros sobre capital pr\u00f3prio (JCP)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/","url":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/","name":"Bradesco (BBDC4) e Santander: Veja quem vai pagar dividendos","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel.jpg","datePublished":"2026-02-01T13:00:00+00:00","dateModified":"2026-02-02T11:54:33+00:00","description":"Confira as empresas t\u00eam data de corte e quais pagam dividendos na semana. Bradesco (BBDC4) e o Santander (SANB11) s\u00e3o os destaques.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel.jpg","width":1200,"height":800,"caption":"Carrefour (CRFB3). Foto: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Bradesco (BBDC4) e Santander (SANB11): Veja quem vai pagar dividendos na semana"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea","name":"Reda\u00e7\u00e3o Suno Not\u00edcias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g","caption":"Reda\u00e7\u00e3o Suno Not\u00edcias"},"description":"O Suno Not\u00edcias \u00e9 um portal de informa\u00e7\u00f5es sobre Mercado Financeiro, Pol\u00edtica, Neg\u00f3cios, Economia e Finan\u00e7as Pessoais.","sameAs":["https:\/\/www.suno.com.br\/noticias","https:\/\/www.facebook.com\/sunonoticias\/","https:\/\/www.instagram.com\/sunonoticias\/","https:\/\/x.com\/https:\/\/twitter.com\/sunoresearch","https:\/\/www.youtube.com\/sunonoticias"],"url":"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/carrefour-atacadao-transacao-barzel-400x200.jpg\" alt=\"Bradesco (BBDC4) e Santander (SANB11): Veja quem vai pagar dividendos na semana\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/o-bradesco-bbdc4-o-santander-sanb11-agenda-dividendos-30012026-g\/\"><h2 class=\"content__title\">Bradesco (BBDC4) e Santander (SANB11): Veja quem vai pagar dividendos na semana<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/0ace682d-redacao-1-150x150.webp\" alt=\"Reda\u00e7\u00e3o Suno Not\u00edcias\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/\"><span itemprop=\"author\">Reda\u00e7\u00e3o Suno Not\u00edcias<\/span><\/a><\/span><time datetime=\"2026-02-01T10:00:00-03:00\" itemprop=\"datePublished\">01\/02\/2026 10:00<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/640278"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=640278"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/640278\/revisions"}],"predecessor-version":[{"id":640564,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/640278\/revisions\/640564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/424228"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=640278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=640278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=640278"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=640278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}