{"id":634354,"date":"2025-12-03T10:55:33","date_gmt":"2025-12-03T13:55:33","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/"},"modified":"2025-12-03T11:11:54","modified_gmt":"2025-12-03T14:11:54","slug":"snel11-60-mil-cotistas-dividendos-estaveis","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/","title":{"rendered":"SNEL11 bate 60 mil cotistas e refor\u00e7a combina\u00e7\u00e3o de rentabilidade e respeito ao ambiente"},"content":{"rendered":"<p>O fundo imobili\u00e1rio <strong>SNEL11<\/strong>, gerido pela Suno Asset e voltado a usinas fotovoltaicas de gera\u00e7\u00e3o distribu\u00edda, atingiu 60 mil cotistas, refor\u00e7ando a confian\u00e7a do mercado na tese que combina renda e impacto ambiental positivo. O marco vem acompanhado de sinais de sustenta\u00e7\u00e3o operacional e de melhoria de liquidez, apontando para uma trajet\u00f3ria de consolida\u00e7\u00e3o do portf\u00f3lio.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-800x450.webp\" width=\"800\" height=\"450\" alt=\"SNEL11 bate 60 mil cotistas e refor\u00e7a combina\u00e7\u00e3o de rentabilidade e respeito ao ambiente\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">SNEL11 atua na loca\u00e7\u00e3o de usinas fotovoltaicas - Foto: Pixabay<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"383123\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>No relat\u00f3rio mais recente, a gestora respondeu \u00e0 principal d\u00favida do mercado: a perenidade dos <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" target=\"_blank\" rel=\"noopener\">dividendos<\/a> ancorados na receita imobili\u00e1ria das usinas. Em outubro, o FII apurou R$ 3,207 milh\u00f5es em alugu\u00e9is dos ativos, resultado que espelha a matura\u00e7\u00e3o gradual do pipeline e a maior previsibilidade dos contratos. <\/p>\n\n\n\n<p> perspectiva \u00e9 de avan\u00e7o adicional nos pr\u00f3ximos meses. Diversas plantas j\u00e1 locadas est\u00e3o em fase de ramp-up, quando gera\u00e7\u00e3o e faturamento crescem at\u00e9 a estabiliza\u00e7\u00e3o plena. H\u00e1 ainda contratos com valores acumulados que ser\u00e3o refletidos em faturas futuras, ampliando a visibilidade de caixa. As UFVs Petrolina 2 e 4, por exemplo, com loca\u00e7\u00f5es  firmadas recentemente, ter\u00e3o seus montantes de loca\u00e7\u00e3o recebidos ao longo de 2026, ap\u00f3s o per\u00edodo de car\u00eancia.<\/p>\n\n\n\n<p>A UFV Pirassununga come\u00e7ar\u00e1 a receber neste ano os valores de car\u00eancia da Safira, com quita\u00e7\u00e3o at\u00e9 julho do ano que vem. O ramp-up das usinas Mundo Melhor e S\u00e3o Bento Abade deve encerrar at\u00e9 dezembro de 2025, com impacto de caixa a partir de meados de fevereiro seguinte, criando um efeito positivo escalonado sobre as distribui\u00e7\u00f5es.<\/p>\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"89005\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">SNEL11: liquidez maior tamb\u00e9m \u00e9 sinal positivo do mercado<\/h2>\n\n\n\n<p>A Suno Asset manteve a proje\u00e7\u00e3o de R$ 4,870 milh\u00f5es de receita imobili\u00e1ria para o portf\u00f3lio atual, formado por 17 usinas. O montante considera projetos constru\u00eddos sob supervis\u00e3o do FII com recursos das duas primeiras emiss\u00f5es, al\u00e9m de ativos j\u00e1 operacionais adquiridos em condi\u00e7\u00f5es atrativas durante a 3\u00aa emiss\u00e3o.<\/p>\n\n\n\n<p>Em novembro, o interesse pelo fundo extrapolou a busca por proventos imediatos, com volume di\u00e1rio m\u00e9dio de R$ 1,513 milh\u00e3o \u2014 o segundo maior da s\u00e9rie hist\u00f3rica, atr\u00e1s apenas de setembro. No dia 25, data de pagamento dos <strong>dividendos do SNEL11<\/strong> referentes a outubro, a liquidez superou R$ 3 milh\u00f5es, com distribui\u00e7\u00e3o de R$ 0,10 por cota pelo 17\u00ba m\u00eas seguido.<\/p>\n\n\n\n<p>Com a <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/artigos\/dividendos-datas-importantes\/\" rel=\"noopener\">Data Com<\/a> marcada para o dia 15 e sem valores do pr\u00f3ximo pagamento anunciados, o apetite recente sugere foco na tese de <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/longo-prazo\/\" rel=\"noopener\">longo prazo<\/a>. O <strong>SNEL11<\/strong> segue entregando rentabilidade \u2014 dividend yield anualizado de 15,26% \u2014 enquanto impulsiona a transi\u00e7\u00e3o energ\u00e9tica por meio da gera\u00e7\u00e3o renov\u00e1vel.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/minicurso-investindo-fiis\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Minicurso-FIIS.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Minicurso-FIIS.png\"\n\t\t\t\t\tdata-promo-id=\"383125\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Minicurso-FIIS.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O fundo imobili\u00e1rio SNEL11, gerido pela Suno Asset e voltado a usinas fotovoltaicas de gera\u00e7\u00e3o distribu\u00edda, atingiu 60 mil cotistas, refor\u00e7ando a confian\u00e7a do mercado na tese que combina renda e impacto ambiental positivo. O marco vem acompanhado de sinais de sustenta\u00e7\u00e3o operacional e de melhoria de liquidez, apontando para uma trajet\u00f3ria de consolida\u00e7\u00e3o do &hellip; Continued<\/p>\n","protected":false},"author":43,"featured_media":634355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[66],"tags":[315,107095,105966],"suno_strategy":[],"class_list":["post-634354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiis","tag-fundos-imobiliarios-fiis","tag-snel11","tag-suno-asset"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SNEL11 atinge 60 mil cotistas e celebra aval do mercado<\/title>\n<meta name=\"description\" content=\"SNEL11 chega a 60 mil cotistas, receita de R$ 3,2 mi em outubro e dividendos de R$ 0,10 por cota pelo 17\u00ba m\u00eas, com liquidez e portf\u00f3lio em ramp-up.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SNEL11 atinge 60 mil cotistas e celebra aval do mercado\" \/>\n<meta property=\"og:description\" content=\"SNEL11 chega a 60 mil cotistas, receita de R$ 3,2 mi em outubro e dividendos de R$ 0,10 por cota pelo 17\u00ba m\u00eas, com liquidez e portf\u00f3lio em ramp-up.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sunonoticias\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"835\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Suno Not\u00edcias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Suno Not\u00edcias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Suno Not\u00edcias\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea\"},\"headline\":\"SNEL11 bate 60 mil cotistas e refor\u00e7a combina\u00e7\u00e3o de rentabilidade e respeito ao ambiente\",\"datePublished\":\"2025-12-03T13:55:33+00:00\",\"dateModified\":\"2025-12-03T14:11:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/\"},\"wordCount\":457,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-jpg.webp\",\"keywords\":[\"Fundos Imobili\u00e1rios (FIIs)\",\"SNEL11\",\"Suno Asset\"],\"articleSection\":[\"FIIs\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/\",\"name\":\"SNEL11 atinge 60 mil cotistas e celebra aval do mercado\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-jpg.webp\",\"datePublished\":\"2025-12-03T13:55:33+00:00\",\"dateModified\":\"2025-12-03T14:11:54+00:00\",\"description\":\"SNEL11 chega a 60 mil cotistas, receita de R$ 3,2 mi em outubro e dividendos de R$ 0,10 por cota pelo 17\u00ba m\u00eas, com liquidez e portf\u00f3lio em ramp-up.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-jpg.webp\",\"width\":1280,\"height\":835,\"caption\":\"SNEL11 atua na loca\u00e7\u00e3o de usinas fotovoltaicas - Foto: Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FIIs\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/fiis\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SNEL11 bate 60 mil cotistas e refor\u00e7a combina\u00e7\u00e3o de rentabilidade e respeito ao ambiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea\",\"name\":\"Reda\u00e7\u00e3o Suno Not\u00edcias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g\",\"caption\":\"Reda\u00e7\u00e3o Suno Not\u00edcias\"},\"description\":\"O Suno Not\u00edcias \u00e9 um portal de informa\u00e7\u00f5es sobre Mercado Financeiro, Pol\u00edtica, Neg\u00f3cios, Economia e Finan\u00e7as Pessoais.\",\"sameAs\":[\"https:\/\/www.suno.com.br\/noticias\",\"https:\/\/www.facebook.com\/sunonoticias\/\",\"https:\/\/www.instagram.com\/sunonoticias\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/sunoresearch\",\"https:\/\/www.youtube.com\/sunonoticias\"],\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SNEL11 atinge 60 mil cotistas e celebra aval do mercado","description":"SNEL11 chega a 60 mil cotistas, receita de R$ 3,2 mi em outubro e dividendos de R$ 0,10 por cota pelo 17\u00ba m\u00eas, com liquidez e portf\u00f3lio em ramp-up.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/","og_locale":"pt_BR","og_type":"article","og_title":"SNEL11 atinge 60 mil cotistas e celebra aval do mercado","og_description":"SNEL11 chega a 60 mil cotistas, receita de R$ 3,2 mi em outubro e dividendos de R$ 0,10 por cota pelo 17\u00ba m\u00eas, com liquidez e portf\u00f3lio em ramp-up.","og_url":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","article_author":"https:\/\/www.facebook.com\/sunonoticias\/","og_image":[{"width":1280,"height":835,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-jpg.webp","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Suno Not\u00edcias","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Suno Not\u00edcias","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/"},"author":{"name":"Reda\u00e7\u00e3o Suno Not\u00edcias","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea"},"headline":"SNEL11 bate 60 mil cotistas e refor\u00e7a combina\u00e7\u00e3o de rentabilidade e respeito ao ambiente","datePublished":"2025-12-03T13:55:33+00:00","dateModified":"2025-12-03T14:11:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/"},"wordCount":457,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-jpg.webp","keywords":["Fundos Imobili\u00e1rios (FIIs)","SNEL11","Suno Asset"],"articleSection":["FIIs"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/","url":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/","name":"SNEL11 atinge 60 mil cotistas e celebra aval do mercado","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-jpg.webp","datePublished":"2025-12-03T13:55:33+00:00","dateModified":"2025-12-03T14:11:54+00:00","description":"SNEL11 chega a 60 mil cotistas, receita de R$ 3,2 mi em outubro e dividendos de R$ 0,10 por cota pelo 17\u00ba m\u00eas, com liquidez e portf\u00f3lio em ramp-up.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-jpg.webp","width":1280,"height":835,"caption":"SNEL11 atua na loca\u00e7\u00e3o de usinas fotovoltaicas - Foto: Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"FIIs","item":"https:\/\/www.suno.com.br\/noticias\/fiis\/"},{"@type":"ListItem","position":3,"name":"SNEL11 bate 60 mil cotistas e refor\u00e7a combina\u00e7\u00e3o de rentabilidade e respeito ao ambiente"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea","name":"Reda\u00e7\u00e3o Suno Not\u00edcias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g","caption":"Reda\u00e7\u00e3o Suno Not\u00edcias"},"description":"O Suno Not\u00edcias \u00e9 um portal de informa\u00e7\u00f5es sobre Mercado Financeiro, Pol\u00edtica, Neg\u00f3cios, Economia e Finan\u00e7as Pessoais.","sameAs":["https:\/\/www.suno.com.br\/noticias","https:\/\/www.facebook.com\/sunonoticias\/","https:\/\/www.instagram.com\/sunonoticias\/","https:\/\/x.com\/https:\/\/twitter.com\/sunoresearch","https:\/\/www.youtube.com\/sunonoticias"],"url":"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/solar-panels-3507949_1280-400x200.webp\" alt=\"SNEL11 bate 60 mil cotistas e refor\u00e7a combina\u00e7\u00e3o de rentabilidade e respeito ao ambiente\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/fiis\/\">FIIs<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/snel11-60-mil-cotistas-dividendos-estaveis\/\"><h2 class=\"content__title\">SNEL11 bate 60 mil cotistas e refor\u00e7a combina\u00e7\u00e3o de rentabilidade e respeito ao ambiente<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/0ace682d-redacao-1-150x150.webp\" alt=\"Reda\u00e7\u00e3o Suno Not\u00edcias\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/\"><span itemprop=\"author\">Reda\u00e7\u00e3o Suno Not\u00edcias<\/span><\/a><\/span><time datetime=\"2025-12-03T10:55:33-03:00\" itemprop=\"datePublished\">03\/12\/2025 10:55<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/634354"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=634354"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/634354\/revisions"}],"predecessor-version":[{"id":634359,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/634354\/revisions\/634359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/634355"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=634354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=634354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=634354"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=634354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}