{"id":62668,"date":"2020-04-25T13:09:56","date_gmt":"2020-04-25T16:09:56","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=62668"},"modified":"2020-04-25T13:09:56","modified_gmt":"2020-04-25T16:09:56","slug":"hypera-pharma-lucro-liquido-primeiro-trimestre-hype3","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/","title":{"rendered":"Hypera Pharma (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20"},"content":{"rendered":"<p>A <a href=\"https:\/\/www.suno.com.br\/acoes\/hype3\/?_ga=2.174010913.329417069.1587510839-986735203.1581161885\"><strong>Hypera Pharma<\/strong> (HYPE3)<\/a> registrou um <a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\">lucro l\u00edquido<\/a> de R$ 238,2 milh\u00f5es no primeiro trimestre de 2020. Esse valor \u00e9 equivalente a uma queda de 26% em compara\u00e7\u00e3o com o mesmo per\u00edodo no ano anterior, quando havia registrado lucro de R$ 321,2 milh\u00f5es.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera-800x450.webp\" width=\"800\" height=\"450\" alt=\"Hypera Pharma (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">A Hypera apresentou um lucro l\u00edquido de R$ 345,6 milh\u00f5es referente ao terceiro trimestre de 2020<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n<p>A <a href=\"https:\/\/www.suno.com.br\/artigos\/receita-total\/\">receita<\/a> da Hypera no trimestre ficou em R$ 815 milh\u00f5es, alta de 112,5% em compara\u00e7\u00e3o com os primeiros tr\u00eas meses de 2019, quando havia totalizado R$ 383,6 milh\u00f5es. Por sua vez, as &#8220;outras receitas operacionais&#8221; registrou recuo de 93,6%.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: O primeiro passo para alcan\u00e7ar a sua independ\u00eancia financeira<\/a><\/p>\n<p>As <a href=\"https:\/\/www.suno.com.br\/artigos\/custos-e-gastos\/\">despesas operacionais<\/a> totalizaram R$ 324,7 milh\u00f5es, destaque para despesas com vendas e com frete e log\u00edstica devido ao aumento no volume investido para acelerar a produ\u00e7\u00e3o de novos produtos.<\/p>\n<p>O <a href=\"https:\/\/www.suno.com.br\/artigos\/ebitda\/\">Ebtida (lucro antes de juros, impostos, deprecia\u00e7\u00e3o e amortiza\u00e7\u00e3o)<\/a> registrou queda de 39,2%, para R$ 235,3 milh\u00f5es. O Ebtida ajustado recuou 38%, para R$ 248,7 milh\u00f5es.<\/p>\n<p>&#8220;Esse desempenho foi impactado pelo forte aumento do sell-out (medicamento isentos de prescri\u00e7\u00e3o) no in\u00edcio do m\u00eas de mar\u00e7o, consequ\u00eancia da corrida dos consumidores \u00e0s farm\u00e1cias para compra de medicamentos isentos de prescri\u00e7\u00e3o ap\u00f3s o in\u00edcio das regras de restri\u00e7\u00e3o para circula\u00e7\u00e3o da popula\u00e7\u00e3o por conta da pandemia da covid-19&#8221;, informou a companhia em seu relat\u00f3rio.<\/p>\n<h2>Hypera compra portf\u00f3lio de medicamentos sem prescri\u00e7\u00e3o da Takeda<\/h2>\n<p>A Hypera Pharma adquiriu, em mar\u00e7o, o portf\u00f3lio de medicamentos sem prescri\u00e7\u00e3o da Takeda Pharmaceutical International por US$ 825 milh\u00f5es (cerca de R$ 3,7 bilh\u00f5es).<\/p>\n<p><a href=\"\/\/www.suno.com.br\/noticias\/hypera-pharma-compra-portfolio-medicamentos-takeda\/\">Saiba Mais: Hypera Pharma compra portf\u00f3lio de medicamentos sem prescri\u00e7\u00e3o da Takeda<\/a><\/p>\n<p>O novo portf\u00f3lio de rem\u00e9dios, isentos de prescri\u00e7\u00e3o, adquiridos pela Hypera conta com os seguintes medicamentos: Neosaldina, Dramin e Nesina. A empresa informou que j\u00e1 tratou com os bancos sobre as linhas de cr\u00e9dito que ser\u00e3o necess\u00e1rias para o financiamento da negocia\u00e7\u00e3o com a Takeda. A maior ind\u00fastria farmac\u00eautica do Brasil utilizar\u00e1 R$ 3,5 bilh\u00f5es para financiar a compra.<\/p>\n<p>\u201cA <strong>Hypera Pharma<\/strong> e a Takeda tamb\u00e9m assinar\u00e3o acordo de fabrica\u00e7\u00e3o e fornecimento em conex\u00e3o com a transa\u00e7\u00e3o, por meio do qual a Takeda continuar\u00e1 a fornecer produtos \u00e0 companhia\u201d, comunicou a Hypera. A farmac\u00eautica brasileira publicou em seu comunicado que a compra ser\u00e1 fechada no final de 2020.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>A Hypera Pharma (HYPE3) registrou um lucro l\u00edquido de R$ 238,2 milh\u00f5es no primeiro trimestre de 2020. Esse valor \u00e9 equivalente a uma queda de 26% em compara\u00e7\u00e3o com o mesmo per\u00edodo no ano anterior, quando havia registrado lucro de R$ 321,2 milh\u00f5es. A Hypera apresentou um lucro l\u00edquido de R$ 345,6 milh\u00f5es referente ao [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":32382,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[501,1607],"suno_strategy":[],"class_list":["post-62668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-hypera-pharma-hype3","tag-resultado-das-empresas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hypera (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20<\/title>\n<meta name=\"description\" content=\"A Hypera Pharma (HYPE3) registrou um lucro l\u00edquido de R$ 238,2 milh\u00f5es no primeiro trimestre de 2020. Clique aqui e saiba mais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hypera (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20\" \/>\n<meta property=\"og:description\" content=\"A Hypera Pharma (HYPE3) registrou um lucro l\u00edquido de R$ 238,2 milh\u00f5es no primeiro trimestre de 2020. Clique aqui e saiba mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Poliana Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Poliana Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/\"},\"author\":{\"name\":\"Poliana Santos\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\"},\"headline\":\"Hypera Pharma (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20\",\"datePublished\":\"2020-04-25T16:09:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/\"},\"wordCount\":417,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera-jpg.webp\",\"keywords\":[\"Hypera Pharma (HYPE3)\",\"Resultado das empresas\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/\",\"name\":\"Hypera (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera-jpg.webp\",\"datePublished\":\"2020-04-25T16:09:56+00:00\",\"description\":\"A Hypera Pharma (HYPE3) registrou um lucro l\u00edquido de R$ 238,2 milh\u00f5es no primeiro trimestre de 2020. Clique aqui e saiba mais\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera-jpg.webp\",\"width\":1140,\"height\":600,\"caption\":\"A Hypera apresentou um lucro l\u00edquido de R$ 345,6 milh\u00f5es referente ao terceiro trimestre de 2020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hypera Pharma (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\",\"name\":\"Poliana Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"caption\":\"Poliana Santos\"},\"description\":\"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hypera (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20","description":"A Hypera Pharma (HYPE3) registrou um lucro l\u00edquido de R$ 238,2 milh\u00f5es no primeiro trimestre de 2020. Clique aqui e saiba mais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/","og_locale":"pt_BR","og_type":"article","og_title":"Hypera (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20","og_description":"A Hypera Pharma (HYPE3) registrou um lucro l\u00edquido de R$ 238,2 milh\u00f5es no primeiro trimestre de 2020. Clique aqui e saiba mais","og_url":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1140,"height":600,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera.jpg","type":"image\/jpeg"}],"author":"Poliana Santos","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Poliana Santos","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/"},"author":{"name":"Poliana Santos","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda"},"headline":"Hypera Pharma (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20","datePublished":"2020-04-25T16:09:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/"},"wordCount":417,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera-jpg.webp","keywords":["Hypera Pharma (HYPE3)","Resultado das empresas"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/","url":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/","name":"Hypera (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera-jpg.webp","datePublished":"2020-04-25T16:09:56+00:00","description":"A Hypera Pharma (HYPE3) registrou um lucro l\u00edquido de R$ 238,2 milh\u00f5es no primeiro trimestre de 2020. Clique aqui e saiba mais","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera-jpg.webp","width":1140,"height":600,"caption":"A Hypera apresentou um lucro l\u00edquido de R$ 345,6 milh\u00f5es referente ao terceiro trimestre de 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Hypera Pharma (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda","name":"Poliana Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","caption":"Poliana Santos"},"description":"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.","url":"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/477bac07-hyphera-400x200.webp\" alt=\"Hypera Pharma (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/hypera-pharma-lucro-liquido-primeiro-trimestre-hype3\/\"><h2 class=\"content__title\">Hypera Pharma (HYPE3) registra queda de 26% no lucro l\u00edquido do 1T20<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2020-04-25T13:09:56-03:00\" itemprop=\"datePublished\">25\/04\/2020 13:09<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/62668"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=62668"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/62668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/32382"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=62668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=62668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=62668"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=62668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}