{"id":618356,"date":"2025-08-06T18:11:50","date_gmt":"2025-08-06T21:11:50","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=618356"},"modified":"2025-08-06T18:11:54","modified_gmt":"2025-08-06T21:11:54","slug":"petrobras-petr4-acoes-podem-subir-entenda-go","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/","title":{"rendered":"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41% em 12 meses, diz UBS"},"content":{"rendered":"<p>O UBS BB projeta que as a\u00e7\u00f5es da Petrobras (<strong>PETR4<\/strong>) podem subir cerca de 41% em um per\u00edodo de 12 meses. A avalia\u00e7\u00e3o faz parte de um relat\u00f3rio divulgado pelo banco, que tamb\u00e9m destaca a expectativa de <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" target=\"_blank\" rel=\"noopener\">dividendos<\/a> atrativos da petroleira em 2025, apesar do recuo da <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/cotacao-do-petroleo\/\" target=\"_blank\" rel=\"noopener\">cota\u00e7\u00e3o do petr\u00f3leo<\/a>, com dividend yield acima de 10%.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41% em 12 meses, diz UBS\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Petrobras (PETR4). Foto: Reprodu\u00e7\u00e3o<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>Al\u00e9m da distribui\u00e7\u00e3o robusta de proventos, a institui\u00e7\u00e3o financeira v\u00ea com bons olhos o crescimento da produ\u00e7\u00e3o de petr\u00f3leo da <strong>Petrobras<\/strong> at\u00e9 2028, os resultados operacionais s\u00f3lidos no segundo trimestre e a manuten\u00e7\u00e3o da estrat\u00e9gia atual da companhia, mesmo diante das incertezas eleitorais no Brasil.<\/p>\n\n\n\n<p>&#8220;Apesar da esperada queda nos pre\u00e7os do petr\u00f3leo at\u00e9 o final do ano, mantemos nossa vis\u00e3o positiva sobre a Petrobras, sustentada por um dividend yield acima de 10% em 2025&#8221;, destaca o relat\u00f3rio. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Proje\u00e7\u00f5es para os dividendos de Petrobras<\/h2>\n\n\n\n<p>O UBS estima que a Petrobras dever\u00e1 pagar um <strong>dividend yield<\/strong> superior a 10% em 2025, mesmo com a expectativa de queda no <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/preco-do-petroleo\/\" rel=\"noopener\">pre\u00e7o do petr\u00f3leo<\/a> at\u00e9 o final do ano. Para o segundo trimestre de 2025, a proje\u00e7\u00e3o \u00e9 de rendimento de dividendos de 2,5%.<\/p>\n\n\n\n<p>A estimativa considera um EBITDA de US$ 10,3 bilh\u00f5es no per\u00edodo, o que representa uma leve queda de 2% em rela\u00e7\u00e3o ao trimestre anterior. Segundo o relat\u00f3rio, os volumes mais altos de produ\u00e7\u00e3o no upstream e no downstream, combinados com spreads robustos de refino, compensam parcialmente a queda do Brent.<\/p>\n\n\n\n<p>A casa reconhece algumas preocupa\u00e7\u00f5es do mercado em rela\u00e7\u00e3o aos investimentos (capex) da estatal, especialmente diante das elei\u00e7\u00f5es presidenciais de 2026. No entanto, projeta que os gastos n\u00e3o devem apresentar surpresas negativas, com varia\u00e7\u00e3o sazonal dentro do esperado.<\/p>\n\n\n\n<p>&#8220;Acreditamos que o mercado subestima esses fatores [dividendos e produ\u00e7\u00e3o], principalmente por preocupa\u00e7\u00f5es de curto prazo relacionadas \u00e0s elei\u00e7\u00f5es presidenciais do pr\u00f3ximo ano&#8221;, destaca o UBS.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Pre\u00e7o-alvo de PETR4<\/h2>\n\n\n\n<p>No documento, o UBS reafirma a recomenda\u00e7\u00e3o de compra, com <strong>pre\u00e7o-alvo PETR4<\/strong> em R$ 46 por a\u00e7\u00e3o. A proje\u00e7\u00e3o foi constru\u00edda com base em uma combina\u00e7\u00e3o de m\u00faltiplos e avalia\u00e7\u00e3o do valor dos ativos.<\/p>\n\n\n\n<p>A produ\u00e7\u00e3o dom\u00e9stica de petr\u00f3leo da Petrobras subiu para 2,32 milh\u00f5es de barris por dia no segundo trimestre de 2025, um crescimento de 8% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior. Esse aumento foi impulsionado pela entrada em opera\u00e7\u00e3o de novas plataformas e 14 novos po\u00e7os.<\/p>\n\n\n\n<p>No segmento de refino, o relat\u00f3rio aponta taxa de utiliza\u00e7\u00e3o de 89%, com aumento de 1,4% na produ\u00e7\u00e3o total, puxada principalmente por diesel e nafta. A venda de g\u00e1s natural tamb\u00e9m cresceu 8% no trimestre, enquanto as importa\u00e7\u00f5es da Bol\u00edvia ca\u00edram 18%.<\/p>\n\n\n\n<p>Para o UBS, tanto o crescimento da produ\u00e7\u00e3o quanto os dividendos da companhia est\u00e3o subestimados pelo mercado. O banco refor\u00e7a a vis\u00e3o positiva, com base na solidez operacional da <strong>Petrobras<\/strong> e na manuten\u00e7\u00e3o da estrat\u00e9gia atual da empresa.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"383123\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O UBS BB projeta que as a\u00e7\u00f5es da Petrobras (PETR4) podem subir cerca de 41% em um per\u00edodo de 12 meses. A avalia\u00e7\u00e3o faz parte de um relat\u00f3rio divulgado pelo banco, que tamb\u00e9m destaca a expectativa de dividendos atrativos da petroleira em 2025, apesar do recuo da cota\u00e7\u00e3o do petr\u00f3leo, com dividend yield acima de [&hellip;]<\/p>\n","protected":false},"author":404,"featured_media":534216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[595],"suno_strategy":[],"class_list":["post-618356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-petrobras-petr4"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41%, diz UBS<\/title>\n<meta name=\"description\" content=\"O UBS BB projeta que as a\u00e7\u00f5es da Petrobras (PETR4) podem subir cerca de 41% em um per\u00edodo de 12 meses. Clique e saiba mais!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41%, diz UBS\" \/>\n<meta property=\"og:description\" content=\"O UBS BB projeta que as a\u00e7\u00f5es da Petrobras (PETR4) podem subir cerca de 41% em um per\u00edodo de 12 meses. Clique e saiba mais!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanna Oliveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanna Oliveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/\"},\"author\":{\"name\":\"Giovanna Oliveira\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/506bb13f624e6983050ae5bf648c7a54\"},\"headline\":\"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41% em 12 meses, diz UBS\",\"datePublished\":\"2025-08-06T21:11:50+00:00\",\"dateModified\":\"2025-08-06T21:11:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/\"},\"wordCount\":529,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-scaled.jpg\",\"keywords\":[\"Petrobras (PETR4)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/\",\"name\":\"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41%, diz UBS\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-scaled.jpg\",\"datePublished\":\"2025-08-06T21:11:50+00:00\",\"dateModified\":\"2025-08-06T21:11:54+00:00\",\"description\":\"O UBS BB projeta que as a\u00e7\u00f5es da Petrobras (PETR4) podem subir cerca de 41% em um per\u00edodo de 12 meses. Clique e saiba mais!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-scaled.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Petrobras (PETR4). Foto: Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41% em 12 meses, diz UBS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/506bb13f624e6983050ae5bf648c7a54\",\"name\":\"Giovanna Oliveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8d180e5cea232a9bb3af521589b133fa?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8d180e5cea232a9bb3af521589b133fa?s=96&r=g\",\"caption\":\"Giovanna Oliveira\"},\"description\":\"Jornalista com mais de sete anos de experi\u00eancia na cobertura de finan\u00e7as e economia. P\u00f3s-graduada em Neg\u00f3cios e Inova\u00e7\u00e3o (ESPM-SP) e mestranda em Finan\u00e7as (UADE Business School\u2013Buenos Aires).\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/giovannalmd-oliveiragmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41%, diz UBS","description":"O UBS BB projeta que as a\u00e7\u00f5es da Petrobras (PETR4) podem subir cerca de 41% em um per\u00edodo de 12 meses. Clique e saiba mais!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/","og_locale":"pt_BR","og_type":"article","og_title":"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41%, diz UBS","og_description":"O UBS BB projeta que as a\u00e7\u00f5es da Petrobras (PETR4) podem subir cerca de 41% em um per\u00edodo de 12 meses. Clique e saiba mais!","og_url":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":2560,"height":1707,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-scaled.jpg","type":"image\/jpeg"}],"author":"Giovanna Oliveira","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Giovanna Oliveira","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/"},"author":{"name":"Giovanna Oliveira","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/506bb13f624e6983050ae5bf648c7a54"},"headline":"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41% em 12 meses, diz UBS","datePublished":"2025-08-06T21:11:50+00:00","dateModified":"2025-08-06T21:11:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/"},"wordCount":529,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-scaled.jpg","keywords":["Petrobras (PETR4)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/","url":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/","name":"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41%, diz UBS","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-scaled.jpg","datePublished":"2025-08-06T21:11:50+00:00","dateModified":"2025-08-06T21:11:54+00:00","description":"O UBS BB projeta que as a\u00e7\u00f5es da Petrobras (PETR4) podem subir cerca de 41% em um per\u00edodo de 12 meses. Clique e saiba mais!","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-scaled.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-scaled.jpg","width":2560,"height":1707,"caption":"Petrobras (PETR4). Foto: Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41% em 12 meses, diz UBS"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/506bb13f624e6983050ae5bf648c7a54","name":"Giovanna Oliveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8d180e5cea232a9bb3af521589b133fa?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d180e5cea232a9bb3af521589b133fa?s=96&r=g","caption":"Giovanna Oliveira"},"description":"Jornalista com mais de sete anos de experi\u00eancia na cobertura de finan\u00e7as e economia. P\u00f3s-graduada em Neg\u00f3cios e Inova\u00e7\u00e3o (ESPM-SP) e mestranda em Finan\u00e7as (UADE Business School\u2013Buenos Aires).","url":"https:\/\/www.suno.com.br\/noticias\/author\/giovannalmd-oliveiragmail-com\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/Petro-400x200.jpg\" alt=\"Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41% em 12 meses, diz UBS\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-acoes-podem-subir-entenda-go\/\"><h2 class=\"content__title\">Petrobras (PETR4): a\u00e7\u00f5es podem subir mais de 41% em 12 meses, diz UBS<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovannalmd-oliveiragmail-com\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/8d180e5cea232a9bb3af521589b133fa?s=96&#038;r=g\" alt=\"Giovanna Oliveira\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovannalmd-oliveiragmail-com\/\"><span itemprop=\"author\">Giovanna Oliveira<\/span><\/a><\/span><time datetime=\"2025-08-06T18:11:50-03:00\" itemprop=\"datePublished\">06\/08\/2025 18:11<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/618356"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/404"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=618356"}],"version-history":[{"count":2,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/618356\/revisions"}],"predecessor-version":[{"id":618414,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/618356\/revisions\/618414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/534216"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=618356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=618356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=618356"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=618356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}