{"id":61399,"date":"2020-04-14T13:02:38","date_gmt":"2020-04-14T16:02:38","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=61399"},"modified":"2020-04-14T13:02:38","modified_gmt":"2020-04-14T16:02:38","slug":"tesouro-direto-rentabilidade-14042020","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/","title":{"rendered":"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira"},"content":{"rendered":"<p>As taxas de rentabilidade dos t\u00edtulos do <strong>Tesouro Direto<\/strong> Indexados ao <a href=\"https:\/\/www.suno.com.br\/artigos\/ipca\/\">\u00cdndice de Pre\u00e7os ao Consumidor Amplo (IPCA)<\/a> operam em queda nesta ter\u00e7a-feira (14), em compara\u00e7\u00e3o com a \u00faltima segunda-feira (13).<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro-800x450.webp\" width=\"800\" height=\"450\" alt=\"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">A Anbima informou que os fundos de investimentos registraram sa\u00edda l\u00edquida de R$ 63,05 bilh\u00f5es em outubro. <\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n<p>O t\u00edtulo do Tesouro Direto Indexado ao <strong>IPCA+ 2026<\/strong>, tem a taxa de rentabilidade de 3,33% a.a., com um valor m\u00ednimo estabelecido de R$ 53,85 e pre\u00e7o unit\u00e1rio de R$ 2.692,95.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Garanta acesso gratuito \u00e0 eBooks, Minicursos, Artigos e Video Aulas com um \u00fanico cadastro. Clique para saber mais.<\/a><\/p>\n<p>O <strong>Tesouro IPCA+ 2035<\/strong>, na \u00faltima segunda, estava a 4,60% a.a., com o valor m\u00ednimo de R$ 33,69 e o pre\u00e7o m\u00ednimo R$ 1.684,82. Nesta ter\u00e7a, apresenta uma taxa de rendimento de 4,53%, com valor m\u00ednimo de R$ 34,04 com pre\u00e7o unit\u00e1rio de R$ 1.702,20.<\/p>\n<p>O <strong>Tesouro IPCA+ 2045 <\/strong>\u00e9 cotado a 4,53% a.a, com valor m\u00ednimo de R$ 32,82 e pre\u00e7o unit\u00e1rio de R$ 1.094,30.<\/p>\n<p>A rentabilidade do <strong>Tesouro IPCA+ com Juros Semestrais 2055 <\/strong>\u00e9 de 4,61% a.a. O valor m\u00ednimo foi estabelecido em R$ 41,86 e o pre\u00e7o unit\u00e1rio \u00e9 de R$ 4.186,13.<\/p>\n<h2>Prefixados do Tesouro Direto<\/h2>\n<p>Os t\u00edtulos prefixados, da mesma forma, apresentam uma forma queda em suas taxas de rentabilidade nesta ter\u00e7a-feira.<\/p>\n<p><span style=\"font-size: 1.21429rem;\">\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/minicurso-investindo-fiis\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/400x300-Minicurso-FIIS.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/1420x240-Minicurso-FIIS.png\"\n\t\t\t\t\tdata-promo-id=\"311935\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/1420x240-Minicurso-FIIS.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n<\/span><\/p>\n<p>O <strong>Tesouro Prefixado 2023<\/strong> apresenta a rentabilidade de 4,82% a.a., com um valor m\u00ednimo de R$ 35,21 e pre\u00e7o unit\u00e1rio de R$ 880,38.<\/p>\n<p>A taxa do <strong>Tesouro Prefixado<\/strong> <strong>2026<\/strong>, nesta ter\u00e7a, \u00e9 de 6,91% a.a. Seu valor m\u00ednimo se encontra em R$ 35,21. Al\u00e9m disso, o pre\u00e7o unit\u00e1rio est\u00e1 em R$ 682,98.<\/p>\n<p>Os t\u00edtulos do<strong> Tesouro Prefixado com Juros Semestrais 2031<\/strong> apresentam uma taxa de 7,75% a.a., enquanto na \u00faltima quinta estava 7,92% a.a. Seu valor m\u00ednimo \u00e9 de R$ 35,57 e o pre\u00e7o unit\u00e1rio saiu de R$ 1.172,69 para R$ 1.185,99.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/tesouro-nacional-titulos-dolares-mercado-internacional\/\">Confira: Tesouro Nacional ir\u00e1 emitir t\u00edtulos em d\u00f3lares no mercado internacional<\/a><\/p>\n<p>J\u00e1 o <strong>Tesouro Selic 2025<\/strong> (<a href=\"https:\/\/www.suno.com.br\/artigos\/tesouro-selic\/\">LFT<\/a>) mant\u00e9m a taxa de rendimento de 0,03 ponto percentual ao ano. Seu valor m\u00ednimo \u00e9 de R$ 105,76 e seu pre\u00e7o unit\u00e1rio \u00e9 de R$ 10.576,00.<\/p>\n<figure id=\"attachment_61400\" aria-describedby=\"caption-attachment-61400\" style=\"width: 743px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-61400 size-full\" src=\"https:\/\/storage.googleapis.com\/wp-noticias\/2020\/04\/tesouro-direto.png\" alt=\"\" width=\"743\" height=\"462\" \/><figcaption id=\"caption-attachment-61400\" class=\"wp-caption-text\">Tesouro Direto, 14\/04\/2020<\/figcaption><\/figure>\n<p>O preg\u00e3o do<strong> Tesouro Direto<\/strong> funciona das 9h30 \u00e0s 18h, no site do <a href=\"https:\/\/www.suno.com.br\/artigos\/tesouro-nacional\/\">Tesouro Nacional<\/a>. \u00c9 poss\u00edvel, tamb\u00e9m, realizar simula\u00e7\u00f5es referentes \u00e0 rentabilidade de um t\u00edtulo clicando <a href=\"http:\/\/www.tesouro.fazenda.gov.br\/tesouro-direto-calculadora\">aqui<\/a>.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>As taxas de rentabilidade dos t\u00edtulos do Tesouro Direto Indexados ao \u00cdndice de Pre\u00e7os ao Consumidor Amplo (IPCA) operam em queda nesta ter\u00e7a-feira (14), em compara\u00e7\u00e3o com a \u00faltima segunda-feira (13). A Anbima informou que os fundos de investimentos registraram sa\u00edda l\u00edquida de R$ 63,05 bilh\u00f5es em outubro. O t\u00edtulo do Tesouro Direto Indexado ao [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":21790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[65],"tags":[316,1044],"suno_strategy":[],"class_list":["post-61399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financas-pessoais","tag-tesouro-direto","tag-tesouro-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira<\/title>\n<meta name=\"description\" content=\"As taxas de rentabilidade dos t\u00edtulos do Tesouro Direto IPCA operam em queda nesta ter\u00e7a, em compara\u00e7\u00e3o com a \u00faltima segunda. Saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira\" \/>\n<meta property=\"og:description\" content=\"As taxas de rentabilidade dos t\u00edtulos do Tesouro Direto IPCA operam em queda nesta ter\u00e7a, em compara\u00e7\u00e3o com a \u00faltima segunda. Saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jader Lazarini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jader Lazarini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/\"},\"author\":{\"name\":\"Jader Lazarini\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\"},\"headline\":\"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira\",\"datePublished\":\"2020-04-14T16:02:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/\"},\"wordCount\":394,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro-jpg.webp\",\"keywords\":[\"Tesouro Direto\",\"Tesouro Nacional\"],\"articleSection\":[\"Finan\u00e7as Pessoais\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/\",\"name\":\"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro-jpg.webp\",\"datePublished\":\"2020-04-14T16:02:38+00:00\",\"description\":\"As taxas de rentabilidade dos t\u00edtulos do Tesouro Direto IPCA operam em queda nesta ter\u00e7a, em compara\u00e7\u00e3o com a \u00faltima segunda. Saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro-jpg.webp\",\"width\":1920,\"height\":1275,\"caption\":\"A Anbima informou que os fundos de investimentos registraram sa\u00edda l\u00edquida de R$ 63,05 bilh\u00f5es em outubro.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finan\u00e7as Pessoais\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/financas-pessoais\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\",\"name\":\"Jader Lazarini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"caption\":\"Jader Lazarini\"},\"description\":\"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira","description":"As taxas de rentabilidade dos t\u00edtulos do Tesouro Direto IPCA operam em queda nesta ter\u00e7a, em compara\u00e7\u00e3o com a \u00faltima segunda. Saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/","og_locale":"pt_BR","og_type":"article","og_title":"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira","og_description":"As taxas de rentabilidade dos t\u00edtulos do Tesouro Direto IPCA operam em queda nesta ter\u00e7a, em compara\u00e7\u00e3o com a \u00faltima segunda. Saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1920,"height":1275,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro.jpg","type":"image\/jpeg"}],"author":"Jader Lazarini","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Jader Lazarini","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/"},"author":{"name":"Jader Lazarini","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f"},"headline":"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira","datePublished":"2020-04-14T16:02:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/"},"wordCount":394,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro-jpg.webp","keywords":["Tesouro Direto","Tesouro Nacional"],"articleSection":["Finan\u00e7as Pessoais"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/","url":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/","name":"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro-jpg.webp","datePublished":"2020-04-14T16:02:38+00:00","description":"As taxas de rentabilidade dos t\u00edtulos do Tesouro Direto IPCA operam em queda nesta ter\u00e7a, em compara\u00e7\u00e3o com a \u00faltima segunda. Saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro-jpg.webp","width":1920,"height":1275,"caption":"A Anbima informou que os fundos de investimentos registraram sa\u00edda l\u00edquida de R$ 63,05 bilh\u00f5es em outubro."},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Finan\u00e7as Pessoais","item":"https:\/\/www.suno.com.br\/noticias\/financas-pessoais\/"},{"@type":"ListItem","position":3,"name":"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f","name":"Jader Lazarini","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","caption":"Jader Lazarini"},"description":"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).","url":"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/ebc41642-dinheiro-400x200.webp\" alt=\"Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/financas-pessoais\/\">Finan\u00e7as Pessoais<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/tesouro-direto-rentabilidade-14042020\/\"><h2 class=\"content__title\">Tesouro Direto: confira as taxas de rentabilidade desta ter\u00e7a-feira<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/178e6598-foto-perfil-2-150x150.jpg\" alt=\"Jader Lazarini\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"><span itemprop=\"author\">Jader Lazarini<\/span><\/a><\/span><time datetime=\"2020-04-14T13:02:38-03:00\" itemprop=\"datePublished\">14\/04\/2020 13:02<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/61399"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=61399"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/61399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/21790"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=61399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=61399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=61399"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=61399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}