{"id":576384,"date":"2024-09-20T12:05:09","date_gmt":"2024-09-20T15:05:09","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=576384"},"modified":"2024-09-20T19:59:56","modified_gmt":"2024-09-20T22:59:56","slug":"bradesco-bbdc4-jcp-bilionario-evm","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/","title":{"rendered":"Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja"},"content":{"rendered":"<p>O <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/analitica\/acoes\/BBDC4\/\" target=\"_blank\" rel=\"noopener\"><strong>Bradesco<\/strong> (BBDC4)<\/a> pagar\u00e1 R$ 2 bilh\u00f5es em <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/entenda-o-jcp\/\" target=\"_blank\" rel=\"noopener\">Juros Sobre Capital Pr\u00f3prio<\/a> (JCP) aos seus acionistas, segundo <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/fato-relevante\/\" target=\"_blank\" rel=\"noopener\">fato relevante<\/a> divulgado nesta sexta-feira (20).<\/p><div class=\"videoFull \">\n\t\t\t<div class=\"videoWrapper yt-lazyload center\"\n\t\t\t\tdata-width=\"960\"\n\t\t\t\tdata-height=\"540\"\n\t\t\t\tdata-id=\"LCcOhtAhMaI\"\n\t\t\t\tdata-alt=\"V\u00eddeo do YouTube - clique para reproduzir\"\n\t\t\t\tdata-logo=\"3\"\n\t\t\t\tdata-imagequality=\"maxres\">\n\t\t\t<\/div>\n\t\t<\/div><script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"VideoObject\",\"name\":\"\ud83d\udd34IBOVESPA RECUA NA CONTRAM\u00c3O DE NY | Brava (BRAV3) afunda | Dividendos maiores da Ita\u00fasa (ITSA4)?\",\"description\":\"\ud83d\udd34TENHA UMA CARTEIRA PERSONALIZADA: https:\/\/lp.suno.com.br\/ao\/consultoria-de-investimentos\/?utm_source=suno-noticias&utm_medium=live&utm_campaign=seuconsultorresponde&utm_content=19092024 00:00 In\u00edcio do v\u00eddeo 01:40 Fechamento de preg\u00e3o 04:43 BRAV3 afunda na bolsa 11:50 Declara\u00e7\u00f5es de diretor da Petrobras 14:25 ITSA4 aumentar\u00e1 dividendos? 17:02 Indicadores do dia & agenda \ud83d\udd34\ud835\udc08\ud835\udc0d\ud835\udc12\ud835\udc02\ud835\udc11\ud835\udc04\ud835\udc15\ud835\udc00-\ud835\udc12\ud835\udc04 \ud835\udc0d\ud835\udc0e \ud835\udc02\ud835\udc00\ud835\udc0d\ud835\udc00\ud835\udc0b \ud835\udc04 \ud835\udc00\ud835\udc13\ud835\udc08\ud835\udc15\ud835\udc04 \ud835\udc0e \ud835\udc12\ud835\udc08\ud835\udc0d\ud835\udc0e \ud83d\udc47 https:\/\/bit.ly\/INSCREVA-SEATIVEOSINO \ud83d\udc47 \ud835\udc12\ud835\udc22\ud835\udc20\ud835\udc1a \ud835\udc27\ud835\udc28\ud835\udc2c\ud835\udc2c\ud835\udc1a\ud835\udc2c r\ud835\udc1e\ud835\udc1d\ud835\udc1e\ud835\udc2c \ud835\udc2c\ud835\udc28\ud835\udc1c\ud835\udc22\ud835\udc1ai\ud835\udc2c: Portal Suno Not\u00edcias: https:\/\/www.suno.com.br\/noticias\/ Twitter: x.com\/sunonoticias Instagram:\u2026\",\"duration\":\"PT19M37S\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/LCcOhtAhMaI\",\"regionsAllowed\":\"en-US\",\"interactionStatistic\":{\"@type\":\"InteractionCounter\",\"interactionType\":{\"@type\":\"WatchAction\"},\"userInteractionCount\":3150},\"thumbnailUrl\":\"https:\/\/i.ytimg.com\/vi\/LCcOhtAhMaI\/default.jpg\",\"uploadDate\":\"2024-09-20T10:26:30Z\"}<\/script>\n\n\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"287932\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n\n\n<p>O valor dos <strong>JCP do Bradesco<\/strong> ser\u00e1 de R$ R$ 0,19 por a\u00e7\u00e3o preferencial e R$ 0,17 por a\u00e7\u00e3o ordin\u00e1ria.<\/p>\n\n\n\n<p>O pagamento dos <strong>rendimentos<\/strong> em quest\u00e3o ocorrer\u00e1 at\u00e9 o dia 30 de abril de 2025.<\/p>\n\n\n\n<p>Apenas os investidores com <strong>a\u00e7\u00f5es do Bradesco<\/strong> no dia 30 de setembro ter\u00e3o direito de receber os <strong>JCP<\/strong>. <\/p>\n\n\n\n<p>Ou seja, a partir do dia 1\u00ba de outubro, as a\u00e7\u00f5es <strong>BBDC4<\/strong> e <strong>BBDC3<\/strong> ser\u00e3o negociadas sem direito aos proventos.<\/p>\n\n\n\n<p>Segundo <a href=\"https:\/\/www.rad.cvm.gov.br\/ENET\/frmExibirArquivoIPEExterno.aspx?NumeroProtocoloEntrega=1283765\">documento arquivado na Comiss\u00e3o de Valores Mobili\u00e1rios (CVM)<\/a>, esses proventos fazem parte dos <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" target=\"_blank\" rel=\"noopener\">dividendos<\/a> obrigat\u00f3rios da companhia.<\/p>\n\n\n\n<p>&#8220;Os juros ora aprovados representam, aproximadamente, 10,4 vezes o valor dos juros mensalmente pagos, l\u00edquidos de imposto de renda na fonte, e ser\u00e3o computados no c\u00e1lculo dos dividendos obrigat\u00f3rios do exerc\u00edcio previstos no <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/estatuto-social\/\" rel=\"noopener\">Estatuto Social<\/a>&#8220;, diz o comunicado do banco.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>O valor dos JCP ter\u00e1 reten\u00e7\u00e3o do imposto de renda na fonte, com al\u00edquota de 15%, resultando em aproximadamente R$ 0,15 por a\u00e7\u00e3o ordin\u00e1ria e R$ 0,16 por a\u00e7\u00e3o preferencial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JCP do Bradesco<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Valor total:<\/strong> R$ 2 bilh\u00f5es <\/li>\n\n\n\n<li><strong>Valor por a\u00e7\u00e3o:<\/strong> R$0,179570675 por a\u00e7\u00e3o ordin\u00e1ria e R$0,197527743 por a\u00e7\u00e3o preferencial<\/li>\n\n\n\n<li><strong>Valor por a\u00e7\u00e3o ap\u00f3s a reten\u00e7\u00e3o do IR na fonte:<\/strong>  R$ 0,152635 por a\u00e7\u00e3o ordin\u00e1ria e R$ 0,1678985 por a\u00e7\u00e3o preferencial<\/li>\n\n\n\n<li><strong>Data de corte:<\/strong> 30 de setembro<\/li>\n\n\n\n<li><strong>Data do pagamento:<\/strong> At\u00e9 o dia 30 de abril de 2025<\/li>\n<\/ul>\n\n\n\n<p>No preg\u00e3o de hoje, a cota\u00e7\u00e3o das a\u00e7\u00f5es do <strong>Bradesco<\/strong> recua 1,7% por volta das 12h. No acumulado de 2024 as a\u00e7\u00f5es do banco recuam 12%.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/plataforma-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"383162\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O Bradesco (BBDC4) pagar\u00e1 R$ 2 bilh\u00f5es em Juros Sobre Capital Pr\u00f3prio (JCP) aos seus acionistas, segundo fato relevante divulgado nesta sexta-feira (20). O valor dos JCP do Bradesco ser\u00e1 de R$ R$ 0,19 por a\u00e7\u00e3o preferencial e R$ 0,17 por a\u00e7\u00e3o ordin\u00e1ria. O pagamento dos rendimentos em quest\u00e3o ocorrer\u00e1 at\u00e9 o dia 30 de [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":406450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[392,1957],"suno_strategy":[],"class_list":["post-576384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-bradesco-bbdc3-bbdc4","tag-juros-sobre-capital-proprio-jcp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja<\/title>\n<meta name=\"description\" content=\"O valor dos JCP do Bradesco ser\u00e1 de R$ R$ 0,19 por a\u00e7\u00e3o preferencial e R$ 0,17 por a\u00e7\u00e3o ordin\u00e1ria, conforme fato relevante\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja\" \/>\n<meta property=\"og:description\" content=\"O valor dos JCP do Bradesco ser\u00e1 de R$ R$ 0,19 por a\u00e7\u00e3o preferencial e R$ 0,17 por a\u00e7\u00e3o ordin\u00e1ria, conforme fato relevante\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bradesco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Vargas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Vargas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/\"},\"author\":{\"name\":\"Eduardo Vargas\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5\"},\"headline\":\"Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja\",\"datePublished\":\"2024-09-20T15:05:09+00:00\",\"dateModified\":\"2024-09-20T22:59:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/\"},\"wordCount\":301,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bradesco.jpg\",\"keywords\":[\"Bradesco (BBDC3\/BBDC4)\",\"juros sobre capital pr\u00f3prio (JCP)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/\",\"name\":\"Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bradesco.jpg\",\"datePublished\":\"2024-09-20T15:05:09+00:00\",\"dateModified\":\"2024-09-20T22:59:56+00:00\",\"description\":\"O valor dos JCP do Bradesco ser\u00e1 de R$ R$ 0,19 por a\u00e7\u00e3o preferencial e R$ 0,17 por a\u00e7\u00e3o ordin\u00e1ria, conforme fato relevante\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bradesco.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bradesco.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Bradesco (BBDC4). Foto: iStock\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5\",\"name\":\"Eduardo Vargas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g\",\"caption\":\"Eduardo Vargas\"},\"description\":\"Jornalista formado pela UFSC, cobre macroeconomia, neg\u00f3cios e startups para o Suno Not\u00edcias, escrevendo principalmente not\u00edcias sobre o mercado financeiro e a bolsa de valores. No YouTube e no Instagram, \u00e9 respons\u00e1vel pela produ\u00e7\u00e3o de Reels e Shorts do Suno Not\u00edcias. Anteriormente, trabalhou cobrindo economia e cotidiano no ND+ e para o ND, maior jornal impresso de Santa Catarina. Cursou um semestre letivo de Estudos de M\u00eddia na Universidad de Buenos Aires.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja","description":"O valor dos JCP do Bradesco ser\u00e1 de R$ R$ 0,19 por a\u00e7\u00e3o preferencial e R$ 0,17 por a\u00e7\u00e3o ordin\u00e1ria, conforme fato relevante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/","og_locale":"pt_BR","og_type":"article","og_title":"Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja","og_description":"O valor dos JCP do Bradesco ser\u00e1 de R$ R$ 0,19 por a\u00e7\u00e3o preferencial e R$ 0,17 por a\u00e7\u00e3o ordin\u00e1ria, conforme fato relevante","og_url":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1200,"height":800,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bradesco.jpg","type":"image\/jpeg"}],"author":"Eduardo Vargas","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Eduardo Vargas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/"},"author":{"name":"Eduardo Vargas","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5"},"headline":"Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja","datePublished":"2024-09-20T15:05:09+00:00","dateModified":"2024-09-20T22:59:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/"},"wordCount":301,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bradesco.jpg","keywords":["Bradesco (BBDC3\/BBDC4)","juros sobre capital pr\u00f3prio (JCP)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/","url":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/","name":"Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bradesco.jpg","datePublished":"2024-09-20T15:05:09+00:00","dateModified":"2024-09-20T22:59:56+00:00","description":"O valor dos JCP do Bradesco ser\u00e1 de R$ R$ 0,19 por a\u00e7\u00e3o preferencial e R$ 0,17 por a\u00e7\u00e3o ordin\u00e1ria, conforme fato relevante","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bradesco.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bradesco.jpg","width":1200,"height":800,"caption":"Bradesco (BBDC4). Foto: iStock"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5","name":"Eduardo Vargas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g","caption":"Eduardo Vargas"},"description":"Jornalista formado pela UFSC, cobre macroeconomia, neg\u00f3cios e startups para o Suno Not\u00edcias, escrevendo principalmente not\u00edcias sobre o mercado financeiro e a bolsa de valores. No YouTube e no Instagram, \u00e9 respons\u00e1vel pela produ\u00e7\u00e3o de Reels e Shorts do Suno Not\u00edcias. Anteriormente, trabalhou cobrindo economia e cotidiano no ND+ e para o ND, maior jornal impresso de Santa Catarina. Cursou um semestre letivo de Estudos de M\u00eddia na Universidad de Buenos Aires.","url":"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bradesco-400x200.jpg\" alt=\"Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/bradesco-bbdc4-jcp-bilionario-evm\/\"><h2 class=\"content__title\">Bradesco (BBDC4) pagar\u00e1 JCP bilion\u00e1rio; veja<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&#038;r=g\" alt=\"Eduardo Vargas\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\"><span itemprop=\"author\">Eduardo Vargas<\/span><\/a><\/span><time datetime=\"2024-09-20T12:05:09-03:00\" itemprop=\"datePublished\">20\/09\/2024 12:05<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/576384"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=576384"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/576384\/revisions"}],"predecessor-version":[{"id":576497,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/576384\/revisions\/576497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/406450"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=576384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=576384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=576384"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=576384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}