{"id":566636,"date":"2024-07-16T11:20:26","date_gmt":"2024-07-16T14:20:26","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=566636"},"modified":"2024-07-16T11:20:29","modified_gmt":"2024-07-16T14:20:29","slug":"news-agenda-dividendos-direcional-dirr3-julho-gss","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/","title":{"rendered":"Direcional (DIRR3) pagar\u00e1 R$ 1,60 por a\u00e7\u00e3o em dividendos hoje; veja quem recebe"},"content":{"rendered":"<p>A <a class=\"suno-keyword\" target=\"_blank\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/DIRR3\/\" rel=\"noopener\">Direcional (DIRR3)<\/a> vai pagar <strong>dividendos<\/strong> aos seus acionistas nesta ter\u00e7a-feira (16).<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Direcional (DIRR3) pagar\u00e1 R$ 1,60 por a\u00e7\u00e3o em dividendos hoje; veja quem recebe\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Direcional (DIRR3). Foto: Divulga\u00e7\u00e3o<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"89005\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>O valor a ser pago aos investidores em <strong>dividendos da Direcional<\/strong> \u00e9 de R$ 1,6 por a\u00e7\u00e3o.<\/p>\n\n\n\n<p>Receber\u00e3o os <strong>proventos da Direcional<\/strong> os investidores que tinham pap\u00e9is da companhia at\u00e9 04 de julho, data de corte para o pagamento.<\/p>\n\n\n\n<p>A partir de 05 de julho, as a\u00e7\u00f5es passaram a ser negociadas sem direito aos <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" rel=\"noopener\">dividendos<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dividendos da a Direcional<\/h2>\n\n\n\n<p><strong>Direcional (DIRR3)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tipo: Dividendo<\/li>\n\n\n\n<li>Valor por a\u00e7\u00e3o: R$ 1,6<\/li>\n\n\n\n<li>Data de corte: 04\/07\/2024<\/li>\n\n\n\n<li>Rendimento: 5,54%<\/li>\n<\/ul>\n\n\n\n<p>Dividendos s\u00e3o uma parte do <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" rel=\"noopener\">lucro l\u00edquido<\/a> de uma empresa que s\u00e3o distribu\u00eddos periodicamente aos seus acionistas, como forma de remunera\u00e7\u00e3o. Este pagamento ocorre de forma proporcional ao n\u00famero de a\u00e7\u00f5es detido por cada acionista.<\/p>\n\n\n\n<p>Estes rendimentos s\u00e3o isentos de Imposto de Renda. Existe outro tipo de distribui\u00e7\u00e3o de valores aos acionistas que \u00e9 chamada de <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/entenda-o-jcp\/\" rel=\"noopener\">Juros sobre Capital Pr\u00f3prio<\/a> (JCP). No caso dos JCP, os acionistas precisam pagar 15% de IR sobre o valor recebido da empresa.<\/p>\n\n\n\n<p>Esta mat\u00e9ria \u00e9 uma agenda de <strong>dividendos<\/strong> e n\u00e3o se trata de uma recomenda\u00e7\u00e3o de compra ou venda de ativos.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>A Direcional (DIRR3) vai pagar dividendos aos seus acionistas nesta ter\u00e7a-feira (16). Direcional (DIRR3). Foto: Divulga\u00e7\u00e3o O valor a ser pago aos investidores em dividendos da Direcional \u00e9 de R$ 1,6 por a\u00e7\u00e3o. Receber\u00e3o os proventos da Direcional os investidores que tinham pap\u00e9is da companhia at\u00e9 04 de julho, data de corte para o pagamento. [&hellip;]<\/p>\n","protected":false},"author":376,"featured_media":331759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[446,295,1957],"suno_strategy":[],"class_list":["post-566636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-direcional-dirr3","tag-dividendos","tag-juros-sobre-capital-proprio-jcp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dividendos: Direcional (DIRR3) paga R$ 1,60 por a\u00e7\u00e3o hoje<\/title>\n<meta name=\"description\" content=\"A Direcional \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dividendos: Direcional (DIRR3) paga R$ 1,60 por a\u00e7\u00e3o hoje\" \/>\n<meta property=\"og:description\" content=\"A Direcional \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guilherme Serrano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guilherme Serrano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/\"},\"author\":{\"name\":\"Guilherme Serrano\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f07e64bce64aa671feadfb844f04ca\"},\"headline\":\"Direcional (DIRR3) pagar\u00e1 R$ 1,60 por a\u00e7\u00e3o em dividendos hoje; veja quem recebe\",\"datePublished\":\"2024-07-16T14:20:26+00:00\",\"dateModified\":\"2024-07-16T14:20:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/\"},\"wordCount\":211,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3.jpg\",\"keywords\":[\"Direcional (DIRR3)\",\"dividendos\",\"juros sobre capital pr\u00f3prio (JCP)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/\",\"name\":\"Dividendos: Direcional (DIRR3) paga R$ 1,60 por a\u00e7\u00e3o hoje\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3.jpg\",\"datePublished\":\"2024-07-16T14:20:26+00:00\",\"dateModified\":\"2024-07-16T14:20:29+00:00\",\"description\":\"A Direcional \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Direcional (DIRR3). Foto: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Direcional (DIRR3) pagar\u00e1 R$ 1,60 por a\u00e7\u00e3o em dividendos hoje; veja quem recebe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f07e64bce64aa671feadfb844f04ca\",\"name\":\"Guilherme Serrano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a90be19d8c67bef61497e4522de30ac4?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a90be19d8c67bef61497e4522de30ac4?s=96&r=g\",\"caption\":\"Guilherme Serrano\"},\"description\":\"Jornalista formado pela Faculdade C\u00e1sper L\u00edbero e p\u00f3s-graduado em Can\u00e7\u00e3o Popular pela Faculdade Santa Marcelina. Passagens por R\u00e1dio Gazeta AM, gazetaesportiva.com e TC R\u00e1dio.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/guilherme-silvasuno-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dividendos: Direcional (DIRR3) paga R$ 1,60 por a\u00e7\u00e3o hoje","description":"A Direcional \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/","og_locale":"pt_BR","og_type":"article","og_title":"Dividendos: Direcional (DIRR3) paga R$ 1,60 por a\u00e7\u00e3o hoje","og_description":"A Direcional \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!","og_url":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1200,"height":800,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3.jpg","type":"image\/jpeg"}],"author":"Guilherme Serrano","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Guilherme Serrano","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/"},"author":{"name":"Guilherme Serrano","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f07e64bce64aa671feadfb844f04ca"},"headline":"Direcional (DIRR3) pagar\u00e1 R$ 1,60 por a\u00e7\u00e3o em dividendos hoje; veja quem recebe","datePublished":"2024-07-16T14:20:26+00:00","dateModified":"2024-07-16T14:20:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/"},"wordCount":211,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3.jpg","keywords":["Direcional (DIRR3)","dividendos","juros sobre capital pr\u00f3prio (JCP)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/","url":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/","name":"Dividendos: Direcional (DIRR3) paga R$ 1,60 por a\u00e7\u00e3o hoje","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3.jpg","datePublished":"2024-07-16T14:20:26+00:00","dateModified":"2024-07-16T14:20:29+00:00","description":"A Direcional \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3.jpg","width":1200,"height":800,"caption":"Direcional (DIRR3). Foto: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Direcional (DIRR3) pagar\u00e1 R$ 1,60 por a\u00e7\u00e3o em dividendos hoje; veja quem recebe"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f07e64bce64aa671feadfb844f04ca","name":"Guilherme Serrano","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a90be19d8c67bef61497e4522de30ac4?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a90be19d8c67bef61497e4522de30ac4?s=96&r=g","caption":"Guilherme Serrano"},"description":"Jornalista formado pela Faculdade C\u00e1sper L\u00edbero e p\u00f3s-graduado em Can\u00e7\u00e3o Popular pela Faculdade Santa Marcelina. Passagens por R\u00e1dio Gazeta AM, gazetaesportiva.com e TC R\u00e1dio.","url":"https:\/\/www.suno.com.br\/noticias\/author\/guilherme-silvasuno-com-br\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/direcional-dirr3-400x200.jpg\" alt=\"Direcional (DIRR3) pagar\u00e1 R$ 1,60 por a\u00e7\u00e3o em dividendos hoje; veja quem recebe\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/news-agenda-dividendos-direcional-dirr3-julho-gss\/\"><h2 class=\"content__title\">Direcional (DIRR3) pagar\u00e1 R$ 1,60 por a\u00e7\u00e3o em dividendos hoje; veja quem recebe<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/guilherme-silvasuno-com-br\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/a90be19d8c67bef61497e4522de30ac4?s=96&#038;r=g\" alt=\"Guilherme Serrano\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/guilherme-silvasuno-com-br\/\"><span itemprop=\"author\">Guilherme Serrano<\/span><\/a><\/span><time datetime=\"2024-07-16T11:20:26-03:00\" itemprop=\"datePublished\">16\/07\/2024 11:20<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/566636"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/376"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=566636"}],"version-history":[{"count":2,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/566636\/revisions"}],"predecessor-version":[{"id":566669,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/566636\/revisions\/566669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/331759"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=566636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=566636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=566636"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=566636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}