{"id":561715,"date":"2024-06-12T20:54:50","date_gmt":"2024-06-12T23:54:50","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=561715"},"modified":"2024-06-12T20:54:55","modified_gmt":"2024-06-12T23:54:55","slug":"roberto-campos-neto-ministro-fazenda-evm","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/","title":{"rendered":"Roberto Campos Neto Ministro da Fazenda? Entenda"},"content":{"rendered":"<p>Segundo informa\u00e7\u00f5es de bastidores do Painel da Folha de S. Paulo, o atual presidente do Banco Central, <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/tudo-sobre\/roberto-campos-neto\/\" target=\"_blank\" rel=\"noopener\">Roberto <strong>Campos Neto<\/strong><\/a>, sinalizou para Tarc\u00edsio de Freitas que poderia ser seu ministro da Fazenda em um eventual mandato presidencial seu.<\/p><div class=\"videoFull \">\n\t\t\t<div class=\"videoWrapper yt-lazyload center\"\n\t\t\t\tdata-width=\"960\"\n\t\t\t\tdata-height=\"540\"\n\t\t\t\tdata-id=\"qwaqXajXso8\"\n\t\t\t\tdata-alt=\"V\u00eddeo do YouTube - clique para reproduzir\"\n\t\t\t\tdata-logo=\"3\"\n\t\t\t\tdata-imagequality=\"maxres\">\n\t\t\t<\/div>\n\t\t<\/div><script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"VideoObject\",\"name\":\"\ud83d\udd34IBOVESPA NA M\u00cdNIMA DE 8 MESES | Campos Neto Ministro da Fazenda? | Decis\u00e3o do Fed\",\"description\":\"#mercadofinanceiro #a\u00e7\u00f5es #investimentos #bolsadevalores #ibovespa #dinheiro #finan\u00e7as #pol\u00edtica #d\u00f3lar #livedas19h #petr4 #petr3 #petrobras #vale3 #vale #a\u00e7\u00f5es #economia #dividendos #min\u00e9riodeferro #min\u00e9rio #petr\u00f3leo #commodities #proventos #dividendos #jcp #statusinvest #statusalpha #sunoconsultoria #powell #fed #federalreserve #camposneto #robertocamposneto #bancocentral #bc \ud83d\udd34TENHA UM CONSULTOR PRA TE AJUDAR NOS SEUS INVESTIMENTOS: https:\/\/lp.suno.com.br\/ao\/consultoria-de-investimentos\/?utm_source=youtube.noticias&utm_campaign=020524&utm_medium=live 00:00 In\u00edcio do v\u00eddeo 01:35 Fechamento de preg\u00e3o 13:30 Decis\u00e3o\u2026\",\"duration\":\"PT29M59S\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/qwaqXajXso8\",\"regionsAllowed\":\"en-US\",\"interactionStatistic\":{\"@type\":\"InteractionCounter\",\"interactionType\":{\"@type\":\"WatchAction\"},\"userInteractionCount\":3356},\"thumbnailUrl\":\"https:\/\/i.ytimg.com\/vi\/qwaqXajXso8\/default.jpg\",\"uploadDate\":\"2024-06-12T22:38:49Z\"}<\/script>\n\n\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"240038\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n\n\n<p>Apesar disso, no encontro com o atual <strong>governador de S\u00e3o Paulo<\/strong>, Campos Neto teria desestimulado a candidatura. <\/p>\n\n\n\n<p>O atual <strong>presidente do Banco Central<\/strong> sinalizou que o melhor caminho seria pavimentar um segundo mandato como Governador do Estado de S\u00e3o Paulo e, s\u00f3 a\u00ed, se lan\u00e7ar candidato para <strong>presidente da Rep\u00fablica<\/strong>.<\/p>\n\n\n\n<p>O nome de Campos Neto poderia ser anunciado ainda durante a campanha de <strong>Tarc\u00edsio de Freitas<\/strong> para presidente da Rep\u00fablica, em estrat\u00e9gia an\u00e1loga \u00e0 de Jair Bolsonaro, que anunciou o nome de <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/tudo-sobre\/paulo-guedes\/\" rel=\"noopener\">Paulo Guedes<\/a> durante a campanha e conquistou uma maior credibilidade junto ao mercado financeiro.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-gratuito-investindo-no-exterior\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Investindo-no-exterior.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Investindo-no-exterior.png\"\n\t\t\t\t\tdata-promo-id=\"383161\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Investindo-no-exterior.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Campos Neto deixa BC ainda neste ano<\/h2>\n\n\n\n<p>O <strong>presidente do BC<\/strong> deixar\u00e1 sue cargo em 31 de dezembro de 2024. Ap\u00f3s isso, Campos Neto, pelas normativas atuais, ter\u00e1 de cumprir uma quarentena que \u00e9 exigida pelo seu cargo dentro da autoridade monet\u00e1ria.<\/p>\n\n\n\n<p>Assim, n\u00e3o pode assumir cargos na <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/iniciativa-privada\/\" rel=\"noopener\">iniciativa privada<\/a> &#8211; em um mecanismo como o de uma cl\u00e1usula de Non-Compete, evitando que ex-diretores e ex-presidentes usem informa\u00e7\u00f5es que tinham no BC para seu benef\u00edcio e de seus contratantes.<\/p>\n\n\n\n<p>Segundo o Painel da Folha de S. Paulo, nestas \u00faltimas semanas, Campos Neto conversou com amigos, pol\u00edticos e colegas do mercado financeiro sobre seu futuro p\u00f3s-BC.<\/p>\n\n\n\n<p>A sua sucess\u00e3o ainda \u00e9 uma inc\u00f3gnita e n\u00e3o se sabe quem ir\u00e1 passar pela sabatina do Senado e posteriormente assumir\u00e1 a cadeira de presidente da autoridade monet\u00e1ria.<\/p>\n\n\n\n<p>Roberto Campos Neto tomou posse como Presidente do Banco Central, ap\u00f3s ser indicado por Jair Bolsonaro, presidente em exerc\u00edcio \u00e0 \u00e9poca.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"383123\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Segundo informa\u00e7\u00f5es de bastidores do Painel da Folha de S. Paulo, o atual presidente do Banco Central, Roberto Campos Neto, sinalizou para Tarc\u00edsio de Freitas que poderia ser seu ministro da Fazenda em um eventual mandato presidencial seu. Apesar disso, no encontro com o atual governador de S\u00e3o Paulo, Campos Neto teria desestimulado a candidatura. [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":549774,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[62],"tags":[1842,824,1113],"suno_strategy":[],"class_list":["post-561715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-banco-central-bc","tag-ministerio-fazenda","tag-roberto-campos-neto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Roberto Campos Neto Ministro da Fazenda? Entenda<\/title>\n<meta name=\"description\" content=\"Em encontro com Tarc\u00edsio, Roberto Campos Neto sinalizou que poderia vir a ser Ministro da Fazenda em um eventual mandato presidencial seu\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roberto Campos Neto Ministro da Fazenda? Entenda\" \/>\n<meta property=\"og:description\" content=\"Em encontro com Tarc\u00edsio, Roberto Campos Neto sinalizou que poderia vir a ser Ministro da Fazenda em um eventual mandato presidencial seu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/Copom-Campos-Neto-Selic-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Vargas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Vargas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/\"},\"author\":{\"name\":\"Eduardo Vargas\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5\"},\"headline\":\"Roberto Campos Neto Ministro da Fazenda? Entenda\",\"datePublished\":\"2024-06-12T23:54:50+00:00\",\"dateModified\":\"2024-06-12T23:54:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/\"},\"wordCount\":322,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/Copom-Campos-Neto-Selic-scaled.jpg\",\"keywords\":[\"Banco Central (BC)\",\"Minist\u00e9rio da Fazenda\",\"Roberto Campos Neto\"],\"articleSection\":[\"Economia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/\",\"name\":\"Roberto Campos Neto Ministro da Fazenda? Entenda\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/Copom-Campos-Neto-Selic-scaled.jpg\",\"datePublished\":\"2024-06-12T23:54:50+00:00\",\"dateModified\":\"2024-06-12T23:54:55+00:00\",\"description\":\"Em encontro com Tarc\u00edsio, Roberto Campos Neto sinalizou que poderia vir a ser Ministro da Fazenda em um eventual mandato presidencial seu\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/Copom-Campos-Neto-Selic-scaled.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/Copom-Campos-Neto-Selic-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Taxas sobem ap\u00f3s fala de Campos Neto e avan\u00e7o no rendimento dos t\u00edtulos dos Estados Unidos. Foto: Fabio Rodrigues-Pozzebom\/Ag\u00eancia Brasil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Economia\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/economia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Roberto Campos Neto Ministro da Fazenda? Entenda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5\",\"name\":\"Eduardo Vargas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g\",\"caption\":\"Eduardo Vargas\"},\"description\":\"Jornalista formado pela UFSC, cobre macroeconomia, neg\u00f3cios e startups para o Suno Not\u00edcias, escrevendo principalmente not\u00edcias sobre o mercado financeiro e a bolsa de valores. No YouTube e no Instagram, \u00e9 respons\u00e1vel pela produ\u00e7\u00e3o de Reels e Shorts do Suno Not\u00edcias. Anteriormente, trabalhou cobrindo economia e cotidiano no ND+ e para o ND, maior jornal impresso de Santa Catarina. Cursou um semestre letivo de Estudos de M\u00eddia na Universidad de Buenos Aires.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roberto Campos Neto Ministro da Fazenda? Entenda","description":"Em encontro com Tarc\u00edsio, Roberto Campos Neto sinalizou que poderia vir a ser Ministro da Fazenda em um eventual mandato presidencial seu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/","og_locale":"pt_BR","og_type":"article","og_title":"Roberto Campos Neto Ministro da Fazenda? Entenda","og_description":"Em encontro com Tarc\u00edsio, Roberto Campos Neto sinalizou que poderia vir a ser Ministro da Fazenda em um eventual mandato presidencial seu","og_url":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":2560,"height":1707,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/Copom-Campos-Neto-Selic-scaled.jpg","type":"image\/jpeg"}],"author":"Eduardo Vargas","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Eduardo Vargas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/"},"author":{"name":"Eduardo Vargas","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5"},"headline":"Roberto Campos Neto Ministro da Fazenda? Entenda","datePublished":"2024-06-12T23:54:50+00:00","dateModified":"2024-06-12T23:54:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/"},"wordCount":322,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/Copom-Campos-Neto-Selic-scaled.jpg","keywords":["Banco Central (BC)","Minist\u00e9rio da Fazenda","Roberto Campos Neto"],"articleSection":["Economia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/","url":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/","name":"Roberto Campos Neto Ministro da Fazenda? Entenda","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/Copom-Campos-Neto-Selic-scaled.jpg","datePublished":"2024-06-12T23:54:50+00:00","dateModified":"2024-06-12T23:54:55+00:00","description":"Em encontro com Tarc\u00edsio, Roberto Campos Neto sinalizou que poderia vir a ser Ministro da Fazenda em um eventual mandato presidencial seu","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/Copom-Campos-Neto-Selic-scaled.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/Copom-Campos-Neto-Selic-scaled.jpg","width":2560,"height":1707,"caption":"Taxas sobem ap\u00f3s fala de Campos Neto e avan\u00e7o no rendimento dos t\u00edtulos dos Estados Unidos. Foto: Fabio Rodrigues-Pozzebom\/Ag\u00eancia Brasil"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Economia","item":"https:\/\/www.suno.com.br\/noticias\/economia\/"},{"@type":"ListItem","position":3,"name":"Roberto Campos Neto Ministro da Fazenda? Entenda"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5","name":"Eduardo Vargas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g","caption":"Eduardo Vargas"},"description":"Jornalista formado pela UFSC, cobre macroeconomia, neg\u00f3cios e startups para o Suno Not\u00edcias, escrevendo principalmente not\u00edcias sobre o mercado financeiro e a bolsa de valores. No YouTube e no Instagram, \u00e9 respons\u00e1vel pela produ\u00e7\u00e3o de Reels e Shorts do Suno Not\u00edcias. Anteriormente, trabalhou cobrindo economia e cotidiano no ND+ e para o ND, maior jornal impresso de Santa Catarina. Cursou um semestre letivo de Estudos de M\u00eddia na Universidad de Buenos Aires.","url":"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/Copom-Campos-Neto-Selic-400x200.jpg\" alt=\"Roberto Campos Neto Ministro da Fazenda? Entenda\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/economia\/\">Economia<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/roberto-campos-neto-ministro-fazenda-evm\/\"><h2 class=\"content__title\">Roberto Campos Neto Ministro da Fazenda? Entenda<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&#038;r=g\" alt=\"Eduardo Vargas\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\"><span itemprop=\"author\">Eduardo Vargas<\/span><\/a><\/span><time datetime=\"2024-06-12T20:54:50-03:00\" itemprop=\"datePublished\">12\/06\/2024 20:54<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/561715"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=561715"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/561715\/revisions"}],"predecessor-version":[{"id":561721,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/561715\/revisions\/561721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/549774"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=561715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=561715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=561715"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=561715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}