{"id":543426,"date":"2024-04-12T09:22:13","date_gmt":"2024-04-12T12:22:13","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=543426"},"modified":"2024-04-12T09:22:23","modified_gmt":"2024-04-12T12:22:23","slug":"petrobras-petr4-prates-presidente-gpj","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/","title":{"rendered":"Prates ironiza crise na Petrobras (PETR4) em primeira apari\u00e7\u00e3o ap\u00f3s rumores de fritura"},"content":{"rendered":"<p>Nesta quinta-feira (11), o presidente da <a href=\"https:\/\/www.suno.com.br\/acoes\/PETR4\/\"><strong>Petrobras<\/strong> (PETR4)<\/a>, Jean Paul Prates, discursou em evento da Associa\u00e7\u00e3o Brasileira de Empresas de Bens e Servi\u00e7os de Petr\u00f3leo (Abespetro). Foi a primeira apari\u00e7\u00e3o p\u00fablica de Prates desde quando come\u00e7aram as especula\u00e7\u00f5es sobre sua demiss\u00e3o.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Prates ironiza crise na Petrobras (PETR4) em primeira apari\u00e7\u00e3o ap\u00f3s rumores de fritura\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Jean Paul Prates, presidente da Petrobras (PETR4). Foto: Geraldo Magela\/Ag\u00eancia Senado<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"254218\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p><strong>Prates<\/strong> n\u00e3o atendeu a imprensa, mas ironizou a situa\u00e7\u00e3o atual: &#8220;Que crise?&#8221;.<\/p>\n\n\n\n<p>No discurso, o <strong>presidente da Petrobras<\/strong> garantiu novas formas de contrata\u00e7\u00e3o, processos e projetos \u00e0s empresas fornecedoras de produtos e servi\u00e7os da estatal. &#8220;Temos consci\u00eancia e certeza de que a rela\u00e7\u00e3o com fornecedores precisa mudar. \u00c9 prioridade para n\u00f3s&#8221;.<\/p>\n\n\n\n<p><strong>Jean Paul Prates<\/strong> tamb\u00e9m comentou a crise atual da cadeia de fornecedores e prometeu mais proximidade. &#8220;\u00c9 fundamental para n\u00f3s que voc\u00eas [fornecedores] estejam vivos. Vamos ao TCU [Tribunal de Contas da Uni\u00e3o]. Sejam bem-vindos \u00e0 nova rela\u00e7\u00e3o da Petrobras com membros da Abespetro&#8221;.<\/p>\n\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"readToo\">\n\t\t\t\t<span class=\"readToo__title\">Leia mais<\/span>\n\t\t\t\t<ul class=\"readToo__list\">\n\t\t\t<li><a href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-unigel-contrato-gpj\/\">Petrobras (PETR4): Unigel defende contrato firmado e nega irregularidades<\/a><\/li><li><a href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-100424-mm\/\">Petrobras (PETR4): comiss\u00e3o do Senado aprova auditoria para avaliar reten\u00e7\u00e3o de dividendos<\/a><\/li><li><a href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-pagou-bilhoes-icms-sao-paulo-evm\/\">Petrobras (PETR4) pagou R$ 21 bilh\u00f5es em ICMS a S\u00e3o Paulo<\/a><\/li>\t\t<\/ul>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Petrobras (PETR4): presidente do conselho \u00e9 suspenso; estatal vai recorrer da decis\u00e3o<\/h2>\n\n\n\n<p>A Justi\u00e7a Federal de S\u00e3o Paulo determinou na quinta-feira (11) a suspens\u00e3o, em decis\u00e3o liminar, do presidente do conselho de administra\u00e7\u00e3o da Petrobras (<strong>PETR4<\/strong>), Pietro Mendes, atual secret\u00e1rio de Petr\u00f3leo e G\u00e1s do Minist\u00e9rio de Minas e Energia. A estatal informou que vai recorrer da decis\u00e3o judicial.<\/p>\n\n\n\n<p>O juiz Paulo Cezar Neves Junior, da 21\u00aa Vara C\u00edvel Federal de S\u00e3o Paulo, decidiu suspender Mendes de suas fun\u00e7\u00f5es no colegiado da estatal alegando conflito de interesses.<\/p>\n\n\n\n<p>Al\u00e9m de liderar o comit\u00ea de acionistas da Petrobras, Mendes mant\u00e9m o cargo no Minist\u00e9rio de Minas e Energia (MME). A tese \u00e9 que os interesses da empresa podem conflitar com os do governo.<\/p>\n\n\n\n<p>&#8220;A Petrobras buscar\u00e1 a reforma da proferida decis\u00e3o por meio do recurso cab\u00edvel, de forma a defender a higidez dos seus procedimentos de governan\u00e7a interna, como tem atuado em outras a\u00e7\u00f5es em curso na mesma vara questionando indica\u00e7\u00f5es ao conselho&#8221;, informou a empresa por meio de <a href=\"https:\/\/www.suno.com.br\/artigos\/fato-relevante\/\">fato relevante<\/a> divulgado ao mercado.<\/p>\n\n\n\n<p>Na decis\u00e3o, o magistrado afirma que, ao observar as atribui\u00e7\u00f5es de Mendes no Conselho e a sua miss\u00e3o no minist\u00e9rio, &#8220;extrai-se claramente que a ampla atua\u00e7\u00e3o da Secretaria de Petr\u00f3leo, G\u00e1s Natural e Biocombust\u00edveis faz com que haja permanente e potencial conflito de interesses entre esse \u00f3rg\u00e3o e a Petrobras&#8221;.<\/p>\n\n\n\n<p>Dias atr\u00e1s, o mesmo juiz suspendeu um primeiro conselheiro apontado pelo governo, o ex-ministro de Ci\u00eancia e Tecnologia, Sergio Rezende. No ano passado, Rezende e Mendes chegaram a ser considerados ineleg\u00edveis para o colegiado ap\u00f3s o Comit\u00ea de Pessoas da Petrobras (Cope) apontar que os indicados n\u00e3o preenchiam os requisitos necess\u00e1rios previstos no <a href=\"https:\/\/www.suno.com.br\/artigos\/estatuto-social\/\">Estatuto Social<\/a> da empresa. O primeiro por ser membro titular do Diret\u00f3rio Nacional do Partido Socialista Brasileiro (PSB). O segundo, por ocupar cargo no governo.<\/p>\n\n\n\n<p>Ambas as situa\u00e7\u00f5es eram ent\u00e3o vedadas a conselheiros pela reda\u00e7\u00e3o da Lei das Estatais. Mas a lei teve o trecho relativo a essas restri\u00e7\u00f5es suprimido por decis\u00e3o liminar do ex-ministro do Supremo Tribunal Federal e atual ministro da Justi\u00e7a, Ricardo Lewandowski.<\/p>\n\n\n\n<p>A suspens\u00e3o de Rezende era considerada problema menor, visto que ele n\u00e3o figurava na lista de candidatos enviada recentemente pelo governo \u00e0 empresa, para elei\u00e7\u00e3o na assembleia de acionistas do pr\u00f3ximo dia 25 de abril.<\/p>\n\n\n\n<p>Mendes, ao contr\u00e1rio, est\u00e1 na lista para recondu\u00e7\u00e3o. Al\u00e9m disso, \u00e9 um dos piv\u00f4s da crise no comando da empresa, sendo o principal opositor do presidente da <strong>Petrobras<\/strong>, Jean Paul Prates, no colegiado. A decis\u00e3o enfraquece a posi\u00e7\u00e3o de Mendes e a de seu padrinho para o cargo, o ministro de Minas e Energia, Alexandre Silveira.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Nesta quinta-feira (11), o presidente da Petrobras (PETR4), Jean Paul Prates, discursou em evento da Associa\u00e7\u00e3o Brasileira de Empresas de Bens e Servi\u00e7os de Petr\u00f3leo (Abespetro). Foi a primeira apari\u00e7\u00e3o p\u00fablica de Prates desde quando come\u00e7aram as especula\u00e7\u00f5es sobre sua demiss\u00e3o. Jean Paul Prates, presidente da Petrobras (PETR4). Foto: Geraldo Magela\/Ag\u00eancia Senado Prates n\u00e3o atendeu [&hellip;]<\/p>\n","protected":false},"author":313,"featured_media":543443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[595],"suno_strategy":[],"class_list":["post-543426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-petrobras-petr4"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Petrobras (PETR4): Prates ironiza crise ap\u00f3s rumores de demiss\u00e3o<\/title>\n<meta name=\"description\" content=\"O presidente da Petrobras (PETR4), Jean Paul Prates, discursou em evento Abespetro. Veja o que Prates disse sobre a crise na Petrobras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petrobras (PETR4): Prates ironiza crise ap\u00f3s rumores de demiss\u00e3o\" \/>\n<meta property=\"og:description\" content=\"O presidente da Petrobras (PETR4), Jean Paul Prates, discursou em evento Abespetro. Veja o que Prates disse sobre a crise na Petrobras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanni Porf\u00edrio Jacomino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Porf\u00edrio Jacomino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/\"},\"author\":{\"name\":\"Giovanni Porf\u00edrio Jacomino\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40\"},\"headline\":\"Prates ironiza crise na Petrobras (PETR4) em primeira apari\u00e7\u00e3o ap\u00f3s rumores de fritura\",\"datePublished\":\"2024-04-12T12:22:13+00:00\",\"dateModified\":\"2024-04-12T12:22:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/\"},\"wordCount\":652,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k.jpg\",\"keywords\":[\"Petrobras (PETR4)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/\",\"name\":\"Petrobras (PETR4): Prates ironiza crise ap\u00f3s rumores de demiss\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k.jpg\",\"datePublished\":\"2024-04-12T12:22:13+00:00\",\"dateModified\":\"2024-04-12T12:22:23+00:00\",\"description\":\"O presidente da Petrobras (PETR4), Jean Paul Prates, discursou em evento Abespetro. Veja o que Prates disse sobre a crise na Petrobras.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"Jean Paul Prates, presidente da Petrobras (PETR4). Foto: Geraldo Magela\/Ag\u00eancia Senado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prates ironiza crise na Petrobras (PETR4) em primeira apari\u00e7\u00e3o ap\u00f3s rumores de fritura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40\",\"name\":\"Giovanni Porf\u00edrio Jacomino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g\",\"caption\":\"Giovanni Porf\u00edrio Jacomino\"},\"description\":\"Giovanni Porf\u00edrio Jacomino \u00e9 jornalista formado pela Universidade Estadual de Londrina (UEL) e p\u00f3s-graduado em Produ\u00e7\u00e3o e Pr\u00e1ticas Jornal\u00edsticas na Contemporaneidade na Faculdade C\u00e1sper L\u00edbero (FCL). Foi editor web no Startupi e no Finsiders, atuando ainda como editor no TC Mover, portal de not\u00edcias da TradersClub, fazendo a cobertura de assuntos relacionados ao mercado financeiro interno e externo. Atualmente, \u00e9 Rep\u00f3rter do Suno Not\u00edcias.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petrobras (PETR4): Prates ironiza crise ap\u00f3s rumores de demiss\u00e3o","description":"O presidente da Petrobras (PETR4), Jean Paul Prates, discursou em evento Abespetro. Veja o que Prates disse sobre a crise na Petrobras.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/","og_locale":"pt_BR","og_type":"article","og_title":"Petrobras (PETR4): Prates ironiza crise ap\u00f3s rumores de demiss\u00e3o","og_description":"O presidente da Petrobras (PETR4), Jean Paul Prates, discursou em evento Abespetro. Veja o que Prates disse sobre a crise na Petrobras.","og_url":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":2048,"height":1365,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k.jpg","type":"image\/jpeg"}],"author":"Giovanni Porf\u00edrio Jacomino","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Giovanni Porf\u00edrio Jacomino","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/"},"author":{"name":"Giovanni Porf\u00edrio Jacomino","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40"},"headline":"Prates ironiza crise na Petrobras (PETR4) em primeira apari\u00e7\u00e3o ap\u00f3s rumores de fritura","datePublished":"2024-04-12T12:22:13+00:00","dateModified":"2024-04-12T12:22:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/"},"wordCount":652,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k.jpg","keywords":["Petrobras (PETR4)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/","url":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/","name":"Petrobras (PETR4): Prates ironiza crise ap\u00f3s rumores de demiss\u00e3o","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k.jpg","datePublished":"2024-04-12T12:22:13+00:00","dateModified":"2024-04-12T12:22:23+00:00","description":"O presidente da Petrobras (PETR4), Jean Paul Prates, discursou em evento Abespetro. Veja o que Prates disse sobre a crise na Petrobras.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k.jpg","width":2048,"height":1365,"caption":"Jean Paul Prates, presidente da Petrobras (PETR4). Foto: Geraldo Magela\/Ag\u00eancia Senado"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Prates ironiza crise na Petrobras (PETR4) em primeira apari\u00e7\u00e3o ap\u00f3s rumores de fritura"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40","name":"Giovanni Porf\u00edrio Jacomino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g","caption":"Giovanni Porf\u00edrio Jacomino"},"description":"Giovanni Porf\u00edrio Jacomino \u00e9 jornalista formado pela Universidade Estadual de Londrina (UEL) e p\u00f3s-graduado em Produ\u00e7\u00e3o e Pr\u00e1ticas Jornal\u00edsticas na Contemporaneidade na Faculdade C\u00e1sper L\u00edbero (FCL). Foi editor web no Startupi e no Finsiders, atuando ainda como editor no TC Mover, portal de not\u00edcias da TradersClub, fazendo a cobertura de assuntos relacionados ao mercado financeiro interno e externo. Atualmente, \u00e9 Rep\u00f3rter do Suno Not\u00edcias.","url":"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/04\/52373389277_d33679ec23_k-400x200.jpg\" alt=\"Prates ironiza crise na Petrobras (PETR4) em primeira apari\u00e7\u00e3o ap\u00f3s rumores de fritura\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-prates-presidente-gpj\/\"><h2 class=\"content__title\">Prates ironiza crise na Petrobras (PETR4) em primeira apari\u00e7\u00e3o ap\u00f3s rumores de fritura<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&#038;r=g\" alt=\"Eduardo Vargas\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\"><span itemprop=\"author\">Eduardo Vargas<\/span><\/a><\/span><time datetime=\"2024-04-12T09:22:13-03:00\" itemprop=\"datePublished\">12\/04\/2024 09:22<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/543426"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/313"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=543426"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/543426\/revisions"}],"predecessor-version":[{"id":543449,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/543426\/revisions\/543449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/543443"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=543426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=543426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=543426"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=543426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}