{"id":535831,"date":"2024-03-20T16:02:51","date_gmt":"2024-03-20T19:02:51","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=535831"},"modified":"2024-03-20T17:14:00","modified_gmt":"2024-03-20T20:14:00","slug":"fed-eua-mantem-juros-mais-cortes-cpf","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/","title":{"rendered":"Fed mant\u00e9m taxa b\u00e1sica de juros entre 5,25% a 5,50% e reitera chance de tr\u00eas cortes em 2024"},"content":{"rendered":"<p>O Federal Reserve, ou <strong>Fed<\/strong>, manteve a <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/artigos\/juros\/\" rel=\"noopener\">taxa de juros<\/a> dos Estados Unidos entre 5,25% e 5,50%. A reuni\u00e3o do comit\u00ea FOMC chegou \u00e0 decis\u00e3o nesta quarta-feira (20).<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Fed mant\u00e9m taxa b\u00e1sica de juros entre 5,25% a 5,50% e reitera chance de tr\u00eas cortes em 2024\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Estados Unidos - Foto: Unsplash<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>Segundo comunicado do banco central norte-americano, os indicadores sugerem que a<strong> atividade econ\u00f4mica nos EUA<\/strong> est\u00e1 expandindo a um ritmo s\u00f3lido. &#8220;Os ganhos de emprego permaneceram fortes, e a taxa de desemprego permaneceu baixa. A <strong>infla\u00e7\u00e3o<\/strong> diminuiu ao longo do \u00faltimo ano, mas permanece elevada&#8221;, ressaltou a organiza\u00e7\u00e3o.<\/p>\n\n\n\n<p>O comit\u00ea de <strong>pol\u00edtica monet\u00e1ria dos Estados Unidos<\/strong> (FOMC, similar ao Copom no Brasil) refor\u00e7ou que seu objetivo \u00e9 alcan\u00e7ar o <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/pleno-emprego\/\" target=\"_blank\" rel=\"noopener\">pleno emprego<\/a> e uma infla\u00e7\u00e3o na taxa de 2% no <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/longo-prazo\/\" target=\"_blank\" rel=\"noopener\">longo prazo<\/a>. <\/p>\n\n\n\n<p>No cen\u00e1rio atual, os membros, liderados pelo <strong>presidente do Fed<\/strong>, Jerome Powell, acreditam que os riscos para atingir a meta est\u00e3o se &#8220;movendo para um melhor equil\u00edbrio&#8221;.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;O Comit\u00ea est\u00e1 fortemente comprometido em retornar a infla\u00e7\u00e3o ao seu objetivo de 2%&#8221;, refor\u00e7ou o comunicado oficial do Federal Reserve.<\/p>\n<\/blockquote>\n\n\n\n<p>Em discurso ap\u00f3s divulga\u00e7\u00e3o dos n\u00fameros, <strong>Jerome Powell <\/strong>afirmou que o mercado de trabalho &#8220;est\u00e1 em boa forma&#8221;. <\/p>\n\n\n\n<p>Apesar disso, eles afirmam que a perspectiva econ\u00f4mica norte-americana permanece incerta e que o <strong>FOMC <\/strong>est\u00e1 atento aos riscos inflacion\u00e1rios.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-gratuito-investindo-no-exterior\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Investindo-no-exterior.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Investindo-no-exterior.png\"\n\t\t\t\t\tdata-promo-id=\"383161\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Investindo-no-exterior.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Fed persiste em manter juros em patamar acima de 5%<\/h2>\n\n\n\n<p>Na reuni\u00e3o do FOMC, dos 19 membros do Fed, nove esperam que a taxa b\u00e1sica de juros dos Estados Unidos termine 2024 na faixa entre 4,50% e 4,75%, conforme aponta o gr\u00e1fico de pontos. <\/p>\n\n\n\n<p>Segundo o economista-chefe da Suno Research, Gustavo Sung, a postura de cautela adotada pelo FOMC tamb\u00e9m era esperada no discurso de <strong>Jerome Powell, <\/strong>que acontece hoje (20).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;Estamos na segunda fase do processo desinflacion\u00e1rio, onde a queda dos pre\u00e7os \u00e9 mais lenta e mais dependente do ciclo econ\u00f4mico. Logo, os pr\u00f3ximos dados ser\u00e3o importantes &#8211; principalmente, infla\u00e7\u00e3o de servi\u00e7os&#8221;, analisa Sung. <\/p>\n<\/blockquote>\n\n\n\n<p>Na interpreta\u00e7\u00e3o de Andr\u00e9 Fernandes, head de renda vari\u00e1vel da A7 Capital, o discurso do Fed hoje foi mais &#8220;dovish, apesar de n\u00e3o indicar quando devem cortar os juros.&#8221; <\/p>\n\n\n\n<p>Al\u00e9m disso, o especialista ressalta a vis\u00e3o do presidente de que a pol\u00edtica monet\u00e1ria j\u00e1 teria chegado ao seu pico. &#8220;Com isso, acredito que as apostas seguem firmes para junho em rela\u00e7\u00e3o ao primeiro corte do juros americano&#8221;, disse Fernandes. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Federal Reserve vai resistir \u00e0s press\u00f5es para corte mais seguro<\/h2>\n\n\n\n<p>Apesar da press\u00e3o para a redu\u00e7\u00e3o da infla\u00e7\u00e3o, os membros do<strong> Federal Reserve<\/strong> reiteraram que os cortes apenas vir\u00e3o quando houver &#8220;adquirido maior confian\u00e7a de que a infla\u00e7\u00e3o est\u00e1 se movendo de forma sustent\u00e1vel em dire\u00e7\u00e3o a 2%.&#8221; <\/p>\n\n\n\n<p>Para Daniel Cunha, estrategista-chefe da BGC Liquidez, a decis\u00e3o do FOMC, assim como as novas proje\u00e7\u00f5es, &#8220;vieram melhores do que o temido, mas mostram menor convic\u00e7\u00e3o com o ciclo de afrouxamento \u00e0 frente.&#8221;<\/p>\n\n\n\n<p>Sung explica que o <strong>FOMC <\/strong>atualmente est\u00e1 diante de um dilema: se o Fed afrouxar a <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/politica-monetaria\/\" rel=\"noopener\">pol\u00edtica monet\u00e1ria<\/a> prematuramente, pode gerar um descontrole de pre\u00e7os. Por\u00e9m, se aguardar muito para cortar os juros, poder\u00e1 comprometer a atividade econ\u00f4mica.<\/p>\n\n\n\n<p>&#8220;Dado que a atividade econ\u00f4mica e o mercado de trabalho continuam sustentando a economia, o <strong>Fed <\/strong>n\u00e3o ter\u00e1 pressa em tomar decis\u00f5es&#8221;, avalia o economista.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gr\u00e1fico de pontos aponta que 9 dirigentes do Fed veem juros entre 4,50% e 4,75% no fim de 2024<\/h2>\n\n\n\n<p>Entre os 19 dirigentes que submeteram proje\u00e7\u00f5es na <strong>reuni\u00e3o do Comit\u00ea Federal de Mercado Aberto<\/strong> (Fomc, na sigla em ingl\u00eas) do Federal Reserve (Fed, o banco central norte-americano) nesta quarta-feira, nove esperam que a taxa b\u00e1sica de juros dos Estados Unidos termine 2024 na faixa entre 4,50% e 4,75%, conforme aponta o gr\u00e1fico de pontos. Atualmente, a taxa dos Fed Funds est\u00e1 entre 5,25% e 5,50% e foi mantida nesta quarta-feira, conforme decis\u00e3o do comit\u00ea.<\/p>\n\n\n\n<p>Apenas um dirigente v\u00ea um relaxamento monet\u00e1rio mais profundo no per\u00edodo, com expectativa de juros a 4,25% e 4,50% at\u00e9 dezembro pr\u00f3ximo.<\/p>\n\n\n\n<p>Mais conservadores, dois<strong> membros do FOMC<\/strong> projetam manuten\u00e7\u00e3o no n\u00edvel atual este ano e outros dois espera, apenas um corte de 25 pontos-base nesse horizonte.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o a 2025, seis dirigentes esperam juros no intervalo entre 3,75% e 4,00% e outros cinco na faixa entre 3,50% e 3,75%. Uma autoridade enxerga a taxa inalterada tamb\u00e9m no fim do ano que vem, enquanto outras duas considera o patamar entre 4,25% e 4,50% mais prov\u00e1vel naquela altura.<\/p>\n\n\n\n<p>Para o fim de 2026, seis dirigentes preveem juros b\u00e1sicos entre 3,00% e 3,25% e outros cinco entre 2,75% e 3,00%. No longo prazo, oito integrantes veem a taxa no ponto m\u00e9dio de 2,5%.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Chance de Fed cortar juros em junho avan\u00e7a de 64,7% a 73,6%, ap\u00f3s decis\u00e3o de hoje, mostra CME<\/h2>\n\n\n\n<p>A chance de os <strong>juros dos EUA<\/strong> come\u00e7arem a cair em junho nos Estados Unidos aumentou, depois que o Federal Reserve (Fed, o banco central norte-americano) divulgou decis\u00e3o de manter as taxas inalteradas no per\u00edodo da tarde desta quarta-feira, 20. A probabilidade de o corte vir ao final do semestre subiu a 73,6%, de 64,7% antes do an\u00fancio, segundo monitoramento do CME Group.<\/p>\n\n\n\n<p>O cen\u00e1rio de cortes acumulados de 75 pontos-base ao longo do ano se manteve como o mais prov\u00e1vel. Sua probabilidade passou de 34,5% para 34,3%. Em segundo lugar, a chance de cortes de 100 pontos-base at\u00e9 o fim do ano avan\u00e7ou de 24,1% a 28%.<\/p>\n\n\n\n<p>O gr\u00e1fico de pontos do Fed mostra que a maioria dos dirigentes do Fed v\u00ea o juro entre 4,50% e 4,75% no fim de 2024.<\/p>\n\n\n\n<p>Dificilmente o Fed n\u00e3o entregar\u00e1 o corte de juros em junho &#8211; afinal, houve aumento de PIB e infla\u00e7\u00e3o, e mesmo assim o or\u00e7amento de cortes seguiu o mesmo.<\/p>\n\n\n\n<p>Na entrevista, quando questionado sobre como subir o PIB nos tr\u00eas anos de proje\u00e7\u00e3o sem mexer com a infla\u00e7\u00e3o para 25 e 26, Powell disse que s\u00e3o coisas em separado. Em v\u00e1rias situa\u00e7\u00f5es, ele destacou o movimento do lado da oferta da economia para explicar essa pujan\u00e7a da atividade, o que n\u00e3o seria inflacion\u00e1rio.<\/p>\n\n\n\n<p>Sobre o mercado de trabalho, quando questionado diretamente se n\u00fameros fortes de contrata\u00e7\u00e3o o levariam a rever o or\u00e7amento dos juros ele disse que &#8216;Not in itself, no. You saw last year, strong hiring and inflation coming down quickly. We now have a better sense that a bigger part of that was supply-side healing particularly with growth in the labor force&#8217;. Essa mensagem combina com um comit\u00ea que d\u00e1 uma import\u00e2ncia menor ao timo de vagas criadas, contanto que sigamos vendo modera\u00e7\u00e3o dos reajustes dos sal\u00e1rios para um patamar mais &#8216;sustent\u00e1vel&#8217;.<\/p>\n\n\n\n<p>Quando questionado sobre o que o tornar\u00e1 mais confiante para cortar, ele respondeu que ser\u00e1 a infla\u00e7\u00e3o dar sinais de que est\u00e1 caminhando para o objetivo de 2%. De maneira geral, o discurso dele coloca toda a aten\u00e7\u00e3o nos pr\u00f3ximos n\u00fameros de infla\u00e7\u00e3o e diminui a relev\u00e2ncia dos dados de atividade para a defini\u00e7\u00e3o do in\u00edcio do ciclo de cortes.<\/p>\n\n\n\n<p>Sobre o programa de redu\u00e7\u00e3o do balan\u00e7o, ele disse que houve a discuss\u00e3o para em breve reduzir o ritmo de redu\u00e7\u00e3o passiva do balan\u00e7o. Isso combina com uma decis\u00e3o j\u00e1 em maio, o que tamb\u00e9m \u00e9 uma inova\u00e7\u00e3o para o lado mais dovish.<\/p>\n\n\n\n<p>Seguimos esperando in\u00edcio do ciclo de cortes em junho e antecipamos, assim como o FED, cortes de 75 bps em 2024.<\/p>\n\n\n\n<p>D\u00e9bora Nogueira, economista-chefe da Tenax Capital, comenta: &#8220;Dificilmente o Fed n\u00e3o entregar\u00e1 o corte de juros em junho &#8211; afinal, houve aumento de PIB e infla\u00e7\u00e3o, e mesmo assim o or\u00e7amento de cortes seguiu o mesmo.&#8221;<\/p>\n\n\n\n<p>Ela acrescenta: &#8220;Na entrevista [do presidente do Fed, Jerome Powell], quando questionado sobre como subir o PIB nos tr\u00eas anos de proje\u00e7\u00e3o sem mexer com a infla\u00e7\u00e3o para 25 e 26, Powell disse que s\u00e3o coisas em separado. Em v\u00e1rias situa\u00e7\u00f5es, ele destacou o movimento do lado da oferta da economia para explicar essa pujan\u00e7a da atividade, o que n\u00e3o seria inflacion\u00e1rio.&#8221;<\/p>\n\n\n\n<p>D\u00e9bora completa: &#8220;Quando questionado sobre o que o tornar\u00e1 mais confiante para cortar, ele respondeu que ser\u00e1 a infla\u00e7\u00e3o dar sinais de que est\u00e1 caminhando para o objetivo de 2%. De maneira geral, o discurso dele coloca toda a aten\u00e7\u00e3o nos pr\u00f3ximos n\u00fameros de infla\u00e7\u00e3o e diminui a relev\u00e2ncia dos dados de atividade para a defini\u00e7\u00e3o do in\u00edcio do ciclo de cortes.&#8221;<\/p>\n\n\n\n<p>A economista espera in\u00edcio do ciclo de cortes em junho: &#8220;Antecipamos, assim como o Fed, cortes de 75 bps em 2024.&#8221;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Infla\u00e7\u00e3o desacelera nos EUA, mas segue muito alta, com rumo adiante ainda incerto, diz Powell<\/h2>\n\n\n\n<p>O <strong>presidente do Federal Reserve<\/strong>, Jerome Powell, afirmou que a infla\u00e7\u00e3o nos Estados Unidos desacelerou, mas segue muito elevada e, portanto, o caminho da pol\u00edtica monet\u00e1ria no pa\u00eds ainda \u00e9 &#8220;incerto&#8221;. <\/p>\n\n\n\n<p>&#8220;A infla\u00e7\u00e3o ainda \u00e9 muito elevada e estamos vendo progressos em seu processo de desacelera\u00e7\u00e3o. N\u00e3o est\u00e1 garantido progresso em andamento e o caminho a seguir \u00e9 incerto&#8221;, disse Powell, em coletiva de imprensa, no per\u00edodo da tarde desta quarta-feira, 20, na sequ\u00eancia da <strong>decis\u00e3o do Fed<\/strong> que manteve os juros dos EUA est\u00e1veis entre 5,25% e 5,50% ao ano, como amplamente esperado no mercado.<\/p>\n\n\n\n<p>Segundo ele, o Fed segue focado em seu duplo mandato para emprego e infla\u00e7\u00e3o, focado em retornar o \u00edndice de pre\u00e7os \u00e0 meta de 2% ao ano. &#8220;Nossa postura tem colocado press\u00e3o de baixa na atividade e na infla\u00e7\u00e3o&#8221;, acrescentou.<\/p>\n\n\n\n<p>Tamb\u00e9m em linha com as expectativas de Wall Street, o BC dos EUA manteve a proje\u00e7\u00e3o de tr\u00eas cortes de juros para este ano, a despeito de uma infla\u00e7\u00e3o resistente e o forte crescimento da economia americana.<\/p>\n\n\n\n<p>&#8220;Dirigentes em geral revisaram para cima proje\u00e7\u00f5es de crescimento&#8221;, destacou Powell, a jornalistas.<\/p>\n\n\n\n<p>A proje\u00e7\u00e3o do <strong>Fed<\/strong> para o n\u00facleo do \u00edndice de pre\u00e7os de gastos com consumo (PCE, na sigla em ingl\u00eas) foi elevada para 2,6%, de 2,4% em dezembro. O indicador exclui itens vol\u00e1teis como os pre\u00e7os de alimentos e energia. Por sua vez, a estimativa para o Produto Interno Bruto (PIB) dos EUA subiu para 2,1% contra 1,4%, nesta ordem.<\/p>\n\n\n\n<p><em>Com Estad\u00e3o Conte\u00fado<\/em><\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"383123\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O Federal Reserve, ou Fed, manteve a taxa de juros dos Estados Unidos entre 5,25% e 5,50%. A reuni\u00e3o do comit\u00ea FOMC chegou \u00e0 decis\u00e3o nesta quarta-feira (20). Estados Unidos &#8211; Foto: Unsplash Segundo comunicado do banco central norte-americano, os indicadores sugerem que a atividade econ\u00f4mica nos EUA est\u00e1 expandindo a um ritmo s\u00f3lido. &#8220;Os [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":345798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[105816,793,776,2448],"suno_strategy":[],"class_list":["post-535831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-especialistas","tag-estados-unidos-eua","tag-federal-reseve-fed","tag-politica-monetaria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fed mant\u00e9m juros entre 5,25% a 5,50% e sinaliza mais tr\u00eas cortes<\/title>\n<meta name=\"description\" content=\"Na Super Quarta, o Fed anunciou a manuten\u00e7\u00e3o da taxa de juros nos Estados Unidos. Veja mais sobre os pr\u00f3ximos cortes de juros do Fed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fed mant\u00e9m juros entre 5,25% a 5,50% e sinaliza mais tr\u00eas cortes\" \/>\n<meta property=\"og:description\" content=\"Na Super Quarta, o Fed anunciou a manuten\u00e7\u00e3o da taxa de juros nos Estados Unidos. Veja mais sobre os pr\u00f3ximos cortes de juros do Fed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1677\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camila Paim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camila Paim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/\"},\"author\":{\"name\":\"Camila Paim\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/f341d3ae5d1cc685176c9a5327cdfdbb\"},\"headline\":\"Fed mant\u00e9m taxa b\u00e1sica de juros entre 5,25% a 5,50% e reitera chance de tr\u00eas cortes em 2024\",\"datePublished\":\"2024-03-20T19:02:51+00:00\",\"dateModified\":\"2024-03-20T20:14:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/\"},\"wordCount\":1756,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-scaled.jpg\",\"keywords\":[\"Especialistas\",\"Estados Unidos (EUA)\",\"Federal Reserve (FED)\",\"pol\u00edtica monet\u00e1ria\"],\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/\",\"name\":\"Fed mant\u00e9m juros entre 5,25% a 5,50% e sinaliza mais tr\u00eas cortes\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-scaled.jpg\",\"datePublished\":\"2024-03-20T19:02:51+00:00\",\"dateModified\":\"2024-03-20T20:14:00+00:00\",\"description\":\"Na Super Quarta, o Fed anunciou a manuten\u00e7\u00e3o da taxa de juros nos Estados Unidos. Veja mais sobre os pr\u00f3ximos cortes de juros do Fed.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-scaled.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-scaled.jpg\",\"width\":2560,\"height\":1677,\"caption\":\"Estados Unidos - Foto: Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fed mant\u00e9m taxa b\u00e1sica de juros entre 5,25% a 5,50% e reitera chance de tr\u00eas cortes em 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/f341d3ae5d1cc685176c9a5327cdfdbb\",\"name\":\"Camila Paim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f33728e65febb1aa7ecf6792956f9b20?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f33728e65febb1aa7ecf6792956f9b20?s=96&r=g\",\"caption\":\"Camila Paim\"},\"description\":\"Jornalista formada pela USP, tem experi\u00eancia em reda\u00e7\u00f5es, SEO, Branded Content e Webdesign. Com passagem pelo Jornal da USP, Empiricus e C6 Bank, hoje \u00e9 rep\u00f3rter no Suno Not\u00edcias cobrindo macroeconomia, finan\u00e7as pessoais e startups.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/camila-figueiredosuno-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fed mant\u00e9m juros entre 5,25% a 5,50% e sinaliza mais tr\u00eas cortes","description":"Na Super Quarta, o Fed anunciou a manuten\u00e7\u00e3o da taxa de juros nos Estados Unidos. Veja mais sobre os pr\u00f3ximos cortes de juros do Fed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/","og_locale":"pt_BR","og_type":"article","og_title":"Fed mant\u00e9m juros entre 5,25% a 5,50% e sinaliza mais tr\u00eas cortes","og_description":"Na Super Quarta, o Fed anunciou a manuten\u00e7\u00e3o da taxa de juros nos Estados Unidos. Veja mais sobre os pr\u00f3ximos cortes de juros do Fed.","og_url":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":2560,"height":1677,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-scaled.jpg","type":"image\/jpeg"}],"author":"Camila Paim","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Camila Paim","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/"},"author":{"name":"Camila Paim","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/f341d3ae5d1cc685176c9a5327cdfdbb"},"headline":"Fed mant\u00e9m taxa b\u00e1sica de juros entre 5,25% a 5,50% e reitera chance de tr\u00eas cortes em 2024","datePublished":"2024-03-20T19:02:51+00:00","dateModified":"2024-03-20T20:14:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/"},"wordCount":1756,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-scaled.jpg","keywords":["Especialistas","Estados Unidos (EUA)","Federal Reserve (FED)","pol\u00edtica monet\u00e1ria"],"articleSection":["Internacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/","url":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/","name":"Fed mant\u00e9m juros entre 5,25% a 5,50% e sinaliza mais tr\u00eas cortes","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-scaled.jpg","datePublished":"2024-03-20T19:02:51+00:00","dateModified":"2024-03-20T20:14:00+00:00","description":"Na Super Quarta, o Fed anunciou a manuten\u00e7\u00e3o da taxa de juros nos Estados Unidos. Veja mais sobre os pr\u00f3ximos cortes de juros do Fed.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-scaled.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-scaled.jpg","width":2560,"height":1677,"caption":"Estados Unidos - Foto: Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Internacional","item":"https:\/\/www.suno.com.br\/noticias\/internacional\/"},{"@type":"ListItem","position":3,"name":"Fed mant\u00e9m taxa b\u00e1sica de juros entre 5,25% a 5,50% e reitera chance de tr\u00eas cortes em 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/f341d3ae5d1cc685176c9a5327cdfdbb","name":"Camila Paim","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f33728e65febb1aa7ecf6792956f9b20?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f33728e65febb1aa7ecf6792956f9b20?s=96&r=g","caption":"Camila Paim"},"description":"Jornalista formada pela USP, tem experi\u00eancia em reda\u00e7\u00f5es, SEO, Branded Content e Webdesign. Com passagem pelo Jornal da USP, Empiricus e C6 Bank, hoje \u00e9 rep\u00f3rter no Suno Not\u00edcias cobrindo macroeconomia, finan\u00e7as pessoais e startups.","url":"https:\/\/www.suno.com.br\/noticias\/author\/camila-figueiredosuno-com-br\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/eua-usa-400x200.jpg\" alt=\"Fed mant\u00e9m taxa b\u00e1sica de juros entre 5,25% a 5,50% e reitera chance de tr\u00eas cortes em 2024\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/internacional\/\">Internacional<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/fed-eua-mantem-juros-mais-cortes-cpf\/\"><h2 class=\"content__title\">Fed mant\u00e9m taxa b\u00e1sica de juros entre 5,25% a 5,50% e reitera chance de tr\u00eas cortes em 2024<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/camila-figueiredosuno-com-br\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/camila-paim-square-150x150.jpg\" alt=\"Camila Paim\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/camila-figueiredosuno-com-br\/\"><span itemprop=\"author\">Camila Paim<\/span><\/a><\/span><time datetime=\"2024-03-20T16:02:51-03:00\" itemprop=\"datePublished\">20\/03\/2024 16:02<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/535831"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=535831"}],"version-history":[{"count":2,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/535831\/revisions"}],"predecessor-version":[{"id":535893,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/535831\/revisions\/535893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/345798"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=535831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=535831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=535831"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=535831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}