{"id":519007,"date":"2024-02-01T12:22:45","date_gmt":"2024-02-01T15:22:45","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=519007"},"modified":"2024-02-01T17:52:35","modified_gmt":"2024-02-01T20:52:35","slug":"selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/","title":{"rendered":"V\u00eam quedas ainda mais fortes da Selic: taxa pode chegar a 8% no final do ano, diz UBS-BB; entenda o motivo"},"content":{"rendered":"<p>Em relat\u00f3rio logo ap\u00f3s a decis\u00e3o do <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/artigos\/copom\/\" target=\"_blank\" rel=\"noopener\">Comit\u00ea de Pol\u00edtica Monet\u00e1ria (Copom)<\/a> de reduzir a <a href=\"https:\/\/www.suno.com.br\/noticias\/copom-selic-economistas-juros-proximos-cortes-mal\/\">Taxa <strong>Selic<\/strong><\/a> em 0,50 ponto percentual (p.p.), analistas do UBS-BB estimam uma queda nos juros para al\u00e9m do que j\u00e1 vinha sendo projetado pelo mercado. <\/p><div class=\"videoFull \">\n\t\t\t<div class=\"videoWrapper yt-lazyload center\"\n\t\t\t\tdata-width=\"960\"\n\t\t\t\tdata-height=\"540\"\n\t\t\t\tdata-id=\"8oXPzF5-GM0\"\n\t\t\t\tdata-alt=\"V\u00eddeo do YouTube - clique para reproduzir\"\n\t\t\t\tdata-logo=\"3\"\n\t\t\t\tdata-imagequality=\"maxres\">\n\t\t\t<\/div>\n\t\t<\/div><script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"VideoObject\",\"name\":\"\ud83d\udd34COPOM CORTA SELIC EM 0,50 | Ibovespa sobe | Santander (SANB11) derrete com 4T23\",\"description\":\"#mercadofinanceiro #a\u00e7\u00f5es #investimentos #bolsadevalores #ibovespa #dinheiro #finan\u00e7as #pol\u00edtica #d\u00f3lar #livedas19h #petr4 #petr3 #petrobras #vale3 #vale #a\u00e7\u00f5es #economia #dividendos #copom #bancocentral #bc #selic #juros #taxadejuros #taxaselic #fed #federalreserve #pol\u00edticamonet\u00e1ria #macroeconomia 00:00 In\u00edcio do v\u00eddeo 01:35 Fechamento de preg\u00e3o 05:05 Fed mant\u00e9m juros 06:49 Copom corta Selic 17:55 4T23 do Santander decepciona 22:23 Fus\u00e3o entre Soma e\u2026\",\"duration\":\"PT27M44S\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/8oXPzF5-GM0\",\"regionsAllowed\":\"en-US\",\"interactionStatistic\":{\"@type\":\"InteractionCounter\",\"interactionType\":{\"@type\":\"WatchAction\"},\"userInteractionCount\":1748},\"thumbnailUrl\":\"https:\/\/i.ytimg.com\/vi\/8oXPzF5-GM0\/default.jpg\",\"uploadDate\":\"2024-01-31T22:42:03Z\"}<\/script>\n\n\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"240038\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n\n\n<p>De acordo com a casa, o comit\u00ea deve reduzir a taxa em 50 pontos-base mais duas vezes. J\u00e1 na reuni\u00e3o de junho, o <strong>corte na Selic <\/strong>deve ser de 75 pontos-base.<\/p>\n\n\n\n<p>Ainda segundo as proje\u00e7\u00f5es do UBS, a <strong>taxa terminal<\/strong>, ou seja, o patamar no qual o Copom cessar\u00e1 o ciclo de cortes, ser\u00e1 de 8%. Esse n\u00famero deve ser alcan\u00e7ado j\u00e1 em novembro, diz o relat\u00f3rio. E \u00e9 menor que o mercado espera: as proje\u00e7\u00f5es das maioria das casas ficam em torno de 9 a 10%. <\/p>\n\n\n\n<p>O Boletim Focus da \u00faltima ter\u00e7a (30) tamb\u00e9m tem essa estimativa. Segundo&nbsp;o <strong>Banco Central<\/strong>&nbsp;(BC), a <strong>taxa de juros<\/strong>, a Selic, continua em 9% ao final deste ano. De acordo com a pesquisa, para 2025, o mercado espera que a&nbsp;taxa de juros&nbsp;termine em 8,50%, mesma proje\u00e7\u00e3o da semana anterior. <\/p>\n\n\n\n<p>Mas por que o UBS-BB tem uma proje\u00e7\u00e3o de queda maior da Selic ainda em 2024? O relat\u00f3rio do banco su\u00ed\u00e7o prev\u00ea uma queda maior da infla\u00e7\u00e3o este ano &#8211; o que poderia fazer com que o Copom acelerasse os cortes.<\/p>\n\n\n\n<p>&#8220;Esperamos mais dois cortes de 50 pontos base antes de uma acelera\u00e7\u00e3o no ritmo de flexibiliza\u00e7\u00e3o de 75 pb na reuni\u00e3o de junho. A acelera\u00e7\u00e3o acontece em fun\u00e7\u00e3o de dois principais fatores: 1) continuamos 80 pontos base abaixo do consenso em nossa previs\u00e3o de infla\u00e7\u00e3o para 2024 e esperamos que a parte significativa desta surpresa descendente da infla\u00e7\u00e3o aconte\u00e7a no segundo trimestre&#8221;, explicam os analistas do UBS-BB.<\/p>\n\n\n\n<p>Isso levaria o Copom a come\u00e7ar seu ciclo de flexibiliza\u00e7\u00e3o antes de junho. Por isso o UBS-BB prev\u00ea, nas reuni\u00f5es do comit\u00ea do BC, mais dois cortes de 75 pontos-base em junho e julho.<\/p>\n\n\n\n<p>&#8220;Em \u00faltima an\u00e1lise, nosso cen\u00e1rio \u00e9 que a taxa Selic chegue a 8% at\u00e9 novembro. O consenso do mercado tem uma expectativa 1ppt maior para a taxa Selic no final do ano, mas a expectativa da maioria dos analistas \u00e9 por uma infla\u00e7\u00e3o 0,8 pp maior em rela\u00e7\u00e3o ao nosso cen\u00e1rio, que prev\u00ea 3% no IPCA para 2024&#8221;, explica o UBS.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Copom desta quarta (31): sem novidades, segundo o UBS-BB<\/h2>\n\n\n\n<p>J\u00e1 em rela\u00e7\u00e3o \u00e0 decis\u00e3o do <strong>Copom<\/strong> da quarta (31), o UBS diz n\u00e3o enxergar grandes novidades.<\/p>\n\n\n\n<p>&#8220;Isto [corte de 50bps] j\u00e1 era esperado pelos mercados, pelo consenso e pelo UBS. A decis\u00e3o foi un\u00e2nime e houve pequenas altera\u00e7\u00f5es na comunica\u00e7\u00e3o&#8221;, diz.<\/p>\n\n\n\n<p>Segundo os especialistas da casa, a \u00fanica mudan\u00e7a relevante no comunicado foi quando o <strong>Banco Central (BC)<\/strong> falou sobre o cen\u00e1rio internacional <\/p>\n\n\n\n<p>&#8220;A \u00fanica mudan\u00e7a na comunica\u00e7\u00e3o ocorreu na se\u00e7\u00e3o internacional. O comit\u00ea destacou agora o debate sobre o in\u00edcio do ciclo de flexibiliza\u00e7\u00e3o em principais economias e que os sinais de infla\u00e7\u00e3o subjacente mais baixa j\u00e1 n\u00e3o s\u00e3o &#8216;incipientes'&#8221;, disse o UBS-BB.<\/p>\n\n\n\n<p>Al\u00e9m disso, os analistas destacam que no cen\u00e1rio dom\u00e9stico e nas proje\u00e7\u00f5es de infla\u00e7\u00e3o global o Copom manteve a proje\u00e7\u00e3o para a infla\u00e7\u00e3o de 2024 em 3,5% e para 2025 em 3,2%. <\/p>\n\n\n\n<p>Em seu parecer, o UBS-BB lembra ainda que continua com os 80 pontos base abaixo do consenso em sua previs\u00e3o de infla\u00e7\u00e3o para 2024 e espera que a parte significativa desta surpresa de desacelera\u00e7\u00e3o da infla\u00e7\u00e3o aconte\u00e7a no segundo trimestre.<\/p>\n\n\n\n<p>Al\u00e9m disso, o UBS-BB espera que o comit\u00ea de <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/politica-monetaria\/\" rel=\"noopener\">pol\u00edtica monet\u00e1ria<\/a> do Federal Reserve (Fed) &#8211; o FOMC &#8211; inicie seu ciclo de flexibiliza\u00e7\u00e3o antes de junho.<\/p>\n\n\n\n<p>&#8220;A combina\u00e7\u00e3o destes dois fatores nos levou a continuar a prever dois cortes de 75 pontos-base em junho e julho&#8221;, conclui a casa.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-gratuito-investindo-no-exterior\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Investindo-no-exterior.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Investindo-no-exterior.png\"\n\t\t\t\t\tdata-promo-id=\"383161\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Investindo-no-exterior.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Veja o que o Copom disse ap\u00f3s o corte na Selic<\/h2>\n\n\n\n<p>O Copom divulgou nesta quarta (31) o quinto corte seguido da Selic. Com o corte de 0,5 p.p divulgado hoje, a <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/taxa-de-juros\/\" target=\"_blank\" rel=\"noopener\">taxa b\u00e1sica de juros<\/a> foi reduzida para 11,25% na primeira reuni\u00e3o do ano do comit\u00ea do BC. <\/p>\n\n\n\n<p>A redu\u00e7\u00e3o dos juros era aguardada pelo mercado. A decis\u00e3o foi un\u00e2nime.<\/p>\n\n\n\n<p>Os <strong>dirigentes do Copom <\/strong>preveem corte da mesma magnitude nas pr\u00f3ximas reuni\u00f5es do Comit\u00ea.  <\/p>\n\n\n\n<p>&#8220;Em se confirmando o cen\u00e1rio esperado, os membros do Comit\u00ea, unanimemente, anteveem redu\u00e7\u00e3o de mesma magnitude nas pr\u00f3ximas reuni\u00f5es e avaliam que esse \u00e9 o ritmo apropriado para manter a <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/politica-monetaria-contracionista\/\" rel=\"noopener\">pol\u00edtica monet\u00e1ria contracionista<\/a> necess\u00e1ria para o processo desinflacion\u00e1ria&#8221;, diz o <strong>comunicado do Copom<\/strong>.<\/p>\n\n\n\n<p>O texto que acompanha a<strong> decis\u00e3o do Copom <\/strong>sobre a Selic acrescenta: &#8220;O ritmo [dos cortes] \u00e9 apropriado para manter pol\u00edtica contracionista necess\u00e1ria para desinfla\u00e7\u00e3o. Magnitude total do ciclo depende, em especial, de itens mais sens\u00edveis \u00e0 Selic e atividade.&#8221;<\/p>\n\n\n\n<p>O comit\u00ea fala sobre o cen\u00e1rio dom\u00e9stico: &#8220;O conjunto dos <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/indicadores-de-atividade\/\" rel=\"noopener\">indicadores de atividade<\/a> econ\u00f4mica segue consistente com o cen\u00e1rio de desacelera\u00e7\u00e3o da economia antecipado pelo Copom. A infla\u00e7\u00e3o cheia ao consumidor, conforme esperado, manteve trajet\u00f3ria de desinfla\u00e7\u00e3o, assim como as medidas de infla\u00e7\u00e3o subjacente, que se aproximam da meta para a infla\u00e7\u00e3o nas divulga\u00e7\u00f5es mais recentes.&#8221;<\/p>\n\n\n\n<p>A <strong>expectativa de infla\u00e7\u00e3o<\/strong> do Boletim Focus deste ano variou para baixo entre os dois encontros do Comit\u00ea, mas as estimativas de prazos mais longos seguiram desancoradas. A mediana para a infla\u00e7\u00e3o de 2024 passou de 3,93% no \u00faltimo Copom, em meados de dezembro, para 3,81% na \u00faltima divulga\u00e7\u00e3o, ontem. J\u00e1 para 2025 e 2026, as estimativas ficaram estacionadas em 3,50%, tamb\u00e9m acima da meta cont\u00ednua de 3,00%.<\/p>\n\n\n\n<p>Conforme pesquisa do Proje\u00e7\u00f5es Broadcast, 63 de 64 <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/instituicoes-financeiras\/\" rel=\"noopener\">institui\u00e7\u00f5es financeiras<\/a> consultadas acreditavam que o BC manteria o plano de voo e faria mais um <strong>corte na Selic<\/strong> de 0,50 ponto, para 11,25%, enquanto uma casa apostava em um corte mais agressivo para 11% ao ano. Para 56 entre 60 (93%), o colegiado seguir\u00e1 nesse ritmo tamb\u00e9m nas reuni\u00f5es de mar\u00e7o e maio.<\/p>\n\n\n\n<p>No encontro de dezembro, o BC repetiu no comunicado sobre a <strong>decis\u00e3o do Copom<\/strong> que antevia redu\u00e7\u00e3o de 0,50 ponto porcentual da <strong>taxa Selic<\/strong> nas pr\u00f3ximas reuni\u00f5es e que seria o ritmo apropriado para &#8220;manter a <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/politica-monetaria-contracionista\/\" rel=\"noopener\">pol\u00edtica monet\u00e1ria contracionista<\/a> necess\u00e1ria para o processo desinflacion\u00e1rio&#8221;.<\/p>\n\n\n\n<p>Segundo o Copom, o corte de 0,5 pp \u00e9 compat\u00edvel com converg\u00eancia para redor da meta ao longo do horizonte relevante. &#8220;A pol\u00edtica contracionista \u00e9 necess\u00e1ria para consolidar desinfla\u00e7\u00e3o e ancoragem em torno de metas. O horizonte relevante inclui 2024 e, em maior&nbsp;grau,&nbsp;2025.&#8221;<\/p>\n\n\n\n<p>O comunicado do BC ap\u00f3s a decis\u00e3o de corte da <strong>Selic<\/strong> ainda diz que &#8220;os bancos centrais das principais economias permanecem determinados em promover a converg\u00eancia das taxas de infla\u00e7\u00e3o para suas metas em um ambiente marcado por press\u00f5es nos mercados de trabalho. O Comit\u00ea avalia que o cen\u00e1rio segue exigindo cautela por parte de <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/artigos\/paises-emergentes\/\" rel=\"noopener\">pa\u00edses emergentes<\/a>.&#8221;<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"383123\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Em relat\u00f3rio logo ap\u00f3s a decis\u00e3o do Comit\u00ea de Pol\u00edtica Monet\u00e1ria (Copom) de reduzir a Taxa Selic em 0,50 ponto percentual (p.p.), analistas do UBS-BB estimam uma queda nos juros para al\u00e9m do que j\u00e1 vinha sendo projetado pelo mercado. De acordo com a casa, o comit\u00ea deve reduzir a taxa em 50 pontos-base mais [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":330794,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[62],"tags":[1842,105816,1752,290],"suno_strategy":[],"class_list":["post-519007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-banco-central-bc","tag-especialistas","tag-taxa-de-juros","tag-taxa-selic"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Selic pode cair mais e chegar a 8% ao final do ano, diz UBS-BB<\/title>\n<meta name=\"description\" content=\"Os especialistas destacam que o cen\u00e1rio base estima uma acelera\u00e7\u00e3o para um corte na Selic de 75 pontos base na reuni\u00e3o de junho\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Selic pode cair mais e chegar a 8% ao final do ano, diz UBS-BB\" \/>\n<meta property=\"og:description\" content=\"Os especialistas destacam que o cen\u00e1rio base estima uma acelera\u00e7\u00e3o para um corte na Selic de 75 pontos base na reuni\u00e3o de junho\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/Banco-Central.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"808\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Vargas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Vargas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/\"},\"author\":{\"name\":\"Eduardo Vargas\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5\"},\"headline\":\"V\u00eam quedas ainda mais fortes da Selic: taxa pode chegar a 8% no final do ano, diz UBS-BB; entenda o motivo\",\"datePublished\":\"2024-02-01T15:22:45+00:00\",\"dateModified\":\"2024-02-01T20:52:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/\"},\"wordCount\":1217,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/Banco-Central.jpg\",\"keywords\":[\"Banco Central (BC)\",\"Especialistas\",\"taxa de juros\",\"Taxa Selic\"],\"articleSection\":[\"Economia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/\",\"name\":\"Selic pode cair mais e chegar a 8% ao final do ano, diz UBS-BB\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/Banco-Central.jpg\",\"datePublished\":\"2024-02-01T15:22:45+00:00\",\"dateModified\":\"2024-02-01T20:52:35+00:00\",\"description\":\"Os especialistas destacam que o cen\u00e1rio base estima uma acelera\u00e7\u00e3o para um corte na Selic de 75 pontos base na reuni\u00e3o de junho\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/Banco-Central.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/Banco-Central.jpg\",\"width\":1350,\"height\":808,\"caption\":\"Copom: pr\u00e9dio do Banco Central. Foto Antonio Cruz\/Ag\u00eancia Brasil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Economia\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/economia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"V\u00eam quedas ainda mais fortes da Selic: taxa pode chegar a 8% no final do ano, diz UBS-BB; entenda o motivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5\",\"name\":\"Eduardo Vargas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g\",\"caption\":\"Eduardo Vargas\"},\"description\":\"Jornalista formado pela UFSC, cobre macroeconomia, neg\u00f3cios e startups para o Suno Not\u00edcias, escrevendo principalmente not\u00edcias sobre o mercado financeiro e a bolsa de valores. No YouTube e no Instagram, \u00e9 respons\u00e1vel pela produ\u00e7\u00e3o de Reels e Shorts do Suno Not\u00edcias. Anteriormente, trabalhou cobrindo economia e cotidiano no ND+ e para o ND, maior jornal impresso de Santa Catarina. Cursou um semestre letivo de Estudos de M\u00eddia na Universidad de Buenos Aires.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Selic pode cair mais e chegar a 8% ao final do ano, diz UBS-BB","description":"Os especialistas destacam que o cen\u00e1rio base estima uma acelera\u00e7\u00e3o para um corte na Selic de 75 pontos base na reuni\u00e3o de junho","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/","og_locale":"pt_BR","og_type":"article","og_title":"Selic pode cair mais e chegar a 8% ao final do ano, diz UBS-BB","og_description":"Os especialistas destacam que o cen\u00e1rio base estima uma acelera\u00e7\u00e3o para um corte na Selic de 75 pontos base na reuni\u00e3o de junho","og_url":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1350,"height":808,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/Banco-Central.jpg","type":"image\/jpeg"}],"author":"Eduardo Vargas","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Eduardo Vargas","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/"},"author":{"name":"Eduardo Vargas","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5"},"headline":"V\u00eam quedas ainda mais fortes da Selic: taxa pode chegar a 8% no final do ano, diz UBS-BB; entenda o motivo","datePublished":"2024-02-01T15:22:45+00:00","dateModified":"2024-02-01T20:52:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/"},"wordCount":1217,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/Banco-Central.jpg","keywords":["Banco Central (BC)","Especialistas","taxa de juros","Taxa Selic"],"articleSection":["Economia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/","url":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/","name":"Selic pode cair mais e chegar a 8% ao final do ano, diz UBS-BB","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/Banco-Central.jpg","datePublished":"2024-02-01T15:22:45+00:00","dateModified":"2024-02-01T20:52:35+00:00","description":"Os especialistas destacam que o cen\u00e1rio base estima uma acelera\u00e7\u00e3o para um corte na Selic de 75 pontos base na reuni\u00e3o de junho","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/Banco-Central.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/Banco-Central.jpg","width":1350,"height":808,"caption":"Copom: pr\u00e9dio do Banco Central. Foto Antonio Cruz\/Ag\u00eancia Brasil"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Economia","item":"https:\/\/www.suno.com.br\/noticias\/economia\/"},{"@type":"ListItem","position":3,"name":"V\u00eam quedas ainda mais fortes da Selic: taxa pode chegar a 8% no final do ano, diz UBS-BB; entenda o motivo"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5","name":"Eduardo Vargas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g","caption":"Eduardo Vargas"},"description":"Jornalista formado pela UFSC, cobre macroeconomia, neg\u00f3cios e startups para o Suno Not\u00edcias, escrevendo principalmente not\u00edcias sobre o mercado financeiro e a bolsa de valores. No YouTube e no Instagram, \u00e9 respons\u00e1vel pela produ\u00e7\u00e3o de Reels e Shorts do Suno Not\u00edcias. Anteriormente, trabalhou cobrindo economia e cotidiano no ND+ e para o ND, maior jornal impresso de Santa Catarina. Cursou um semestre letivo de Estudos de M\u00eddia na Universidad de Buenos Aires.","url":"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/Banco-Central-400x200.jpg\" alt=\"V\u00eam quedas ainda mais fortes da Selic: taxa pode chegar a 8% no final do ano, diz UBS-BB; entenda o motivo\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/economia\/\">Economia<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/selic-cortes-copom-2024-bc-flexibilizacao-ubs-bb-evm\/\"><h2 class=\"content__title\">V\u00eam quedas ainda mais fortes da Selic: taxa pode chegar a 8% no final do ano, diz UBS-BB; entenda o motivo<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&#038;r=g\" alt=\"Eduardo Vargas\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\"><span itemprop=\"author\">Eduardo Vargas<\/span><\/a><\/span><time datetime=\"2024-02-01T12:22:45-03:00\" itemprop=\"datePublished\">01\/02\/2024 12:22<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/519007"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=519007"}],"version-history":[{"count":2,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/519007\/revisions"}],"predecessor-version":[{"id":519157,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/519007\/revisions\/519157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/330794"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=519007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=519007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=519007"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=519007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}