{"id":495230,"date":"2023-12-05T07:40:20","date_gmt":"2023-12-05T10:40:20","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=495230"},"modified":"2023-12-05T07:45:54","modified_gmt":"2023-12-05T10:45:54","slug":"braskem-brkm5-maceio-gpj-2","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/","title":{"rendered":"Braskem (BRKM5) cancela participa\u00e7\u00e3o na COP28 e cita &#8216;agravamento&#8217; da crise de Macei\u00f3"},"content":{"rendered":"<p>A <strong>Braskem\u00a0<\/strong>(<a href=\"https:\/\/www.suno.com.br\/acoes\/brkm5\/\">BRKM5<\/a>) cancelou sua participa\u00e7\u00e3o na Confer\u00eancia das Na\u00e7\u00f5es Unidas sobre Mudan\u00e7as Clim\u00e1ticas (COP28), em Dubai, nos Emirados \u00c1rabes Unidos. <\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1-800x450.webp\" width=\"800\" height=\"450\" alt=\"Braskem (BRKM5) cancela participa\u00e7\u00e3o na COP28 e cita &#8216;agravamento&#8217; da crise de Macei\u00f3\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Braskem (BRKM5). Foto: Reprodu\u00e7\u00e3o Instagram<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>Em nota, a Braskem citou que o cancelamento se deve ao &#8220;agravamento da <strong>crise em Macei\u00f3<\/strong>&#8220;, onde a petroqu\u00edmica enfrenta o risco de colapso em uma de suas minas de extra\u00e7\u00e3o de <strong>sal-gema<\/strong>.<\/p>\n\n\n\n<p>\u201cNos \u00faltimos dias, diante do agravamento da <strong>crise de Macei\u00f3<\/strong>, a Braskem achou melhor cancelar sua participa\u00e7\u00e3o para evitar que o assunto sobrepujasse quaisquer outras discuss\u00f5es t\u00e9cnicas, dificultando eventuais contribui\u00e7\u00f5es que a empresa pudesse oferecer\u201d, explicou a empresa&#8221;, diz o texto.<\/p>\n\n\n\n<p>Ainda de acordo com o comunicado sobre a ida \u00e0 <strong>COP28<\/strong>, a Braskem informou que \u201cest\u00e1 acompanhando a COP e todas as discuss\u00f5es sobre mudan\u00e7as clim\u00e1ticas, uma vez que tem metas de redu\u00e7\u00e3o de emiss\u00f5es de gases de efeito estufa e de crescimento com produtos mais sustent\u00e1veis, entre eles bioprodutos e produtos com conte\u00fado reciclado\u201d.<\/p>\n\n\n\n<p>A agenda inicial da <strong>Braskem na COP28<\/strong> previa a participa\u00e7\u00e3o de diretores da petroqu\u00edmica em dois pain\u00e9is, entre os dias 8 e 11 de dezembro.\u00a0<\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-mina-gpj\/\">\n\t\t\tBraskem (BRKM5): conclus\u00e3o de fechamento definitivo de cavidades est\u00e1 previsto para 2025\t\t<\/a>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Defesa Civil registra leve acelera\u00e7\u00e3o na movimenta\u00e7\u00e3o do solo em mina da Braskem<\/h2>\n\n\n\n<p>A Defesa Civil de Macei\u00f3 divulgou nota na noite desta segunda-feira (4) informando que houve leve acelera\u00e7\u00e3o na velocidade vertical de afundamento do solo acima da <strong>mina 18 da Braskem<\/strong>.<\/p>\n\n\n\n<p>O deslocamento vertical acumulado da <strong>mina da Braskem<\/strong> n\u00b0 18 \u00e9 de 1,80m e a velocidade vertical \u00e9 de 0,26 cm por hora, apresentando um movimento de 6,3 cm nas \u00faltimas 24 horas.<\/p>\n\n\n\n<p>No boletim divulgado ainda pela manh\u00e3 pela <strong>Defesa Civil de Macei\u00f3<\/strong>, a velocidade vertical era de 0,25 cm por hora. A mina n\u00b0 18 est\u00e1 localizada na regi\u00e3o do antigo campo do Centro Sportivo Alagoano (CSA), no Mutange. Ainda existe risco iminente de <strong>colapso em Macei\u00f3<\/strong>.<\/p>\n\n\n\n<p>Assim, o \u00f3rg\u00e3o mant\u00e9m o alerta m\u00e1ximo para a <strong>mina de sal-gema da Braskem<\/strong>. \u201cPor precau\u00e7\u00e3o, a recomenda\u00e7\u00e3o \u00e9 clara: a popula\u00e7\u00e3o n\u00e3o deve transitar na \u00e1rea desocupada at\u00e9 uma nova atualiza\u00e7\u00e3o da Defesa Civil, enquanto medidas de controle e monitoramento s\u00e3o aplicadas para reduzir o perigo\u201d.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Braskem (BRKM5) tenta atenuar preocupa\u00e7\u00f5es sobre Macei\u00f3 e diz que \u201csolo vem se acomodando\u201d<\/h2>\n\n\n\n<p>Na segunda-feira (4), o <strong>presidente da Braskem<\/strong>, <strong>Roberto Bischoff<\/strong>, afirmou que a petroqu\u00edmica tem feito esfor\u00e7os consistentes para minimizar os impactos ambientais provocados pelo<strong> afundamento do solo em Macei\u00f3<\/strong> (AL).<\/p>\n\n\n\n<p>Em situa\u00e7\u00e3o de emerg\u00eancia desde a \u00faltima quarta-feira (29), a cidade de Macei\u00f3 vive um clima de espera, afli\u00e7\u00e3o e revolta por causa da possibilidade de colapso de uma mina de sal-gema da\u00a0<strong>petroqu\u00edmica Braskem<\/strong>, no bairro do Mutange. \u00c9 mais um cap\u00edtulo de uma hist\u00f3ria que se arrasta desde 2018, quando foram registrados afundamentos em cinco bairros. Estima-se que cerca de 60 mil residentes tiveram que se mudar do local e deixar para tr\u00e1s os seus im\u00f3veis.<\/p>\n\n\n\n<p>Roberto Bischoff,<strong>\u00a0CEO da Braskem<\/strong>, disse que a empresa identificou a acelera\u00e7\u00e3o da instabilidade na regi\u00e3o em novembro, a partir de um relat\u00f3rio interno. Em seguida, compartilhou informa\u00e7\u00f5es com as autoridades.<\/p>\n\n\n\n<p>\u201cPercebemos a partir de um monitoramento que realizamos uma mudan\u00e7a no comportamento do solo e imediatamente informamos \u00e0s autoridades. O bairro j\u00e1 estava desocupado, quem estava na regi\u00e3o eram apenas as equipes da Braskem e 23 fam\u00edlias resistentes que n\u00e3o haviam deixado o local, mas foram retiradas ap\u00f3s ordem judicial\u201d, afirmou Bischoff durante o 28\u00ba Encontro Anual da Ind\u00fastria Qu\u00edmica (Enaiq), evento tradicional do setor qu\u00edmico promovido pela Associa\u00e7\u00e3o Brasileira de Ind\u00fastrias Qu\u00edmica (Abiquim).<\/p>\n\n\n\n<p>O executivo afirmou que decidiu falar sobre a <strong>crise em Macei\u00f3<\/strong>\u00a0durante a realiza\u00e7\u00e3o do evento em fun\u00e7\u00e3o de, segundo ele, haver uma grande quantidade de informa\u00e7\u00f5es veiculadas nas redes sociais e que \u201cn\u00e3o necessariamente s\u00e3o precisas\u201d. Completou: \u201cTemos bons indicativos de que o solo vem se acomodando.\u201d<\/p>\n\n\n\n<p>Bischoff disse ainda que nos \u00faltimos quatro anos foram realocadas 40 mil pessoas em 14,5 mil im\u00f3veis e mais de 97% das propostas de indeniza\u00e7\u00e3o foram aceitas e pagas por meio do Programa de Compensa\u00e7\u00e3o Financeira (PCF).<\/p>\n\n\n\n<p><em>*Com informa\u00e7\u00f5es de Ag\u00eancia Brasil<\/em><\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"383123\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>A Braskem\u00a0(BRKM5) cancelou sua participa\u00e7\u00e3o na Confer\u00eancia das Na\u00e7\u00f5es Unidas sobre Mudan\u00e7as Clim\u00e1ticas (COP28), em Dubai, nos Emirados \u00c1rabes Unidos. Braskem (BRKM5). Foto: Reprodu\u00e7\u00e3o Instagram Em nota, a Braskem citou que o cancelamento se deve ao &#8220;agravamento da crise em Macei\u00f3&#8220;, onde a petroqu\u00edmica enfrenta o risco de colapso em uma de suas minas de [&hellip;]<\/p>\n","protected":false},"author":313,"featured_media":139982,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[395],"suno_strategy":[],"class_list":["post-495230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-braskem-brkm3-brkm5-brkm6"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Braskem cancela ida \u00e0 COP28 e cita &#039;agravamento&#039; da crise de Macei\u00f3<\/title>\n<meta name=\"description\" content=\"Em nota, a Braskem citou que o cancelamento da participa\u00e7\u00e3o na COP28 se deve ao &quot;agravamento da crise em Macei\u00f3&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Braskem cancela ida \u00e0 COP28 e cita &#039;agravamento&#039; da crise de Macei\u00f3\" \/>\n<meta property=\"og:description\" content=\"Em nota, a Braskem citou que o cancelamento da participa\u00e7\u00e3o na COP28 se deve ao &quot;agravamento da crise em Macei\u00f3&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"786\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanni Porf\u00edrio Jacomino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Porf\u00edrio Jacomino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/\"},\"author\":{\"name\":\"Giovanni Porf\u00edrio Jacomino\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40\"},\"headline\":\"Braskem (BRKM5) cancela participa\u00e7\u00e3o na COP28 e cita &#8216;agravamento&#8217; da crise de Macei\u00f3\",\"datePublished\":\"2023-12-05T10:40:20+00:00\",\"dateModified\":\"2023-12-05T10:45:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/\"},\"wordCount\":730,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1-jpg.webp\",\"keywords\":[\"Braskem (BRKM3\/BRKM5\/BRKM6)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/\",\"name\":\"Braskem cancela ida \u00e0 COP28 e cita 'agravamento' da crise de Macei\u00f3\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1-jpg.webp\",\"datePublished\":\"2023-12-05T10:40:20+00:00\",\"dateModified\":\"2023-12-05T10:45:54+00:00\",\"description\":\"Em nota, a Braskem citou que o cancelamento da participa\u00e7\u00e3o na COP28 se deve ao \\\"agravamento da crise em Macei\u00f3\\\".\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1-jpg.webp\",\"width\":1200,\"height\":786,\"caption\":\"Braskem (BRKM5). Foto: Reprodu\u00e7\u00e3o Instagram\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Braskem (BRKM5) cancela participa\u00e7\u00e3o na COP28 e cita &#8216;agravamento&#8217; da crise de Macei\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40\",\"name\":\"Giovanni Porf\u00edrio Jacomino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g\",\"caption\":\"Giovanni Porf\u00edrio Jacomino\"},\"description\":\"Giovanni Porf\u00edrio Jacomino \u00e9 jornalista formado pela Universidade Estadual de Londrina (UEL) e p\u00f3s-graduado em Produ\u00e7\u00e3o e Pr\u00e1ticas Jornal\u00edsticas na Contemporaneidade na Faculdade C\u00e1sper L\u00edbero (FCL). Foi editor web no Startupi e no Finsiders, atuando ainda como editor no TC Mover, portal de not\u00edcias da TradersClub, fazendo a cobertura de assuntos relacionados ao mercado financeiro interno e externo. Atualmente, \u00e9 Rep\u00f3rter do Suno Not\u00edcias.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Braskem cancela ida \u00e0 COP28 e cita 'agravamento' da crise de Macei\u00f3","description":"Em nota, a Braskem citou que o cancelamento da participa\u00e7\u00e3o na COP28 se deve ao \"agravamento da crise em Macei\u00f3\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Braskem cancela ida \u00e0 COP28 e cita 'agravamento' da crise de Macei\u00f3","og_description":"Em nota, a Braskem citou que o cancelamento da participa\u00e7\u00e3o na COP28 se deve ao \"agravamento da crise em Macei\u00f3\".","og_url":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1200,"height":786,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1.jpg","type":"image\/jpeg"}],"author":"Giovanni Porf\u00edrio Jacomino","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Giovanni Porf\u00edrio Jacomino","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/"},"author":{"name":"Giovanni Porf\u00edrio Jacomino","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40"},"headline":"Braskem (BRKM5) cancela participa\u00e7\u00e3o na COP28 e cita &#8216;agravamento&#8217; da crise de Macei\u00f3","datePublished":"2023-12-05T10:40:20+00:00","dateModified":"2023-12-05T10:45:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/"},"wordCount":730,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1-jpg.webp","keywords":["Braskem (BRKM3\/BRKM5\/BRKM6)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/","url":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/","name":"Braskem cancela ida \u00e0 COP28 e cita 'agravamento' da crise de Macei\u00f3","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1-jpg.webp","datePublished":"2023-12-05T10:40:20+00:00","dateModified":"2023-12-05T10:45:54+00:00","description":"Em nota, a Braskem citou que o cancelamento da participa\u00e7\u00e3o na COP28 se deve ao \"agravamento da crise em Macei\u00f3\".","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1-jpg.webp","width":1200,"height":786,"caption":"Braskem (BRKM5). Foto: Reprodu\u00e7\u00e3o Instagram"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Braskem (BRKM5) cancela participa\u00e7\u00e3o na COP28 e cita &#8216;agravamento&#8217; da crise de Macei\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40","name":"Giovanni Porf\u00edrio Jacomino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g","caption":"Giovanni Porf\u00edrio Jacomino"},"description":"Giovanni Porf\u00edrio Jacomino \u00e9 jornalista formado pela Universidade Estadual de Londrina (UEL) e p\u00f3s-graduado em Produ\u00e7\u00e3o e Pr\u00e1ticas Jornal\u00edsticas na Contemporaneidade na Faculdade C\u00e1sper L\u00edbero (FCL). Foi editor web no Startupi e no Finsiders, atuando ainda como editor no TC Mover, portal de not\u00edcias da TradersClub, fazendo a cobertura de assuntos relacionados ao mercado financeiro interno e externo. Atualmente, \u00e9 Rep\u00f3rter do Suno Not\u00edcias.","url":"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/04\/91b37d54-whatsapp-image-2021-04-15-at-19.53.57-1-400x200.webp\" alt=\"Braskem (BRKM5) cancela participa\u00e7\u00e3o na COP28 e cita &#8216;agravamento&#8217; da crise de Macei\u00f3\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/braskem-brkm5-maceio-gpj-2\/\"><h2 class=\"content__title\">Braskem (BRKM5) cancela participa\u00e7\u00e3o na COP28 e cita &#8216;agravamento&#8217; da crise de Macei\u00f3<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/DSCF4115-1-1-150x150.webp\" alt=\"Giovanni Porf\u00edrio Jacomino\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/\"><span itemprop=\"author\">Giovanni Porf\u00edrio Jacomino<\/span><\/a><\/span><time datetime=\"2023-12-05T07:40:20-03:00\" itemprop=\"datePublished\">05\/12\/2023 07:40<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/495230"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/313"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=495230"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/495230\/revisions"}],"predecessor-version":[{"id":495254,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/495230\/revisions\/495254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/139982"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=495230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=495230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=495230"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=495230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}