{"id":482458,"date":"2023-11-08T09:40:27","date_gmt":"2023-11-08T12:40:27","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=482458"},"modified":"2023-11-08T16:28:14","modified_gmt":"2023-11-08T19:28:14","slug":"casas-bahia-bhia3-fidc-gpj","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/","title":{"rendered":"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em primeira etapa de FIDC; saiba mais"},"content":{"rendered":"<p>Em <a href=\"https:\/\/www.suno.com.br\/artigos\/fato-relevante\/\">fato relevante<\/a> divulgado na manh\u00e3 desta quarta-feira (8), a <strong>Casas Bahia<\/strong> (BHIA3) informou que a estrutura\u00e7\u00e3o do fundo de investimento em direitos credit\u00f3rios (FIDC), com o objetivo de otimizar a opera\u00e7\u00e3o de credi\u00e1rio da companhia, buscar\u00e1 uma capta\u00e7\u00e3o inicial de R$ 600 milh\u00f5es.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em primeira etapa de FIDC; saiba mais\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Casas Bahia (BHIA3). Foto: Reprodu\u00e7\u00e3o\/ Via<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"250707\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>Segundo a companhia, a estrutura\u00e7\u00e3o do FIDC, que est\u00e1 sendo conduzida pela <strong>Pol\u00edgono Capital<\/strong> com administra\u00e7\u00e3o do <a href=\"https:\/\/www.suno.com.br\/acoes\/BPAC11\/\"><strong>BTG Pactual <\/strong>(BPAC11)<\/a>, est\u00e1 em fase pr\u00e9-operacional. Ap\u00f3s a primeira capta\u00e7\u00e3o, o <strong>FIDC da Casas Bahia<\/strong> poder\u00e1 contar com aportes adicionais chegando at\u00e9 um capital total de R$ 1,5 bilh\u00e3o.<\/p>\n\n\n\n<p>A Casas Bahia informou tamb\u00e9m que nesta ter\u00e7a-feira (8) foi protocolada na Comiss\u00e3o de Valores Mobili\u00e1rios (CVM) a altera\u00e7\u00e3o do regulamento do FIDC, que passar\u00e1 a ser denominado \u201cGrupo Casas Bahia Fundo de Investimento em Direito Credit\u00f3rios\u201d e cuja classe \u00fanica contar\u00e1 com cotas seniores, cotas subordinadas mezanino e cotas subordinadas j\u00fanior.<\/p>\n\n\n\n<p>&#8220;A efetiva estrutura\u00e7\u00e3o do FIDC, bem como a defini\u00e7\u00e3o de seus termos e condi\u00e7\u00f5es, est\u00e1 sujeita, entre outros fatores, \u00e0 obten\u00e7\u00e3o das aprova\u00e7\u00f5es necess\u00e1rias, incluindo as respectivas aprova\u00e7\u00f5es societ\u00e1rias aplic\u00e1veis, bem como \u00e0s condi\u00e7\u00f5es pol\u00edticas e macroecon\u00f4mica nacionais e internacionais e ao interesse dos investidores, dentre outros fatores alheios \u00e0 vontade da companhia, e, portanto, nesta data, n\u00e3o est\u00e1 sendo realizada qualquer oferta p\u00fablica do FIDC e\/ou de quaisquer valores mobili\u00e1rios de emiss\u00e3o da companhia em qualquer jurisdi\u00e7\u00e3o&#8221;.<\/p>\n\n\n\n<p>A Casas Bahia informou ainda que, caso efetivada, a estrutura\u00e7\u00e3o do FIDC ser\u00e1 conduzida &#8220;em conformidade com a legisla\u00e7\u00e3o e regulamenta\u00e7\u00e3o aplic\u00e1veis&#8221;. <\/p>\n\n\n\n<p>&#8220;Este <a href=\"https:\/\/www.suno.com.br\/artigos\/fato-relevante\/\">fato relevante<\/a> n\u00e3o constitui uma oferta de venda de valores mobili\u00e1rios, no Brasil ou no exterior, incluindo nos Estados Unidos, ou em qualquer outra jurisdi\u00e7\u00e3o, e possui car\u00e1ter meramente informativo e n\u00e3o deve, em nenhuma circunst\u00e2ncia, ser considerado e\/ou interpretado como, nem constituir, uma recomenda\u00e7\u00e3o de investimento ou oferta de venda, solicita\u00e7\u00e3o ou oferta de compra de quaisquer valores mobili\u00e1rios&#8221;, informou a companhia.<\/p>\n\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"readToo\">\n\t\t\t\t<span class=\"readToo__title\">Leia mais<\/span>\n\t\t\t\t<ul class=\"readToo__list\">\n\t\t\t<li><a href=\"https:\/\/www.suno.com.br\/noticias\/mubadala-capital-controlada-aumenta-participacao-na-zamp-saiba-mais-gpj\/\">Mubadala Capital: controlada aumenta participa\u00e7\u00e3o na Zamp; saiba mais<\/a><\/li><li><a href=\"https:\/\/www.suno.com.br\/noticias\/agenda-dividendos-valid-vlid3-novembro-cpf\/\">Valid (VLID3) vai pagar dividendos de R$ 0,27 por a\u00e7\u00e3o nesta quarta-feira (8)<\/a><\/li><li><a href=\"https:\/\/www.suno.com.br\/noticias\/irani-rani3-pagamento-dividendos-milionarios-gpj\/\">Irani (RANI3) anuncia pagamento de dividendos milion\u00e1rios; veja valores<\/a><\/li>\t\t<\/ul>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Casas Bahia (BHIA3) deve mais do que triplicar preju\u00edzo no 3T23, dizem analistas<\/h2>\n\n\n\n<p>Previsto para ser divulgado nesta quarta-feira (8), depois do&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/fechamento-do-mercado\/\">fechamento do mercado<\/a>, o resultado do terceiro trimestre da&nbsp;Casas Bahia&nbsp;deve apresentar mais uma retra\u00e7\u00e3o em seus principais indicadores, em linha com um cen\u00e1rio macroecon\u00f4mico ainda adverso, retra\u00e7\u00e3o da rentabilidade devido ao sald\u00e3o de estoques, al\u00e9m da alavancagem elevada.<\/p>\n\n\n\n<p>Segundo estimativas da&nbsp;<strong>Genial Investimentos<\/strong>, a Casas Bahia deve reportar preju\u00edzo de R$ 689 milh\u00f5es no terceiro trimestre \u2013 mais do que o triplo do registrado no mesmo per\u00edodo em 2022, quando a companhia teve preju\u00edzo de R$ 203 milh\u00f5es \u2013 impactado pela forte retra\u00e7\u00e3o de rentabilidade devido ao sald\u00e3o de estoques.<\/p>\n\n\n\n<p>Ainda de acordo com a gestora, apesar dos esfor\u00e7os da companhia em reduzir os n\u00edveis de despesas, com corte do quadro de pessoas e enxugamento de despesas de marketing, o&nbsp;<strong>lucro operacional da Casas Bahia<\/strong>&nbsp;precisar\u00e1 lidar com o carrego negativo da&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/margem-bruta-entenda-sua-importancia\/\">margem bruta<\/a>&nbsp;e a desalavancagem operacional.<\/p>\n\n\n\n<p>Assim, a Genial projeta um&nbsp;<strong>Ebitda ajustado da Casas Bahia<\/strong>&nbsp;em R$ 36 milh\u00f5es no terceiro trimestre (queda de 90,9% na base anual), e uma&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/margem-ebitda\/\">margem Ebitda<\/a>&nbsp;ajustada de 0,5%. J\u00e1 a&nbsp;<strong>receita l\u00edquida da Casas Bahia<\/strong>&nbsp;deve ficar em R$ 6,7 bilh\u00f5es no 3T23, queda de 3,5% na base anual.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sald\u00e3o de estoques da Casas Bahia pode impactar balan\u00e7o<\/h2>\n\n\n\n<p>A Genial cruzou dados da&nbsp;<strong>Neotrust<\/strong>&nbsp;\u2013 sinalizando que o faturamento anual do e-commerce brasileiro caiu 7% no 3T23 \u2013 com a Pesquisa Mensal de Com\u00e9rcio (<strong>IBGE<\/strong>), e entendeu que a categoria de m\u00f3veis continua a ser uma das principais detratoras de crescimento de vendas para empresas como a Casas Bahia e tamb\u00e9m o&nbsp;<strong>Magazine Luiza<\/strong>&nbsp;(MGLU3).<\/p>\n\n\n\n<p>Em relat\u00f3rio, a casa apontou ainda tr\u00eas efeitos que devem ser levados em considera\u00e7\u00e3o para entender a din\u00e2mica de&nbsp;<strong>vendas da Casas Bahia<\/strong>&nbsp;neste trimestre:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fechamento de aproximadamente 31 lojas (dentro de um plano de encerrar atividades em cerca de 75 unidades);<\/li>\n\n\n\n<li>Sald\u00e3o de produtos para ajustar os n\u00edveis de estoques da companhia;<\/li>\n\n\n\n<li>Menores n\u00edveis de concess\u00e3o de cr\u00e9dito (ainda sem o FIDC para impulsionar as vendas pelo credi\u00e1rio.<\/li>\n<\/ul>\n\n\n\n<p>\u201cCorrelacionando esses tr\u00eas efeitos, entendemos que o plano de ajuste de&nbsp;<strong>estoque da Casas Bahia<\/strong>, iniciado ainda no segundo trimestre, deve apimentar os \u00e2nimos do varejo e-commerce neste resultado\u201d, apontaram os analistas Iago Souza, Vinicius Esteves e Nina Mirazon.<\/p>\n\n\n\n<p>Apesar de n\u00e3o enxergar espa\u00e7os para a varejista elevar a&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/concessao-de-credito\/\">concess\u00e3o de cr\u00e9dito<\/a>, dado o cen\u00e1rio macroecon\u00f4mico ainda fr\u00e1gil, na vis\u00e3o da casa, o sald\u00e3o de estoques deve contrabalancear o impacto negativo do fechamento de lojas e menor \u2018poder de fogo\u2019 de cr\u00e9dito neste trimestre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mesmo com plano de transforma\u00e7\u00e3o, alavancagem permanece elevada, diz Goldman<\/h2>\n\n\n\n<p>Segundo o Goldman, nos \u00faltimos meses, a Casas Bahia tem voltado as suas aten\u00e7\u00f5es para a&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/geracao-de-caixa\/\">gera\u00e7\u00e3o de caixa<\/a>, e n\u00e3o para os ganhos de a\u00e7\u00f5es.<\/p>\n\n\n\n<p>Assim, diz o banco, mesmo com a oferta prim\u00e1ria de R$ 620 milh\u00f5es no contexto de um plano de transforma\u00e7\u00e3o mais amplo, focado em preparar a empresa para um crescimento sustent\u00e1vel a partir de 2025, a alavancagem permanece relativamente elevada.<\/p>\n\n\n\n<p>Sobre esse indicador, inclusive, a institui\u00e7\u00e3o estima que ele feche o ano de 2023 em 7,3 vezes, impactado negativamente pelo baixo Ebitda esperado para o 3T23, dada a alta atividade promocional no contexto de otimiza\u00e7\u00e3o de estoques.<\/p>\n\n\n\n<p>\u201cAt\u00e9 o final de 2024, sob um ambiente operacional mais normalizado, estimamos que este indicador poder\u00e1 cair para 4,2 vezes\u201d, apontaram os analistas Irma Sgarz, Felipe Rached e Gustavo Fratini.<\/p>\n\n\n\n<p>O Goldman estima ainda que a<strong>&nbsp;Casas Bahia&nbsp;<\/strong>tenha aumentado sua participa\u00e7\u00e3o no e-commerce brasileiro em 7,5% (8,0% em 2022), atr\u00e1s de Magazine Luiza, com 17,7% (17,5% em 2022) e de Mercado Livre (<a href=\"https:\/\/www.suno.com.br\/bdrs\/meli34\/\">MELI34<\/a>), acima de 40% (33,7% em 2022).<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Desempenho das a\u00e7\u00f5es da Casas Bahia<\/h2>\n\n\n\n<div class=\"pluginQuotation\">\n  <p class=\"ticker\">\n    Cota\u00e7\u00e3o <span>BHIA3<\/span>\n  <\/p>\n  <div class=\"info\">\n    <div class=\"leftSide\">\n      Gr\u00e1fico gerado em: 08\/11\/2023    <\/div>\n\t\t\t\t\t<div class=\"rightSide\">\n\t\t\t\t\t<span class=\"period\">\n\t\t\t\t\t\t1 Dia\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t  <\/div>\n\n  <div id=\"chart-30de2072c202b71429e1f6e7dfc5e07a\" data-block-hash=\"30de2072c202b71429e1f6e7dfc5e07a\"  class=\"chart\" style=\"width:100%;height:400px;\"><\/div>\n\n  <div class=\"pluginQuotation__footer\">\n    <div class=\"dataChart\">\n\n      <div class=\"dataChart__div1 variation\">\n        <div class=\"value-positive\">\n          15,69 (+0,08%)        <\/div>\n        <div class=\"text\">\n          Varia\u00e7\u00e3o do per\u00edodo\n        <\/div>\n      <\/div>\n\n      <div class=\"dataChart__div2 minMax\">\n        <div class=\"value\">\n          R$\u00a00,51        <\/div>\n        <div class=\"text\">\n          M\u00ednima\n        <\/div>\n      <\/div>\n\n      <div class=\"dataChart__div3 minMax\">\n        <div class=\"value\">\n          R$\u00a00,59        <\/div>\n        <div class=\"text\">\n          M\u00e1xima\n        <\/div>\n      <\/div>\n\n\t\t\t<div class=\"dataChart__div4 rightSide\">\n\t\t\t\t<div class=\"analiticaSource\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tFonte:\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<img decoding=\"async\" class=\"analiticaLogo\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/plugins\/suno-block-ticker-quotation\/src\/suno-analitica-logo.png\" alt=\"Logo Suno Anal\u00edtica\" \/>\n\t\t\t\t<\/div>\n\n\t\t\t\t<a href=\"https:\/\/www.suno.com.br\/analitica\/acoes\/BHIA3\" target=\"_blank\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tVer mais cota\u00e7\u00f5es\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\">\n\t\t\t\t\t\t<path d=\"M4.20996 0L3.50496 0.705L6.29496 3.5H0.209961V4.5H6.29496L3.50496 7.295L4.20996 8L8.20996 4L4.20996 0Z\" fill=\"#D42126\" \/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/a>\n    <\/div>\n\n    <\/div>\n  <\/div>\n<\/div>\n\n\n<script type=\"text\/javascript\">\n  let chart_30de2072c202b71429e1f6e7dfc5e07a = document.getElementById('chart-30de2072c202b71429e1f6e7dfc5e07a');\n  let data_json_30de2072c202b71429e1f6e7dfc5e07a = \"[{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 10:06\\\",\\\"value\\\":0.51},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 10:08\\\",\\\"value\\\":0.52},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 10:10\\\",\\\"value\\\":0.51},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 10:12\\\",\\\"value\\\":0.52},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 10:14\\\",\\\"value\\\":0.52},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 10:16\\\",\\\"value\\\":0.52},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 10:18\\\",\\\"value\\\":0.51},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:06\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:08\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:10\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:12\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:14\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:16\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:18\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:20\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:22\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:24\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:26\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:28\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:30\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:32\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:34\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:36\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:38\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:40\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:42\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:44\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:46\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:48\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:50\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:52\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:54\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:56\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 12:58\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:00\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:02\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:04\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:06\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:08\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:10\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:12\\\",\\\"value\\\":0.53},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:14\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:22\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:24\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:26\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:28\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:30\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:32\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:34\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:36\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:38\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:40\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:42\\\",\\\"value\\\":0.56},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:44\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:46\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:48\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:50\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:52\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:54\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:56\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 13:58\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 14:00\\\",\\\"value\\\":0.56},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 14:02\\\",\\\"value\\\":0.56},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 14:04\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 14:06\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 14:08\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 14:10\\\",\\\"value\\\":0.59},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 14:12\\\",\\\"value\\\":0.55},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 14:14\\\",\\\"value\\\":0.54},{\\\"date\\\":\\\"07\\\\\\\/11\\\\\\\/23 14:16\\\",\\\"value\\\":0.59}]\";\n  let isPositive_30de2072c202b71429e1f6e7dfc5e07a = true;\n\n  let color_30de2072c202b71429e1f6e7dfc5e07a = isPositive_30de2072c202b71429e1f6e7dfc5e07a ? '#3AB53A' : '#D92C2D';\n\n  let data_30de2072c202b71429e1f6e7dfc5e07a = JSON.parse(data_json_30de2072c202b71429e1f6e7dfc5e07a);\n\n  const result_30de2072c202b71429e1f6e7dfc5e07a = {\n    date: [],\n    value: [],\n  };\n\n  data_30de2072c202b71429e1f6e7dfc5e07a.forEach((item) => {\n    result_30de2072c202b71429e1f6e7dfc5e07a.date.push(item.date);\n    result_30de2072c202b71429e1f6e7dfc5e07a.value.push(Number(item.value));\n  });\n\n  let option_30de2072c202b71429e1f6e7dfc5e07a = {\n    \/\/ variavel de cor global\n    color: [color_30de2072c202b71429e1f6e7dfc5e07a],\n    title: {\n      text: '',\n    },\n    tooltip: {\n      trigger: 'axis',\n      axisPointer: {\n        type: 'cross',\n        label: {\n          \/\/ cor dos valores em X e Y\n          backgroundColor: color_30de2072c202b71429e1f6e7dfc5e07a,\n          formatter: (value) => {\n            if (typeof value.value === 'number') {\n              return Number(value.value).toLocaleString('pt-br', {\n                style: 'currency',\n                currency: 'BRL'\n              });\n            }\n            return value.value;\n          },\n        },\n      },\n      valueFormatter: (value) => Number(value).toLocaleString('pt-br', {\n        style: 'currency',\n        currency: 'BRL'\n      }),\n    },\n    legend: {\n      \/\/ data: ['Valor de Fechamento'],\n      show: false,\n    },\n    toolbox: {\n      feature: {\n        saveAsImage: {\n          show: false,\n        },\n      },\n    },\n    grid: {\n      left: '0px',\n      right: '0px',\n      bottom: '0px',\n      containLabel: true,\n    },\n    xAxis: [{\n      type: 'category',\n      data: result_30de2072c202b71429e1f6e7dfc5e07a.date,\n      boundaryGap: true,\n    }],\n    yAxis: [{\n      type: 'value',\n      min: Math.min(...result_30de2072c202b71429e1f6e7dfc5e07a.value),\n      max: Math.max(...result_30de2072c202b71429e1f6e7dfc5e07a.value),\n      axisLabel: {\n        formatter: (value) => value.toLocaleString('pt-br', {\n          style: 'currency',\n          currency: 'BRL'\n        }),\n      },\n    }],\n    series: [{\n      name: 'Valor de Fechamento',\n      type: 'line',\n      stack: 'Total',\n      \/\/ cor do grafico\n      areaStyle: {},\n      emphasis: {\n        focus: 'series',\n      },\n      data: result_30de2072c202b71429e1f6e7dfc5e07a.value,\n      \/\/ cor da linha\n      lineStyle: {\n        color: color_30de2072c202b71429e1f6e7dfc5e07a,\n      },\n    }, ],\n  };\n\n\twindow.chart_30de2072c202b71429e1f6e7dfc5e07a = {\n\t\tel: chart_30de2072c202b71429e1f6e7dfc5e07a,\n\t\toption: option_30de2072c202b71429e1f6e7dfc5e07a\t};\n\n\n<\/script>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Em fato relevante divulgado na manh\u00e3 desta quarta-feira (8), a Casas Bahia (BHIA3) informou que a estrutura\u00e7\u00e3o do fundo de investimento em direitos credit\u00f3rios (FIDC), com o objetivo de otimizar a opera\u00e7\u00e3o de credi\u00e1rio da companhia, buscar\u00e1 uma capta\u00e7\u00e3o inicial de R$ 600 milh\u00f5es. Casas Bahia (BHIA3). Foto: Reprodu\u00e7\u00e3o\/ Via Segundo a companhia, a estrutura\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":313,"featured_media":452779,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[286,107138,38650],"suno_strategy":[],"class_list":["post-482458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-acoes","tag-casas-bahia-bhia3","tag-fidc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em 1\u00aa etapa de FIDC<\/title>\n<meta name=\"description\" content=\"O fundo de investimento em direitos credit\u00f3rios (FIDC) da Casas Bahia tem o objetivo de otimizar sua opera\u00e7\u00e3o de credi\u00e1rio. Saiba mais!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em 1\u00aa etapa de FIDC\" \/>\n<meta property=\"og:description\" content=\"O fundo de investimento em direitos credit\u00f3rios (FIDC) da Casas Bahia tem o objetivo de otimizar sua opera\u00e7\u00e3o de credi\u00e1rio. Saiba mais!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanni Porf\u00edrio Jacomino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Porf\u00edrio Jacomino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/\"},\"author\":{\"name\":\"Giovanni Porf\u00edrio Jacomino\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40\"},\"headline\":\"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em primeira etapa de FIDC; saiba mais\",\"datePublished\":\"2023-11-08T12:40:27+00:00\",\"dateModified\":\"2023-11-08T19:28:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/\"},\"wordCount\":1051,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja.jpg\",\"keywords\":[\"A\u00e7\u00f5es\",\"Casas Bahia (BHIA3)\",\"FIDC\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/\",\"name\":\"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em 1\u00aa etapa de FIDC\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja.jpg\",\"datePublished\":\"2023-11-08T12:40:27+00:00\",\"dateModified\":\"2023-11-08T19:28:14+00:00\",\"description\":\"O fundo de investimento em direitos credit\u00f3rios (FIDC) da Casas Bahia tem o objetivo de otimizar sua opera\u00e7\u00e3o de credi\u00e1rio. Saiba mais!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Casas Bahia (BHIA3). Foto: Reprodu\u00e7\u00e3o\/ Via\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em primeira etapa de FIDC; saiba mais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40\",\"name\":\"Giovanni Porf\u00edrio Jacomino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g\",\"caption\":\"Giovanni Porf\u00edrio Jacomino\"},\"description\":\"Giovanni Porf\u00edrio Jacomino \u00e9 jornalista formado pela Universidade Estadual de Londrina (UEL) e p\u00f3s-graduado em Produ\u00e7\u00e3o e Pr\u00e1ticas Jornal\u00edsticas na Contemporaneidade na Faculdade C\u00e1sper L\u00edbero (FCL). Foi editor web no Startupi e no Finsiders, atuando ainda como editor no TC Mover, portal de not\u00edcias da TradersClub, fazendo a cobertura de assuntos relacionados ao mercado financeiro interno e externo. Atualmente, \u00e9 Rep\u00f3rter do Suno Not\u00edcias.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em 1\u00aa etapa de FIDC","description":"O fundo de investimento em direitos credit\u00f3rios (FIDC) da Casas Bahia tem o objetivo de otimizar sua opera\u00e7\u00e3o de credi\u00e1rio. Saiba mais!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/","og_locale":"pt_BR","og_type":"article","og_title":"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em 1\u00aa etapa de FIDC","og_description":"O fundo de investimento em direitos credit\u00f3rios (FIDC) da Casas Bahia tem o objetivo de otimizar sua opera\u00e7\u00e3o de credi\u00e1rio. Saiba mais!","og_url":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1200,"height":800,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja.jpg","type":"image\/jpeg"}],"author":"Giovanni Porf\u00edrio Jacomino","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Giovanni Porf\u00edrio Jacomino","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/"},"author":{"name":"Giovanni Porf\u00edrio Jacomino","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40"},"headline":"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em primeira etapa de FIDC; saiba mais","datePublished":"2023-11-08T12:40:27+00:00","dateModified":"2023-11-08T19:28:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/"},"wordCount":1051,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja.jpg","keywords":["A\u00e7\u00f5es","Casas Bahia (BHIA3)","FIDC"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/","url":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/","name":"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em 1\u00aa etapa de FIDC","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja.jpg","datePublished":"2023-11-08T12:40:27+00:00","dateModified":"2023-11-08T19:28:14+00:00","description":"O fundo de investimento em direitos credit\u00f3rios (FIDC) da Casas Bahia tem o objetivo de otimizar sua opera\u00e7\u00e3o de credi\u00e1rio. Saiba mais!","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja.jpg","width":1200,"height":800,"caption":"Casas Bahia (BHIA3). Foto: Reprodu\u00e7\u00e3o\/ Via"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em primeira etapa de FIDC; saiba mais"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40","name":"Giovanni Porf\u00edrio Jacomino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g","caption":"Giovanni Porf\u00edrio Jacomino"},"description":"Giovanni Porf\u00edrio Jacomino \u00e9 jornalista formado pela Universidade Estadual de Londrina (UEL) e p\u00f3s-graduado em Produ\u00e7\u00e3o e Pr\u00e1ticas Jornal\u00edsticas na Contemporaneidade na Faculdade C\u00e1sper L\u00edbero (FCL). Foi editor web no Startupi e no Finsiders, atuando ainda como editor no TC Mover, portal de not\u00edcias da TradersClub, fazendo a cobertura de assuntos relacionados ao mercado financeiro interno e externo. Atualmente, \u00e9 Rep\u00f3rter do Suno Not\u00edcias.","url":"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/09\/casas-bahia-via-viia3-loja-400x200.jpg\" alt=\"Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em primeira etapa de FIDC; saiba mais\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/casas-bahia-bhia3-fidc-gpj\/\"><h2 class=\"content__title\">Casas Bahia (BHIA3) buscar\u00e1 captar R$ 600 milh\u00f5es em primeira etapa de FIDC; saiba mais<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/DSCF4115-1-1-150x150.webp\" alt=\"Giovanni Porf\u00edrio Jacomino\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/\"><span itemprop=\"author\">Giovanni Porf\u00edrio Jacomino<\/span><\/a><\/span><time datetime=\"2023-11-08T09:40:27-03:00\" itemprop=\"datePublished\">08\/11\/2023 09:40<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/482458"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/313"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=482458"}],"version-history":[{"count":2,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/482458\/revisions"}],"predecessor-version":[{"id":482797,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/482458\/revisions\/482797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/452779"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=482458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=482458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=482458"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=482458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}