{"id":478666,"date":"2023-10-30T22:40:59","date_gmt":"2023-10-31T01:40:59","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=478666"},"modified":"2023-10-30T22:41:12","modified_gmt":"2023-10-31T01:41:12","slug":"radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/","title":{"rendered":"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)"},"content":{"rendered":"<p>Em nova an\u00e1lise sobre as a\u00e7\u00f5es da&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/EGIE3\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Engie<\/strong>&nbsp;(EGIE3)<\/a>, analistas do Ita\u00fa BBA destacaram que, dados os movimentos recentes da companhia, a expectativa atual \u00e9 de menores proventos.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Engie. Foto: Divulga\u00e7\u00e3o\/Engie<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n\n\n<p>Os especialistas apontaram para o fato de que nesta segunda (30) a Engie anunciou que adquiriu um complexo solar da Atlas Renov\u00e1vel, composto por cinco ativos com&nbsp;<a target=\"_blank\" href=\"https:\/\/www.suno.com.br\/artigos\/capacidade-instalada\/\" rel=\"noreferrer noopener\">capacidade instalada<\/a>&nbsp;total de 545 MWac.<\/p>\n\n\n\n<p>\u201cO valor total da empresa \u00e9 de R$ 3,2 bilh\u00f5es. Com base nas informa\u00e7\u00f5es fornecidas pela empresa e em alguns suposi\u00e7\u00f5es que fizemos, nossa percep\u00e7\u00e3o \u00e9 que este neg\u00f3cio \u00e9 neutro em termos de VPL. No entanto, dado do tamanho da transa\u00e7\u00e3o, esperamos que os&nbsp;<strong>dividendos da Engie<\/strong>&nbsp;sejam reduzidos \u00e0 frente\u201d, diz o BBA.<\/p>\n\n\n\n<p>Com a transa\u00e7\u00e3o, os analistas esperam um rendimento m\u00e9dio de&nbsp;<strong>dividendos&nbsp;<\/strong>de 6,4% para 2023-2024, em compara\u00e7\u00e3o com uma estimativa anterior de um rendimento de ~12% no cen\u00e1rio de um payout de 100%.<\/p>\n\n\n\n<p>O complexo adquirido pela Engie possui:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>545 MWac de capacidade instalada<\/li>\n\n\n\n<li>145,1 MW m\u00e9dios de energia<\/li>\n\n\n\n<li>Rodos os projetos j\u00e1 em pleno funcionamento e em sua maioria contratados (ACR e ACL)<\/li>\n<\/ul>\n\n\n\n<p>\u201cPara os quatro projetos contratados no mercado regulado, o&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/preco-medio\/\" target=\"_blank\" rel=\"noreferrer noopener\">pre\u00e7o m\u00e9dio<\/a>&nbsp;de venda \u00e9 muito elevado<br>(R$ ~380\/MWh). Existe apenas um projeto contratado no mercado livre (Lar do Sol), mas<br>a empresa n\u00e3o divulgou o pre\u00e7o m\u00e9dio dos CAEs\u201d, observa o BBA sobre a transa\u00e7\u00e3o.<\/p>\n\n\n\n<p>A companhia tem um&nbsp;<a target=\"_blank\" href=\"https:\/\/www.suno.com.br\/artigos\/valor-patrimonial\/\" rel=\"noreferrer noopener\">valor patrimonial<\/a>&nbsp;de R$ 2,269 bilh\u00f5es e&nbsp;<a target=\"_blank\" href=\"https:\/\/www.suno.com.br\/artigos\/divida-liquida\/\" rel=\"noreferrer noopener\">d\u00edvida l\u00edquida<\/a>&nbsp;de R$ 971 milh\u00f5es. Segundo Engie, o valor patrimonial ser\u00e1 atualizado pela Selic at\u00e9 a data de fechamento do neg\u00f3cio, que deve ser ainda no fim deste ano.<\/p>\n\n\n\n<p>O BBA destaca que espera que a Engie ser\u00e1 capaz de alavancar 70% do desembolso de capital ao IPCA + 6% na holding com benef\u00edcio fiscal.<\/p>\n\n\n\n<p>\u201cNa aus\u00eancia de uma an\u00e1lise completa do custo de financiamento da nova d\u00edvida que a Engie est\u00e1 assumindo, estamos assumindo um custo m\u00e9dio da d\u00edvida de IPCA+ 5% para a d\u00edvida assumida (R$ 971 milh\u00f5es), a ser integralmente amortizada dentro 20 anos\u201d, diz a casa.<\/p>\n\n\n\n<p>Al\u00e9m de Engie, confira outros destaques desta segunda-feira:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Eletrobras (ELET3) deve lan\u00e7ar oferta para vender fatia na ISA Cteep (TRPL4) nos pr\u00f3ximos dias, diz jornal<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/ELET3\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Eletrobras<\/strong>&nbsp;(ELET3)<\/a>, seguindo seu plano estrat\u00e9gico de desinvestimento em ativos n\u00e3o essenciais, planeja anunciar esta semana uma oferta subsequente de a\u00e7\u00f5es (follow-on) para vender sua participa\u00e7\u00e3o na&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/TRPL4\/\" target=\"_blank\" rel=\"noreferrer noopener\">ISA Cteep (TRPL4)<\/a>, segundo informa\u00e7\u00f5es do jornal Valor Econ\u00f4mico.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A Eletrobras atualmente det\u00e9m 35,74% do capital total da&nbsp;<strong>empresa de transmiss\u00e3o<\/strong>, o que representa uma fatia consider\u00e1vel do quadro societ\u00e1rio da companhia.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para estruturar a&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/oferta-de-acoes\/\" target=\"_blank\" rel=\"noreferrer noopener\">oferta de a\u00e7\u00f5es<\/a>, a Eletrobras contratou o Citi, Ita\u00fa BBA, Santander e Safra, conforme fontes a par do assunto.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A decis\u00e3o de seguir com o desinvestimento na&nbsp;<strong>ISA Cteep<\/strong>&nbsp;\u00e9 parte da estrat\u00e9gia da Eletrobras de racionalizar sua estrutura societ\u00e1ria e concentrar recursos em ativos mais alinhados com suas opera\u00e7\u00f5es centrais.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A expectativa \u00e9 de que a oferta p\u00fablica seja lan\u00e7ada ap\u00f3s a divulga\u00e7\u00e3o do resultado do terceiro trimestre da ISA Cteep, que ocorre nesta segunda (30).<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A Eletrobras busca melhorar sua&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/eficiencia-operacional\/\" target=\"_blank\" rel=\"noreferrer noopener\">efici\u00eancia operacional<\/a>&nbsp;e tribut\u00e1ria, bem como potencialmente direcionar recursos para novos projetos alinhados com sua estrat\u00e9gia de neg\u00f3cios ou para o pagamento de&nbsp;<strong>dividendos<\/strong>&nbsp;aos acionistas.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A Eletrobras j\u00e1 tomou medidas semelhantes em outras empresas em que detinha participa\u00e7\u00f5es minorit\u00e1rias, como parte de seu processo de reestrutura\u00e7\u00e3o.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A empresa reduziu o n\u00famero de Sociedades de Prop\u00f3sito Espec\u00edfico (SPEs), transformou subsidi\u00e1rias em subsidi\u00e1rias integrais, anunciou desinvestimentos em t\u00e9rmicas, reduziu sua for\u00e7a de trabalho e vendeu sua posi\u00e7\u00e3o em empresas consideradas n\u00e3o estrat\u00e9gicas, como na&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/CPLE6\/\" target=\"_blank\" rel=\"noreferrer noopener\">Copel (CPLE6)<\/a>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Lucro no trimestre da B3 (B3SA3)? Analistas recomendam compra das a\u00e7\u00f5es e veem upside de 42,8%<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A&nbsp;<strong>B3<\/strong>&nbsp;(B3SA3) deve ter um&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noreferrer noopener\">lucro l\u00edquido<\/a>&nbsp;est\u00e1vel no terceiro trimestre de 2023 (3T23), projeta a Genial Investimentos. A corretora recomenda as a\u00e7\u00f5es da B3, visando um upside de 42,8%.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>De acordo com estimativas dos analistas, o&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noreferrer noopener\">lucro l\u00edquido<\/a>&nbsp;deve aumentar 1,3% em rela\u00e7\u00e3o ao trimestre anterior, com um crescimento de 3,6% na base anual, atingindo o valor total de R$ 1,06 bilh\u00e3o.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para a Genial , a queda trimestral de 11,6%&nbsp; do&nbsp;<strong>volume financeiro m\u00e9dio di\u00e1rio (ADTV) da B3<\/strong>, chegando a R$ 24,5 bilh\u00f5es, sinaliza um cen\u00e1rio ainda desafiador para o&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/mercado-de-capitais-conceito\/\" target=\"_blank\" rel=\"noreferrer noopener\">mercado de capitais<\/a>&nbsp;brasileiro.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No entanto, a diminui\u00e7\u00e3o de&nbsp;<strong>volumes na B3<\/strong>&nbsp;resultou em um aumento do&nbsp;<strong>pre\u00e7o das opera\u00e7\u00f5es<\/strong>, o que, por sua vez, gerou margens mais elevadas e uma receita est\u00e1vel.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cAl\u00e9m de nossa expectativa de que a receita permane\u00e7a est\u00e1vel, prevemos um aumento nas<strong>&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/despesas-operacionais\/\" target=\"_blank\" rel=\"noreferrer noopener\">despesas operacionais<\/a>&nbsp;da B3<\/strong>&nbsp;devido a acordos salariais, embora isso deva ser compensado por um aumento no&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/resultado-financeiro\/\" target=\"_blank\" rel=\"noreferrer noopener\">resultado financeiro<\/a>&nbsp;e uma redu\u00e7\u00e3o na al\u00edquota de imposto\u201d, explica a Genial.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Em rela\u00e7\u00e3o a 2024, a Genial projeta a retomada dos&nbsp;<strong>resultados da empresa que administra a Bolsa<\/strong>, com um&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-contabil\/\" target=\"_blank\" rel=\"noreferrer noopener\">lucro cont\u00e1bil<\/a>&nbsp;estimado em R$ 5,1 bilh\u00f5es, representando um aumento de 19%. \u201cDo lado positivo, observamos um crescimento na receita mais atrativo, impulsionado por uma recupera\u00e7\u00e3o do mercado, com a perspectiva de um maior volume financeiro m\u00e9dio di\u00e1rio (ADTV).\u201d<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Do lado negativo \u00e9 prevista uma queda no&nbsp;<strong><a href=\"https:\/\/www.suno.com.br\/artigos\/resultado-financeiro\/\" target=\"_blank\" rel=\"noreferrer noopener\">resultado financeiro<\/a>&nbsp;da B3<\/strong>&nbsp;devido \u00e0 expectativa de redu\u00e7\u00e3o nas taxas de juros.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Neste contexto, a corretora recomenda compra das<strong>&nbsp;a\u00e7\u00f5es da B3<\/strong>, com&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/preco-alvo\/\" target=\"_blank\" rel=\"noreferrer noopener\">pre\u00e7o alvo<\/a>&nbsp;de R$ 16 \u2013 ante os R$ 11,08 atuais. \u201cAcreditamos que a a\u00e7\u00e3o est\u00e1 negociando a patamares atrativos, passando de um m\u00faltiplo de 13,5x P\/L em 2023 para 12,5x P\/L em 2024.\u201d<\/li>\n<\/ul>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">ISA Cteep (TRPL4) tem lucro 22,7% maior no 3T23, para R$ 474,5 milh\u00f5es<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/TRPL4\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>ISA CTeep<\/strong>&nbsp;(TRPL4)<\/a>&nbsp;anunciou um&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noreferrer noopener\">lucro l\u00edquido<\/a>&nbsp;de R$ 474,5 milh\u00f5es no terceiro trimestre de 2023 (3T23), o que representa um aumento de 22,7% na compara\u00e7\u00e3o com o lucro do mesmo trimestre do ano passado, que tinha sido de R$ 386,7 milh\u00f5es.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conforme aponta o novo&nbsp;<strong>balan\u00e7o da ISA Cteep<\/strong>&nbsp;no 3T23, o Ebtida da empresa, que representa o lucro antes de juros, impostos, deprecia\u00e7\u00f5es e amortiza\u00e7\u00f5es, teve um crescimento anual de 17,9%, chegando a R$ 876,6 milh\u00f5es.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>J\u00e1 a margem&nbsp;<strong>Ebtida&nbsp;<\/strong>alcan\u00e7ou os 80,2% no 3T23, com varia\u00e7\u00e3o negativa de 0,6 ponto percentual em rela\u00e7\u00e3o ao terceiro trimestre de 2022.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>De acordo com o documento divulgado ao mercado hoje (30), os<strong>&nbsp;resultados da&nbsp;ISA Cteep&nbsp;<\/strong>foram impactados positivamente pelas opera\u00e7\u00f5es de projetos que visam aprimoramento, greenfield e refor\u00e7os no intervalo de 1 ano.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Al\u00e9m disso, o resultado do<strong>&nbsp;3T23 da<\/strong>&nbsp;<strong>ISA Cteep<\/strong>&nbsp;tamb\u00e9m foi impactado de forma positiva pelo reajuste do IPCA durante o ciclo tarif\u00e1rio dos anos 2023\/2024.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Natura (NTCO3): analistas projetam impacto positivo nas a\u00e7\u00f5es ap\u00f3s acordo para venda da The Body Shop<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O Ita\u00fa BBA avalia que o acordo da&nbsp;<strong>Natura&nbsp;<\/strong>(NTCO3) sobre a exclusividade para potencial venda da The Body Shop demonstra o esfor\u00e7o da companhia em simplificar sua estrutura organizacional. Segundo o BBA, o potencial das vendas pode ter impacto positivo nas a\u00e7\u00f5es. Dessa forma, a casa recomenda compra da NTCO3.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nesta segunda-feira (30), a Natura celebrou um acordo de exclusividade com a Aurelius Investment Advisory Limited, dono de neg\u00f3cios como a rede Lloyds Pharmacy, visando a potencial&nbsp;<strong>venda da The Body Shop<\/strong>, marca inglesa de cosm\u00e9ticos, produtos de beleza e perfumes da fabricante brasileira.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cNossa opini\u00e3o sobre \u00e9 neutra, j\u00e1 que isso era em certa medida esperado. Essa not\u00edcia destaca o compromisso da Natura &amp; Co em priorizar a venda da The Body Shop\u201d, ressalta o BBA.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A equipe do&nbsp;<strong>BBA<\/strong>&nbsp;estima que o<strong>&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/valor-patrimonial\/\" target=\"_blank\" rel=\"noreferrer noopener\">valor patrimonial<\/a>&nbsp;da The Body Shop<\/strong>&nbsp;chegue a US$ 200 milh\u00f5es, considerando o pre\u00e7o atual das a\u00e7\u00f5es. No entanto, o BBA ressalta que alguns investidores projetam valores mais altos, entre US$ 300 a 400 milh\u00f5es.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cDependendo do&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/valor-patrimonial\/\" target=\"_blank\" rel=\"noreferrer noopener\">valor patrimonial<\/a>&nbsp;anunciado, esperamos que esse desenvolvimento sirva como um gatilho para o desempenho das a\u00e7\u00f5es\u201d, explica&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O BBA reitera recomenda\u00e7\u00e3o de compra das&nbsp;<strong>a\u00e7\u00f5es na Natura<\/strong>, com pre\u00e7o-alvo de R$ 21.&nbsp;As a\u00e7\u00f5es est\u00e3o cotadas hoje a R$ 12,45.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Automob, da Simpar (SIMH3), adquire rede de lojas de carros por R$ 120 milh\u00f5es<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A Automob, empresa de vendas de autom\u00f3veis da&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/SIMH3\/\"><strong>Simpar<\/strong>&nbsp;(SIMH3)<\/a>, anunciou nesta segunda-feira (30) a aquisi\u00e7\u00e3o de 100% da rede de lojas Best Points, que possui oito concession\u00e1rias das marcas Renault, Ford e Honda na cidade de S\u00e3o Paulo, pelo valor de R$ 120 milh\u00f5es.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Segundo a Simpar, a&nbsp;<strong>aquisi\u00e7\u00e3o da Best Points<\/strong>&nbsp;adicionar\u00e1 R$ 620 milh\u00f5es \u00e0&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/o-que-receita-bruta\/\">receita bruta<\/a>&nbsp;anualizada da&nbsp;<strong>Automob<\/strong>, que chega a R$ 8 bilh\u00f5es com base no segundo trimestre de 2023 anualizado \u2013 considerando os resultados combinados da Original, UAB Motors, Sagamar, Autostar, Green Autom\u00f3veis, Nova Quality, Grupo Alta e&nbsp;<strong>Best Points<\/strong>.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Com essa mais nova aquisi\u00e7\u00e3o, a&nbsp;<strong>Automob<\/strong>&nbsp;atinge a marca de 105 lojas, presentes em 18 cidades e mix de 27 marcas, ampliando sua escala e capilaridade.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nos 12 meses at\u00e9 o segundo trimestre deste ano, a Best Points apresentou R$ 585 milh\u00f5es em receita bruta, com R$ 25 milh\u00f5es em Ebitda e&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\">lucro l\u00edquido<\/a>&nbsp;de R$ 15 milh\u00f5es. A empresa vendeu 2,2 mil ve\u00edculos e 1,9 mil seminovos no per\u00edodo.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cA Best Points contar\u00e1 com todo o suporte da&nbsp;<strong>controlada Automob<\/strong>&nbsp;para um novo ciclo de desenvolvimento, ao mesmo tempo em que manter\u00e1 sua equipe e gest\u00e3o independentes, tendo como foco primordial a excel\u00eancia no atendimento para proporcionar a melhor experi\u00eancia aos clientes\u201d, explicou a Simpar.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A Simpar controla tamb\u00e9m a Movida (MOVI3), de aluguel de carros, a Vamos (VAMO3), de caminh\u00f5es e m\u00e1quinas, e a JSL (JSLG3), de log\u00edstica e transporte rodovi\u00e1rio.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Nubank (ROXO34) deve ter lucro de US$ 270 milh\u00f5es, diz XP<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Segundo analistas da XP, o&nbsp;<strong>Nubank<\/strong>&nbsp;(<a href=\"https:\/\/statusinvest.com.br\/bdrs\/roxo34?__hstc=189907700.5f71d10b1b3a8989035e4b4597164a73.1667498058593.1698709883019.1698710664818.72&amp;__hssc=189907700.27.1698710664818&amp;__hsfp=1287607957\" target=\"_blank\" rel=\"noreferrer noopener\">ROXO34<\/a>) deve apresentar mais um trimestre s\u00f3lido no seu pr\u00f3ximo resultado, com lucro acima das expectativas do consenso de mercado.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A proje\u00e7\u00e3o da casa \u00e9 de que o&nbsp;<strong>lucro do Nubank<\/strong>&nbsp;seja de US$ 269 milh\u00f5es no acumulado do 3T23.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O&nbsp;<strong>resultado do Nubank<\/strong>&nbsp;ser\u00e1 divulgado no dia 14 de novembro, ap\u00f3s o&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/fechamento-do-mercado\/\" target=\"_blank\" rel=\"noreferrer noopener\">fechamento do mercado<\/a>.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cEsperamos resultados positivos no 3T23 para a Nu. Por mais um trimestre, a Nu dever\u00e1 manter o bom ritmo de aquisi\u00e7\u00e3o de clientes aliado \u00e0 maior&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/alavancagem-operacional\/\" target=\"_blank\" rel=\"noreferrer noopener\">alavancagem operacional<\/a>&nbsp;(aumentando o ARPAC e mantendo o Custo de Servir (CTS) abaixo de US$ 1)\u201d, diz a XP.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cPrevemos um crescimento robusto da carteira de cr\u00e9dito de +9% T\/T e +76% A\/A, \u00e0 medida que o banco consegue manter a inadimpl\u00eancia sob controle. Como as novas safras apresentam desempenho melhor do que o previsto, esperamos que a inadimpl\u00eancia permane\u00e7a est\u00e1vel\u201d, completa.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sobre o segmento de fintechs e neobancos, a XP reitera que o trimestre foi marcado por<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Taxas de juro elevadas<\/li>\n\n\n\n<li>Sinais de estabiliza\u00e7\u00e3o da inadimpl\u00eancia, ainda que em patamar elevado<\/li>\n\n\n\n<li>Melhoria do \u00edndice de efici\u00eancia atrav\u00e9s do controle de custos e alavancagem operacional<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cEspera-se que os neobanks continuem a monetizar a sua base de clientes, a reprecificar as carteiras de cr\u00e9dito e a implementar iniciativas para melhorar os custos de financiamento e o custo de servi\u00e7o (CTS)\u201d, observam os analistas.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cNo geral, os neobanks dever\u00e3o reportar resultados s\u00f3lidos, com o Nubank provavelmente apresentando um forte desempenho e o Inter&amp;Co (INBR32) se destacando. M\u00e9liuz (CASH3) poder\u00e1 ter mais um trimestre desafiador devido ao est\u00e1gio inicial da parceria BV\u201d, seguem.<\/li>\n<\/ul>\n\n\n\n<p>Da Engie \u00e0 B3, essas foram as empresas que se destacaram hoje. Para ler todas as mat\u00e9rias&nbsp;<strong><a href=\"https:\/\/www.suno.com.br\/noticias\/todos\/?utm_content=XYOE2ItQuUY.20201113&amp;utm_campaign=Track%2B&amp;utm_medium=video&amp;utm_source=telegram.sunoresearch\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a><\/strong>.<a href=\"https:\/\/lp.suno.com.br\/cl\/black-friday-suno-2023\/?_fs=16412753060-15131594205&amp;_fsRef=https%3A%2F%2Fwww.suno.com.br%2Fnoticias%2Fradar-caixa-seguridade-cxse3-itausa-itsa4-pao-de-acucar-pcar3%2F\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/cl\/black-friday-suno-2023\/?_fs=16412753060-15131594205&amp;_fsRef=https%3A%2F%2Fwww.suno.com.br%2Fnoticias%2Fcopel-cple6-xp-reitera-recomendacao-compra-va%2F\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/cl\/black-friday-suno-2023\/?_fs=16412753060-15131594205&amp;_fsRef=https%3A%2F%2Fwww.suno.com.br%2Fnoticias%2Fradar-magazine-luiza-mglu3-oi-oibr3-copel-cple6%2F\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/cl\/black-friday-suno-2023\/?_fs=16412753060-15131594205&amp;_fsRef=https%3A%2F%2Fwww.suno.com.br%2Fnoticias%2Fradar-irb-brasil-irbr3-klabin-klbn11-telefonica-vivt3%2F\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/cl\/black-friday-suno-2023\/?_fs=16439326504-15158167008&amp;_fsRef=https%3A%2F%2Fwww.suno.com.br%2Fnoticias%2Fradar-itausa-itsa4-brasilagro-agro3-weg-wege3%2F\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/cl\/black-friday-suno-2023\/?_fs=16439326504-15158167008&amp;_fsRef=https%3A%2F%2Fwww.suno.com.br%2Fnoticias%2Fradar-boa-safra-soja3-neoenergia-neoe3-kabin-klbn11%2F\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/cl\/black-friday-suno-2023\/?_fs=16439326504-15158167008&amp;_fsRef=https%3A%2F%2Fwww.suno.com.br%2Fnoticias%2Fsuzano-suzb3-3t23-reverte-lucro-prejuizo%2F\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/cl\/black-friday-suno-2023\/?_fs=16414994788-15133835730&amp;_fsRef=https%3A%2F%2Fwww.suno.com.br%2Fnoticias%2Fradar-vale-vale3-petrobras-petr4-lojas-marisa-amar3%2F\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"383123\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Em nova an\u00e1lise sobre as a\u00e7\u00f5es da&nbsp;Engie&nbsp;(EGIE3), analistas do Ita\u00fa BBA destacaram que, dados os movimentos recentes da companhia, a expectativa atual \u00e9 de menores proventos. Engie. Foto: Divulga\u00e7\u00e3o\/Engie Os especialistas apontaram para o fato de que nesta segunda (30) a Engie anunciou que adquiriu um complexo solar da Atlas Renov\u00e1vel, composto por cinco ativos [&hellip;]<\/p>\n","protected":false},"author":227,"featured_media":336256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[367,455,465,106964,574,107135,76282],"suno_strategy":[],"class_list":["post-478666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-b3-b3sa3","tag-eletrobras-elet3-elet5-elet6","tag-engie-egie3","tag-isa-cteep-trpl4","tag-natura-ntco3","tag-roxo34","tag-simpar-simh3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)<\/title>\n<meta name=\"description\" content=\"Banco projeta queda nos dividendos de Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas prev\u00eaem upside de 42,8% para B3 (B3SA3)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)\" \/>\n<meta property=\"og:description\" content=\"Banco projeta queda nos dividendos de Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas prev\u00eaem upside de 42,8% para B3 (B3SA3)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vanessa Loiola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vanessa Loiola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/\"},\"author\":{\"name\":\"Vanessa Loiola\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/450c455ecff319bab1f1a0e643451479\"},\"headline\":\"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)\",\"datePublished\":\"2023-10-31T01:40:59+00:00\",\"dateModified\":\"2023-10-31T01:41:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/\"},\"wordCount\":2105,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3.jpg\",\"keywords\":[\"B3 (B3SA3)\",\"Eletrobras (ELET3\/ELET5\/ELET6)\",\"Engie (EGIE3)\",\"Isa CTEEP (TRPL4)\",\"Natura (NTCO3)\",\"ROXO34\",\"Simpar (SIMH3)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/\",\"name\":\"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3.jpg\",\"datePublished\":\"2023-10-31T01:40:59+00:00\",\"dateModified\":\"2023-10-31T01:41:12+00:00\",\"description\":\"Banco projeta queda nos dividendos de Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas prev\u00eaem upside de 42,8% para B3 (B3SA3)\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Engie. Foto: Divulga\u00e7\u00e3o\/Engie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/450c455ecff319bab1f1a0e643451479\",\"name\":\"Vanessa Loiola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8b41117f9780831919eb38da349c3f20?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8b41117f9780831919eb38da349c3f20?s=96&r=g\",\"caption\":\"Vanessa Loiola\"},\"description\":\"Jornalista formada pela PUC-SP, com experi\u00eancia na cobertura das editorias de economia, finan\u00e7as, bolsa de valores, pol\u00edtica, energia solar e entretenimento. Com passagem pela BM&amp;C News e RedeTV!\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/vanessal-loiolagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)","description":"Banco projeta queda nos dividendos de Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas prev\u00eaem upside de 42,8% para B3 (B3SA3)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/","og_locale":"pt_BR","og_type":"article","og_title":"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)","og_description":"Banco projeta queda nos dividendos de Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas prev\u00eaem upside de 42,8% para B3 (B3SA3)","og_url":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1200,"height":800,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3.jpg","type":"image\/jpeg"}],"author":"Vanessa Loiola","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Vanessa Loiola","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/"},"author":{"name":"Vanessa Loiola","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/450c455ecff319bab1f1a0e643451479"},"headline":"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)","datePublished":"2023-10-31T01:40:59+00:00","dateModified":"2023-10-31T01:41:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/"},"wordCount":2105,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3.jpg","keywords":["B3 (B3SA3)","Eletrobras (ELET3\/ELET5\/ELET6)","Engie (EGIE3)","Isa CTEEP (TRPL4)","Natura (NTCO3)","ROXO34","Simpar (SIMH3)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/","url":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/","name":"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3.jpg","datePublished":"2023-10-31T01:40:59+00:00","dateModified":"2023-10-31T01:41:12+00:00","description":"Banco projeta queda nos dividendos de Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas prev\u00eaem upside de 42,8% para B3 (B3SA3)","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3.jpg","width":1200,"height":800,"caption":"Engie. Foto: Divulga\u00e7\u00e3o\/Engie"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/450c455ecff319bab1f1a0e643451479","name":"Vanessa Loiola","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8b41117f9780831919eb38da349c3f20?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b41117f9780831919eb38da349c3f20?s=96&r=g","caption":"Vanessa Loiola"},"description":"Jornalista formada pela PUC-SP, com experi\u00eancia na cobertura das editorias de economia, finan\u00e7as, bolsa de valores, pol\u00edtica, energia solar e entretenimento. Com passagem pela BM&amp;C News e RedeTV!","url":"https:\/\/www.suno.com.br\/noticias\/author\/vanessal-loiolagmail-com\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/engie-egie3-400x200.jpg\" alt=\"Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/radar-engie-egie3-eletrobras-elet3-isa-cteep-trpl4-b3-b3sa3\/\"><h2 class=\"content__title\">Radar: Banco projeta queda nos dividendos da Engie (EGIE3), Eletrobras (ELET3) deve vender fatia na ISA Cteep (TRPL4) e analistas preveem upside para B3 (B3SA3)<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/vanessal-loiolagmail-com\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/8b41117f9780831919eb38da349c3f20?s=96&#038;r=g\" alt=\"Vanessa Loiola\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/vanessal-loiolagmail-com\/\"><span itemprop=\"author\">Vanessa Loiola<\/span><\/a><\/span><time datetime=\"2023-10-30T22:40:59-03:00\" itemprop=\"datePublished\">30\/10\/2023 22:40<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/478666"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/227"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=478666"}],"version-history":[{"count":2,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/478666\/revisions"}],"predecessor-version":[{"id":478738,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/478666\/revisions\/478738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/336256"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=478666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=478666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=478666"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=478666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}