{"id":478265,"date":"2023-10-30T11:28:03","date_gmt":"2023-10-30T14:28:03","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=478265"},"modified":"2023-10-30T11:28:13","modified_gmt":"2023-10-30T14:28:13","slug":"petrobras-petr4-assembleia-gpj","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/","title":{"rendered":"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto; veja quando ser\u00e1"},"content":{"rendered":"<p>A <a href=\"https:\/\/www.suno.com.br\/acoes\/PETR4\/\"><strong>Petrobras <\/strong>(PETR4)<\/a> convocou para o dia 30 de novembro a assembleia geral extraordin\u00e1ria que ir\u00e1 deliberar sobre a cria\u00e7\u00e3o de uma nova reserva de remunera\u00e7\u00e3o de capital e mudan\u00e7as no <a href=\"https:\/\/www.suno.com.br\/artigos\/estatuto-social\/\">estatuto social<\/a>.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto; veja quando ser\u00e1\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Petrobras (PETR4). Foto: iStock<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"254218\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>No manual da<strong> assembleia da Petrobras<\/strong>, publicado pela Comiss\u00e3o de Valores Mobili\u00e1rios (CVM), a estatal reitera que a cria\u00e7\u00e3o de nova reserva estatu\u00e1ria servir\u00e1 &#8220;para assegurar recursos para remunera\u00e7\u00e3o do capital, em alinhamento com a pol\u00edtica de remunera\u00e7\u00e3o ao acionista&#8221;.<\/p>\n\n\n\n<p>Ainda de acordo com texto, o <strong>estatuto social da Petrobras<\/strong> ser\u00e1 alterado para prever que &#8220;somente considerar\u00e1 hip\u00f3teses de conflito de interesses formal nos casos expressamente previstos em lei&#8221;, alinhando o documento \u00e0 interpreta\u00e7\u00e3o atual da <strong>Lei das Estatais<\/strong>.<\/p>\n\n\n\n<p>No fim de semana, a Justi\u00e7a de S\u00e3o Paulo negou um pedido do deputado federal Leonardo Siqueira (Novo-SP) para que n\u00e3o fosse autorizada a realiza\u00e7\u00e3o da assembleia da Petrobras.<\/p>\n\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"readToo\">\n\t\t\t\t<span class=\"readToo__title\">Leia mais<\/span>\n\t\t\t\t<ul class=\"readToo__list\">\n\t\t\t<li><a href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-copel-cple6-venda-ueg-araucaria-uega-jvj\/\">Petrobras (PETR4) e Copel (CPLE6) anunciam novas informa\u00e7\u00f5es sobre venda de ativo; Veja detalhes<\/a><\/li><li><a href=\"https:\/\/www.suno.com.br\/noticias\/producao-petrobras-petr4-3t23-jvj\/\">Petrobras (PETR4) aumenta produ\u00e7\u00e3o anual em 8,8% no 3T23 e registra dois novos recordes<\/a><\/li><li><a href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-fertilizantes-bolivia-gpj\/\">Petrobras (PETR4) nega instala\u00e7\u00e3o de f\u00e1brica de fertilizantes na Bol\u00edvia<\/a><\/li>\t\t<\/ul>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Petrobras (PETR4) pagar\u00e1 quantos bilh\u00f5es em dividendos ap\u00f3s 3T23?<\/h2>\n\n\n\n<p>A\u00a0Petrobras anunciou recentemente um resultado operacional s\u00f3lido no terceiro trimestre, segundo analistas do\u00a0<a href=\"https:\/\/www.suno.com.br\/artigos\/sell-side\/\" target=\"_blank\" rel=\"noreferrer noopener\">sell side<\/a>.<\/p>\n\n\n\n<p>Com isso, os mais recentes n\u00fameros aumentam expectativas para o&nbsp;<strong>resultado da Petrobras<\/strong>, deixando proje\u00e7\u00f5es mais otimistas nas planilhas de especialistas de research.<\/p>\n\n\n\n<p>Isso especialmente em rela\u00e7\u00e3o ao seu Ebitda (lucro antes de juros, impostos,&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/depreciacao-amortizacao\/\" target=\"_blank\" rel=\"noreferrer noopener\">deprecia\u00e7\u00e3o e amortiza\u00e7\u00e3o<\/a>) e ao pagamento de&nbsp;<strong>dividendos da Petrobras<\/strong>.<\/p>\n\n\n\n<p>De acordo com o Santander, o Ebitda deve ser de US$ 13,7 bilh\u00f5es, juntamente com um pagamento de&nbsp;<a target=\"_blank\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" rel=\"noreferrer noopener\">dividendos<\/a>&nbsp;de US$ 3,3 bilh\u00f5es.<\/p>\n\n\n\n<p>O Ita\u00fa BBA \u00e9 ainda mais otimista, projetando um Ebitda de US$ 14,5 bilh\u00f5es, gra\u00e7as aos pre\u00e7os mais elevados do petr\u00f3leo, produ\u00e7\u00e3o robusta e s\u00f3lidos n\u00fameros de vendas relatados recentemente.<\/p>\n\n\n\n<p>O cen\u00e1rio favor\u00e1vel, conforme observado pelo Ita\u00fa BBA, deve permitir um pagamento de&nbsp;<a target=\"_blank\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" rel=\"noreferrer noopener\">dividendos<\/a>&nbsp;de US$ 3,9 bilh\u00f5es, o que implica um rendimento de 4,1%, alinhado com a pol\u00edtica da Petrobras.<\/p>\n\n\n\n<p>O relat\u00f3rio do Santander tamb\u00e9m enfatiza que, al\u00e9m do destaque na produ\u00e7\u00e3o, a Petrobras apresentou margens de refino sequencialmente mais fortes, o que contribui para sua robustez financeira.<\/p>\n\n\n\n<p>Mesmo em meio \u00e0s mudan\u00e7as propostas no estatuto da empresa, o banco mant\u00e9m uma vis\u00e3o positiva sobre a <strong>Petrobras<\/strong>, ressaltando sua habilidade cont\u00ednua de pagar\u00a0<a href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" target=\"_blank\" rel=\"noreferrer noopener\">dividendos<\/a>\u00a0substanciais.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Produ\u00e7\u00e3o da Petrobras no 3T23 traz boa perspectiva, diz Goldman Sachs<\/h2>\n\n\n\n<p>Ap\u00f3s a divulga\u00e7\u00e3o do relat\u00f3rio de produ\u00e7\u00e3o da&nbsp;<strong>PETR4<\/strong>&nbsp;nesta quinta-feira (26), o Goldman Sachs (<a href=\"https:\/\/www.suno.com.br\/bdrs\/gsgi34\/\">GSGI34<\/a>) destacou que os n\u00fameros reportados pela estatal corroboram a expectativa de um resultado forte para a companhia no terceiro trimestre. A Petrobras divulga seu balan\u00e7o financeiro do per\u00edodo no pr\u00f3ximo dia 9 de novembro, ap\u00f3s o&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/fechamento-do-mercado\/\">fechamento do mercado<\/a>.<\/p>\n\n\n\n<p>\u201cAtualmente, estamos 16% acima do consenso da Bloomberg no n\u00edvel de Ebitda, o que acreditamos que pode ser parcialmente atribu\u00eddo \u00e0 produ\u00e7\u00e3o mais forte do que a esperada\u201d, dizem os analistas Bruno Amorim, Jo\u00e3o Frizo e Guilherme Martins.<\/p>\n\n\n\n<p>No segmento de refino em especial, a casa observou uma expans\u00e3o de 6% na venda de derivados de petr\u00f3leo da Petrobras, principalmente impulsionado pela maior demanda sazonal por diesel.<\/p>\n\n\n\n<p>Para o Goldman, a produ\u00e7\u00e3o do combust\u00edvel somado \u00e0s importa\u00e7\u00f5es ficou abaixo dos n\u00edveis do segundo trimestre, enquanto as vendas de diesel foram quase 11% maiores, o que leva o banco a acreditar em um ambiente de pre\u00e7os mais saud\u00e1vel para o material.<\/p>\n\n\n\n<p>\u201cContinuamos vendo riscos de um potencial cen\u00e1rio de baixa, percebido por alguns investidores (abordagem intervencionista na pol\u00edtica de pre\u00e7os e uma elevada aloca\u00e7\u00e3o de investimentos para energias renov\u00e1veis), t\u00e3o menor do que antes. Al\u00e9m disso, continuamos a ver a empresa negociando com uma avalia\u00e7\u00e3o pouco exigente de aproximadamente 17% de&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/fluxo-caixa-livre\/\">fluxo de caixa livre<\/a>&nbsp;em 2024\u2033.<\/p>\n\n\n\n<p>O Goldman tem recomenda\u00e7\u00e3o de \u2018compra\u2019 para as a\u00e7\u00f5es da&nbsp;<strong>Petrobras<\/strong>, com pre\u00e7o-alvo a R$ 46,60 para as&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/acoes-preferenciais\/\">a\u00e7\u00f5es preferenciais<\/a>&nbsp;(PETR3) e R$ 42,40 para as&nbsp;<a target=\"_blank\" href=\"https:\/\/www.suno.com.br\/artigos\/acoes-preferenciais\/\" rel=\"noreferrer noopener\">a\u00e7\u00f5es preferenciais<\/a>&nbsp;(PETR4).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Desempenho das a\u00e7\u00f5es da Petrobras<\/h2>\n\n\n\n<div class=\"pluginQuotation\">\n  <p class=\"ticker\">\n    Cota\u00e7\u00e3o <span>PETR4<\/span>\n  <\/p>\n  <div class=\"info\">\n    <div class=\"leftSide\">\n      Gr\u00e1fico gerado em: 30\/10\/2023    <\/div>\n\t\t\t\t\t<div class=\"rightSide\">\n\t\t\t\t\t<span class=\"period\">\n\t\t\t\t\t\t1 Dia\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t  <\/div>\n\n  <div id=\"chart-d08c3c95e14f8db70b9bbd5d770160ac\" data-block-hash=\"d08c3c95e14f8db70b9bbd5d770160ac\"  class=\"chart\" style=\"width:100%;height:400px;\"><\/div>\n\n  <div class=\"pluginQuotation__footer\">\n    <div class=\"dataChart\">\n\n      <div class=\"dataChart__div1 variation\">\n        <div class=\"value-negative\">\n          -0,67 (-0,24%)        <\/div>\n        <div class=\"text\">\n          Varia\u00e7\u00e3o do per\u00edodo\n        <\/div>\n      <\/div>\n\n      <div class=\"dataChart__div2 minMax\">\n        <div class=\"value\">\n          R$\u00a035,28        <\/div>\n        <div class=\"text\">\n          M\u00ednima\n        <\/div>\n      <\/div>\n\n      <div class=\"dataChart__div3 minMax\">\n        <div class=\"value\">\n          R$\u00a035,62        <\/div>\n        <div class=\"text\">\n          M\u00e1xima\n        <\/div>\n      <\/div>\n\n\t\t\t<div class=\"dataChart__div4 rightSide\">\n\t\t\t\t<div class=\"analiticaSource\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tFonte:\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<img decoding=\"async\" class=\"analiticaLogo\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/plugins\/suno-block-ticker-quotation\/src\/suno-analitica-logo.png\" alt=\"Logo Suno Anal\u00edtica\" \/>\n\t\t\t\t<\/div>\n\n\t\t\t\t<a href=\"https:\/\/www.suno.com.br\/analitica\/acoes\/PETR4\" target=\"_blank\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tVer mais cota\u00e7\u00f5es\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\">\n\t\t\t\t\t\t<path d=\"M4.20996 0L3.50496 0.705L6.29496 3.5H0.209961V4.5H6.29496L3.50496 7.295L4.20996 8L8.20996 4L4.20996 0Z\" fill=\"#D42126\" \/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/a>\n    <\/div>\n\n    <\/div>\n  <\/div>\n<\/div>\n\n\n<script type=\"text\/javascript\">\n  let chart_d08c3c95e14f8db70b9bbd5d770160ac = document.getElementById('chart-d08c3c95e14f8db70b9bbd5d770160ac');\n  let data_json_d08c3c95e14f8db70b9bbd5d770160ac = \"[{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:02\\\",\\\"value\\\":35.62},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:04\\\",\\\"value\\\":35.47},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:06\\\",\\\"value\\\":35.38},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:08\\\",\\\"value\\\":35.28},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:10\\\",\\\"value\\\":35.33},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:12\\\",\\\"value\\\":35.39},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:14\\\",\\\"value\\\":35.41},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:16\\\",\\\"value\\\":35.33},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:18\\\",\\\"value\\\":35.48},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:20\\\",\\\"value\\\":35.44},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:22\\\",\\\"value\\\":35.44},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:24\\\",\\\"value\\\":35.47},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:26\\\",\\\"value\\\":35.53},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:28\\\",\\\"value\\\":35.47},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:30\\\",\\\"value\\\":35.62},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:32\\\",\\\"value\\\":35.54},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:34\\\",\\\"value\\\":35.32},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:36\\\",\\\"value\\\":35.43},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:38\\\",\\\"value\\\":35.4},{\\\"date\\\":\\\"30\\\\\\\/10\\\\\\\/23 10:40\\\",\\\"value\\\":35.38}]\";\n  let isPositive_d08c3c95e14f8db70b9bbd5d770160ac = \"\";\n\n  let color_d08c3c95e14f8db70b9bbd5d770160ac = isPositive_d08c3c95e14f8db70b9bbd5d770160ac ? '#3AB53A' : '#D92C2D';\n\n  let data_d08c3c95e14f8db70b9bbd5d770160ac = JSON.parse(data_json_d08c3c95e14f8db70b9bbd5d770160ac);\n\n  const result_d08c3c95e14f8db70b9bbd5d770160ac = {\n    date: [],\n    value: [],\n  };\n\n  data_d08c3c95e14f8db70b9bbd5d770160ac.forEach((item) => {\n    result_d08c3c95e14f8db70b9bbd5d770160ac.date.push(item.date);\n    result_d08c3c95e14f8db70b9bbd5d770160ac.value.push(Number(item.value));\n  });\n\n  let option_d08c3c95e14f8db70b9bbd5d770160ac = {\n    \/\/ variavel de cor global\n    color: [color_d08c3c95e14f8db70b9bbd5d770160ac],\n    title: {\n      text: '',\n    },\n    tooltip: {\n      trigger: 'axis',\n      axisPointer: {\n        type: 'cross',\n        label: {\n          \/\/ cor dos valores em X e Y\n          backgroundColor: color_d08c3c95e14f8db70b9bbd5d770160ac,\n          formatter: (value) => {\n            if (typeof value.value === 'number') {\n              return Number(value.value).toLocaleString('pt-br', {\n                style: 'currency',\n                currency: 'BRL'\n              });\n            }\n            return value.value;\n          },\n        },\n      },\n      valueFormatter: (value) => Number(value).toLocaleString('pt-br', {\n        style: 'currency',\n        currency: 'BRL'\n      }),\n    },\n    legend: {\n      \/\/ data: ['Valor de Fechamento'],\n      show: false,\n    },\n    toolbox: {\n      feature: {\n        saveAsImage: {\n          show: false,\n        },\n      },\n    },\n    grid: {\n      left: '0px',\n      right: '0px',\n      bottom: '0px',\n      containLabel: true,\n    },\n    xAxis: [{\n      type: 'category',\n      data: result_d08c3c95e14f8db70b9bbd5d770160ac.date,\n      boundaryGap: true,\n    }],\n    yAxis: [{\n      type: 'value',\n      min: Math.min(...result_d08c3c95e14f8db70b9bbd5d770160ac.value),\n      max: Math.max(...result_d08c3c95e14f8db70b9bbd5d770160ac.value),\n      axisLabel: {\n        formatter: (value) => value.toLocaleString('pt-br', {\n          style: 'currency',\n          currency: 'BRL'\n        }),\n      },\n    }],\n    series: [{\n      name: 'Valor de Fechamento',\n      type: 'line',\n      stack: 'Total',\n      \/\/ cor do grafico\n      areaStyle: {},\n      emphasis: {\n        focus: 'series',\n      },\n      data: result_d08c3c95e14f8db70b9bbd5d770160ac.value,\n      \/\/ cor da linha\n      lineStyle: {\n        color: color_d08c3c95e14f8db70b9bbd5d770160ac,\n      },\n    }, ],\n  };\n\n\twindow.chart_d08c3c95e14f8db70b9bbd5d770160ac = {\n\t\tel: chart_d08c3c95e14f8db70b9bbd5d770160ac,\n\t\toption: option_d08c3c95e14f8db70b9bbd5d770160ac\t};\n\n\n<\/script>\n\n\n<p>etr\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/plataforma-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"383162\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Petrobras (PETR4) convocou para o dia 30 de novembro a assembleia geral extraordin\u00e1ria que ir\u00e1 deliberar sobre a cria\u00e7\u00e3o de uma nova reserva de remunera\u00e7\u00e3o de capital e mudan\u00e7as no estatuto social. Petrobras (PETR4). Foto: iStock No manual da assembleia da Petrobras, publicado pela Comiss\u00e3o de Valores Mobili\u00e1rios (CVM), a estatal reitera que a [&hellip;]<\/p>\n","protected":false},"author":313,"featured_media":403562,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[595],"suno_strategy":[],"class_list":["post-478265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-petrobras-petr4"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto<\/title>\n<meta name=\"description\" content=\"A Petrobras convocou a assembleia que ir\u00e1 deliberar sobre a cria\u00e7\u00e3o de uma nova reserva de remunera\u00e7\u00e3o de capital e mudan\u00e7as no estatuto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto\" \/>\n<meta property=\"og:description\" content=\"A Petrobras convocou a assembleia que ir\u00e1 deliberar sobre a cria\u00e7\u00e3o de uma nova reserva de remunera\u00e7\u00e3o de capital e mudan\u00e7as no estatuto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1254\" \/>\n\t<meta property=\"og:image:height\" content=\"836\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanni Porf\u00edrio Jacomino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Porf\u00edrio Jacomino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/\"},\"author\":{\"name\":\"Giovanni Porf\u00edrio Jacomino\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40\"},\"headline\":\"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto; veja quando ser\u00e1\",\"datePublished\":\"2023-10-30T14:28:03+00:00\",\"dateModified\":\"2023-10-30T14:28:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/\"},\"wordCount\":719,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras.jpg\",\"keywords\":[\"Petrobras (PETR4)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/\",\"name\":\"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras.jpg\",\"datePublished\":\"2023-10-30T14:28:03+00:00\",\"dateModified\":\"2023-10-30T14:28:13+00:00\",\"description\":\"A Petrobras convocou a assembleia que ir\u00e1 deliberar sobre a cria\u00e7\u00e3o de uma nova reserva de remunera\u00e7\u00e3o de capital e mudan\u00e7as no estatuto.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras.jpg\",\"width\":1254,\"height\":836,\"caption\":\"Petrobras (PETR4). Foto: iStock\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto; veja quando ser\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40\",\"name\":\"Giovanni Porf\u00edrio Jacomino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g\",\"caption\":\"Giovanni Porf\u00edrio Jacomino\"},\"description\":\"Giovanni Porf\u00edrio Jacomino \u00e9 jornalista formado pela Universidade Estadual de Londrina (UEL) e p\u00f3s-graduado em Produ\u00e7\u00e3o e Pr\u00e1ticas Jornal\u00edsticas na Contemporaneidade na Faculdade C\u00e1sper L\u00edbero (FCL). Foi editor web no Startupi e no Finsiders, atuando ainda como editor no TC Mover, portal de not\u00edcias da TradersClub, fazendo a cobertura de assuntos relacionados ao mercado financeiro interno e externo. Atualmente, \u00e9 Rep\u00f3rter do Suno Not\u00edcias.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto","description":"A Petrobras convocou a assembleia que ir\u00e1 deliberar sobre a cria\u00e7\u00e3o de uma nova reserva de remunera\u00e7\u00e3o de capital e mudan\u00e7as no estatuto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/","og_locale":"pt_BR","og_type":"article","og_title":"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto","og_description":"A Petrobras convocou a assembleia que ir\u00e1 deliberar sobre a cria\u00e7\u00e3o de uma nova reserva de remunera\u00e7\u00e3o de capital e mudan\u00e7as no estatuto.","og_url":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1254,"height":836,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras.jpg","type":"image\/jpeg"}],"author":"Giovanni Porf\u00edrio Jacomino","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Giovanni Porf\u00edrio Jacomino","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/"},"author":{"name":"Giovanni Porf\u00edrio Jacomino","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40"},"headline":"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto; veja quando ser\u00e1","datePublished":"2023-10-30T14:28:03+00:00","dateModified":"2023-10-30T14:28:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/"},"wordCount":719,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras.jpg","keywords":["Petrobras (PETR4)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/","url":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/","name":"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras.jpg","datePublished":"2023-10-30T14:28:03+00:00","dateModified":"2023-10-30T14:28:13+00:00","description":"A Petrobras convocou a assembleia que ir\u00e1 deliberar sobre a cria\u00e7\u00e3o de uma nova reserva de remunera\u00e7\u00e3o de capital e mudan\u00e7as no estatuto.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras.jpg","width":1254,"height":836,"caption":"Petrobras (PETR4). Foto: iStock"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto; veja quando ser\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d0f32748bbca4bee871fa191ee4e2d40","name":"Giovanni Porf\u00edrio Jacomino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efb32e19b730a121cb7a80f41ffec01a?s=96&r=g","caption":"Giovanni Porf\u00edrio Jacomino"},"description":"Giovanni Porf\u00edrio Jacomino \u00e9 jornalista formado pela Universidade Estadual de Londrina (UEL) e p\u00f3s-graduado em Produ\u00e7\u00e3o e Pr\u00e1ticas Jornal\u00edsticas na Contemporaneidade na Faculdade C\u00e1sper L\u00edbero (FCL). Foi editor web no Startupi e no Finsiders, atuando ainda como editor no TC Mover, portal de not\u00edcias da TradersClub, fazendo a cobertura de assuntos relacionados ao mercado financeiro interno e externo. Atualmente, \u00e9 Rep\u00f3rter do Suno Not\u00edcias.","url":"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/petrobras-400x200.jpg\" alt=\"Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto; veja quando ser\u00e1\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-assembleia-gpj\/\"><h2 class=\"content__title\">Petrobras (PETR4) convoca assembleia sobre mudan\u00e7as no estatuto; veja quando ser\u00e1<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/DSCF4115-1-1-150x150.webp\" alt=\"Giovanni Porf\u00edrio Jacomino\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanni-porfiriosuno-com-br\/\"><span itemprop=\"author\">Giovanni Porf\u00edrio Jacomino<\/span><\/a><\/span><time datetime=\"2023-10-30T11:28:03-03:00\" itemprop=\"datePublished\">30\/10\/2023 11:28<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/478265"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/313"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=478265"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/478265\/revisions"}],"predecessor-version":[{"id":478307,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/478265\/revisions\/478307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/403562"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=478265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=478265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=478265"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=478265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}