{"id":472552,"date":"2023-10-18T11:13:51","date_gmt":"2023-10-18T14:13:51","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=472552"},"modified":"2023-10-18T20:39:17","modified_gmt":"2023-10-18T23:39:17","slug":"israel-guerra-hamas-biden-chega-conflito-cpf","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/","title":{"rendered":"Guerra Israel-Hamas: 12\u00ba dia \u00e9 marcado por encontro de Biden com Netanyahu e manifesta\u00e7\u00f5es; pr\u00e9dio da ONU \u00e9 incendiado no L\u00edbano"},"content":{"rendered":"<p>Em meio \u00e0 <strong>guerra em Israel <\/strong>que atrai todos os olhares internacionais, a chegada do presidente dos Estados Unidos, Joe Biden, ao Estado acontece um dia ap\u00f3s uma explos\u00e3o em hospital de Gaza. <\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Guerra Israel-Hamas: 12\u00ba dia \u00e9 marcado por encontro de Biden com Netanyahu e manifesta\u00e7\u00f5es; pr\u00e9dio da ONU \u00e9 incendiado no L\u00edbano\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Israel. Foto: Israel Defense Forces<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>Biden desembarcou em <strong>Tel Aviv<\/strong> nesta quarta-feira (18) simbolizando o apoio dos EUA ao aliado no Oriente M\u00e9dio.<\/p>\n\n\n\n<p>Os EUA pediram que Israel autorizasse ajuda humanit\u00e1ria pelo Sul de Gaza, com caminh\u00f5es de mantimentos entrando pela fronteira com o Egito &#8211; o que foi autorizado pelas autoridades israelenses.<\/p>\n\n\n\n<p>Mas a guerra ganhou outro cap\u00edtulo com a amea\u00e7a do presidente russo Vladimir Putin, que amea\u00e7ou dois porta-avi\u00f5es enviados pelos EUA para dar apoio a Israel. Putin disse que a R\u00fassia pode patrulhar o espa\u00e7o a\u00e9reo na regi\u00e3o com ca\u00e7as armados com m\u00edsseis hipers\u00f4nicos, e afirmou que pretende impedir que Ir\u00e3, aliado da R\u00fassia, entre na guerra.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Biden fala sobre ataque de Israel a hospital em Gaza<\/h2>\n\n\n\n<p>O <strong>presidente dos Estados Unidos <\/strong>encontrou-se com o primeiro-ministro de Israel Benjamin Netanyahu e emitiu algumas declara\u00e7\u00f5es iniciais sobre o<a href=\"https:\/\/www.suno.com.br\/noticias\/onu-conselho-seguranca-guerra-israel-hamas\/\" target=\"_blank\" rel=\"noreferrer noopener\"> bombardeio ao hospital al-Ahli<\/a>, pr\u00f3ximo \u00e0 <strong>Faixa de Gaza,<\/strong> onde estima-se que morreram ao menos 500 pessoas \u2013 autoridades palestinas citam cerca de 870 pessoas. O tom do discurso americano foi de que a resposta de Israel era &#8220;culpa&#8221; do outro lado.<\/p>\n\n\n\n<p>Al\u00e9m disso, <strong>Biden <\/strong>tinha na agenda compromissos marcados na Jord\u00e2nia ap\u00f3s a visita a <strong>Israel<\/strong>. Contudo, ap\u00f3s o bombardeio sua agenda foi esvaziada. <\/p>\n\n\n\n<p>&#8220;Fiquei profundamente triste e indignado com a explos\u00e3o ontem no hospital em Gaza. E com base no que vi, parece que foi feito pelo outro time, n\u00e3o por voc\u00eas&#8221; afirmou o presidente dos EUA. <\/p>\n\n\n\n<p>As For\u00e7as Armadas israelenses, por sua vez, afirmaram que a culpa do ataque \u00e9 do grupo Jihad Isl\u00e2mica, extremistas <strong>palestinos<\/strong>. Para oficializa\u00e7\u00e3o, foi publicado um v\u00eddeo institucional demonstrando o motivo do grupo para condu\u00e7\u00e3o do ataque ter sido conduzido pelo grupo. A pe\u00e7a foi posteriormente apaga.<\/p>\n\n\n\n<p>A Jihad Isl\u00e2mica negou o envolvimento no ataque ao hospital.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">EUA prometem US$ 100 milh\u00f5es em ajuda humanit\u00e1ria a palestinos<\/h2>\n\n\n\n<p>O presidente dos Estados Unidos, Joe Biden, anunciou nesta quarta-feira (18) que o pa\u00eds vai destinar US$ 100 milh\u00f5es de ajuda humanit\u00e1ria aos palestinos na Faixa de Gaza e na Cisjord\u00e2nia.<\/p>\n\n\n\n<p>Biden esteve reunido, em Tel Aviv, em Israel, com o primeiro-ministro israelense, Benjamin Netanyahu, para falar sobre o conflito entre Israel e Hamas, no Oriente M\u00e9dio.<\/p>\n\n\n\n<p>\u201cEsse financiamento ajudar\u00e1 a apoiar mais de um milh\u00e3o de pessoas deslocadas e afetadas pelo conflito, fornecendo \u00e1gua pot\u00e1vel, alimentos, produtos de higiene pessoal, assist\u00eancia m\u00e9dica e outras necessidades essenciais. Os Estados Unidos fornecem assist\u00eancia humanit\u00e1ria por meio de parceiros confi\u00e1veis, incluindo ag\u00eancias da ONU e ONGs internacionais\u201d, diz nota divulgada pelo governo norte-americano.<\/p>\n\n\n\n<p>Na nota, os Estados Unidos destacam que os civis \u201cn\u00e3o s\u00e3o culpados e n\u00e3o devem sofrer com o terr\u00edvel terrorismo do Hamas\u201d.<\/p>\n\n\n\n<p>\u201cAs vidas dos civis devem ser protegidas e a assist\u00eancia deve chegar com urg\u00eancia aos necessitados. Continuaremos a trabalhar em estreita colabora\u00e7\u00e3o com os parceiros na regi\u00e3o para enfatizar a import\u00e2ncia de cumprir a lei da guerra, apoiar aqueles que est\u00e3o tentando se refugiar, ou fornecer assist\u00eancia e facilitar o acesso a alimentos, \u00e1gua, cuidados m\u00e9dicos e abrigo\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Declara\u00e7\u00f5es de Biden em Israel<\/h2>\n\n\n\n<p>O desembarque de Biden aconteceu no Aeroporto Internacional Ben-Gurion, onde foi recebido por <strong>Benjamin Netanyahu,<\/strong> o primeiro-ministro de Israel, e pelo presidente de Israel, Isaac Herzog. <\/p>\n\n\n\n<p>Na pista de pouso, os representantes trocaram abra\u00e7os e algumas palavras.<\/p>\n\n\n\n<p>&#8220;Desde o ataque, vemos o ataque sendo descrito como o 11 de setembro de Israel. para uma terra do tamanho de Israel, o que aconteceu equivale a 15 &#8217;11 de setembros'&#8221;, comparou o presidente dos Estados Unidos em uma coletiva em Israel nesta quarta-feira (18). <\/p>\n\n\n\n<p>&#8220;A escala pode ser diferente, mas eu tenho certeza de que o sentimento \u00e9 mesmo: de choque, dor, raiva. Eu entendo e n\u00e3o podemos olhar para o que aconteceu aqui e n\u00e3o gritar por justi\u00e7a, justi\u00e7a que precisa ser feita. Mas n\u00e3o deixe essa raiva te consumir&#8221;, aconselhou Biden.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-gratuito-investindo-no-exterior\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Investindo-no-exterior.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Investindo-no-exterior.png\"\n\t\t\t\t\tdata-promo-id=\"383161\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Investindo-no-exterior.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Pr\u00e9dio da ONU incendiado no L\u00edbano e amea\u00e7as na Europa<\/h2>\n\n\n\n<p>Algumas horas ap\u00f3s o bombardeio ao hospital, o pr\u00e9dio da <a href=\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-onu-conselho-resolucao-proposta-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\">Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU)<\/a> foi incendiado no <strong>L\u00edbano<\/strong>. <\/p>\n\n\n\n<p>Enquanto isso, eventos na Europa que podem ser relacionados ao antissemitismo tumultuaram a manh\u00e3 desta quarta-feira (18):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Em Roma, uma escola judaica foi fechada ap\u00f3s uma amea\u00e7a de bomba;<\/li>\n\n\n\n<li>Em Berlim, o chancelar Olaf Scholz condenou atos violentos contra uma sinagoga, onde foram arremados coquet\u00e9is molotov;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Conflito no L\u00edbano esquenta<\/h2>\n\n\n\n<p>No L\u00edbano, a <strong>Embaixada dos Estados Unidos <\/strong>em Beirute est\u00e1 em conflito tensionado entre manifestantes palestinos e as for\u00e7as de seguran\u00e7a do pa\u00eds. <\/p>\n\n\n\n<p>Bombas de g\u00e1s s\u00e3o arremessadas contra os manifestantes, que revidaram com pedras.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"383123\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Em meio \u00e0 guerra em Israel que atrai todos os olhares internacionais, a chegada do presidente dos Estados Unidos, Joe Biden, ao Estado acontece um dia ap\u00f3s uma explos\u00e3o em hospital de Gaza. Israel. Foto: Israel Defense Forces Biden desembarcou em Tel Aviv nesta quarta-feira (18) simbolizando o apoio dos EUA ao aliado no Oriente [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":467788,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[926],"suno_strategy":[],"class_list":["post-472552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-israel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guerra em Israel: Biden chega ao Estado em 12\u00ba dia do conflito<\/title>\n<meta name=\"description\" content=\"Al\u00e9m do territ\u00f3rio em guerra em Israel, conflitos s\u00e3o registrados na sede da ONU no L\u00edbano em Roma e Berlim, ap\u00f3s bombardeio em hospital.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerra em Israel: Biden chega ao Estado em 12\u00ba dia do conflito\" \/>\n<meta property=\"og:description\" content=\"Al\u00e9m do territ\u00f3rio em guerra em Israel, conflitos s\u00e3o registrados na sede da ONU no L\u00edbano em Roma e Berlim, ap\u00f3s bombardeio em hospital.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camila Paim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camila Paim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/\"},\"author\":{\"name\":\"Camila Paim\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/f341d3ae5d1cc685176c9a5327cdfdbb\"},\"headline\":\"Guerra Israel-Hamas: 12\u00ba dia \u00e9 marcado por encontro de Biden com Netanyahu e manifesta\u00e7\u00f5es; pr\u00e9dio da ONU \u00e9 incendiado no L\u00edbano\",\"datePublished\":\"2023-10-18T14:13:51+00:00\",\"dateModified\":\"2023-10-18T23:39:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/\"},\"wordCount\":873,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6.jpg\",\"keywords\":[\"Israel\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/\",\"name\":\"Guerra em Israel: Biden chega ao Estado em 12\u00ba dia do conflito\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6.jpg\",\"datePublished\":\"2023-10-18T14:13:51+00:00\",\"dateModified\":\"2023-10-18T23:39:17+00:00\",\"description\":\"Al\u00e9m do territ\u00f3rio em guerra em Israel, conflitos s\u00e3o registrados na sede da ONU no L\u00edbano em Roma e Berlim, ap\u00f3s bombardeio em hospital.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6.jpg\",\"width\":1600,\"height\":1066,\"caption\":\"Israel. Foto: Israel Defense Forces\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Guerra Israel-Hamas: 12\u00ba dia \u00e9 marcado por encontro de Biden com Netanyahu e manifesta\u00e7\u00f5es; pr\u00e9dio da ONU \u00e9 incendiado no L\u00edbano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/f341d3ae5d1cc685176c9a5327cdfdbb\",\"name\":\"Camila Paim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f33728e65febb1aa7ecf6792956f9b20?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f33728e65febb1aa7ecf6792956f9b20?s=96&r=g\",\"caption\":\"Camila Paim\"},\"description\":\"Jornalista formada pela USP, tem experi\u00eancia em reda\u00e7\u00f5es, SEO, Branded Content e Webdesign. Com passagem pelo Jornal da USP, Empiricus e C6 Bank, hoje \u00e9 rep\u00f3rter no Suno Not\u00edcias cobrindo macroeconomia, finan\u00e7as pessoais e startups.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/camila-figueiredosuno-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guerra em Israel: Biden chega ao Estado em 12\u00ba dia do conflito","description":"Al\u00e9m do territ\u00f3rio em guerra em Israel, conflitos s\u00e3o registrados na sede da ONU no L\u00edbano em Roma e Berlim, ap\u00f3s bombardeio em hospital.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/","og_locale":"pt_BR","og_type":"article","og_title":"Guerra em Israel: Biden chega ao Estado em 12\u00ba dia do conflito","og_description":"Al\u00e9m do territ\u00f3rio em guerra em Israel, conflitos s\u00e3o registrados na sede da ONU no L\u00edbano em Roma e Berlim, ap\u00f3s bombardeio em hospital.","og_url":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1600,"height":1066,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6.jpg","type":"image\/jpeg"}],"author":"Camila Paim","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Camila Paim","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/"},"author":{"name":"Camila Paim","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/f341d3ae5d1cc685176c9a5327cdfdbb"},"headline":"Guerra Israel-Hamas: 12\u00ba dia \u00e9 marcado por encontro de Biden com Netanyahu e manifesta\u00e7\u00f5es; pr\u00e9dio da ONU \u00e9 incendiado no L\u00edbano","datePublished":"2023-10-18T14:13:51+00:00","dateModified":"2023-10-18T23:39:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/"},"wordCount":873,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6.jpg","keywords":["Israel"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/","url":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/","name":"Guerra em Israel: Biden chega ao Estado em 12\u00ba dia do conflito","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6.jpg","datePublished":"2023-10-18T14:13:51+00:00","dateModified":"2023-10-18T23:39:17+00:00","description":"Al\u00e9m do territ\u00f3rio em guerra em Israel, conflitos s\u00e3o registrados na sede da ONU no L\u00edbano em Roma e Berlim, ap\u00f3s bombardeio em hospital.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6.jpg","width":1600,"height":1066,"caption":"Israel. Foto: Israel Defense Forces"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Guerra Israel-Hamas: 12\u00ba dia \u00e9 marcado por encontro de Biden com Netanyahu e manifesta\u00e7\u00f5es; pr\u00e9dio da ONU \u00e9 incendiado no L\u00edbano"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/f341d3ae5d1cc685176c9a5327cdfdbb","name":"Camila Paim","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f33728e65febb1aa7ecf6792956f9b20?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f33728e65febb1aa7ecf6792956f9b20?s=96&r=g","caption":"Camila Paim"},"description":"Jornalista formada pela USP, tem experi\u00eancia em reda\u00e7\u00f5es, SEO, Branded Content e Webdesign. Com passagem pelo Jornal da USP, Empiricus e C6 Bank, hoje \u00e9 rep\u00f3rter no Suno Not\u00edcias cobrindo macroeconomia, finan\u00e7as pessoais e startups.","url":"https:\/\/www.suno.com.br\/noticias\/author\/camila-figueiredosuno-com-br\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/Guerra-Israel-Defense-Forces6-400x200.jpg\" alt=\"Guerra Israel-Hamas: 12\u00ba dia \u00e9 marcado por encontro de Biden com Netanyahu e manifesta\u00e7\u00f5es; pr\u00e9dio da ONU \u00e9 incendiado no L\u00edbano\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/israel-guerra-hamas-biden-chega-conflito-cpf\/\"><h2 class=\"content__title\">Guerra Israel-Hamas: 12\u00ba dia \u00e9 marcado por encontro de Biden com Netanyahu e manifesta\u00e7\u00f5es; pr\u00e9dio da ONU \u00e9 incendiado no L\u00edbano<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/camila-figueiredosuno-com-br\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/05\/camila-paim-square-150x150.jpg\" alt=\"Camila Paim\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/camila-figueiredosuno-com-br\/\"><span itemprop=\"author\">Camila Paim<\/span><\/a><\/span><time datetime=\"2023-10-18T11:13:51-03:00\" itemprop=\"datePublished\">18\/10\/2023 11:13<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/472552"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=472552"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/472552\/revisions"}],"predecessor-version":[{"id":472979,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/472552\/revisions\/472979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/467788"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=472552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=472552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=472552"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=472552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}