{"id":464149,"date":"2023-09-29T18:27:08","date_gmt":"2023-09-29T21:27:08","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=464149"},"modified":"2023-09-29T23:23:38","modified_gmt":"2023-09-30T02:23:38","slug":"fii-mxrf11-pagamento-dividendos-outubro-2023-jvj","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/","title":{"rendered":"MXRF11 divulga novo pagamento de dividendos para outubro"},"content":{"rendered":"<p>O fundo imobili\u00e1rio <strong><a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/fundos-imobiliarios\/mxrf11\/\" target=\"_blank\" rel=\"noopener\">MXRF11<\/a> <\/strong>divulgou novos <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" target=\"_blank\" rel=\"noopener\">dividendos<\/a> para o m\u00eas de outubro. O novo valor anunciado foi de R$ 0,11 por cota, mantendo a quantia distribu\u00edda no m\u00eas anterior.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-800x450.jpg\" width=\"800\" height=\"450\" alt=\"MXRF11 divulga novo pagamento de dividendos para outubro\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">SNFF11 anuncia dividendos com retorno de quase 1% ao m\u00eas. Foto: Unsplash<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp2.suno.com.br\/cl\/black-friday-2025\/?utm_campaign=_SNCDF0E4858_\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/10\/Artigos-e-Noticias-Banner-Home-artigos-01-Mobile_-400x300-1-png.webp\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/10\/Artigos-e-Noticias-Banner-Home-artigos-01-Desktop_-1420x240-1-png.webp\"\n\t\t\t\t\tdata-promo-id=\"311259\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/10\/Artigos-e-Noticias-Banner-Home-artigos-01-Desktop_-1420x240-1-png.webp\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>Somente ter\u00e3o direito ao recebimento dos <strong>dividendos do MXRF11<\/strong> os investidores que tiverem comprado e mantido cotas do fundo at\u00e9 o final do preg\u00e3o de hoje (29). A partir disso, o valor ser\u00e1 creditado automaticamente na conta da corretora de valores dos cotistas aptos a receber.<\/p>\n\n\n\n<p>Nesse caso, o pagamento dos novos <strong>rendimentos do MXRF11<\/strong> vai ocorrer em 16 de outubro de 2023. O valor poder\u00e1 ser recebido sem a necessidade de que algum imposto seja pago, uma vez que esse tipo de provento \u00e9 isento de tributa\u00e7\u00e3o.<\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/jbs-jbss3-banco-recomenda-compra-acoes-upside-va\/\">\n\t\t\tJBS (JBSS3): banco recomenda compra das a\u00e7\u00f5es e prev\u00ea valoriza\u00e7\u00e3o de quase 100%: &quot;Top pick do setor&quot;\t\t<\/a>\n\t<\/div>\n\n\n\n\n<p>No m\u00eas anterior, o fundo tamb\u00e9m havia distribu\u00eddo R$ 0,11 por cota. Quando o novo pagamento for concretizado, os dividendos do Maxi Renda somar\u00e3o R$ 1,33 por cota no intervalo de 1 ano.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o \u00e0 cota\u00e7\u00e3o atual do FII, que \u00e9 de R$ 11,07, os dividendos distribu\u00eddos nos \u00faltimos 12 meses correspondem a um retorno de 12,01%.<\/p>\n\n\n\n<div class=\"pluginQuotation\">\n  <p class=\"ticker\">\n    Cota\u00e7\u00e3o <span>MXRF11<\/span>\n  <\/p>\n  <div class=\"info\">\n    <div class=\"leftSide\">\n      Gr\u00e1fico gerado em: 29\/09\/2023    <\/div>\n\t\t\t\t\t<div class=\"rightSide\">\n\t\t\t\t\t<span class=\"period\">\n\t\t\t\t\t\t1 Dia\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t  <\/div>\n\n  <div id=\"chart-673263da82f2b8242c5bec265b69aeba\" data-block-hash=\"673263da82f2b8242c5bec265b69aeba\"  class=\"chart\" style=\"width:100%;height:400px;\"><\/div>\n\n  <div class=\"pluginQuotation__footer\">\n    <div class=\"dataChart\">\n\n      <div class=\"dataChart__div1 variation\">\n        <div class=\"value-positive\">\n          0,82 (+0,09%)        <\/div>\n        <div class=\"text\">\n          Varia\u00e7\u00e3o do per\u00edodo\n        <\/div>\n      <\/div>\n\n      <div class=\"dataChart__div2 minMax\">\n        <div class=\"value\">\n          R$\u00a010,98        <\/div>\n        <div class=\"text\">\n          M\u00ednima\n        <\/div>\n      <\/div>\n\n      <div class=\"dataChart__div3 minMax\">\n        <div class=\"value\">\n          R$\u00a011,08        <\/div>\n        <div class=\"text\">\n          M\u00e1xima\n        <\/div>\n      <\/div>\n\n\t\t\t<div class=\"dataChart__div4 rightSide\">\n\t\t\t\t<div class=\"analiticaSource\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tFonte:\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<img decoding=\"async\" class=\"analiticaLogo\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/plugins\/suno-block-ticker-quotation\/src\/suno-analitica-logo.png\" alt=\"Logo Suno Anal\u00edtica\" \/>\n\t\t\t\t<\/div>\n\n\t\t\t\t<a href=\"https:\/\/www.suno.com.br\/analitica\/fundos-imobiliarios\/MXRF11\" target=\"_blank\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tVer mais cota\u00e7\u00f5es\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\">\n\t\t\t\t\t\t<path d=\"M4.20996 0L3.50496 0.705L6.29496 3.5H0.209961V4.5H6.29496L3.50496 7.295L4.20996 8L8.20996 4L4.20996 0Z\" fill=\"#D42126\" \/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/a>\n    <\/div>\n\n    <\/div>\n  <\/div>\n<\/div>\n\n\n<script type=\"text\/javascript\">\n  let chart_673263da82f2b8242c5bec265b69aeba = document.getElementById('chart-673263da82f2b8242c5bec265b69aeba');\n  let data_json_673263da82f2b8242c5bec265b69aeba = \"[{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:02\\\",\\\"value\\\":10.99},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:04\\\",\\\"value\\\":10.98},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:06\\\",\\\"value\\\":11},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:08\\\",\\\"value\\\":11},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:10\\\",\\\"value\\\":11},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:12\\\",\\\"value\\\":11},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:14\\\",\\\"value\\\":11},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:16\\\",\\\"value\\\":11.01},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:18\\\",\\\"value\\\":11},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:20\\\",\\\"value\\\":11.01},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:22\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:24\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:26\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:28\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:30\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:32\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:34\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:36\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:38\\\",\\\"value\\\":11.03},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:40\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:42\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:44\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:46\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:48\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:50\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:52\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:54\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:56\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 10:58\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:00\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:02\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:04\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:06\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:08\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:10\\\",\\\"value\\\":11.03},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:12\\\",\\\"value\\\":11.02},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:14\\\",\\\"value\\\":11.03},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:16\\\",\\\"value\\\":11.02},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:18\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:20\\\",\\\"value\\\":11.02},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:22\\\",\\\"value\\\":11.03},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:24\\\",\\\"value\\\":11.02},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:26\\\",\\\"value\\\":11.03},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:28\\\",\\\"value\\\":11.03},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:30\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:32\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:34\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:36\\\",\\\"value\\\":11.03},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:38\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:40\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:42\\\",\\\"value\\\":11.03},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:44\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:46\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:48\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:50\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:52\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:54\\\",\\\"value\\\":11.03},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:56\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 11:58\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 12:00\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 12:02\\\",\\\"value\\\":11.03},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 12:04\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 12:06\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 12:08\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 12:10\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 14:50\\\",\\\"value\\\":11.04},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 14:52\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 14:54\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 14:56\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 14:58\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:00\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:02\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:04\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:06\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:08\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:10\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:12\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:14\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:16\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:18\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:20\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:22\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:24\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:26\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:28\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:30\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:32\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:34\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:36\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:38\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:40\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:42\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:44\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:46\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:48\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:50\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:52\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:54\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:56\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 15:58\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:00\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:02\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:04\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:06\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:08\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:10\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:12\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:14\\\",\\\"value\\\":11.06},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:16\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:18\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:20\\\",\\\"value\\\":11.08},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:22\\\",\\\"value\\\":11.05},{\\\"date\\\":\\\"29\\\\\\\/09\\\\\\\/23 16:24\\\",\\\"value\\\":11.08}]\";\n  let isPositive_673263da82f2b8242c5bec265b69aeba = true;\n\n  let color_673263da82f2b8242c5bec265b69aeba = isPositive_673263da82f2b8242c5bec265b69aeba ? '#3AB53A' : '#D92C2D';\n\n  let data_673263da82f2b8242c5bec265b69aeba = JSON.parse(data_json_673263da82f2b8242c5bec265b69aeba);\n\n  const result_673263da82f2b8242c5bec265b69aeba = {\n    date: [],\n    value: [],\n  };\n\n  data_673263da82f2b8242c5bec265b69aeba.forEach((item) => {\n    result_673263da82f2b8242c5bec265b69aeba.date.push(item.date);\n    result_673263da82f2b8242c5bec265b69aeba.value.push(Number(item.value));\n  });\n\n  let option_673263da82f2b8242c5bec265b69aeba = {\n    \/\/ variavel de cor global\n    color: [color_673263da82f2b8242c5bec265b69aeba],\n    title: {\n      text: '',\n    },\n    tooltip: {\n      trigger: 'axis',\n      axisPointer: {\n        type: 'cross',\n        label: {\n          \/\/ cor dos valores em X e Y\n          backgroundColor: color_673263da82f2b8242c5bec265b69aeba,\n          formatter: (value) => {\n            if (typeof value.value === 'number') {\n              return Number(value.value).toLocaleString('pt-br', {\n                style: 'currency',\n                currency: 'BRL'\n              });\n            }\n            return value.value;\n          },\n        },\n      },\n      valueFormatter: (value) => Number(value).toLocaleString('pt-br', {\n        style: 'currency',\n        currency: 'BRL'\n      }),\n    },\n    legend: {\n      \/\/ data: ['Valor de Fechamento'],\n      show: false,\n    },\n    toolbox: {\n      feature: {\n        saveAsImage: {\n          show: false,\n        },\n      },\n    },\n    grid: {\n      left: '0px',\n      right: '0px',\n      bottom: '0px',\n      containLabel: true,\n    },\n    xAxis: [{\n      type: 'category',\n      data: result_673263da82f2b8242c5bec265b69aeba.date,\n      boundaryGap: true,\n    }],\n    yAxis: [{\n      type: 'value',\n      min: Math.min(...result_673263da82f2b8242c5bec265b69aeba.value),\n      max: Math.max(...result_673263da82f2b8242c5bec265b69aeba.value),\n      axisLabel: {\n        formatter: (value) => value.toLocaleString('pt-br', {\n          style: 'currency',\n          currency: 'BRL'\n        }),\n      },\n    }],\n    series: [{\n      name: 'Valor de Fechamento',\n      type: 'line',\n      stack: 'Total',\n      \/\/ cor do grafico\n      areaStyle: {},\n      emphasis: {\n        focus: 'series',\n      },\n      data: result_673263da82f2b8242c5bec265b69aeba.value,\n      \/\/ cor da linha\n      lineStyle: {\n        color: color_673263da82f2b8242c5bec265b69aeba,\n      },\n    }, ],\n  };\n\n\twindow.chart_673263da82f2b8242c5bec265b69aeba = {\n\t\tel: chart_673263da82f2b8242c5bec265b69aeba,\n\t\toption: option_673263da82f2b8242c5bec265b69aeba\t};\n\n\n<\/script>\n\n\n\n<p>O valor anunciado hoje (29) se baseia no exerc\u00edcio de setembro. Os resultados deste m\u00eas, assim como as movimenta\u00e7\u00f5es da carteira do Maxi Renda ser\u00e3o divulgados em outubro, por meio de seu relat\u00f3rio gerencial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a><\/a>Em quais ativos investe o MXRF11?<\/h2>\n\n\n\n<p>Conforme atualiza\u00e7\u00e3o de seu \u00faltimo relat\u00f3rio, o <strong>FII MXRF11<\/strong> ultrapassou a marca de 953 mil investidores, sendo o maior da Bolsa de Valores nesse quesito.<\/p>\n\n\n\n<p>O <strong>Maxi Renda<\/strong> tem como principal <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/estrategia-de-investimento\/\" rel=\"noopener\">estrat\u00e9gia de investimento<\/a> alocar seus recursos em ativos financeiros com lastro imobili\u00e1rio, incluindo CRI, deb\u00eanture, LCI, LH e cotas de FIIs. Outros investimentos que ele poder\u00e1 aderir s\u00e3o os ativos imobili\u00e1rios, como im\u00f3veis comerciais e projetos imobili\u00e1rios residenciais.<\/p>\n\n\n\n<p>At\u00e9 o final de agosto, 77% da carteira do <strong>fundo MXRF11<\/strong> estava alocada em CRIs, enquanto 15% estava aplicada em cotas de fundos imobili\u00e1rios. A parcela remanescente estava distribu\u00edda em permutas financeiras (5%) e caixa (3%).<\/p>\n\n\n\n<p>O lucro registrado em agosto foi de R$ 24,495 milh\u00f5es, dos quais R$ 28,52 milh\u00f5es foram pagos aos investidores em rendimentos. O resultado com CRIs fora de R$ 21,46 milh\u00f5es, j\u00e1 o lucro obtido com FII foi de R$ 3,61 milh\u00f5es.<\/p>\n\n\n\n<p>O resultado foi impactado em agosto de maneira negativa pela defla\u00e7\u00e3o registrada em junho. A gest\u00e3o ainda destacou que grande parte das movimenta\u00e7\u00f5es recentemente feitas na carteira do <strong>MXRF11<\/strong> n\u00e3o trouxeram efeito para o lucro de agosto.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/12\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/12\/Ebook-Acoes-Desktop.webp\"\n\t\t\t\t\tdata-promo-id=\"311260\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/12\/Ebook-Acoes-Desktop.webp\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O fundo imobili\u00e1rio MXRF11 divulgou novos dividendos para o m\u00eas de outubro. O novo valor anunciado foi de R$ 0,11 por cota, mantendo a quantia distribu\u00edda no m\u00eas anterior. SNFF11 anuncia dividendos com retorno de quase 1% ao m\u00eas. Foto: Unsplash Somente ter\u00e3o direito ao recebimento dos dividendos do MXRF11 os investidores que tiverem comprado [&hellip;]<\/p>\n","protected":false},"author":173,"featured_media":332671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[66],"tags":[295,104577],"suno_strategy":[],"class_list":["post-464149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiis","tag-dividendos","tag-mxrf11"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MXRF11 divulga novo pagamento de dividendos para outubro; veja o valor<\/title>\n<meta name=\"description\" content=\"O fundo imobili\u00e1rio MXRF11 anunciou um novo pagamento de dividendos para o m\u00eas de outubro. Veja o valor por cota dos dividendos do MXRF11.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MXRF11 divulga novo pagamento de dividendos para outubro; veja o valor\" \/>\n<meta property=\"og:description\" content=\"O fundo imobili\u00e1rio MXRF11 anunciou um novo pagamento de dividendos para o m\u00eas de outubro. Veja o valor por cota dos dividendos do MXRF11.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1922\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jo\u00e3o Vitor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jo\u00e3o Vitor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/\"},\"author\":{\"name\":\"Jo\u00e3o Vitor\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/87fc6973867c52dd884811905c43afba\"},\"headline\":\"MXRF11 divulga novo pagamento de dividendos para outubro\",\"datePublished\":\"2023-09-29T21:27:08+00:00\",\"dateModified\":\"2023-09-30T02:23:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/\"},\"wordCount\":427,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-scaled.jpg\",\"keywords\":[\"dividendos\",\"MXRF11\"],\"articleSection\":[\"FIIs\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/\",\"name\":\"MXRF11 divulga novo pagamento de dividendos para outubro; veja o valor\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-scaled.jpg\",\"datePublished\":\"2023-09-29T21:27:08+00:00\",\"dateModified\":\"2023-09-30T02:23:38+00:00\",\"description\":\"O fundo imobili\u00e1rio MXRF11 anunciou um novo pagamento de dividendos para o m\u00eas de outubro. Veja o valor por cota dos dividendos do MXRF11.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-scaled.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-scaled.jpg\",\"width\":2560,\"height\":1922,\"caption\":\"SNFF11 anuncia dividendos com retorno de quase 1% ao m\u00eas. Foto: Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FIIs\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/fiis\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MXRF11 divulga novo pagamento de dividendos para outubro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/87fc6973867c52dd884811905c43afba\",\"name\":\"Jo\u00e3o Vitor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2843227ca03ccf8cc7ccca45204c127e?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2843227ca03ccf8cc7ccca45204c127e?s=96&r=g\",\"caption\":\"Jo\u00e3o Vitor\"},\"description\":\"Redator profissional, com atua\u00e7\u00e3o no mercado editorial na produ\u00e7\u00e3o de not\u00edcias e conte\u00fados sobre o mercado de a\u00e7\u00f5es, fundos imobili\u00e1rios e economia popular. Graduando em Engenharia Qu\u00edmica pela Unesp, tamb\u00e9m j\u00e1 atuou como consultor financeiro.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/joao-vitor-jacintho\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MXRF11 divulga novo pagamento de dividendos para outubro; veja o valor","description":"O fundo imobili\u00e1rio MXRF11 anunciou um novo pagamento de dividendos para o m\u00eas de outubro. Veja o valor por cota dos dividendos do MXRF11.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/","og_locale":"pt_BR","og_type":"article","og_title":"MXRF11 divulga novo pagamento de dividendos para outubro; veja o valor","og_description":"O fundo imobili\u00e1rio MXRF11 anunciou um novo pagamento de dividendos para o m\u00eas de outubro. Veja o valor por cota dos dividendos do MXRF11.","og_url":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":2560,"height":1922,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Jo\u00e3o Vitor","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Jo\u00e3o Vitor","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/"},"author":{"name":"Jo\u00e3o Vitor","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/87fc6973867c52dd884811905c43afba"},"headline":"MXRF11 divulga novo pagamento de dividendos para outubro","datePublished":"2023-09-29T21:27:08+00:00","dateModified":"2023-09-30T02:23:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/"},"wordCount":427,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-scaled.jpg","keywords":["dividendos","MXRF11"],"articleSection":["FIIs"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/","url":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/","name":"MXRF11 divulga novo pagamento de dividendos para outubro; veja o valor","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-scaled.jpg","datePublished":"2023-09-29T21:27:08+00:00","dateModified":"2023-09-30T02:23:38+00:00","description":"O fundo imobili\u00e1rio MXRF11 anunciou um novo pagamento de dividendos para o m\u00eas de outubro. Veja o valor por cota dos dividendos do MXRF11.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-scaled.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-scaled.jpg","width":2560,"height":1922,"caption":"SNFF11 anuncia dividendos com retorno de quase 1% ao m\u00eas. Foto: Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"FIIs","item":"https:\/\/www.suno.com.br\/noticias\/fiis\/"},{"@type":"ListItem","position":3,"name":"MXRF11 divulga novo pagamento de dividendos para outubro"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/87fc6973867c52dd884811905c43afba","name":"Jo\u00e3o Vitor","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2843227ca03ccf8cc7ccca45204c127e?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2843227ca03ccf8cc7ccca45204c127e?s=96&r=g","caption":"Jo\u00e3o Vitor"},"description":"Redator profissional, com atua\u00e7\u00e3o no mercado editorial na produ\u00e7\u00e3o de not\u00edcias e conte\u00fados sobre o mercado de a\u00e7\u00f5es, fundos imobili\u00e1rios e economia popular. Graduando em Engenharia Qu\u00edmica pela Unesp, tamb\u00e9m j\u00e1 atuou como consultor financeiro.","url":"https:\/\/www.suno.com.br\/noticias\/author\/joao-vitor-jacintho\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/12\/josh-appel-NeTPASr-bmQ-unsplash-400x200.jpg\" alt=\"MXRF11 divulga novo pagamento de dividendos para outubro\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/fiis\/\">FIIs<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/fii-mxrf11-pagamento-dividendos-outubro-2023-jvj\/\"><h2 class=\"content__title\">MXRF11 divulga novo pagamento de dividendos para outubro<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/joao-vitor-jacintho\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/2843227ca03ccf8cc7ccca45204c127e?s=96&#038;r=g\" alt=\"Jo\u00e3o Vitor Jacintho\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/joao-vitor-jacintho\/\"><span itemprop=\"author\">Jo\u00e3o Vitor Jacintho<\/span><\/a><\/span><time datetime=\"2023-09-29T18:27:08-03:00\" itemprop=\"datePublished\">29\/09\/2023 18:27<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/464149"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/173"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=464149"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/464149\/revisions"}],"predecessor-version":[{"id":464269,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/464149\/revisions\/464269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/332671"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=464149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=464149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=464149"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=464149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}