{"id":455260,"date":"2023-09-12T22:29:50","date_gmt":"2023-09-13T01:29:50","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=455260"},"modified":"2023-09-12T22:30:02","modified_gmt":"2023-09-13T01:30:02","slug":"radar-via-viia3-hapvida-hapv3-itau-itub4","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/","title":{"rendered":"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais&#8217; bilion\u00e1rios para o Ita\u00fa (ITUB4)"},"content":{"rendered":"<p>O&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/conselho-administracao\/\" target=\"_blank\" rel=\"noreferrer noopener\">conselho de administra\u00e7\u00e3o<\/a>&nbsp;da&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/viia3\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Via<\/strong>&nbsp;(VIIA3)<\/a>&nbsp;aprovou uma nova altera\u00e7\u00e3o da denomina\u00e7\u00e3o social da empresa para \u201cGrupo Casas Bahia S.A.\u201d, conforme comunicado nesta ter\u00e7a-feira (12), ap\u00f3s decis\u00e3o tomada em assembleia geral extraordin\u00e1ria.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais&#8217; bilion\u00e1rios para o Ita\u00fa (ITUB4)\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Casas Bahia (BHIA3). Foto: Divulga\u00e7\u00e3o\/ Casas Bahia.<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n\n\n<p>Al\u00e9m da mudan\u00e7a na denomina\u00e7\u00e3o social, a Via informou que a partir do preg\u00e3o do dia 20 de setembro de 2023, suas a\u00e7\u00f5es passar\u00e3o a ser negociadas na bolsa de valores com um novo c\u00f3digo de negocia\u00e7\u00e3o, o&nbsp;<strong>BHIA3<\/strong>.<\/p>\n\n\n\n<p>O ticker BHIA3 vem em substitui\u00e7\u00e3o ao c\u00f3digo atual&nbsp;<strong>VIIA3<\/strong>. O nome de preg\u00e3o da empresa passar\u00e1 a ser somente \u201c<strong>Casas Bahia<\/strong>\u201d, em substitui\u00e7\u00e3o \u00e0 \u201cVia\u201d.<\/p>\n\n\n\n<p>\u201cO novo posicionamento da marca institucional, nova assinatura corporativa e agora a altera\u00e7\u00e3o do ticker para BHIA3 refor\u00e7am a estrat\u00e9gia da companhia de focar no DNA da sua principal bandeira, resgatando o hist\u00f3rico de bons resultados das categorias core, nas quais somos especialistas e reconhecidos como destino de compras\u201d, explicou a Via em seu comunicado.<\/p>\n\n\n\n<p>Outra novidade anunciada foi a retomada do uso do&nbsp;<strong>slogan da Casas Bahia<\/strong>, identificado por muitos anos no Brasil como: \u201cdedica\u00e7\u00e3o total a voc\u00ea\u201d.<\/p>\n\n\n\n<p>Conforme noticiado pelo Valor em meados de agosto, a mudan\u00e7a no nome social da Via j\u00e1 estava sendo discutida nesse per\u00edodo.<\/p>\n\n\n\n<p>Al\u00e9m de Via, confira outros destaques desta ter\u00e7a-feira:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hapvida (HAPV3): analistas explicam por que elevaram o pre\u00e7o-alvo dos pap\u00e9is; a\u00e7\u00f5es fecham em alta&nbsp;<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O Ita\u00fa BBA elevou o pre\u00e7o-alvo das a\u00e7\u00f5es da&nbsp;<strong>Hapvida<\/strong>&nbsp;(HAPV3), ap\u00f3s resultados s\u00f3lidos no 2\u00ba trimestre de 2023 (2T23). Em relat\u00f3rio divulgado nesta ter\u00e7a-feira (12), a institui\u00e7\u00e3o financeira classifica a Hapvida como a favorita no setor de sa\u00fade, recomendando compra. Hoje \u00e0 tarde, as a\u00e7\u00f5es da companhia sobem no Ibovespa.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cAp\u00f3s resultados s\u00f3lidos do&nbsp;<strong>2T23 da Hapvida<\/strong>, estamos revisando nossas proje\u00e7\u00f5es para&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/HAPV3\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hapvida (HAPV3)<\/a>&nbsp;para cima em todos os aspectos. Nosso novo&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/valor-justo\/\" target=\"_blank\" rel=\"noreferrer noopener\">valor justo<\/a>&nbsp;para o final de 2024 \u00e9 de R$ 7 por a\u00e7\u00e3o [antes era R$ 6]\u201d, cita a equipe do BBA.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para analistas, o desempenho fraco&nbsp;<strong>anualizado da Hapvida<\/strong>&nbsp;\u00e9 atribu\u00eddo a fatores macroecon\u00f4micos \u2013 os microecon\u00f4micos t\u00eam menos impacto. Al\u00e9m disso, o BBA aponta que a empresa est\u00e1 negociando com um P\/E (Pre\u00e7o\/Lucro) de 14x em 2024 e 10x em 2025, representando um ponto de entrada atrativo para os investidores.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cOs resultados do 2\u00ba trimestre de 2023 da Hapvida mostraram tend\u00eancias melhores do que as expectativas, concentradas em um crescimento do&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/ticket-medio\/\" target=\"_blank\" rel=\"noreferrer noopener\">ticket m\u00e9dio<\/a>&nbsp;mais r\u00e1pido do que o esperado, que resultou em um MLR melhor do que a sazonalidade sugeriria\u201d, explica o BBA.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Ita\u00fa (ITUB4) deve pagar R$ 6 bilh\u00f5es em \u2018dividendos adicionais\u2019, diz BBI<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estimativas do Bradesco BBI indicam que o&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/ITUB4\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Ita\u00fa&nbsp;<\/strong>Unibanco (ITUB4)<\/a>&nbsp;deve pagar adicionalmente&nbsp;<a href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" target=\"_blank\" rel=\"noreferrer noopener\">dividendos<\/a>&nbsp;de R$ 6 bilh\u00f5es no segundo semestre deste ano.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Com isso, os&nbsp;<strong>dividendos do Ita\u00fa<\/strong>&nbsp;a serem pagos adicionalmente representariam um rendimento (dividend yield) de 2%.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Al\u00e9m disso, o BBI j\u00e1 projeta um payout de 30% para os&nbsp;<strong>dividendos<\/strong>&nbsp;do banco, com distribui\u00e7\u00e3o de R$ 10,2 bilh\u00f5es aos acionistas, mostrando um yield de cerca de 4%.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Com isso, a proje\u00e7\u00e3o \u00e9 de que os&nbsp;<strong>dividendos do Ita\u00fa em 2023<\/strong>&nbsp;somem R$ 16,2 bilh\u00f5es, representando 48% de payout e 6% de dividend yield.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Apesar de os especialistas verem os prov\u00e1veis novos proventos com bons olhos, destacam, em an\u00e1lise, que os n\u00fameros ficam abaixo da mediana do payout dos anos anteriores, que ficou entre 70%-90% entre 2018-2020.<\/li>\n<\/ul>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Minerva (BEEF3): de olho em dividendos maiores e em outro dado operacional, banco recomenda compra das a\u00e7\u00f5es<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O BTG Pactual manteve recomenda\u00e7\u00e3o de compra para as a\u00e7\u00f5es da&nbsp;<strong>Minerva&nbsp;<\/strong>(BEEF3) ap\u00f3s reuni\u00e3o com o alto escal\u00e3o da companhia. Para os analistas, a aquisi\u00e7\u00e3o de ativos da&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/MRFG3\/\" target=\"_blank\" rel=\"noreferrer noopener\">Marfrig (MRFG3)<\/a>&nbsp;pode ser um marco importante na escala global e regional da Minerva.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cPara uma empresa que consistentemente buscou construir sua posi\u00e7\u00e3o como um importante produtor de carne bovina, em algumas das regi\u00f5es de cria\u00e7\u00e3o de gado mais competitivas do mundo, este acordo possui um claro valor estrat\u00e9gico\u201d, explicam os analistas do BTG.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>De acordo com o banco, a&nbsp;<strong>diretoria da Minerva<\/strong>&nbsp;acredita possuir capacidade de gerenciar riscos associados aos pre\u00e7os da carne bovina e flutua\u00e7\u00f5es cambiais. \u201cA&nbsp;<strong>aquisi\u00e7\u00e3o de ativos da Marfrig<\/strong>&nbsp;certamente colocar\u00e1 essa capacidade \u00e0 prova, mas esta dever\u00e1 ser precisamente sua maior fonte de valor.\u201d Ao longo da sua hist\u00f3ria, a Minerva j\u00e1 concluiu 20 aquisi\u00e7\u00f5es.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Al\u00e9m disso, antes da aquisi\u00e7\u00e3o de novos ativos, a Minerva tinha apenas oito plantas com acesso \u00e0 China. Agora, com o acordo entre a Marfrig passa a ter mais nove. Segundo o BTG, integrar as opera\u00e7\u00f5es da frente e de back-office e maximizar a efici\u00eancia e os controles nos novos ativos ser\u00e1 o passo-chave para que eles tenham a flexibilidade necess\u00e1ria para aproveitar diferentes oportunidades de arbitragem.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Diante desse cen\u00e1rio, o BTG recomenda compra das&nbsp;<strong>a\u00e7\u00f5es da Minerva<\/strong>, com pre\u00e7o-alvo de R$ 12.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Via (VIIA3) derrapa, enquanto Magazine Luiza (MGLU3) tem ganhos no Ibovespa; veja motivos<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>As a\u00e7\u00f5es de&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/viia3\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Via&nbsp;<\/strong>(VIIA3)<\/a>&nbsp;oscilaram entre perdas e ganhos, e acabaram fechando em queda \u2013 enquanto as de&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/mglu3\/\" target=\"_blank\" rel=\"noreferrer noopener\">Magazine Luiza (MGLU3)<\/a>&nbsp;tiveram dia positivo no Ibovespa, em linha com a queda na&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/curva-de-juros\/\">curva de juros<\/a>&nbsp;futuros ap\u00f3s a divulga\u00e7\u00e3o dos dados do \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (<strong>IPCA<\/strong>) pela manh\u00e3, principal term\u00f4metro da infla\u00e7\u00e3o oficial no Brasil \u2013 o que tende a mexer com empresas do setor de varejo.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No fechamento, as&nbsp;<strong><a href=\"https:\/\/www.suno.com.br\/artigos\/o-que-sao-acoes-ordinarias-preferenciais-e-units\/\">a\u00e7\u00f5es ordin\u00e1rias<\/a>&nbsp;de Via<\/strong>&nbsp;(VIIA3) ca\u00edram 1,69%, cotadas a R$ 1,16,. J\u00e1 os&nbsp;<strong>pap\u00e9is da&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/MGLU3\/\">Magazine Luiza<\/a><\/strong><a href=\"https:\/\/www.suno.com.br\/acoes\/MGLU3\/\">&nbsp;(MGLU3)<\/a>&nbsp;avan\u00e7aram 2,65%, a R$ 2,61.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (<strong>IPCA<\/strong>), principal term\u00f4metro da infla\u00e7\u00e3o oficial no Brasil, registrou 0,23% em agosto, abaixo do consenso de mercado, que era de aumento de 0,28%. Os dados foram divulgados na manh\u00e3 desta ter\u00e7a-feira (12) pelo&nbsp;<strong>Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE).<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Em 12 meses, a&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/inflacao-acumulada\/\" target=\"_blank\" rel=\"noreferrer noopener\">infla\u00e7\u00e3o acumulada<\/a>&nbsp;no pa\u00eds \u00e9 de 4,61%, tamb\u00e9m abaixo das expectativas do mercado, que era de +4,67%. Levando em considera\u00e7\u00e3o apenas os meses de 2023, a alta \u00e9 de 3,23%.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cCom os dados do IPCA vindo menores do que o esperado e a&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/curva-de-juros\/\"><strong>curva de juros<\/strong><\/a>&nbsp;inteira caindo, principalmente na parte do meio, que mostra mais ou menos uma expectativa de taxa final menor, incentiva bastante essas empresas mais endividadas. A parte de servi\u00e7os vindo mais baixa, permitindo pensar em uma taxa final de Selic menor no ano que vem, estimula olhar empresas que ter\u00e3o um al\u00edvio maior\u201d, diz Gustavo Cruz, analista da RB Investimentos.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sobre as empresas em espec\u00edfico, Cruz acredita em um impacto maior em rela\u00e7\u00e3o \u00e0 Via, diante de toda a desconfian\u00e7a de sua reestrutura\u00e7\u00e3o, anunciada recentemente, ao contr\u00e1rio de uma de suas principais concorrentes.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201cA Magazine Luiza j\u00e1 consegue ter uma alta mais consider\u00e1vel. Acho at\u00e9 que ainda seja considerada pelos gestores uma empresa bem promissora e que, embora tenha um ambiente de concorr\u00eancia bem mais dif\u00edcil do que nos \u00faltimos anos, ela deve ter um momento mais promissor no pr\u00f3ximo ano\u201d, acrescentou.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Ambev (ABEV3) entra na mira da Receita Federal por \u2018opera\u00e7\u00f5es irregulares\u2019 no pagamento de IR; a\u00e7\u00f5es caem<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/receita-federal\/\" target=\"_blank\" rel=\"noreferrer noopener\">Receita Federal<\/a>&nbsp;questionou a&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/ABEV3\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Ambev<\/strong>&nbsp;(ABEV3)<\/a>&nbsp;sobre as opera\u00e7\u00f5es ligadas ao pagamento de imposto de renda sobre lucros no exterior, informa o Broadcast. As a\u00e7\u00f5es da empresa caem nesta ter\u00e7a (12) no Ibovespa.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O centro dos questionamentos foi a pr\u00e1tica de restitui\u00e7\u00e3o bilion\u00e1ria de impostos que a Ambev pagou l\u00e1 fora.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Em suma, a cervejaria, assim como outras companhias, faz compensa\u00e7\u00e3o do imposto de renda devido no Brasil com o imposto de renda anual pago pelas empresas multinacionais brasileiras no exterior.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Na pr\u00e1tica, a companhia usa o Imposto de Renda pago no exterior para abater no Imposto de Renda e CSLL que s\u00e3o pagos mensalmente no Brasil.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Segundo a Receita Federal, a pr\u00e1tica \u00e9 irregular, j\u00e1 que \u00e9 como se o governo pagasse o imposto que a companhia recolheu em outro pa\u00eds.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">PL das deb\u00eantures de infraestrutura \u00e9 aprovado pela CAE do Senado<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A Comiss\u00e3o de Assuntos Econ\u00f4micos (CAE) do Senado aprovou nesta ter\u00e7a-feira (12), o relat\u00f3rio do projeto de lei dos&nbsp;<strong><a href=\"https:\/\/www.suno.com.br\/noticias\/suzano-suzb3-aprova-emissao-debentures-gpj\/\" target=\"_blank\" rel=\"noreferrer noopener\">deb\u00eantures de infraestrutura<\/a><\/strong>. O PL segue agora para a an\u00e1lise do plen\u00e1rio do Senado.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O texto segue o j\u00e1 aprovado na&nbsp;<strong>Comiss\u00e3o de Infraestrutura do Senado<\/strong>, com uma \u00fanica mudan\u00e7a em rela\u00e7\u00e3o \u00e0s al\u00edquotas de&nbsp;<a href=\"https:\/\/www.suno.com.br\/guias\/imposto-de-renda-guia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Imposto de Renda<\/a>&nbsp;incidentes sobre os rendimentos desses t\u00edtulos.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O relator, senador Rog\u00e9rio Carvalho (PT-SE), votou a favor do PL, que permite a&nbsp;<strong>emiss\u00e3o de deb\u00eantures<\/strong>&nbsp;voltados especificamente a a\u00e7\u00f5es de infraestrutura.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Diferente dos deb\u00eantures incentivados, em que o benef\u00edcio fiscal fica com o comprador do papel (ou seja, o investidor que adquire o t\u00edtulo no mercado), os de infraestrutura dar\u00e3o incentivos aos emissores (ou seja, a concession\u00e1ria respons\u00e1vel pelo projeto de infraestrutura que emitir o t\u00edtulo para se capitalizar).<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Com isso, os juros que dever\u00e3o ser pagos aos investidores ser\u00e3o deduzidos da base de c\u00e1lculo do&nbsp;<a href=\"https:\/\/www.suno.com.br\/guias\/imposto-de-renda-guia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Imposto de Renda<\/a>&nbsp;e da Contribui\u00e7\u00e3o Social sobre&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lucro L\u00edquido<\/a>&nbsp;(CSLL).<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O projeto \u00e9 tido como uma das prioridades da equipe econ\u00f4mica na pauta legislativa deste segundo semestre.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Como o projeto passou por mudan\u00e7as no Senado, ter\u00e1 de voltar \u00e0 C\u00e2mara para uma \u00faltima an\u00e1lise caso seja aprovado pelos senadores no plen\u00e1rio.<\/li>\n<\/ul>\n\n\n\n<p>Da Via \u00e0 Ambev, essas foram as empresas que se destacaram hoje. Para ler todas as mat\u00e9rias\u00a0<strong><a href=\"https:\/\/www.suno.com.br\/noticias\/todos\/?utm_content=XYOE2ItQuUY.20201113&amp;utm_campaign=Track%2B&amp;utm_medium=video&amp;utm_source=telegram.sunoresearch\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a>.<\/strong><a href=\"https:\/\/lp.suno.com.br\/pv\/sr-premium\/o-proximo-passo-no-seus-investimentos\/?_fs=16412753060-15131594205\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/?_fs=16412753060-15131594205\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/pv\/sr-premium\/o-proximo-passo-no-seus-investimentos\/?_fs=16412753060-15131594205\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/?_fs=16412753060-15131594205\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/?_fs=16412753060-15131594205\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/?_fs=16412753060-15131594205\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/cl\/interno-fiis-distribuicao\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/?utm_source=GoogleAds&amp;utm_medium=search&amp;utm_campaign=11.b.da.0.search&amp;utm_content=1141_responsivo-research-b\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/cl\/interno-fiis-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/cl\/interno-fiis-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"383123\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O&nbsp;conselho de administra\u00e7\u00e3o&nbsp;da&nbsp;Via&nbsp;(VIIA3)&nbsp;aprovou uma nova altera\u00e7\u00e3o da denomina\u00e7\u00e3o social da empresa para \u201cGrupo Casas Bahia S.A.\u201d, conforme comunicado nesta ter\u00e7a-feira (12), ap\u00f3s decis\u00e3o tomada em assembleia geral extraordin\u00e1ria. Casas Bahia (BHIA3). Foto: Divulga\u00e7\u00e3o\/ Casas Bahia. Al\u00e9m da mudan\u00e7a na denomina\u00e7\u00e3o social, a Via informou que a partir do preg\u00e3o do dia 20 de setembro de [&hellip;]<\/p>\n","protected":false},"author":227,"featured_media":429977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[359,497,519,548,563,106935],"suno_strategy":[],"class_list":["post-455260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-ambev-abev3","tag-hapvida-hapv3","tag-itau-unibanco-itub3-itub4","tag-magazine-luiza-mglu3","tag-minerva-beef11-beef3","tag-via-viia3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais&#039; bilion\u00e1rios para o Ita\u00fa (ITUB4)<\/title>\n<meta name=\"description\" content=\"Via anuncia mudan\u00e7as, Hapvida tem pre\u00e7o-alvo elevado em relat\u00f3rio e banco projeta \u2018dividendos adicionais&#039; bilion\u00e1rios para Ita\u00fa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais&#039; bilion\u00e1rios para o Ita\u00fa (ITUB4)\" \/>\n<meta property=\"og:description\" content=\"Via anuncia mudan\u00e7as, Hapvida tem pre\u00e7o-alvo elevado em relat\u00f3rio e banco projeta \u2018dividendos adicionais&#039; bilion\u00e1rios para Ita\u00fa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vanessa Loiola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vanessa Loiola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/\"},\"author\":{\"name\":\"Vanessa Loiola\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/450c455ecff319bab1f1a0e643451479\"},\"headline\":\"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais&#8217; bilion\u00e1rios para o Ita\u00fa (ITUB4)\",\"datePublished\":\"2023-09-13T01:29:50+00:00\",\"dateModified\":\"2023-09-13T01:30:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/\"},\"wordCount\":1751,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia.jpg\",\"keywords\":[\"AMBEV (ABEV3)\",\"Hapvida (HAPV3)\",\"Ita\u00fa Unibanco (ITUB3\/ITUB4)\",\"Magazine Luiza (MGLU3)\",\"Minerva (BEEF11\/BEEF3)\",\"Via (VIIA3)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/\",\"name\":\"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais' bilion\u00e1rios para o Ita\u00fa (ITUB4)\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia.jpg\",\"datePublished\":\"2023-09-13T01:29:50+00:00\",\"dateModified\":\"2023-09-13T01:30:02+00:00\",\"description\":\"Via anuncia mudan\u00e7as, Hapvida tem pre\u00e7o-alvo elevado em relat\u00f3rio e banco projeta \u2018dividendos adicionais' bilion\u00e1rios para Ita\u00fa\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Casas Bahia (BHIA3). Foto: Divulga\u00e7\u00e3o\/ Casas Bahia.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais&#8217; bilion\u00e1rios para o Ita\u00fa (ITUB4)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/450c455ecff319bab1f1a0e643451479\",\"name\":\"Vanessa Loiola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8b41117f9780831919eb38da349c3f20?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8b41117f9780831919eb38da349c3f20?s=96&r=g\",\"caption\":\"Vanessa Loiola\"},\"description\":\"Jornalista formada pela PUC-SP, com experi\u00eancia na cobertura das editorias de economia, finan\u00e7as, bolsa de valores, pol\u00edtica, energia solar e entretenimento. Com passagem pela BM&amp;C News e RedeTV!\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/vanessal-loiolagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais' bilion\u00e1rios para o Ita\u00fa (ITUB4)","description":"Via anuncia mudan\u00e7as, Hapvida tem pre\u00e7o-alvo elevado em relat\u00f3rio e banco projeta \u2018dividendos adicionais' bilion\u00e1rios para Ita\u00fa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/","og_locale":"pt_BR","og_type":"article","og_title":"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais' bilion\u00e1rios para o Ita\u00fa (ITUB4)","og_description":"Via anuncia mudan\u00e7as, Hapvida tem pre\u00e7o-alvo elevado em relat\u00f3rio e banco projeta \u2018dividendos adicionais' bilion\u00e1rios para Ita\u00fa","og_url":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1200,"height":800,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia.jpg","type":"image\/jpeg"}],"author":"Vanessa Loiola","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Vanessa Loiola","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/"},"author":{"name":"Vanessa Loiola","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/450c455ecff319bab1f1a0e643451479"},"headline":"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais&#8217; bilion\u00e1rios para o Ita\u00fa (ITUB4)","datePublished":"2023-09-13T01:29:50+00:00","dateModified":"2023-09-13T01:30:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/"},"wordCount":1751,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia.jpg","keywords":["AMBEV (ABEV3)","Hapvida (HAPV3)","Ita\u00fa Unibanco (ITUB3\/ITUB4)","Magazine Luiza (MGLU3)","Minerva (BEEF11\/BEEF3)","Via (VIIA3)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/","url":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/","name":"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais' bilion\u00e1rios para o Ita\u00fa (ITUB4)","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia.jpg","datePublished":"2023-09-13T01:29:50+00:00","dateModified":"2023-09-13T01:30:02+00:00","description":"Via anuncia mudan\u00e7as, Hapvida tem pre\u00e7o-alvo elevado em relat\u00f3rio e banco projeta \u2018dividendos adicionais' bilion\u00e1rios para Ita\u00fa","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia.jpg","width":1200,"height":800,"caption":"Casas Bahia (BHIA3). Foto: Divulga\u00e7\u00e3o\/ Casas Bahia."},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais&#8217; bilion\u00e1rios para o Ita\u00fa (ITUB4)"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/450c455ecff319bab1f1a0e643451479","name":"Vanessa Loiola","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8b41117f9780831919eb38da349c3f20?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b41117f9780831919eb38da349c3f20?s=96&r=g","caption":"Vanessa Loiola"},"description":"Jornalista formada pela PUC-SP, com experi\u00eancia na cobertura das editorias de economia, finan\u00e7as, bolsa de valores, pol\u00edtica, energia solar e entretenimento. Com passagem pela BM&amp;C News e RedeTV!","url":"https:\/\/www.suno.com.br\/noticias\/author\/vanessal-loiolagmail-com\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/via-viia3-casas-bahia-400x200.jpg\" alt=\"Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais&#8217; bilion\u00e1rios para o Ita\u00fa (ITUB4)\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/radar-via-viia3-hapvida-hapv3-itau-itub4\/\"><h2 class=\"content__title\">Radar: Via (VIIA3) ter\u00e1 nome e ticker novos, Hapvida (HAPV3) tem pre\u00e7o-alvo elevado e banco projeta \u2018dividendos adicionais&#8217; bilion\u00e1rios para o Ita\u00fa (ITUB4)<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/vanessal-loiolagmail-com\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/8b41117f9780831919eb38da349c3f20?s=96&#038;r=g\" alt=\"Vanessa Loiola\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/vanessal-loiolagmail-com\/\"><span itemprop=\"author\">Vanessa Loiola<\/span><\/a><\/span><time datetime=\"2023-09-12T22:29:50-03:00\" itemprop=\"datePublished\">12\/09\/2023 22:29<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/455260"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/227"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=455260"}],"version-history":[{"count":2,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/455260\/revisions"}],"predecessor-version":[{"id":455303,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/455260\/revisions\/455303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/429977"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=455260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=455260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=455260"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=455260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}