{"id":441455,"date":"2023-08-11T11:03:53","date_gmt":"2023-08-11T14:03:53","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=441455"},"modified":"2023-08-11T11:04:04","modified_gmt":"2023-08-11T14:04:04","slug":"destaques-petrobras-petr4-oi-oibr3-via-viia3-va","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/","title":{"rendered":"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado nesta sexta-feira; veja destaques"},"content":{"rendered":"<p>O comunicado da<strong> Petrobras<\/strong> (PETR4), que afirma n\u00e3o existir qualquer previs\u00e3o ou decis\u00e3o de participar do mercado de distribui\u00e7\u00e3o de combust\u00edveis, est\u00e1 entre os destaques desta sexta-feira (11).<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado nesta sexta-feira; veja destaques\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Casas Bahia (BHIA3): a\u00e7\u00f5es chegam a disparar 14,4% na m\u00e1xima do dia e fecham com ganhos de 8,86%. Foto: iStock<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>Tamb\u00e9m est\u00e1 entre os <strong>destaques do mercado financeiro <\/strong>a <a class=\"suno-keyword\" target=\"_blank\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/OIBR3\/\" rel=\"noopener\">Oi (OIBR3)<\/a>, que reportou um preju\u00edzo de R$ 845 milh\u00f5es no segundo trimestre de 2023.<\/p>\n\n\n\n<p>A Via (VIIA3) tamb\u00e9m \u00e9 destaque hoje, depois de apurar um preju\u00edzo l\u00edquido de R$ 492 milh\u00f5es no 2T23.<\/p>\n\n\n\n\n\n<p>Veja os <strong>destaques do mercado financeiro<\/strong> desta sexta-feira:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Petrobras<\/h2>\n\n\n\n<p>A <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/PETR4\/\" target=\"_blank\" rel=\"noopener\">Petrobras (<strong>PETR4<\/strong>)<\/a> voltou a afirmar que n\u00e3o h\u00e1 decis\u00e3o das inst\u00e2ncias competentes na companhia no sentido de adquirir qualquer participa\u00e7\u00e3o no mercado de distribui\u00e7\u00e3o de combust\u00edveis.<\/p>\n\n\n\n<p>Al\u00e9m disso, a companhia ainda informa que no presente momento n\u00e3o conduz an\u00e1lises sobre entrada no mercado de distribui\u00e7\u00e3o de combust\u00edvel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Oi<\/h2>\n\n\n\n<p>A <strong>Oi (OIBR3)<\/strong> reportou um preju\u00edzo de R$ 845 milh\u00f5es no 2T23. No mesmo per\u00edodo de 2022 (2T22), o preju\u00edzo auferido pela empresa tinha sido de R$ 497 milh\u00f5es \u2013 aumento de 70% no 2T23.<\/p>\n\n\n\n<p>A <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/o-que-receita-liquida\/\" target=\"_blank\" rel=\"noopener\">receita l\u00edquida<\/a> consolidada da Oi foi de R$ 2,434 bilh\u00f5es, queda de 11,2% na base anual.<\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/oi-oibr3-resultados-2t23-prejuizo-milionario-jvj\/\">\n\t\t\tOi (OIBR3): preju\u00edzo aumenta 70% no 2T23 e atinge R$ 845 milh\u00f5es\t\t<\/a>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Via<\/h2>\n\n\n\n<p>Dona da Casas Bahia e do Ponto, a <strong>Via (VIIA3)<\/strong> divulgou nesta quinta-feira, 11, o seus resultados do segundo trimestre de 2023. A varejista apurou um preju\u00edzo l\u00edquido de R$ 492 milh\u00f5es.<\/p>\n\n\n\n<p>O <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/ebitda-ajustado\/\" rel=\"noopener\">Ebitda ajustado<\/a> da Via (lucro antes de juros, impostos, deprecia\u00e7\u00f5es e amortiza\u00e7\u00f5es) foi de R$ 469 milh\u00f5es, com queda de 32% frente ao reportado entre abril e junho de 2022, com margem de 9%, 2,7 pontos porcentuais (p.p.) menor do que um ano atr\u00e1s.<\/p>\n\n\n\n<p>Al\u00e9m disso, a companhia divulgou um novo plano de transforma\u00e7\u00e3o e proje\u00e7\u00f5es, com previs\u00e3o de readequa\u00e7\u00e3o do parque de centros de distribui\u00e7\u00e3o, conforme redu\u00e7\u00e3o de estoques, e impacto potencial no LAIR de R$ 90 milh\u00f5es anuais at\u00e9 2025.<\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/via-viia3-prejuizo-resultado-2t23\/\">\n\t\t\tPreju\u00edzo da Via (VIIA3) chega a R$ 492 mi no 2T23; empresa anuncia &#039;plano de transforma\u00e7\u00e3o&#039; e pode fechar at\u00e9 100 lojas\t\t<\/a>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Sanepar<\/h2>\n\n\n\n<p>A<strong> <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/SAPR11\/\" target=\"_blank\" rel=\"noopener\">Sanepar (SAPR11)<\/a><\/strong> anunciou um <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noopener\">lucro l\u00edquido<\/a> de R$ 422,1 milh\u00f5es no segundo trimestre de 2023, representando alta de 80,5% em compara\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior.<\/p>\n\n\n\n<p>O Ebitda alcan\u00e7ou a marca de R$ 663,3 milh\u00f5es, o que reflete um aumento substancial de 49,8% na compara\u00e7\u00e3o anual.<\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/sanepar-sapr11-resultado-balanco-lucro-2t23-evm\/\">\n\t\t\tSanepar (SAPR11) lucra R$ 422 milh\u00f5es, alta de 80%\t\t<\/a>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">B3<\/h2>\n\n\n\n<p>A <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/B3SA3\/\" target=\"_blank\" rel=\"noopener\"><strong>B3 (B3SA3)<\/strong><\/a>, empresa controladora da Bolsa de Valores do Brasil, divulgou seus resultados financeiros, apresentando um <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noopener\">lucro l\u00edquido<\/a> atribu\u00eddo aos acionistas de R$ 1,052 bilh\u00e3o.<\/p>\n\n\n\n<p>O Ebitda recorrente atingiu o total de R$ 1,632 bilh\u00e3o, indicando uma diminui\u00e7\u00e3o de 2,2%.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Sabesp<\/h2>\n\n\n\n<p>A <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/SBSP3\/\" target=\"_blank\" rel=\"noopener\"><strong>Sabesp (SBSP3)<\/strong><\/a> fechou o segundo trimestre de 2023 com <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noopener\">lucro l\u00edquido<\/a> de R$ 743,7 milh\u00f5es, aumento de 76,1% na compara\u00e7\u00e3o anual, quando registrou ganhos de R$ 422,4 milh\u00f5es.<\/p>\n\n\n\n<p>O Ebitda da Sabesp chegou a R$ 2,220 bilh\u00e3o, aumento de 47,1% frente ao mesmo per\u00edodo de 2022.<\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/sabesp-sbsp3-lucro-anual-segundo-trimestre-gpj\/\">\n\t\t\tSabesp (SBSP3): lucro anual salta 76,1% no segundo trimestre, para R$ 743,7 milh\u00f5es\t\t<\/a>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Eneva<\/h2>\n\n\n\n<p>A <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/ENEV3\/\" target=\"_blank\" rel=\"noopener\"><strong>Eneva (ENEV3)<\/strong><\/a> registrou <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noopener\">lucro l\u00edquido<\/a> de R$ 372,3 milh\u00f5es no segundo trimestre deste ano, o que corresponde a um crescimento de 152,7% em rela\u00e7\u00e3o aos R$ 147,3 milh\u00f5es contabilizados no mesmo per\u00edodo de 2022.<\/p>\n\n\n\n<p>O Ebitda da Eneva foi de R$ 197,8 milh\u00f5es entre abril e junho deste ano, acima dos R$ 114 milh\u00f5es no mesmo per\u00edodo de 2022.<\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/eneva-enev3-lucro-liquido-sobe-2t23\/\">\n\t\t\tEneva (ENEV3): lucro sobe para R$ 372,3 milh\u00f5es no 2T23, 152,7% acima na compara\u00e7\u00e3o anual\t\t<\/a>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Unipar<\/h2>\n\n\n\n<p>A <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/UNIP6\/\" target=\"_blank\" rel=\"noopener\"><strong>Unipar (UNIP6)<\/strong><\/a> reportou hoje um <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noopener\">lucro l\u00edquido<\/a> de 185,67 milh\u00f5es no segundo trimestre de 2023, um valor 65,3% menor do que o apurado no mesmo per\u00edodo de 2022.<\/p>\n\n\n\n<p>O Ebitda da Unipar foi de R$ 310,50 milh\u00f5es, o que equivale a uma perda de 53,2% em um ano.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Equatorial<\/h2>\n\n\n\n<p>A Equatorial Energia (EQTL3) reportou um <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" rel=\"noopener\">lucro l\u00edquido<\/a> ajustado de R$ 227 milh\u00f5es, uma alta de 49,2% na compara\u00e7\u00e3o com o mesmo per\u00edodo do ano passado.<\/p>\n\n\n\n<p>O Ebitda em base ajustada avan\u00e7ou 48,6%, para R$ 2,26 bilh\u00f5es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Yduqs<\/h2>\n\n\n\n<p>A <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/yduq3\/\" target=\"_blank\" rel=\"noopener\"><strong>Yduqs (YDUQ3)<\/strong><\/a> anotou um <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noopener\">lucro l\u00edquido<\/a> de R$ 32 milh\u00f5es no segundo trimestre deste ano. O Ebitda totalizou R$ 415,2 milh\u00f5es, crescimento de 36,2%.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Rumo<\/h2>\n\n\n\n<p>A<strong> <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/RAIL3\/\" target=\"_blank\" rel=\"noopener\">Rumo (RAIL3)<\/a><\/strong> registrou um <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noopener\">lucro l\u00edquido<\/a> de R$ 167 milh\u00f5es no 2T23 ante R$ 30 milh\u00f5es apurados em igual per\u00edodo de 2022.<\/p>\n\n\n\n<p>O Ebitda atingiu R$ 1,4 bilh\u00e3o, alta de 21,0% na compara\u00e7\u00e3o anual.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">PetroRec\u00f4ncavo<\/h2>\n\n\n\n<p>A <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/recv3\/\" target=\"_blank\" rel=\"noopener\"><strong>PetroRec\u00f4ncavo (RECV3)<\/strong><\/a> teve <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noopener\">lucro l\u00edquido<\/a> de R$ 177,64 milh\u00f5es no segundo trimestre de 2023 , avan\u00e7o de 35,6% na base anual.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Arezzo &amp;Co<\/h2>\n\n\n\n<p>A <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/ARZZ3\/\" target=\"_blank\" rel=\"noopener\"><strong>Arezzo (ARZZ3)<\/strong><\/a> reportou queda de 7,7% no <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noopener\">lucro l\u00edquido<\/a> recorrente no segundo trimestre de 2023 em rela\u00e7\u00e3o ao ano anterior, de R$ 123,4 milh\u00f5es para R$ 113,9 milh\u00f5es.<\/p>\n\n\n\n<p>O Ebitda foi de R$ 198,2 milh\u00f5es, crescimento de 22,1%.<\/p>\n\n\n\n<p>Os destaques do mercado financeiro do Suno Not\u00edcias mostram os principais acontecimentos que prometem movimentar o mercado durante o dia, como a <strong>Petrobras<\/strong> (PETR4), que deve estar no foco dos investidores ao longo do dia.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"383123\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O comunicado da Petrobras (PETR4), que afirma n\u00e3o existir qualquer previs\u00e3o ou decis\u00e3o de participar do mercado de distribui\u00e7\u00e3o de combust\u00edveis, est\u00e1 entre os destaques desta sexta-feira (11). Casas Bahia (BHIA3): a\u00e7\u00f5es chegam a disparar 14,4% na m\u00e1xima do dia e fecham com ganhos de 8,86%. Foto: iStock Tamb\u00e9m est\u00e1 entre os destaques do mercado [&hellip;]<\/p>\n","protected":false},"author":301,"featured_media":408648,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[286,362,367,464,105039,584,595,106252,354,621,622,673,106935,2363],"suno_strategy":[],"class_list":["post-441455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-acoes","tag-arezzo-arzz3","tag-b3-b3sa3","tag-eneva-enev3","tag-equatorial-eqtl3","tag-oi-oibr3-oibr4","tag-petrobras-petr4","tag-petroreconcavo-recv3","tag-rumo-rail3","tag-sabesp","tag-sanepar-sapr11-sapr3-sapr4","tag-unipar-unip3-unip5-unip6","tag-via-viia3","tag-yduqs-yduq3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado hoje; confira<\/title>\n<meta name=\"description\" content=\"O comunicado da Petrobras (PETR4), que afirma n\u00e3o existir decis\u00e3o de participar do mercado de distribui\u00e7\u00e3o de combust\u00edveis, \u00e9 destaque hoje.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado hoje; confira\" \/>\n<meta property=\"og:description\" content=\"O comunicado da Petrobras (PETR4), que afirma n\u00e3o existir decis\u00e3o de participar do mercado de distribui\u00e7\u00e3o de combust\u00edveis, \u00e9 destaque hoje.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vin\u00edcius Alves\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vin\u00edcius Alves\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/\"},\"author\":{\"name\":\"Vin\u00edcius Alves\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4a180549702d0e236b3e420862bcded3\"},\"headline\":\"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado nesta sexta-feira; veja destaques\",\"datePublished\":\"2023-08-11T14:03:53+00:00\",\"dateModified\":\"2023-08-11T14:04:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/\"},\"wordCount\":800,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta.jpg\",\"keywords\":[\"A\u00e7\u00f5es\",\"Arezzo (ARZZ3)\",\"B3 (B3SA3)\",\"Eneva (ENEV3)\",\"Equatorial (EQTL3)\",\"Oi (OIBR3\/OIBR4)\",\"Petrobras (PETR4)\",\"PetroRec\u00f4ncavo (RECV3)\",\"Rumo (RAIL3)\",\"Sabesp\",\"Sanepar (SAPR11\/SAPR3\/SAPR4)\",\"Unipar (UNIP3\/UNIP5\/UNIP6)\",\"Via (VIIA3)\",\"Yduqs (YDUQ3)\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/\",\"name\":\"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado hoje; confira\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta.jpg\",\"datePublished\":\"2023-08-11T14:03:53+00:00\",\"dateModified\":\"2023-08-11T14:04:04+00:00\",\"description\":\"O comunicado da Petrobras (PETR4), que afirma n\u00e3o existir decis\u00e3o de participar do mercado de distribui\u00e7\u00e3o de combust\u00edveis, \u00e9 destaque hoje.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Casas Bahia (BHIA3): a\u00e7\u00f5es chegam a disparar 14,4% na m\u00e1xima do dia e fecham com ganhos de 8,86%. Foto: iStock\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/mercado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado nesta sexta-feira; veja destaques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4a180549702d0e236b3e420862bcded3\",\"name\":\"Vin\u00edcius Alves\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a95b7fe6d1b813f7907d4f476d5a39e1?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a95b7fe6d1b813f7907d4f476d5a39e1?s=96&r=g\",\"caption\":\"Vin\u00edcius Alves\"},\"description\":\"Jornalista formado na Faculdade C\u00e1sper L\u00edbero. Com passagens pela Ag\u00eancia Estado, InfoMoney e Editora Globo.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/vini08correiagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado hoje; confira","description":"O comunicado da Petrobras (PETR4), que afirma n\u00e3o existir decis\u00e3o de participar do mercado de distribui\u00e7\u00e3o de combust\u00edveis, \u00e9 destaque hoje.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/","og_locale":"pt_BR","og_type":"article","og_title":"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado hoje; confira","og_description":"O comunicado da Petrobras (PETR4), que afirma n\u00e3o existir decis\u00e3o de participar do mercado de distribui\u00e7\u00e3o de combust\u00edveis, \u00e9 destaque hoje.","og_url":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1200,"height":800,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta.jpg","type":"image\/jpeg"}],"author":"Vin\u00edcius Alves","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Vin\u00edcius Alves","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/"},"author":{"name":"Vin\u00edcius Alves","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4a180549702d0e236b3e420862bcded3"},"headline":"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado nesta sexta-feira; veja destaques","datePublished":"2023-08-11T14:03:53+00:00","dateModified":"2023-08-11T14:04:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/"},"wordCount":800,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta.jpg","keywords":["A\u00e7\u00f5es","Arezzo (ARZZ3)","B3 (B3SA3)","Eneva (ENEV3)","Equatorial (EQTL3)","Oi (OIBR3\/OIBR4)","Petrobras (PETR4)","PetroRec\u00f4ncavo (RECV3)","Rumo (RAIL3)","Sabesp","Sanepar (SAPR11\/SAPR3\/SAPR4)","Unipar (UNIP3\/UNIP5\/UNIP6)","Via (VIIA3)","Yduqs (YDUQ3)"],"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/","url":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/","name":"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado hoje; confira","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta.jpg","datePublished":"2023-08-11T14:03:53+00:00","dateModified":"2023-08-11T14:04:04+00:00","description":"O comunicado da Petrobras (PETR4), que afirma n\u00e3o existir decis\u00e3o de participar do mercado de distribui\u00e7\u00e3o de combust\u00edveis, \u00e9 destaque hoje.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta.jpg","width":1200,"height":800,"caption":"Casas Bahia (BHIA3): a\u00e7\u00f5es chegam a disparar 14,4% na m\u00e1xima do dia e fecham com ganhos de 8,86%. Foto: iStock"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/www.suno.com.br\/noticias\/mercado\/"},{"@type":"ListItem","position":3,"name":"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado nesta sexta-feira; veja destaques"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4a180549702d0e236b3e420862bcded3","name":"Vin\u00edcius Alves","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a95b7fe6d1b813f7907d4f476d5a39e1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a95b7fe6d1b813f7907d4f476d5a39e1?s=96&r=g","caption":"Vin\u00edcius Alves"},"description":"Jornalista formado na Faculdade C\u00e1sper L\u00edbero. Com passagens pela Ag\u00eancia Estado, InfoMoney e Editora Globo.","url":"https:\/\/www.suno.com.br\/noticias\/author\/vini08correiagmail-com\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/05\/bolsa-acoes-alta-400x200.jpg\" alt=\"Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado nesta sexta-feira; veja destaques\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mercado\/\">Mercado<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/destaques-petrobras-petr4-oi-oibr3-via-viia3-va\/\"><h2 class=\"content__title\">Petrobras (PETR4), Oi (OIBR3) e Via (VIIA3) agitam mercado nesta sexta-feira; veja destaques<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/vini08correiagmail-com\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2026\/04\/WhatsApp-Image-2026-04-20-at-19.35.48-150x150.webp\" alt=\"Vin\u00edcius Alves\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/vini08correiagmail-com\/\"><span itemprop=\"author\">Vin\u00edcius Alves<\/span><\/a><\/span><time datetime=\"2023-08-11T11:03:53-03:00\" itemprop=\"datePublished\">11\/08\/2023 11:03<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/441455"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/301"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=441455"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/441455\/revisions"}],"predecessor-version":[{"id":441546,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/441455\/revisions\/441546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/408648"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=441455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=441455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=441455"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=441455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}