{"id":424488,"date":"2023-07-03T18:03:10","date_gmt":"2023-07-03T21:03:10","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=424488"},"modified":"2023-07-04T16:31:56","modified_gmt":"2023-07-04T19:31:56","slug":"prio-prio3-anuncia-pagamento-jcp-milionario-gpj","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/","title":{"rendered":"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento milion\u00e1rio de JCP; veja valor por a\u00e7\u00e3o"},"content":{"rendered":"<p>A Petro Rio Jaguar Petr\u00f3leo SA, subsidi\u00e1ria da <strong>PRIO<\/strong>, ex-<a href=\"https:\/\/www.suno.com.br\/acoes\/PRIO3\/\" target=\"_blank\" rel=\"noreferrer noopener\">PetroRio (PRIO3)<\/a>, anunciou na \u00faltima sexta-feira (30) o pagamento de juros sobre capital pr\u00f3prio (JCP).<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento milion\u00e1rio de JCP; veja valor por a\u00e7\u00e3o\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">PRIO Foto: Divulga\u00e7\u00e3o<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>O valor total dos <strong>JCP da subsidi\u00e1ria da PRIO<\/strong> ser\u00e1 de R$ 188,9 milh\u00f5es, equivalente a R$ 0,00037 por a\u00e7\u00e3o. O pagamento ser\u00e1 realizado em at\u00e9 123 dias ap\u00f3s a aprova\u00e7\u00e3o.<\/p>\n\n\n\n<p>O pagamento dos juros sobre capital pr\u00f3prio estar\u00e1 sujeito \u00e0 incid\u00eancia de 15% de Imposto de Renda, na forma da legisla\u00e7\u00e3o vigente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">PRIO: leve alta no lucro do 1T23; entenda os n\u00fameros<\/h2>\n\n\n\n<p>O balan\u00e7o do primeiro trimestre de 2023 (1T23) da<strong>&nbsp;PRIO<\/strong> mostrou uma leve alta de 1% no&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noreferrer noopener\">lucro l\u00edquido<\/a>&nbsp;da empresa, que chegou na casa dos US$ 231 milh\u00f5es. <\/p>\n\n\n\n<p>Entre os principais n\u00fameros do&nbsp;<strong>balan\u00e7o da PRIO<\/strong>&nbsp;do 1T23, destacam-se:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Receita l\u00edquida de US$ 565 milh\u00f5es, alta de 82% ante 1T22;<\/li>\n\n\n\n<li>Ebitda (Lucros antes de juros, impostos, deprecia\u00e7\u00e3o e amortiza\u00e7\u00e3o) ajustado de US$ 379 milh\u00f5es, alta de 66% ante 1T22;<\/li>\n\n\n\n<li>Lucro l\u00edquido de US$ 231 milh\u00f5es, alta de 1% ante 1T22;<\/li>\n<\/ul>\n\n\n\n<p>\u201cApesar dos ambientes macro e geopol\u00edtico desafiadores e do aperto monet\u00e1rio internacional, o primeiro trimestre foi marcado por um significativo aumento de produ\u00e7\u00e3o que atingiu mais de 90 mil barris de \u00f3leo por dia gra\u00e7as ao bem-sucedido Plano de Revitaliza\u00e7\u00e3o de Frade, ao in\u00edcio da opera\u00e7\u00e3o de Albacora Leste e a alta&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/eficiencia-operacional\/\" target=\"_blank\" rel=\"noreferrer noopener\">efici\u00eancia operacional<\/a>&nbsp;alcan\u00e7ada no cluster de Polvo e Tubar\u00e3o Martelo\u201d, destacou Milton Rangel, CFO da PRIO, ao comentar os resultados da empresa.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">Balan\u00e7o: An\u00e1lises do mercado<\/h2>\n\n\n\n<p>Na vis\u00e3o dos analistas da Genial Investimentos Vitor Sousa e Israel Rodrigues, a empresa apresentou resultados ligeiramente abaixo do consenso.<\/p>\n\n\n\n<p>\u201cComo principais motivos para tal performance, citamos a queda na produ\u00e7\u00e3o do campo de Polvo e Tubar\u00e3o Martelo devido a uma parada t\u00e9cnica ao longo de oito dias e a conclus\u00e3o da aquisi\u00e7\u00e3o de Albacora Leste, que naturalmente, tr\u00e1s consigo um custo relacionado a sua transi\u00e7\u00e3o e uma opera\u00e7\u00e3o que ainda deve ser otimizada pela Prio ao longo dos pr\u00f3ximos meses (efici\u00eancia operacional de apenas 64% no trimestre no que diz respeito a produ\u00e7\u00e3o)\u201d, destacaram os especialistas.<\/p>\n\n\n\n<p>O papel conta com recomenda\u00e7\u00e3o de compra na Genial, com o pre\u00e7o-alvo de R$ 60. Enquanto isso, a analista do Ita\u00fa BBA Monique Greco afirma que os&nbsp;<strong>n\u00fameros da PRIO<\/strong>&nbsp;foram \u201cligeiramente acima\u201d das estimativas do banco.<\/p>\n\n\n\n<p>\u201cO&nbsp;<a target=\"_blank\" href=\"https:\/\/www.suno.com.br\/artigos\/ebitda-ajustado\/\" rel=\"noreferrer noopener\">Ebitda ajustado<\/a>&nbsp;foi de US$ 379 milh\u00f5es, acima de nossa estimativa, e 225% superior ao trimestre anterior, devido a um volume recorde de vendas de petr\u00f3leo, compensando a queda nos pre\u00e7os do Brent\u201d, ressaltou a profissional.<\/p>\n\n\n\n<p>No BBA, as a\u00e7\u00f5es da&nbsp;<strong>PRIO<\/strong>&nbsp;contam com recomenda\u00e7\u00e3o&nbsp;<em>outperform<\/em>, equivalente \u00e0 compra, com o pre\u00e7o-alvo de R$ 58. \u201cReafirmamos nossa classifica\u00e7\u00e3o de&nbsp;<em>outperform<\/em>&nbsp;na PRIO, pois a empresa continua a oferecer uma combina\u00e7\u00e3o de ganhos consistentes de&nbsp;<a href=\"https:\/\/www.suno.com.br\/artigos\/eficiencia-operacional\/\" target=\"_blank\" rel=\"noreferrer noopener\">efici\u00eancia operacional<\/a>&nbsp;e fortes perspectivas de crescimento org\u00e2nico e inorg\u00e2nico\u201d, disse a especialista.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cota\u00e7\u00e3o de PRIO<\/h2>\n\n\n\n<p>No fechamento, as a\u00e7\u00f5es ordin\u00e1rias da <strong>PRIO<\/strong> subiram 0,92%, cotadas a R$ 37,42.<\/p>\n\n\n\n<div class=\"pluginQuotation\">\n  <p class=\"ticker\">\n    Cota\u00e7\u00e3o <span>PRIO3<\/span>\n  <\/p>\n  <div class=\"info\">\n    <div class=\"leftSide\">\n      Gr\u00e1fico gerado em: 03\/07\/2023    <\/div>\n\t\t\t\t\t<div class=\"rightSide\">\n\t\t\t\t\t<span class=\"period\">\n\t\t\t\t\t\t1 Dia\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t  <\/div>\n\n  <div id=\"chart-d92a1e321d61bb5ac8dc688fcdaea59b\" data-block-hash=\"d92a1e321d61bb5ac8dc688fcdaea59b\"  class=\"chart\" style=\"width:100%;height:400px;\"><\/div>\n\n  <div class=\"pluginQuotation__footer\">\n    <div class=\"dataChart\">\n\n      <div class=\"dataChart__div1 variation\">\n        <div class=\"value-negative\">\n          -0,85 (-0,32%)        <\/div>\n        <div class=\"text\">\n          Varia\u00e7\u00e3o do per\u00edodo\n        <\/div>\n      <\/div>\n\n      <div class=\"dataChart__div2 minMax\">\n        <div class=\"value\">\n          R$\u00a037,42        <\/div>\n        <div class=\"text\">\n          M\u00ednima\n        <\/div>\n      <\/div>\n\n      <div class=\"dataChart__div3 minMax\">\n        <div class=\"value\">\n          R$\u00a038,65        <\/div>\n        <div class=\"text\">\n          M\u00e1xima\n        <\/div>\n      <\/div>\n\n\t\t\t<div class=\"dataChart__div4 rightSide\">\n\t\t\t\t<div class=\"analiticaSource\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tFonte:\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<img decoding=\"async\" class=\"analiticaLogo\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/plugins\/suno-block-ticker-quotation\/src\/suno-analitica-logo.png\" alt=\"Logo Suno Anal\u00edtica\" \/>\n\t\t\t\t<\/div>\n\n\t\t\t\t<a href=\"https:\/\/www.suno.com.br\/analitica\/acoes\/PRIO3\" target=\"_blank\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\tVer mais cota\u00e7\u00f5es\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9\" height=\"8\" viewBox=\"0 0 9 8\" fill=\"none\">\n\t\t\t\t\t\t<path d=\"M4.20996 0L3.50496 0.705L6.29496 3.5H0.209961V4.5H6.29496L3.50496 7.295L4.20996 8L8.20996 4L4.20996 0Z\" fill=\"#D42126\" \/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/a>\n    <\/div>\n\n    <\/div>\n  <\/div>\n<\/div>\n\n\n<script type=\"text\/javascript\">\n  let chart_d92a1e321d61bb5ac8dc688fcdaea59b = document.getElementById('chart-d92a1e321d61bb5ac8dc688fcdaea59b');\n  let data_json_d92a1e321d61bb5ac8dc688fcdaea59b = \"[{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:02\\\",\\\"value\\\":37.74},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:04\\\",\\\"value\\\":37.9},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:06\\\",\\\"value\\\":38.14},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:08\\\",\\\"value\\\":38.3},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:10\\\",\\\"value\\\":38.17},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:12\\\",\\\"value\\\":38.12},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:14\\\",\\\"value\\\":38.13},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:16\\\",\\\"value\\\":38.12},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:18\\\",\\\"value\\\":38.1},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:20\\\",\\\"value\\\":38.08},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:22\\\",\\\"value\\\":38.11},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:24\\\",\\\"value\\\":38.09},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:26\\\",\\\"value\\\":37.99},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:28\\\",\\\"value\\\":37.97},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:30\\\",\\\"value\\\":38.1},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:32\\\",\\\"value\\\":38.1},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:34\\\",\\\"value\\\":38.07},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:36\\\",\\\"value\\\":38.1},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:38\\\",\\\"value\\\":38.33},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:40\\\",\\\"value\\\":38.39},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:42\\\",\\\"value\\\":38.34},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:44\\\",\\\"value\\\":38.45},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:46\\\",\\\"value\\\":38.6},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:48\\\",\\\"value\\\":38.6},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 10:50\\\",\\\"value\\\":38.65},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:20\\\",\\\"value\\\":38.1},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:22\\\",\\\"value\\\":38.1},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:24\\\",\\\"value\\\":38.1},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:26\\\",\\\"value\\\":38.09},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:28\\\",\\\"value\\\":37.98},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:30\\\",\\\"value\\\":37.96},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:32\\\",\\\"value\\\":37.98},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:34\\\",\\\"value\\\":37.99},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:36\\\",\\\"value\\\":38},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:38\\\",\\\"value\\\":38.01},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:40\\\",\\\"value\\\":38},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:42\\\",\\\"value\\\":38},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:44\\\",\\\"value\\\":38.01},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:46\\\",\\\"value\\\":38.01},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:48\\\",\\\"value\\\":38.04},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:50\\\",\\\"value\\\":38.12},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:52\\\",\\\"value\\\":38.06},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:54\\\",\\\"value\\\":38.04},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:56\\\",\\\"value\\\":37.96},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 12:58\\\",\\\"value\\\":37.94},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 13:00\\\",\\\"value\\\":37.94},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 13:02\\\",\\\"value\\\":37.88},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 13:04\\\",\\\"value\\\":37.85},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 14:48\\\",\\\"value\\\":37.53},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 14:50\\\",\\\"value\\\":37.52},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 14:52\\\",\\\"value\\\":37.57},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 14:54\\\",\\\"value\\\":37.52},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 14:56\\\",\\\"value\\\":37.49},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 14:58\\\",\\\"value\\\":37.48},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:00\\\",\\\"value\\\":37.54},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:02\\\",\\\"value\\\":37.6},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:04\\\",\\\"value\\\":37.64},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:06\\\",\\\"value\\\":37.67},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:08\\\",\\\"value\\\":37.64},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:10\\\",\\\"value\\\":37.63},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:12\\\",\\\"value\\\":37.61},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:14\\\",\\\"value\\\":37.59},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:16\\\",\\\"value\\\":37.58},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:18\\\",\\\"value\\\":37.59},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:20\\\",\\\"value\\\":37.6},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:22\\\",\\\"value\\\":37.59},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:24\\\",\\\"value\\\":37.59},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:26\\\",\\\"value\\\":37.64},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:28\\\",\\\"value\\\":37.65},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:30\\\",\\\"value\\\":37.42},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:32\\\",\\\"value\\\":37.75},{\\\"date\\\":\\\"03\\\\\\\/07\\\\\\\/23 15:34\\\",\\\"value\\\":37.42}]\";\n  let isPositive_d92a1e321d61bb5ac8dc688fcdaea59b = \"\";\n\n  let color_d92a1e321d61bb5ac8dc688fcdaea59b = isPositive_d92a1e321d61bb5ac8dc688fcdaea59b ? '#3AB53A' : '#D92C2D';\n\n  let data_d92a1e321d61bb5ac8dc688fcdaea59b = JSON.parse(data_json_d92a1e321d61bb5ac8dc688fcdaea59b);\n\n  const result_d92a1e321d61bb5ac8dc688fcdaea59b = {\n    date: [],\n    value: [],\n  };\n\n  data_d92a1e321d61bb5ac8dc688fcdaea59b.forEach((item) => {\n    result_d92a1e321d61bb5ac8dc688fcdaea59b.date.push(item.date);\n    result_d92a1e321d61bb5ac8dc688fcdaea59b.value.push(Number(item.value));\n  });\n\n  let option_d92a1e321d61bb5ac8dc688fcdaea59b = {\n    \/\/ variavel de cor global\n    color: [color_d92a1e321d61bb5ac8dc688fcdaea59b],\n    title: {\n      text: '',\n    },\n    tooltip: {\n      trigger: 'axis',\n      axisPointer: {\n        type: 'cross',\n        label: {\n          \/\/ cor dos valores em X e Y\n          backgroundColor: color_d92a1e321d61bb5ac8dc688fcdaea59b,\n          formatter: (value) => {\n            if (typeof value.value === 'number') {\n              return Number(value.value).toLocaleString('pt-br', {\n                style: 'currency',\n                currency: 'BRL'\n              });\n            }\n            return value.value;\n          },\n        },\n      },\n      valueFormatter: (value) => Number(value).toLocaleString('pt-br', {\n        style: 'currency',\n        currency: 'BRL'\n      }),\n    },\n    legend: {\n      \/\/ data: ['Valor de Fechamento'],\n      show: false,\n    },\n    toolbox: {\n      feature: {\n        saveAsImage: {\n          show: false,\n        },\n      },\n    },\n    grid: {\n      left: '0px',\n      right: '0px',\n      bottom: '0px',\n      containLabel: true,\n    },\n    xAxis: [{\n      type: 'category',\n      data: result_d92a1e321d61bb5ac8dc688fcdaea59b.date,\n      boundaryGap: true,\n    }],\n    yAxis: [{\n      type: 'value',\n      min: Math.min(...result_d92a1e321d61bb5ac8dc688fcdaea59b.value),\n      max: Math.max(...result_d92a1e321d61bb5ac8dc688fcdaea59b.value),\n      axisLabel: {\n        formatter: (value) => value.toLocaleString('pt-br', {\n          style: 'currency',\n          currency: 'BRL'\n        }),\n      },\n    }],\n    series: [{\n      name: 'Valor de Fechamento',\n      type: 'line',\n      stack: 'Total',\n      \/\/ cor do grafico\n      areaStyle: {},\n      emphasis: {\n        focus: 'series',\n      },\n      data: result_d92a1e321d61bb5ac8dc688fcdaea59b.value,\n      \/\/ cor da linha\n      lineStyle: {\n        color: color_d92a1e321d61bb5ac8dc688fcdaea59b,\n      },\n    }, ],\n  };\n\n\twindow.chart_d92a1e321d61bb5ac8dc688fcdaea59b = {\n\t\tel: chart_d92a1e321d61bb5ac8dc688fcdaea59b,\n\t\toption: option_d92a1e321d61bb5ac8dc688fcdaea59b\t};\n\n\n<\/script>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/suno-one\/?utm_campaign=_SNC6964518A_\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/09\/400x300-Suno-One-png.webp\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/09\/1420x240-Suno-One-png.webp\"\n\t\t\t\t\tdata-promo-id=\"383121\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/09\/1420x240-Suno-One-png.webp\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>A Petro Rio Jaguar Petr\u00f3leo SA, subsidi\u00e1ria da PRIO, ex-PetroRio (PRIO3), anunciou na \u00faltima sexta-feira (30) o pagamento de juros sobre capital pr\u00f3prio (JCP). PRIO Foto: Divulga\u00e7\u00e3o O valor total dos JCP da subsidi\u00e1ria da PRIO ser\u00e1 de R$ 188,9 milh\u00f5es, equivalente a R$ 0,00037 por a\u00e7\u00e3o. O pagamento ser\u00e1 realizado em at\u00e9 123 dias [&hellip;]<\/p>\n","protected":false},"author":295,"featured_media":424999,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[286,1957,597],"suno_strategy":[],"class_list":["post-424488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-acoes","tag-juros-sobre-capital-proprio-jcp","tag-petrorio-prio3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento de JCP; veja valor<\/title>\n<meta name=\"description\" content=\"A Petro Rio Jaguar Petr\u00f3leo, subsidi\u00e1ria da PRIO, aprovou na \u00faltima sexta (30) o pagamento de juros sobre capital pr\u00f3prio (JCP). Veja!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento de JCP; veja valor\" \/>\n<meta property=\"og:description\" content=\"A Petro Rio Jaguar Petr\u00f3leo, subsidi\u00e1ria da PRIO, aprovou na \u00faltima sexta (30) o pagamento de juros sobre capital pr\u00f3prio (JCP). Veja!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanni Porf\u00edrio Jacomino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Porf\u00edrio Jacomino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/\"},\"author\":{\"name\":\"Giovanni Porf\u00edrio Jacomino\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/217058341e4dbe1f68f3b898b09ca015\"},\"headline\":\"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento milion\u00e1rio de JCP; veja valor por a\u00e7\u00e3o\",\"datePublished\":\"2023-07-03T21:03:10+00:00\",\"dateModified\":\"2023-07-04T19:31:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/\"},\"wordCount\":568,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio.jpg\",\"keywords\":[\"A\u00e7\u00f5es\",\"juros sobre capital pr\u00f3prio (JCP)\",\"PetroRio (PRIO3)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/\",\"name\":\"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento de JCP; veja valor\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio.jpg\",\"datePublished\":\"2023-07-03T21:03:10+00:00\",\"dateModified\":\"2023-07-04T19:31:56+00:00\",\"description\":\"A Petro Rio Jaguar Petr\u00f3leo, subsidi\u00e1ria da PRIO, aprovou na \u00faltima sexta (30) o pagamento de juros sobre capital pr\u00f3prio (JCP). Veja!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio.jpg\",\"width\":1600,\"height\":806,\"caption\":\"PRIO Foto: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento milion\u00e1rio de JCP; veja valor por a\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/217058341e4dbe1f68f3b898b09ca015\",\"name\":\"Giovanni Porf\u00edrio Jacomino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc678fc5559a55f79ada398443281309?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc678fc5559a55f79ada398443281309?s=96&r=g\",\"caption\":\"Giovanni Porf\u00edrio Jacomino\"},\"description\":\"Giovanni Porf\u00edrio Jacomino \u00e9 jornalista formado pela Universidade Estadual de Londrina (UEL) e p\u00f3s-graduado em Produ\u00e7\u00e3o e Pr\u00e1ticas Jornal\u00edsticas na Contemporaneidade na Faculdade C\u00e1sper L\u00edbero (FCL). Foi editor web no Startupi e no Finsiders, atuando ainda como editor no TC Mover, portal de not\u00edcias da TradersClub, fazendo a cobertura de assuntos relacionados ao mercado financeiro interno e externo. Atualmente, \u00e9 Rep\u00f3rter do Suno Not\u00edcias.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/giovanniporfirio01gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento de JCP; veja valor","description":"A Petro Rio Jaguar Petr\u00f3leo, subsidi\u00e1ria da PRIO, aprovou na \u00faltima sexta (30) o pagamento de juros sobre capital pr\u00f3prio (JCP). Veja!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/","og_locale":"pt_BR","og_type":"article","og_title":"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento de JCP; veja valor","og_description":"A Petro Rio Jaguar Petr\u00f3leo, subsidi\u00e1ria da PRIO, aprovou na \u00faltima sexta (30) o pagamento de juros sobre capital pr\u00f3prio (JCP). Veja!","og_url":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1600,"height":806,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio.jpg","type":"image\/jpeg"}],"author":"Giovanni Porf\u00edrio Jacomino","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Giovanni Porf\u00edrio Jacomino","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/"},"author":{"name":"Giovanni Porf\u00edrio Jacomino","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/217058341e4dbe1f68f3b898b09ca015"},"headline":"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento milion\u00e1rio de JCP; veja valor por a\u00e7\u00e3o","datePublished":"2023-07-03T21:03:10+00:00","dateModified":"2023-07-04T19:31:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/"},"wordCount":568,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio.jpg","keywords":["A\u00e7\u00f5es","juros sobre capital pr\u00f3prio (JCP)","PetroRio (PRIO3)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/","url":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/","name":"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento de JCP; veja valor","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio.jpg","datePublished":"2023-07-03T21:03:10+00:00","dateModified":"2023-07-04T19:31:56+00:00","description":"A Petro Rio Jaguar Petr\u00f3leo, subsidi\u00e1ria da PRIO, aprovou na \u00faltima sexta (30) o pagamento de juros sobre capital pr\u00f3prio (JCP). Veja!","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio.jpg","width":1600,"height":806,"caption":"PRIO Foto: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento milion\u00e1rio de JCP; veja valor por a\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/217058341e4dbe1f68f3b898b09ca015","name":"Giovanni Porf\u00edrio Jacomino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc678fc5559a55f79ada398443281309?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc678fc5559a55f79ada398443281309?s=96&r=g","caption":"Giovanni Porf\u00edrio Jacomino"},"description":"Giovanni Porf\u00edrio Jacomino \u00e9 jornalista formado pela Universidade Estadual de Londrina (UEL) e p\u00f3s-graduado em Produ\u00e7\u00e3o e Pr\u00e1ticas Jornal\u00edsticas na Contemporaneidade na Faculdade C\u00e1sper L\u00edbero (FCL). Foi editor web no Startupi e no Finsiders, atuando ainda como editor no TC Mover, portal de not\u00edcias da TradersClub, fazendo a cobertura de assuntos relacionados ao mercado financeiro interno e externo. Atualmente, \u00e9 Rep\u00f3rter do Suno Not\u00edcias.","url":"https:\/\/www.suno.com.br\/noticias\/author\/giovanniporfirio01gmail-com\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/prio-400x200.jpg\" alt=\"Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento milion\u00e1rio de JCP; veja valor por a\u00e7\u00e3o\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/prio-prio3-anuncia-pagamento-jcp-milionario-gpj\/\"><h2 class=\"content__title\">Subsidi\u00e1ria da PRIO (PRIO3) anuncia pagamento milion\u00e1rio de JCP; veja valor por a\u00e7\u00e3o<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanniporfirio01gmail-com\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/07\/WhatsApp-Image-2023-07-10-at-14.08.39-150x150.jpeg\" alt=\"Giovanni Porf\u00edrio Jacomino\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanniporfirio01gmail-com\/\"><span itemprop=\"author\">Giovanni Porf\u00edrio Jacomino<\/span><\/a><\/span><time datetime=\"2023-07-03T18:03:10-03:00\" itemprop=\"datePublished\">03\/07\/2023 18:03<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/424488"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/295"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=424488"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/424488\/revisions"}],"predecessor-version":[{"id":425032,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/424488\/revisions\/425032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/424999"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=424488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=424488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=424488"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=424488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}