{"id":41751,"date":"2019-10-21T11:01:47","date_gmt":"2019-10-21T13:01:47","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=41751"},"modified":"2019-10-21T11:51:51","modified_gmt":"2019-10-21T13:51:51","slug":"knight-therapeutics-adquire-controle-do-grupo-biotoscana","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/","title":{"rendered":"Knight Therapeutics adquire controle do Grupo Biotoscana"},"content":{"rendered":"<p>A <strong>Knight<\/strong> <strong>Therapeutics<\/strong>, sediada no Canad\u00e1, anunciou, nesta segunda-feira (21), a aquisi\u00e7\u00e3o da participa\u00e7\u00e3o de 51,21% no grupo farmac\u00eautico Biotoscana pelo valor total de R$ 595,662 milh\u00f5es. O valor inclui 48,146 milh\u00f5es de a\u00e7\u00f5es ordin\u00e1rias e 6,202 milh\u00f5es de Brazilian Deposit Receipt (BDRs), sendo R$ 10,96 por a\u00e7\u00e3o ou BDR.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana-800x450.webp\" width=\"800\" height=\"450\" alt=\"Knight Therapeutics adquire controle do Grupo Biotoscana\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">Knight Therapeutics adquire controle do Grupo Biotoscana<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n<p>O fato relevante da <strong>Biotoscana<\/strong> assegura que &#8220;a aliena\u00e7\u00e3o de controle est\u00e1 sujeita a determinadas condi\u00e7\u00f5es precedentes usuais neste tipo de opera\u00e7\u00e3o, e n\u00e3o haver\u00e1 submiss\u00e3o ao Conselho Administrativo de Defesa Econ\u00f4mica (CADE)&#8221;, informa o fato relevante.<\/p>\n<p>A companhia ainda comunicou que, por conta do fechamento da aliena\u00e7\u00e3o de controle, a adquirente dever\u00e1 fazer oferta p\u00fablica de a\u00e7\u00f5es e BDRs remanescentes.<\/p>\n<p>A Knight Therapeutics tem como foco principal o licenciamento de produtos farmac\u00eauticos inovadores no Canad\u00e1 e em mercado internacionais.<\/p>\n<p>Ap\u00f3s o t\u00e9rmino dessa transa\u00e7\u00e3o, a Knight lan\u00e7ar\u00e1 uma oferta de compra obrigat\u00f3ria para adquirir os 48,79% que restam da participa\u00e7\u00e3o no Grupo Biotoscana.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/estacio-yduqs-compra-adtalem-brasil-por-2-bilhoes\/\">Veja tamb\u00e9m: Dona da Est\u00e1cio, Yduqs, compra Adtalem Brasil por R$ 2 bilh\u00f5es<\/a><\/p>\n<p>\u201cA combina\u00e7\u00e3o de Knight e GBT cria uma plataforma atraente em mercados grandes e de r\u00e1pido crescimento. O GBT \u00e9 um ajuste estrat\u00e9gico natural, com um modelo de neg\u00f3cios semelhante ao Knight e fortes relacionamentos com parceiros globais\u201d, \u00a0afirmou Jonathan Ross Goodman, CEO da Knight.<\/p>\n<p>A presidente da Knight, Samira Sakhia, tamb\u00e9m comentou a opera\u00e7\u00e3o feita com o Grupo Biotoscana.\u00a0\u201cDepois de uma extensa busca por oportunidades e parceiros na Am\u00e9rica Latina, estamos muito animados em receber a equipe de pessoas talentosas do GBT, que est\u00e3o fundamentalmente alinhadas com a cultura e os principais valores da Knight\u201d<\/p>\n<h2>Eurofarma tamb\u00e9m estava na disputa pela Biotoscana<\/h2>\n<p>Durante a primeira semana do m\u00eas de outubro, a Eurofarma, assim como a canadense Knight Therapeutics, apresentou uma proposta pelo controle da Biotoscana, gerida pela <strong>Essex<\/strong> e a empresa de investimentos <strong>Advent<\/strong>.<\/p>\n<p>Na \u00e9poca, fontes pr\u00f3ximas ao assunto diziam que a Eurofarma estaria mais perto de um acordo com a Biotoscana.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/cl\/impacto-tarifas-trump\/?utm_source=sunoresearch&#038;utm_medium=banner.noticias&#038;utm_campaign=_SNC903E88AA_\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/trump-mobile.webp\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/trump-banner-desktop.webp\"\n\t\t\t\t\tdata-promo-id=\"613126\"\t\t\t\t\t\t\t\t\t\twidth='1000' height='325'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/trump-banner-desktop.webp\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Depois de sua estreia na Bolsa, a companhia de medicamentos avan\u00e7ados come\u00e7ou a dar preju\u00edzo e perdeu importantes licen\u00e7as de medicamentos. Al\u00e9m disso, a Biotoscana perdeu muito por conta da desvaloriza\u00e7\u00e3o cambial na Argentina.<\/p>\n<p>Com a perda de valor, a empresa come\u00e7ou a atrair interesse de outros grupos farmac\u00eauticos com nome forte no mercado. Isso porque a companhia n\u00e3o precisa de investimentos em pesquisa, o que j\u00e1 \u00e9 um grande atrativo para o setor.<\/p>\n<p>&#8220;A <strong>Biotoscana<\/strong> \u00e9 uma empresa que tem um potencial incr\u00edvel dentro de casa, com produtos e pipeline j\u00e1 assinados &#8211; al\u00e9m de um valor de plataforma gigantesco que pode ser destravado ao longo do tempo&#8221;, diz uma fonte pr\u00f3xima a empresa.\u00a0 &#8220;Esse ativo, na m\u00e3o de um estrat\u00e9gico,vale muito dinheiro&#8221;, completou a fonte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Knight Therapeutics, sediada no Canad\u00e1, anunciou, nesta segunda-feira (21), a aquisi\u00e7\u00e3o da participa\u00e7\u00e3o de 51,21% no grupo farmac\u00eautico Biotoscana pelo valor total de R$ 595,662 milh\u00f5es. O valor inclui 48,146 milh\u00f5es de a\u00e7\u00f5es ordin\u00e1rias e 6,202 milh\u00f5es de Brazilian Deposit Receipt (BDRs), sendo R$ 10,96 por a\u00e7\u00e3o ou BDR. Knight Therapeutics adquire controle do [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":41763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[382],"suno_strategy":[],"class_list":["post-41751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-biotoscana-gbio33"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Knight Therapeutics adquire controle do Grupo Biotoscana<\/title>\n<meta name=\"description\" content=\"A Knight Therapeutics anunciou a aquisi\u00e7\u00e3o da participa\u00e7\u00e3o de 51,21% do grupo farmac\u00eautico Biotoscana. Clique aqui para saber mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Knight Therapeutics adquire controle do Grupo Biotoscana\" \/>\n<meta property=\"og:description\" content=\"A Knight Therapeutics anunciou a aquisi\u00e7\u00e3o da participa\u00e7\u00e3o de 51,21% do grupo farmac\u00eautico Biotoscana. Clique aqui para saber mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juliano Passaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juliano Passaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/\"},\"author\":{\"name\":\"Juliano Passaro\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3\"},\"headline\":\"Knight Therapeutics adquire controle do Grupo Biotoscana\",\"datePublished\":\"2019-10-21T13:01:47+00:00\",\"dateModified\":\"2019-10-21T13:51:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/\"},\"wordCount\":504,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana-jpg.webp\",\"keywords\":[\"Biotoscana (GBIO33)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/\",\"name\":\"Knight Therapeutics adquire controle do Grupo Biotoscana\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana-jpg.webp\",\"datePublished\":\"2019-10-21T13:01:47+00:00\",\"dateModified\":\"2019-10-21T13:51:51+00:00\",\"description\":\"A Knight Therapeutics anunciou a aquisi\u00e7\u00e3o da participa\u00e7\u00e3o de 51,21% do grupo farmac\u00eautico Biotoscana. Clique aqui para saber mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana-jpg.webp\",\"width\":960,\"height\":640,\"caption\":\"Knight Therapeutics adquire controle do Grupo Biotoscana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Knight Therapeutics adquire controle do Grupo Biotoscana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3\",\"name\":\"Juliano Passaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g\",\"caption\":\"Juliano Passaro\"},\"description\":\"Juliano Passaro escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal da Suno Research. Antes da Suno, trabalhou no Portal da Band. \u00c9 formado em jornalismo pela Universidade Presbiteriana Mackenzie.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Knight Therapeutics adquire controle do Grupo Biotoscana","description":"A Knight Therapeutics anunciou a aquisi\u00e7\u00e3o da participa\u00e7\u00e3o de 51,21% do grupo farmac\u00eautico Biotoscana. Clique aqui para saber mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/","og_locale":"pt_BR","og_type":"article","og_title":"Knight Therapeutics adquire controle do Grupo Biotoscana","og_description":"A Knight Therapeutics anunciou a aquisi\u00e7\u00e3o da participa\u00e7\u00e3o de 51,21% do grupo farmac\u00eautico Biotoscana. Clique aqui para saber mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":960,"height":640,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana.jpg","type":"image\/jpeg"}],"author":"Juliano Passaro","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Juliano Passaro","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/"},"author":{"name":"Juliano Passaro","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3"},"headline":"Knight Therapeutics adquire controle do Grupo Biotoscana","datePublished":"2019-10-21T13:01:47+00:00","dateModified":"2019-10-21T13:51:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/"},"wordCount":504,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana-jpg.webp","keywords":["Biotoscana (GBIO33)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/","url":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/","name":"Knight Therapeutics adquire controle do Grupo Biotoscana","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana-jpg.webp","datePublished":"2019-10-21T13:01:47+00:00","dateModified":"2019-10-21T13:51:51+00:00","description":"A Knight Therapeutics anunciou a aquisi\u00e7\u00e3o da participa\u00e7\u00e3o de 51,21% do grupo farmac\u00eautico Biotoscana. Clique aqui para saber mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana-jpg.webp","width":960,"height":640,"caption":"Knight Therapeutics adquire controle do Grupo Biotoscana"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Knight Therapeutics adquire controle do Grupo Biotoscana"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3","name":"Juliano Passaro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g","caption":"Juliano Passaro"},"description":"Juliano Passaro escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal da Suno Research. Antes da Suno, trabalhou no Portal da Band. \u00c9 formado em jornalismo pela Universidade Presbiteriana Mackenzie.","url":"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/10\/eb953c8a-biotoscana-400x200.webp\" alt=\"Knight Therapeutics adquire controle do Grupo Biotoscana\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/knight-therapeutics-adquire-controle-do-grupo-biotoscana\/\"><h2 class=\"content__title\">Knight Therapeutics adquire controle do Grupo Biotoscana<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/7cc3efea-whatsapp-image-2019-07-18-at-21.59.33-e1563499821209-150x150.webp\" alt=\"Juliano Passaro\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\"><span itemprop=\"author\">Juliano Passaro<\/span><\/a><\/span><time datetime=\"2019-10-21T11:01:47-03:00\" itemprop=\"datePublished\">21\/10\/2019 11:01<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/41751"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=41751"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/41751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/41763"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=41751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=41751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=41751"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=41751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}