{"id":39712,"date":"2019-10-03T08:58:04","date_gmt":"2019-10-03T11:58:04","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=39712"},"modified":"2019-10-04T10:33:46","modified_gmt":"2019-10-04T13:33:46","slug":"mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/","title":{"rendered":"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra"},"content":{"rendered":"<p>Ap\u00f3s a divulga\u00e7\u00e3o dos planos do <strong>Facebook<\/strong> para a cria\u00e7\u00e3o de sua pr\u00f3pria moeda digital, a Libra, come\u00e7aram a aparecer os primeiros problemas dentro do grupo de empresas envolvido com o projeto.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra-800x450.webp\" width=\"800\" height=\"450\" alt=\"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra <\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n<p>Alguns dos maiores parceiros da <strong>Libra<\/strong>, a <strong>Visa<\/strong> e <strong>Mastercard<\/strong> agora est\u00e3o reconsiderando a sua participa\u00e7\u00e3o no projeto. A rea\u00e7\u00e3o de \u00f3rg\u00e3os e autoridades reguladoras nos EUA e na Europa podem ter influenciado a decis\u00e3o dos parceiros.<\/p>\n<p>Receosos de que a <a href=\"https:\/\/www.suno.com.br\/artigos\/btc\/\"><strong>criptomoeda<\/strong><\/a> do Facebook possa atrair muita aten\u00e7\u00e3o dos entes regulat\u00f3rios, executivos de algumas companhias que estava aliadas ao projeto recusamos os pedidos da maior rede social do mundo para apoiar a moeda digital.<\/p>\n<p>A parceria de empresas do segmento financeiro seria de extrema import\u00e2ncia para a consolida\u00e7\u00e3o da moeda virtual no mercado. Por isso, o Facebook poder\u00e1 encontrar dificuldades para seguir com a cria\u00e7\u00e3o da moeda.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/amazon-lanca-assistente-de-voz-e-novidades-da-linha-echo\/\">Veja tamb\u00e9m: Amazon lan\u00e7a assistente de voz e novidades da linha Echo<\/a><\/p>\n<p>Fontes ligadas aos membros de um grupo envolvido com o desenvolvimento da criptomoeda, a Libra Association, foram convocados para uma reuni\u00e3o em Washington nesta quinta-feira (3) para discutir o futuro do projeto.<\/p>\n<p>No dia 14 de outubro, os executivos dessas empresas ir\u00e3o se reunir em Genebra, na Su\u00ed\u00e7a, para revisar os termos da Libra Association, com o intuito de formar um Conselho de Administra\u00e7\u00e3o para a administra\u00e7\u00e3o da moeda virtual.<\/p>\n<h2>Presidente da SEC n\u00e3o considera a Libra como um ativo<\/h2>\n<p>O presidente da <strong><a href=\"https:\/\/www.suno.com.br\/artigos\/sec\/\">Securities and Exchange Commission (SEC)<\/a><\/strong>, Jay Clayton, se recusou a declarar a uma comiss\u00e3o do Congresso dos Estados Unidos se a moeda digital do Facebook, a Libra, pode ser considerada um ativo.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/asset\/fundos\/suno-fic-fia\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/SUNO-FIC-FIA-400x300-Mobile-Artigos-5.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/SUNO-FIC-FIA-1420x240-Banner-Artigos-1-_-Banner-Materias-4.png\"\n\t\t\t\t\tdata-promo-id=\"478742\"\t\t\t\t\t\t\t\t\t\twidth='2840' height='480'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/SUNO-FIC-FIA-1420x240-Banner-Artigos-1-_-Banner-Materias-4.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>A declara\u00e7\u00e3o foi dada na primeira audi\u00eancia (desde 2007) entre uma comiss\u00e3o do Congresso dos EUA e todos os diretores do SEC, al\u00e9m do presidente da institui\u00e7\u00e3o.<\/p>\n<p>Na Comiss\u00e3o\u00a0de\u00a0Servi\u00e7os Financeiros, juntamente com outros diretores do SEC, Clayton disse que apesar de n\u00e3o ter discutido com o Facebook o plano para a Libra<strong>,<\/strong> ele mant\u00e9m uma pol\u00edtica de &#8220;portas abertas&#8221;.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/cvm-suspende-empresa-rei-do-bitcoin\/\">Confira: CVM suspende atividades da empresa do \u201cRei do Bitcoin\u201d<\/a><\/p>\n<p>Quando perguntado se acredita que a <b>Libra <\/b>pode ser considerada um ativo financeiro, o presidente teria dito que &#8220;n\u00e3o est\u00e1 preparado para tomar uma decis\u00e3o como esta&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a divulga\u00e7\u00e3o dos planos do Facebook para a cria\u00e7\u00e3o de sua pr\u00f3pria moeda digital, a Libra, come\u00e7aram a aparecer os primeiros problemas dentro do grupo de empresas envolvido com o projeto. Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra Alguns dos maiores parceiros da Libra, a Visa e Mastercard agora est\u00e3o reconsiderando [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":28848,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[693,733,989],"suno_strategy":[],"class_list":["post-39712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-criptomoedas","tag-facebook-fbok34","tag-libra"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra<\/title>\n<meta name=\"description\" content=\"Ap\u00f3s a divulga\u00e7\u00e3o do Facebook para a cria\u00e7\u00e3o de sua pr\u00f3pria moeda digital, a Libra, come\u00e7aram a aparecer os primeiros problemas. Saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra\" \/>\n<meta property=\"og:description\" content=\"Ap\u00f3s a divulga\u00e7\u00e3o do Facebook para a cria\u00e7\u00e3o de sua pr\u00f3pria moeda digital, a Libra, come\u00e7aram a aparecer os primeiros problemas. Saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"950\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jader Lazarini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jader Lazarini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/\"},\"author\":{\"name\":\"Jader Lazarini\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\"},\"headline\":\"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra\",\"datePublished\":\"2019-10-03T11:58:04+00:00\",\"dateModified\":\"2019-10-04T13:33:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/\"},\"wordCount\":413,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra-jpeg.webp\",\"keywords\":[\"criptomoedas\",\"Facebook (FBOK34)\",\"Libra\"],\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/\",\"name\":\"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra-jpeg.webp\",\"datePublished\":\"2019-10-03T11:58:04+00:00\",\"dateModified\":\"2019-10-04T13:33:46+00:00\",\"description\":\"Ap\u00f3s a divulga\u00e7\u00e3o do Facebook para a cria\u00e7\u00e3o de sua pr\u00f3pria moeda digital, a Libra, come\u00e7aram a aparecer os primeiros problemas. Saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra-jpeg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra-jpeg.webp\",\"width\":1400,\"height\":950,\"caption\":\"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\",\"name\":\"Jader Lazarini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"caption\":\"Jader Lazarini\"},\"description\":\"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra","description":"Ap\u00f3s a divulga\u00e7\u00e3o do Facebook para a cria\u00e7\u00e3o de sua pr\u00f3pria moeda digital, a Libra, come\u00e7aram a aparecer os primeiros problemas. Saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/","og_locale":"pt_BR","og_type":"article","og_title":"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra","og_description":"Ap\u00f3s a divulga\u00e7\u00e3o do Facebook para a cria\u00e7\u00e3o de sua pr\u00f3pria moeda digital, a Libra, come\u00e7aram a aparecer os primeiros problemas. Saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1400,"height":950,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra.jpeg","type":"image\/jpeg"}],"author":"Jader Lazarini","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Jader Lazarini","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/"},"author":{"name":"Jader Lazarini","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f"},"headline":"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra","datePublished":"2019-10-03T11:58:04+00:00","dateModified":"2019-10-04T13:33:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/"},"wordCount":413,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra-jpeg.webp","keywords":["criptomoedas","Facebook (FBOK34)","Libra"],"articleSection":["Internacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/","url":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/","name":"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra-jpeg.webp","datePublished":"2019-10-03T11:58:04+00:00","dateModified":"2019-10-04T13:33:46+00:00","description":"Ap\u00f3s a divulga\u00e7\u00e3o do Facebook para a cria\u00e7\u00e3o de sua pr\u00f3pria moeda digital, a Libra, come\u00e7aram a aparecer os primeiros problemas. Saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra-jpeg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra-jpeg.webp","width":1400,"height":950,"caption":"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Internacional","item":"https:\/\/www.suno.com.br\/noticias\/internacional\/"},{"@type":"ListItem","position":3,"name":"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f","name":"Jader Lazarini","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","caption":"Jader Lazarini"},"description":"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).","url":"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/d188fa60-libra-400x200.webp\" alt=\"Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/internacional\/\">Internacional<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mastercard-e-visa-estao-repensando-o-envolvimento-com-a-libra\/\"><h2 class=\"content__title\">Mastercard e Visa est\u00e3o repensando o envolvimento com a Libra<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/178e6598-foto-perfil-2-150x150.jpg\" alt=\"Jader Lazarini\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"><span itemprop=\"author\">Jader Lazarini<\/span><\/a><\/span><time datetime=\"2019-10-03T08:58:04-03:00\" itemprop=\"datePublished\">03\/10\/2019 08:58<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/39712"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=39712"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/39712\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/28848"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=39712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=39712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=39712"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=39712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}