{"id":390215,"date":"2023-04-15T09:00:00","date_gmt":"2023-04-15T12:00:00","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=390215"},"modified":"2023-04-14T21:44:12","modified_gmt":"2023-04-15T00:44:12","slug":"taesa-taee11-taxacao-shein-mais-lidas","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/","title":{"rendered":"Rumor sobre oferta bilion\u00e1ria de a\u00e7\u00f5es da Taesa (TAEE11) e a taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!"},"content":{"rendered":"<p>A not\u00edcia mais lida da semana foi sobre a <strong>Taesa<\/strong> (TAEE11), que causou burburinho no mercado com a not\u00edcia &#8211; n\u00e3o confirmada pela empresa &#8211; de uma prov\u00e1vel oferta de novas a\u00e7\u00f5es avaliada em at\u00e9 R$ 2 bilh\u00f5es.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Rumor sobre oferta bilion\u00e1ria de a\u00e7\u00f5es da Taesa (TAEE11) e a taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Taesa (TAEE11). Foto: Unsplash<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"89005\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>Outro tema de destaque foi\u00a0sobre\u00a0a taxa\u00e7\u00e3o \u00e0s varejistas asi\u00e1ticas, como<strong> Shein, Shopee e Aliexpress<\/strong>. O <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/artigos\/ministerio-da-fazenda\/\" target=\"_blank\" rel=\"noopener\">Minist\u00e9rio da Fazenda<\/a> negou que ser\u00e1 criada uma nova tributa\u00e7\u00e3o \u00e0s compras online.<\/p>\n\n\n\n<p>Despontou ainda entre as mais lidas o <strong>Banco do Brasil<\/strong> (BBAS3), cujas a\u00e7\u00f5es dispararam quase 7% no Ibovespa de quarta-feira (14). Especialistas explicaram o que aconteceu para ocorrer a valoriza\u00e7\u00e3o.<\/p>\n\n\n\n<p>Outra not\u00edcia de destaque foi sobre a<strong> Magazine Luiza<\/strong> (MGLU3), que tamb\u00e9m viu seus pap\u00e9is saltarem na bolsa brasileira na \u00faltima ter\u00e7a (11) em meio a boas novas.<\/p>\n\n\n\n<p>Por fim, a <strong>Copel <\/strong>(CPLE6) tamb\u00e9m figurou entre as mais lidas da semana, ap\u00f3s a possibilidade de privatiza\u00e7\u00e3o ser barrada pelo Supremo Tribunal Federal (STF).<\/p>\n\n\n\n<p>Veja abaixo o resumo das principais not\u00edcias da semana. Acesse os links para ler o texto completo. Bom final de semana!<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/minicurso-investindo-fiis\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Minicurso-FIIS.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Minicurso-FIIS.png\"\n\t\t\t\t\tdata-promo-id=\"383125\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Minicurso-FIIS.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">1. Taesa (TAEE11) planeja anunciar oferta de at\u00e9 R$ 2 bi em novas a\u00e7\u00f5es?<\/h2>\n\n\n\n<p>Com o objetivo de se preparar para leil\u00f5es de transmiss\u00e3o de energia, a <a class=\"suno-keyword\" target=\"_blank\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/TAEE11\/\" rel=\"noopener\">Taesa (TAEE11)<\/a> quer fazer uma oferta de novas a\u00e7\u00f5es avaliada entre R$ 1,5 bilh\u00e3o ao R$ 2 bilh\u00f5es. <\/p>\n\n\n\n<p>As informa\u00e7\u00f5es foram divulgadas no domingo (9) e, na segunda-feira (10), os pap\u00e9is amargaram uma queda no Ibovespa. A empresa n\u00e3o confirmou a opera\u00e7\u00e3o. <\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-oferta-acoes-ibovespa-hoje-10042023\/\">\n\t\t\tTaesa (TAEE11) planeja anunciar oferta de at\u00e9 R$ 2 bi em novas a\u00e7\u00f5es; pap\u00e9is caem no Ibovespa hoje\t\t<\/a>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">2. Taxa\u00e7\u00e3o na Shein: minist\u00e9rio da Fazenda nega nova tributa\u00e7\u00e3o em compras online<\/h2>\n\n\n\n<p>Em meio \u00e0 crescente tributa\u00e7\u00e3o as varejistas asi\u00e1ticas, como a\u00a0<strong>Shein<\/strong>, o\u00a0<a href=\"https:\/\/www.suno.com.br\/artigos\/ministerio-da-fazenda\/\" target=\"_blank\" rel=\"noreferrer noopener\">Minist\u00e9rio da Fazenda<\/a>\u00a0reafirmou na quarta-feira (12) que n\u00e3o ser\u00e1 criada taxa para compras online. <\/p>\n\n\n\n<p>\u201cNunca existiu isen\u00e7\u00e3o de US$ 50 para compras online do exterior. Portanto, n\u00e3o faz sentido afirmar que se pretende acabar com o que n\u00e3o existe. Nada muda para o comprador e para o vendedor online que atua na legalidade\u201d, destaca o minist\u00e9rio em nota.<\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/taxacao-shein-fazenda-nega-nova-tributacao\/\">\n\t\t\tTaxa\u00e7\u00e3o na Shein: minist\u00e9rio da Fazenda nega nova tributa\u00e7\u00e3o em compras online e diz que refor\u00e7ar\u00e1 fiscaliza\u00e7\u00e3o\t\t<\/a>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">3. Banco do Brasil (BBAS3) dispara 7% e puxa ganhos no Ibovespa<\/h2>\n\n\n\n<p>As a\u00e7\u00f5es do&nbsp;<a href=\"https:\/\/www.suno.com.br\/acoes\/BBAS3\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Banco do Brasil<\/strong>&nbsp;(BBAS3)<\/a>&nbsp;fecharam em alta de 6,8%, cotadas a R$ 42,72, na \u00faltima quarta-feira (12), segunda maior alta do Ibovespa na ocasi\u00e3o.<\/p>\n\n\n\n<p>Os especialistas do Santander destacaram que miram um pre\u00e7o-alvo de R$ 62, ante negocia\u00e7\u00f5es na casa dos R$ 42. A expectativa \u00e9 de \u2018resultados s\u00f3lidos\u2019 para o pr\u00f3ximo trimestre.<\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-acoes-bbas3-sobem-ibovespa\/\">\n\t\t\tBanco do Brasil (BBAS3) dispara quase 7% e puxa ganhos no Ibovespa; entenda a alta\t\t<\/a>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">4. Magazine Luiza (MGLU3): com boas novas, a\u00e7\u00f5es disparam<\/h2>\n\n\n\n<p>As a\u00e7\u00f5es do\u00a0<strong>Magazine Luiza<\/strong>\u00a0(<a href=\"https:\/\/suno.com.br\/acoes\/mglu3\/\" target=\"_blank\" rel=\"noreferrer noopener\">MGLU3<\/a>) se destacaram no Ibovespa da \u00faltima ter\u00e7a (11). Os pap\u00e9is fecharam em alta de 12,8%, a R$ 3,78. <\/p>\n\n\n\n<p>De acordo com os especialistas, essa alta era explicada pelas not\u00edcias positivas que atingiram o&nbsp;<a href=\"https:\/\/www.suno.com.br\/guias\/mercado-financeiro\/\" target=\"_blank\" rel=\"noreferrer noopener\">mercado financeiro<\/a>&nbsp;naquele dia.<\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/magazine-luiza-mglu3-ibovespa-hoje-11042023-acoes-disparam\/\">\n\t\t\tMagazine Luiza (MGLU3): com boas novas, a\u00e7\u00f5es disparam no Ibovespa hoje; entenda\t\t<\/a>\n\t<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">5. Copel (CPLE6): amea\u00e7a \u00e0 privatiza\u00e7\u00e3o \u2018morre\u2019 ap\u00f3s STF<\/h2>\n\n\n\n<p>Obst\u00e1culo para a privatiza\u00e7\u00e3o da Copel (CPLE6), a d\u00edvida de R$ 4,5 bilh\u00f5es do Governo do Paran\u00e1 foi parcialmente anulada em um novo acordo no Supremo Tribunal Federal (STF).<\/p>\n\n\n\n<p>A d\u00edvida ter\u00e1 um desconto de 62% conforme a&nbsp;<strong>decis\u00e3o do STF<\/strong>. O R$ 1,7 bilh\u00e3o remanescente, por sua vez, ser\u00e1 pago em dois anos e n\u00e3o envolver\u00e1 precat\u00f3rios \u2013 o que poderia elevar a cifra a R$ 7 bilh\u00f5es. <\/p>\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/copel-cple6-privatizacao-ameaca-decisao-stf\/\">\n\t\t\tCopel (CPLE6): Amea\u00e7a \u00e0 privatiza\u00e7\u00e3o &#039;morre&#039; ap\u00f3s decis\u00e3o do STF\t\t<\/a>\n\t<\/div>\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/suno-one\/?utm_campaign=_SNC6964518A_\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/09\/400x300-Suno-One-png.webp\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/09\/1420x240-Suno-One-png.webp\"\n\t\t\t\t\tdata-promo-id=\"383121\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/09\/1420x240-Suno-One-png.webp\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\t\t<div class=\"web-stories-list alignnone has-archive-link is-view-type-carousel is-style-default is-carousel\" data-id=\"1\">\n\t\t\t<div\n\t\t\tclass=\"web-stories-list__inner-wrapper carousel-1\"\n\t\t\tstyle=\"--ws-story-max-width:185px\"\n\t\t\t>\n\t\t\t\t\t\t<div class=\"web-stories-list__archive-link\">\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/web-stories\/\">\n\t\t\t\tConfira os melhores webstories!\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div\n\t\t\t\t\tclass=\"web-stories-list__carousel carousel\"\n\t\t\t\t\tdata-id=\"carousel-1\"\n\t\t\t\t\tdata-prev=\"Voltar\"\n\t\t\t\t\tdata-next=\"Avan\u00e7ar\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<div\n\t\t\t\tclass=\"web-stories-list__story\"\n\t\t\t\tdata-wp-interactive=\"web-stories-block\"\n\t\t\t\tdata-wp-context='{\"instanceId\":1}'\t\t\t\tdata-wp-on--click=\"actions.open\"\n\t\t\t\tdata-wp-on-window--popstate=\"actions.onPopstate\"\n\t\t\t\t>\n\t\t\t\t\t\t\t<div class=\"web-stories-list__story-poster\">\n\t\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/web-stories\/por-que-as-acoes-da-nvidia-estao-despencando\/\" >\n\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/11\/cropped-pexels-stasknop-19356873-scaled-1.webp\"\n\t\t\t\t\t\talt=\"Por que as a\u00e7\u00f5es da Nvidia est\u00e3o despencando?\"\n\t\t\t\t\t\twidth=\"185\"\n\t\t\t\t\t\theight=\"308\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/11\/cropped-pexels-stasknop-19356873-scaled-1.webp 640w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/11\/cropped-pexels-stasknop-19356873-scaled-1-225x300.webp 225w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/11\/cropped-pexels-stasknop-19356873-scaled-1-150x200.webp 150w\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsizes=\"(max-width: 640px) 100vw, 640px\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"web-stories-list__story-content-overlay\">\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__title\">\n\t\t\t\t\tPor que as a\u00e7\u00f5es da Nvidia est\u00e3o despencando?\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div\n\t\t\t\tclass=\"web-stories-list__story\"\n\t\t\t\tdata-wp-interactive=\"web-stories-block\"\n\t\t\t\tdata-wp-context='{\"instanceId\":1}'\t\t\t\tdata-wp-on--click=\"actions.open\"\n\t\t\t\tdata-wp-on-window--popstate=\"actions.onPopstate\"\n\t\t\t\t>\n\t\t\t\t\t\t\t<div class=\"web-stories-list__story-poster\">\n\t\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/web-stories\/quanto-falta-para-elon-musk-se-tornar-trilionario\/\" >\n\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2026\/01\/cropped-Elon-Musk-jpg.webp\"\n\t\t\t\t\t\talt=\"Quanto falta para Elon Musk se tornar trilion\u00e1rio?\"\n\t\t\t\t\t\twidth=\"185\"\n\t\t\t\t\t\theight=\"308\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2026\/01\/cropped-Elon-Musk-jpg.webp 640w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2026\/01\/cropped-Elon-Musk-jpg-225x300.webp 225w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2026\/01\/cropped-Elon-Musk-jpg-150x200.webp 150w\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsizes=\"(max-width: 640px) 100vw, 640px\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"web-stories-list__story-content-overlay\">\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__title\">\n\t\t\t\t\tQuanto falta para Elon Musk se tornar trilion\u00e1rio?\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div\n\t\t\t\tclass=\"web-stories-list__story\"\n\t\t\t\tdata-wp-interactive=\"web-stories-block\"\n\t\t\t\tdata-wp-context='{\"instanceId\":1}'\t\t\t\tdata-wp-on--click=\"actions.open\"\n\t\t\t\tdata-wp-on-window--popstate=\"actions.onPopstate\"\n\t\t\t\t>\n\t\t\t\t\t\t\t<div class=\"web-stories-list__story-poster\">\n\t\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/web-stories\/ate-onde-vai-a-alta-do-ibovespa\/\" >\n\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/11\/cropped-iStock-1215609239-jpg.webp\"\n\t\t\t\t\t\talt=\"At\u00e9 onde vai a alta do Ibovespa?\"\n\t\t\t\t\t\twidth=\"185\"\n\t\t\t\t\t\theight=\"308\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/11\/cropped-iStock-1215609239-jpg.webp 640w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/11\/cropped-iStock-1215609239-jpg-225x300.webp 225w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/11\/cropped-iStock-1215609239-jpg-150x200.webp 150w\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsizes=\"(max-width: 640px) 100vw, 640px\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"web-stories-list__story-content-overlay\">\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__title\">\n\t\t\t\t\tAt\u00e9 onde vai a alta do Ibovespa?\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div\n\t\t\t\tclass=\"web-stories-list__story\"\n\t\t\t\tdata-wp-interactive=\"web-stories-block\"\n\t\t\t\tdata-wp-context='{\"instanceId\":1}'\t\t\t\tdata-wp-on--click=\"actions.open\"\n\t\t\t\tdata-wp-on-window--popstate=\"actions.onPopstate\"\n\t\t\t\t>\n\t\t\t\t\t\t\t<div class=\"web-stories-list__story-poster\">\n\t\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/web-stories\/banco-brasileiro-itau-lista-marcas-mais-valiosas-mundo\/\" >\n\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/01\/cropped-predio-itau.webp\"\n\t\t\t\t\t\talt=\"Banco brasileiro est\u00e1 entre as 500 marcas mais valiosas do mundo\"\n\t\t\t\t\t\twidth=\"185\"\n\t\t\t\t\t\theight=\"308\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/01\/cropped-predio-itau.webp 640w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/01\/cropped-predio-itau-225x300.webp 225w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/01\/cropped-predio-itau-150x200.webp 150w\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsizes=\"(max-width: 640px) 100vw, 640px\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"web-stories-list__story-content-overlay\">\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__title\">\n\t\t\t\t\tBanco brasileiro est\u00e1 entre as 500 marcas mais valiosas do mundo\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div\n\t\t\t\tclass=\"web-stories-list__story\"\n\t\t\t\tdata-wp-interactive=\"web-stories-block\"\n\t\t\t\tdata-wp-context='{\"instanceId\":1}'\t\t\t\tdata-wp-on--click=\"actions.open\"\n\t\t\t\tdata-wp-on-window--popstate=\"actions.onPopstate\"\n\t\t\t\t>\n\t\t\t\t\t\t\t<div class=\"web-stories-list__story-poster\">\n\t\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/web-stories\/flamengo-lista-times-mais-ricos-do-mundo-hoje\/\" >\n\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2026\/01\/cropped-brazil-6755874_1280-jpg.webp\"\n\t\t\t\t\t\talt=\"Flamengo na lista! Veja os times mais ricos do mundo hoje\"\n\t\t\t\t\t\twidth=\"185\"\n\t\t\t\t\t\theight=\"308\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2026\/01\/cropped-brazil-6755874_1280-jpg.webp 640w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2026\/01\/cropped-brazil-6755874_1280-jpg-225x300.webp 225w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2026\/01\/cropped-brazil-6755874_1280-jpg-150x200.webp 150w\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsizes=\"(max-width: 640px) 100vw, 640px\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"web-stories-list__story-content-overlay\">\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__title\">\n\t\t\t\t\tFlamengo na lista! Veja os times mais ricos do mundo hoje\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div tabindex=\"0\" aria-label=\"Voltar\" class=\"glider-prev\"><\/div>\n\t\t\t\t\t<div tabindex=\"0\" aria-label=\"Avan\u00e7ar\" class=\"glider-next\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A not\u00edcia mais lida da semana foi sobre a Taesa (TAEE11), que causou burburinho no mercado com a not\u00edcia &#8211; n\u00e3o confirmada pela empresa &#8211; de uma prov\u00e1vel oferta de novas a\u00e7\u00f5es avaliada em at\u00e9 R$ 2 bilh\u00f5es. Taesa (TAEE11). Foto: Unsplash Outro tema de destaque foi\u00a0sobre\u00a0a taxa\u00e7\u00e3o \u00e0s varejistas asi\u00e1ticas, como Shein, Shopee e [&hellip;]<\/p>\n","protected":false},"author":233,"featured_media":284103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[732,431,824,649],"suno_strategy":[],"class_list":["post-390215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-banco-do-brasil-bbas3","tag-copel-cple3-cple5-cple6","tag-ministerio-fazenda","tag-taesa-taee11-taee3-taee4"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Taesa (TAEE11) pode anunciar oferta de R$ 2 bi em a\u00e7\u00f5es e taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!<\/title>\n<meta name=\"description\" content=\"Taesa (TAEE11) planeja oferta de R$ 2 bi em novas a\u00e7\u00f5es? Taxa\u00e7\u00e3o na Shein: Confira as not\u00edcias mais lidas da semana!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taesa (TAEE11) pode anunciar oferta de R$ 2 bi em a\u00e7\u00f5es e taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!\" \/>\n<meta property=\"og:description\" content=\"Taesa (TAEE11) planeja oferta de R$ 2 bi em novas a\u00e7\u00f5es? Taxa\u00e7\u00e3o na Shein: Confira as not\u00edcias mais lidas da semana!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-scaled-e1660238194539.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Janize Cola\u00e7o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Janize Cola\u00e7o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/\"},\"author\":{\"name\":\"Janize Cola\u00e7o\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d689f06da5678e1f0b1ee402f001d676\"},\"headline\":\"Rumor sobre oferta bilion\u00e1ria de a\u00e7\u00f5es da Taesa (TAEE11) e a taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!\",\"datePublished\":\"2023-04-15T12:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/\"},\"wordCount\":593,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-scaled-e1660238194539.jpg\",\"keywords\":[\"Banco do Brasil (BBAS3)\",\"Copel (CPLE3\/CPLE5\/CPLE6)\",\"Minist\u00e9rio da Fazenda\",\"Taesa (TAEE11\/TAEE3\/TAEE4)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/\",\"name\":\"Taesa (TAEE11) pode anunciar oferta de R$ 2 bi em a\u00e7\u00f5es e taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-scaled-e1660238194539.jpg\",\"datePublished\":\"2023-04-15T12:00:00+00:00\",\"description\":\"Taesa (TAEE11) planeja oferta de R$ 2 bi em novas a\u00e7\u00f5es? Taxa\u00e7\u00e3o na Shein: Confira as not\u00edcias mais lidas da semana!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-scaled-e1660238194539.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-scaled-e1660238194539.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Taesa (TAEE11). Foto: Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rumor sobre oferta bilion\u00e1ria de a\u00e7\u00f5es da Taesa (TAEE11) e a taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d689f06da5678e1f0b1ee402f001d676\",\"name\":\"Janize Cola\u00e7o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/32b3bf89abae63ca2cf961bc051522d0?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/32b3bf89abae63ca2cf961bc051522d0?s=96&r=g\",\"caption\":\"Janize Cola\u00e7o\"},\"description\":\"Jornalista formada pela PUC-SP com passagens pela Record TV, Globo Cond\u00e9 Nast, Revista Panrotas e Editora Via. Hoje, \u00e9 rep\u00f3rter no Suno Not\u00edcias, cobrindo pautas sobre mercado, pol\u00edtica, economia e bolsa de valores.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/janize-colaco\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taesa (TAEE11) pode anunciar oferta de R$ 2 bi em a\u00e7\u00f5es e taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!","description":"Taesa (TAEE11) planeja oferta de R$ 2 bi em novas a\u00e7\u00f5es? Taxa\u00e7\u00e3o na Shein: Confira as not\u00edcias mais lidas da semana!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/","og_locale":"pt_BR","og_type":"article","og_title":"Taesa (TAEE11) pode anunciar oferta de R$ 2 bi em a\u00e7\u00f5es e taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!","og_description":"Taesa (TAEE11) planeja oferta de R$ 2 bi em novas a\u00e7\u00f5es? Taxa\u00e7\u00e3o na Shein: Confira as not\u00edcias mais lidas da semana!","og_url":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1200,"height":800,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-scaled-e1660238194539.jpg","type":"image\/jpeg"}],"author":"Janize Cola\u00e7o","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Janize Cola\u00e7o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/"},"author":{"name":"Janize Cola\u00e7o","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d689f06da5678e1f0b1ee402f001d676"},"headline":"Rumor sobre oferta bilion\u00e1ria de a\u00e7\u00f5es da Taesa (TAEE11) e a taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!","datePublished":"2023-04-15T12:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/"},"wordCount":593,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-scaled-e1660238194539.jpg","keywords":["Banco do Brasil (BBAS3)","Copel (CPLE3\/CPLE5\/CPLE6)","Minist\u00e9rio da Fazenda","Taesa (TAEE11\/TAEE3\/TAEE4)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/","url":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/","name":"Taesa (TAEE11) pode anunciar oferta de R$ 2 bi em a\u00e7\u00f5es e taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-scaled-e1660238194539.jpg","datePublished":"2023-04-15T12:00:00+00:00","description":"Taesa (TAEE11) planeja oferta de R$ 2 bi em novas a\u00e7\u00f5es? Taxa\u00e7\u00e3o na Shein: Confira as not\u00edcias mais lidas da semana!","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-scaled-e1660238194539.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-scaled-e1660238194539.jpg","width":1200,"height":800,"caption":"Taesa (TAEE11). Foto: Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Rumor sobre oferta bilion\u00e1ria de a\u00e7\u00f5es da Taesa (TAEE11) e a taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/d689f06da5678e1f0b1ee402f001d676","name":"Janize Cola\u00e7o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/32b3bf89abae63ca2cf961bc051522d0?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32b3bf89abae63ca2cf961bc051522d0?s=96&r=g","caption":"Janize Cola\u00e7o"},"description":"Jornalista formada pela PUC-SP com passagens pela Record TV, Globo Cond\u00e9 Nast, Revista Panrotas e Editora Via. Hoje, \u00e9 rep\u00f3rter no Suno Not\u00edcias, cobrindo pautas sobre mercado, pol\u00edtica, economia e bolsa de valores.","url":"https:\/\/www.suno.com.br\/noticias\/author\/janize-colaco\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/08\/taesa-taee11-400x200.jpg\" alt=\"Rumor sobre oferta bilion\u00e1ria de a\u00e7\u00f5es da Taesa (TAEE11) e a taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/taesa-taee11-taxacao-shein-mais-lidas\/\"><h2 class=\"content__title\">Rumor sobre oferta bilion\u00e1ria de a\u00e7\u00f5es da Taesa (TAEE11) e a taxa\u00e7\u00e3o na Shein; confira as mais lidas da semana!<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/janize-colaco\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/11\/20221120_111807-1-150x150.jpg\" alt=\"Janize Cola\u00e7o\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/janize-colaco\/\"><span itemprop=\"author\">Janize Cola\u00e7o<\/span><\/a><\/span><time datetime=\"2023-04-15T09:00:00-03:00\" itemprop=\"datePublished\">15\/04\/2023 09:00<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/390215"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/233"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=390215"}],"version-history":[{"count":2,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/390215\/revisions"}],"predecessor-version":[{"id":390296,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/390215\/revisions\/390296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/284103"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=390215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=390215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=390215"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=390215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}