{"id":38957,"date":"2019-09-26T11:45:51","date_gmt":"2019-09-26T14:45:51","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=38957"},"modified":"2021-06-13T23:41:38","modified_gmt":"2021-06-14T02:41:38","slug":"casa-branca-teria-tentado-interceptar-conversas-donald-trump","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/","title":{"rendered":"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN"},"content":{"rendered":"<p>Segundo uma den\u00fancia an\u00f4nima, a <strong>Casa Branca<\/strong> tentou acobertar registros das conversas do presidente norte-americano <a href=\"https:\/\/www.suno.com.br\/tudo-sobre\/donald-trump\/\">Donald Trump<\/a>. O governo teria tentado interceptar as conversas entre Trump e o presidente da Ucr\u00e2nia, Volodymyr Zelensky, em 25 de julho deste ano.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1-800x450.webp\" width=\"800\" height=\"450\" alt=\"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">Trump diz que negocia\u00e7\u00f5es com China est\u00e3o &#039;indo muito bem&#039;<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n<p>A fonte disse \u00e0 rede de televis\u00e3o estadunidense CNN que a tentativa de reter as informa\u00e7\u00f5es partiu do uso de permiss\u00f5es de administrador no sistema de computadores do governo de <strong>Donald Trump<\/strong>, o que seria classificado como &#8220;abuso&#8221;.<\/p>\n<p>A <strong><a href=\"https:\/\/intelligence.house.gov\/uploadedfiles\/20190812_-_whistleblower_complaint_unclass.pdf\">den\u00fancia<\/a><\/strong>, que foi publicada na \u00edntegra na manh\u00e3 desta quinta-feira (26), indica que o presidente instruiu Mike Pence, seu vice-presidente, a cancelar a viagem \u00e0 posse de Zelensky no Leste Europeu, pouco tempo antes da conversa.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/jp-morgan-diz-solucao-guerra-comercial-apos-eleicoes-2020\/\">Confira: J.P. Morgan: solu\u00e7\u00e3o da guerra comercial acontecer\u00e1 ap\u00f3s as elei\u00e7\u00f5es de 2020<\/a><\/p>\n<p>Segundo a fonte an\u00f4nima, <strong>Trump<\/strong> pretendia aguardar para saber melhor qual seria o comportamento do novo l\u00edder da <strong>Ucr\u00e2nia<\/strong>.<\/p>\n<p>Al\u00e9m disso, a conversa entre o presidente estadunidense e o ucraniano teria sido acompanhada por representantes de diferentes \u00e1reas do governo dos <strong>EUA<\/strong>. Entre eles estavam funcion\u00e1rios do Departamento de Estado e da Intelig\u00eancia do pa\u00eds, j\u00e1 que a expectativa era de uma &#8220;conversa de rotina&#8221;.<\/p>\n<h2>Jon Biden pede que Trump seja responsabilizado<\/h2>\n<p>O ex-vice-presidente dos Estados Unidos e candidato \u00e0 presid\u00eancia em 2020 pelo Partido Democrata, Jon Biden, acusou o presidente <strong>Trump<\/strong> de &#8220;abuso de poder&#8221;.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ao\/cadastro-whatsapp\/?utm_source=sunoresearch&#038;utm_medium=banner.sidebar&#038;utm_campaign=_SNC1787C4C9_\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/09\/wpp-suno.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/09\/wpp-suno.png\"\n\t\t\t\t\tdata-promo-id=\"574195\"\t\t\t\t\t\t\t\t\t\twidth='360' height='98'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/09\/wpp-suno.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>\u201c<strong>Donald Trump<\/strong> pressionou a Ucr\u00e2nia a produzir uma mancha contra um oponente pol\u00edtico, se utilizando de uma conspira\u00e7\u00e3o maliciosa\u201d, disse Biden, em comunicado nesta quinta-feira (26).<\/p>\n<p>O candidato afirmou que o Congresso tem o direito de analisar a \u00edntegra da den\u00fancia an\u00f4nima que motivou o pedido de <strong>impeachment<\/strong> anunciado na \u00faltima ter\u00e7a-feira (24).<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/onu-trump-china-patriotas\/\">Veja tamb\u00e9m: Trump diz que futuro pertence aos patriotas e critica China na ONU<\/a><\/p>\n<p>Na conversa do dia 25 de julho, <strong>Trump<\/strong> solicitou ao novo l\u00edder ucraniano que investigasse a Hunter Biden, filho do candidato opositor, que foi indicado para o conselho de uma empresa de energia na Ucr\u00e2nia.<\/p>\n<p>O candidato, que foi vice-presidente durante todo o mandato de <strong>Barak Obama<\/strong>, pediu ao Congresso que responsabilize <strong>Donald Trump<\/strong> por \u201ccolocar interesses pol\u00edticos pessoais acima do seu juramento sagrado e da seguran\u00e7a nacional\u201d. \u201cN\u00e3o \u00e9 uma quest\u00e3o entre Republicanos e Democratas. \u00c9 um problema de seguran\u00e7a nacional\u201d, declarou Biden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo uma den\u00fancia an\u00f4nima, a Casa Branca tentou acobertar registros das conversas do presidente norte-americano Donald Trump. O governo teria tentado interceptar as conversas entre Trump e o presidente da Ucr\u00e2nia, Volodymyr Zelensky, em 25 de julho deste ano. Trump diz que negocia\u00e7\u00f5es com China est\u00e3o &#039;indo muito bem&#039; A fonte disse \u00e0 rede de [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":22557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[1889,724,793],"suno_strategy":[],"class_list":["post-38957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-casa-branca","tag-donald-trump","tag-estados-unidos-eua"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN<\/title>\n<meta name=\"description\" content=\"Segundo uma den\u00fancia an\u00f4nima, a Casa Branca tentou acobertar registros das conversas do presidente norte-americano Donald Trump. Saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN\" \/>\n<meta property=\"og:description\" content=\"Segundo uma den\u00fancia an\u00f4nima, a Casa Branca tentou acobertar registros das conversas do presidente norte-americano Donald Trump. Saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"541\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jader Lazarini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jader Lazarini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/\"},\"author\":{\"name\":\"Jader Lazarini\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\"},\"headline\":\"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN\",\"datePublished\":\"2019-09-26T14:45:51+00:00\",\"dateModified\":\"2021-06-14T02:41:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/\"},\"wordCount\":411,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1-jpg.webp\",\"keywords\":[\"Casa Branca\",\"Donald Trump\",\"Estados Unidos (EUA)\"],\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/\",\"name\":\"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1-jpg.webp\",\"datePublished\":\"2019-09-26T14:45:51+00:00\",\"dateModified\":\"2021-06-14T02:41:38+00:00\",\"description\":\"Segundo uma den\u00fancia an\u00f4nima, a Casa Branca tentou acobertar registros das conversas do presidente norte-americano Donald Trump. Saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1-jpg.webp\",\"width\":1000,\"height\":541,\"caption\":\"Trump diz que negocia\u00e7\u00f5es com China est\u00e3o 'indo muito bem'\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\",\"name\":\"Jader Lazarini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"caption\":\"Jader Lazarini\"},\"description\":\"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN","description":"Segundo uma den\u00fancia an\u00f4nima, a Casa Branca tentou acobertar registros das conversas do presidente norte-americano Donald Trump. Saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/","og_locale":"pt_BR","og_type":"article","og_title":"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN","og_description":"Segundo uma den\u00fancia an\u00f4nima, a Casa Branca tentou acobertar registros das conversas do presidente norte-americano Donald Trump. Saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1000,"height":541,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1.jpg","type":"image\/jpeg"}],"author":"Jader Lazarini","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Jader Lazarini","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/"},"author":{"name":"Jader Lazarini","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f"},"headline":"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN","datePublished":"2019-09-26T14:45:51+00:00","dateModified":"2021-06-14T02:41:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/"},"wordCount":411,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1-jpg.webp","keywords":["Casa Branca","Donald Trump","Estados Unidos (EUA)"],"articleSection":["Internacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/","url":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/","name":"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1-jpg.webp","datePublished":"2019-09-26T14:45:51+00:00","dateModified":"2021-06-14T02:41:38+00:00","description":"Segundo uma den\u00fancia an\u00f4nima, a Casa Branca tentou acobertar registros das conversas do presidente norte-americano Donald Trump. Saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1-jpg.webp","width":1000,"height":541,"caption":"Trump diz que negocia\u00e7\u00f5es com China est\u00e3o 'indo muito bem'"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Internacional","item":"https:\/\/www.suno.com.br\/noticias\/internacional\/"},{"@type":"ListItem","position":3,"name":"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f","name":"Jader Lazarini","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","caption":"Jader Lazarini"},"description":"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).","url":"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/04\/2fd392b7-trump-1-400x200.webp\" alt=\"Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/internacional\/\">Internacional<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/casa-branca-teria-tentado-interceptar-conversas-donald-trump\/\"><h2 class=\"content__title\">Casa Branca teria tentado acobertar conversas de Donald Trump, diz CNN<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/178e6598-foto-perfil-2-150x150.jpg\" alt=\"Jader Lazarini\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"><span itemprop=\"author\">Jader Lazarini<\/span><\/a><\/span><time datetime=\"2019-09-26T11:45:51-03:00\" itemprop=\"datePublished\">26\/09\/2019 11:45<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38957"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=38957"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38957\/revisions"}],"predecessor-version":[{"id":157268,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38957\/revisions\/157268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/22557"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=38957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=38957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=38957"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=38957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}