{"id":36123,"date":"2019-09-02T12:23:11","date_gmt":"2019-09-02T15:23:11","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=36123"},"modified":"2019-09-03T17:01:42","modified_gmt":"2019-09-03T20:01:42","slug":"b3-nova-carteira-ibovespa-entrada-btg-pactual","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/","title":{"rendered":"B3 divulga nova carteira do Ibovespa com entrada do BTG Pactual"},"content":{"rendered":"<p>A B3 (Brasil, Bolsa, Balc\u00e3o) divulgou, na \u00faltima sexta-feira (30), a nova carteira do <a href=\"https:\/\/www.suno.com.br\/artigos\/ibovespa\/\"><strong>Ibovespa<\/strong><\/a>, que come\u00e7a a valer nesta segunda-feira (2) e vigora at\u00e9 o dia 3 de janeiro de 2020. A nova carteira do Ibovespa conta com a entrada do <strong>BTG<\/strong> <strong>Pactual<\/strong> (BPAC11) e da <strong>Interm\u00e9dica<\/strong> (GNDI3). Dessa forma, s\u00e3o, ao todo, 68 ativos de 65 companhias. As informa\u00e7\u00f5es tem como base o fechamento do preg\u00e3o da \u00faltima sexta.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-800x450.webp\" width=\"800\" height=\"450\" alt=\"B3 divulga nova carteira do Ibovespa com entrada do BTG Pactual\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">A CVM informou que setembro registrou um recorde mensal de IPOs<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n<p>Os ativos que registraram o maior peso no <strong>Ibovespa<\/strong> foram:<\/p>\n<ul>\n<li>Itau Unibanco PN (9,194%)<\/li>\n<li>Vale ON (8,204%)<\/li>\n<li>Bradesco PN (7,300%)<\/li>\n<li>Petrobras PN (6,597%)<\/li>\n<li>B3 ON (5,175%)<\/li>\n<\/ul>\n<p>Para ter uma base comparativa, os ativos que registraram o maior peso na composi\u00e7\u00e3o da carteira anterior, do principal \u00edndice da <strong>B3<\/strong>, v\u00e1lida de 6 de maio de 2019 a 30 de agosto de 2019, foram:<\/p>\n<ul>\n<li>Itau Unibanco PN (9,997%);<\/li>\n<li>Vale ON (9,970%);<\/li>\n<li>Bradesco PN (8,754%);<\/li>\n<li>Petrobras PN (7,310%);<\/li>\n<li>Petrobras ON (5,032%).<\/li>\n<\/ul>\n<p><iframe loading=\"lazy\" title=\"?Oi negocia financiamento com bancos; B3 atualiza Ibovespa e Ita\u00fa aposta na Bolsa\" width=\"200\" height=\"113\" src=\"https:\/\/www.youtube.com\/embed\/DiXuBKAW7yY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>A B3 tem como padr\u00e3o fazer tr\u00eas pr\u00e9vias das novas composi\u00e7\u00f5es dos \u00edndices: a primeira pr\u00e9via, que acontece no primeiro preg\u00e3o do \u00faltimo m\u00eas de vig\u00eancia da carteira que se encontra em vigor; a segunda pr\u00e9via, no preg\u00e3o seguinte ao dia 15 do \u00faltimo m\u00eas de vig\u00eancia da carteira em vigor e a terceira pr\u00e9via, no pen\u00faltimo preg\u00e3o de vig\u00eancia da carteira em atividade.<\/p>\n<h2>Privatiza\u00e7\u00f5es devem alavancar a\u00e7\u00f5es da B3<\/h2>\n<p>De acordo com um relat\u00f3rio divulgado pelo Credit Suisse no dia 26 de agosto, os pap\u00e9is da B3 (<strong>B3SA3<\/strong>) devem ter espa\u00e7o para crescimento conforme o volume em renda vari\u00e1vel aumente.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/itau-ticket-ratificam-parceria-aval-cade-bc\/\">Veja tamb\u00e9m: Ita\u00fa e Ticket ratificam parceria depois de aval do Cade e BC\u00a0<\/a><\/p>\n<p>Analistas do Credit Suisse estiveram com Daniel Sonder, diretor financeiro da <a href=\"https:\/\/www.suno.com.br\/artigos\/b3\/\"><strong>B3<\/strong>,<\/a> <a href=\"https:\/\/www.suno.com.br\/artigos\/b3\/\">a Bolsa de Valores de S\u00e3o Paulo<\/a>, para tratarem das perspectivas da Bolsa.<\/p>\n<p>\u201cA administra\u00e7\u00e3o \u00e9 muito otimista sobre as perspectivas dos volumes de a\u00e7\u00f5es e v\u00ea uma mudan\u00e7a estrutural no mercado local, com uma mudan\u00e7a significativa de renda fixa em a\u00e7\u00f5es, maior participa\u00e7\u00e3o de fundos de investimento e pessoas f\u00edsicas&#8221;, disseram os analistas.<\/p>\n<h2>Brasil, Bolsa, Balc\u00e3o<\/h2>\n<p>A <strong>B3<\/strong> (B3SA3) \u00e9 uma empresa de infraestrutura de mercado financeiro. A companhia se encontra entre as l\u00edderes globais do setor de bolsas. Um dos pap\u00e9is da empresa \u00e9 criar e administrar, no \u00e2mbito de bolsa e balc\u00e3o, sistemas de negocia\u00e7\u00e3o, compensa\u00e7\u00e3o, liquida\u00e7\u00e3o e registro para todas as classes de ativos primordiais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A B3 (Brasil, Bolsa, Balc\u00e3o) divulgou, na \u00faltima sexta-feira (30), a nova carteira do Ibovespa, que come\u00e7a a valer nesta segunda-feira (2) e vigora at\u00e9 o dia 3 de janeiro de 2020. A nova carteira do Ibovespa conta com a entrada do BTG Pactual (BPAC11) e da Interm\u00e9dica (GNDI3). Dessa forma, s\u00e3o, ao todo, 68 [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":35465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[367,1937,721],"suno_strategy":[],"class_list":["post-36123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-b3-b3sa3","tag-bolsa-de-valores-de-sao-paulo-b3","tag-ibovespa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>B3 divulga nova carteira com entrada do BTG Pactual<\/title>\n<meta name=\"description\" content=\"A B3 divulgou, na \u00faltima sexta-feira (30), a nova carteira do Ibovespa, que come\u00e7a a valer nesta segunda-feira (2). Clique aqui e saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B3 divulga nova carteira com entrada do BTG Pactual\" \/>\n<meta property=\"og:description\" content=\"A B3 divulgou, na \u00faltima sexta-feira (30), a nova carteira do Ibovespa, que come\u00e7a a valer nesta segunda-feira (2). Clique aqui e saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juliano Passaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juliano Passaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/\"},\"author\":{\"name\":\"Juliano Passaro\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3\"},\"headline\":\"B3 divulga nova carteira do Ibovespa com entrada do BTG Pactual\",\"datePublished\":\"2019-09-02T15:23:11+00:00\",\"dateModified\":\"2019-09-03T20:01:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/\"},\"wordCount\":432,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-scaled.webp\",\"keywords\":[\"B3 (B3SA3)\",\"Bolsa de Valores de S\u00e3o Paulo (B3)\",\"Ibovespa\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/\",\"name\":\"B3 divulga nova carteira com entrada do BTG Pactual\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-scaled.webp\",\"datePublished\":\"2019-09-02T15:23:11+00:00\",\"dateModified\":\"2019-09-03T20:01:42+00:00\",\"description\":\"A B3 divulgou, na \u00faltima sexta-feira (30), a nova carteira do Ibovespa, que come\u00e7a a valer nesta segunda-feira (2). Clique aqui e saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-scaled.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-scaled.webp\",\"width\":2560,\"height\":1707,\"caption\":\"A CVM informou que setembro registrou um recorde mensal de IPOs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/mercado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"B3 divulga nova carteira do Ibovespa com entrada do BTG Pactual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3\",\"name\":\"Juliano Passaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g\",\"caption\":\"Juliano Passaro\"},\"description\":\"Juliano Passaro escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal da Suno Research. Antes da Suno, trabalhou no Portal da Band. \u00c9 formado em jornalismo pela Universidade Presbiteriana Mackenzie.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B3 divulga nova carteira com entrada do BTG Pactual","description":"A B3 divulgou, na \u00faltima sexta-feira (30), a nova carteira do Ibovespa, que come\u00e7a a valer nesta segunda-feira (2). Clique aqui e saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/","og_locale":"pt_BR","og_type":"article","og_title":"B3 divulga nova carteira com entrada do BTG Pactual","og_description":"A B3 divulgou, na \u00faltima sexta-feira (30), a nova carteira do Ibovespa, que come\u00e7a a valer nesta segunda-feira (2). Clique aqui e saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1024,"height":683,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-1024x683.jpg","type":"image\/jpeg"}],"author":"Juliano Passaro","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Juliano Passaro","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/"},"author":{"name":"Juliano Passaro","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3"},"headline":"B3 divulga nova carteira do Ibovespa com entrada do BTG Pactual","datePublished":"2019-09-02T15:23:11+00:00","dateModified":"2019-09-03T20:01:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/"},"wordCount":432,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-scaled.webp","keywords":["B3 (B3SA3)","Bolsa de Valores de S\u00e3o Paulo (B3)","Ibovespa"],"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/","url":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/","name":"B3 divulga nova carteira com entrada do BTG Pactual","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-scaled.webp","datePublished":"2019-09-02T15:23:11+00:00","dateModified":"2019-09-03T20:01:42+00:00","description":"A B3 divulgou, na \u00faltima sexta-feira (30), a nova carteira do Ibovespa, que come\u00e7a a valer nesta segunda-feira (2). Clique aqui e saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-scaled.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-scaled.webp","width":2560,"height":1707,"caption":"A CVM informou que setembro registrou um recorde mensal de IPOs"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/www.suno.com.br\/noticias\/mercado\/"},{"@type":"ListItem","position":3,"name":"B3 divulga nova carteira do Ibovespa com entrada do BTG Pactual"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3","name":"Juliano Passaro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g","caption":"Juliano Passaro"},"description":"Juliano Passaro escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal da Suno Research. Antes da Suno, trabalhou no Portal da Band. \u00c9 formado em jornalismo pela Universidade Presbiteriana Mackenzie.","url":"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/6cf70dbf-b3-400x200.webp\" alt=\"B3 divulga nova carteira do Ibovespa com entrada do BTG Pactual\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mercado\/\">Mercado<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/b3-nova-carteira-ibovespa-entrada-btg-pactual\/\"><h2 class=\"content__title\">B3 divulga nova carteira do Ibovespa com entrada do BTG Pactual<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/7cc3efea-whatsapp-image-2019-07-18-at-21.59.33-e1563499821209-150x150.webp\" alt=\"Juliano Passaro\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\"><span itemprop=\"author\">Juliano Passaro<\/span><\/a><\/span><time datetime=\"2019-09-02T12:23:11-03:00\" itemprop=\"datePublished\">02\/09\/2019 12:23<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/36123"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=36123"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/36123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/35465"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=36123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=36123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=36123"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=36123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}