{"id":350472,"date":"2023-01-20T16:52:58","date_gmt":"2023-01-20T19:52:58","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=350472"},"modified":"2023-01-20T18:06:30","modified_gmt":"2023-01-20T21:06:30","slug":"fi-infra-quanto-rendem-fundos-dividendos","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/","title":{"rendered":"FI-Infra e dividendos: quanto rendem os principais fundos?"},"content":{"rendered":"<p>Por meio da aplica\u00e7\u00e3o em Fundo Incentivado de Investimento em Infraestrutura (<strong>FI-Infra<\/strong>), os investidores podem ter acesso a um setor com grande demanda no pa\u00eds. Al\u00e9m da diversifica\u00e7\u00e3o da carteira, os essas pessoas ainda t\u00eam a possibilidade de obter rendimentos isentos de impostos. &nbsp;<\/p><div class=\"videoFull \">\n\t\t\t<div class=\"videoWrapper yt-lazyload center\"\n\t\t\t\tdata-width=\"960\"\n\t\t\t\tdata-height=\"540\"\n\t\t\t\tdata-id=\"wphoY_UIDyM\"\n\t\t\t\tdata-alt=\"V\u00eddeo do YouTube - clique para reproduzir\"\n\t\t\t\tdata-logo=\"3\"\n\t\t\t\tdata-imagequality=\"maxres\">\n\t\t\t<\/div>\n\t\t<\/div><script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"VideoObject\",\"name\":\"FI-Infra: o que s\u00e3o e como investir? Entrevista com Miguel Ferreira, da Bocaina Capital (BODB11)\",\"description\":\"Investir em infraestrutura no Brasil costumava ser sin\u00f4nimo de investimento p\u00fablico ou restrito a grandes agentes. Essa realidade, no entanto, foi mudando nos \u00faltimos anos, com o surgimento de novas modalidades de investimentos. Os FI-Infra s\u00e3o parte desta mudan\u00e7a e atraem cada vez mais investidores pessoa f\u00edsica. Nesta transmiss\u00e3o ao vivo, o Suno Not\u00edcias conversa\u2026\",\"duration\":\"PT48M33S\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/wphoY_UIDyM\",\"regionsAllowed\":\"pt-BR\",\"interactionStatistic\":{\"@type\":\"InteractionCounter\",\"interactionType\":{\"@type\":\"WatchAction\"},\"userInteractionCount\":1476},\"thumbnailUrl\":\"https:\/\/i.ytimg.com\/vi\/wphoY_UIDyM\/default.jpg\",\"uploadDate\":\"2022-11-23T17:56:37Z\"}<\/script>\n\n\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"341301\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>Em entrevista ao Suno Not\u00edcias, Gabriel Esteca, cofundador e Head de Investimentos em Infraestrutura da Bocaina Capital, comenta que os FI-Infra s\u00e3o <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/fundos-de-renda-fixa\/\" target=\"_blank\" rel=\"noopener\"><strong>fundos de renda fixa<\/strong><\/a> que realizam investimento em <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/debentures-incentivadas\/\" target=\"_blank\" rel=\"noopener\">deb\u00eantures incentivadas<\/a>, que s\u00e3o <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/titulos-de-credito\/\" target=\"_blank\" rel=\"noopener\">t\u00edtulos de cr\u00e9dito<\/a> privado. <\/p>\n\n\n\n<p>Ele explica que o fundo atua como debenturista das emiss\u00f5es que fazem parte do <strong>portf\u00f3lio do Fi-Infra<\/strong>, recebendo os pagamentos de principal e juros feitos pelas deb\u00eantures.<\/p>\n\n\n\n<p>\u201cAs <strong>deb\u00eantures incentivadas de infraestrutura<\/strong> possuem, em geral, uma remunera\u00e7\u00e3o de IPCA+cupom, ou seja, se assemelham a uma NTN-B, que \u00e9 o t\u00edtulo p\u00fablico atrelado \u00e0 infla\u00e7\u00e3o\u201d, afirma.<\/p>\n\n\n\n<p>O especialista diz que, mesmo que sejam semestrais os pagamentos desses pap\u00e9is, \u201co valor dos t\u00edtulos incorpora todo dia o \u2018accrual\u2019, o acr\u00e9scimo, dessa remunera\u00e7\u00e3o na sua marca\u00e7\u00e3o de pre\u00e7o. Esse rendimento vai incrementando o patrim\u00f4nio dos fundos diariamente, e comp\u00f5e parte das distribui\u00e7\u00f5es de proventos realizadas pelos FI-Infras mensalmente\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-fi-infra-pagamento-de-proventos-e-isencao-de-imposto\">FI-Infra: pagamento de proventos e isen\u00e7\u00e3o de imposto<\/h2>\n\n\n\n<p>Ao Suno Not\u00edcias, Diogo Arantes, Consultor CVM, especialista em fundos fechados e s\u00f3cio do FI F\u00e1cil Investimentos, comenta que, para quem est\u00e1 habituado com os <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/fundos-imobiliarios\/\" target=\"_blank\" rel=\"noopener\">fundos imobili\u00e1rios<\/a>, o <strong>pagamento de proventos dos Fi-Infra<\/strong> \u201c\u00e9 semelhante\u201d.<\/p>\n\n\n\n<p>Neste sentido, ele explica que h\u00e1 an\u00fancio dos <strong>dividendos do FI-Infra<\/strong> com a data de pagamento e a data limite para quem possui o fundo poder receber o rendimento. Dez dias depois, ocorre o pagamento.<\/p>\n\n\n\n<p>Diogo comenta que os FI-Infra n\u00e3o possuem a obriga\u00e7\u00e3o que os fundos imobili\u00e1rios t\u00eam \u2014 de pagar os <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" target=\"_blank\" rel=\"noopener\">dividendos<\/a> semestralmente os 95% dos respectivos resultados financeiros.<\/p>\n\n\n\n<p>\u201cO que acontece \u00e9 que a maioria desses fundos colocou em seus regulamentos algumas regras para poder pagar, e v\u00e3o pagar mensalmente. E a liberdade \u00e9 pagar como distribui\u00e7\u00e3o de juros, ou como distribui\u00e7\u00e3o de rendimento, ou como distribui\u00e7\u00e3o principal\u201d, complementa.<\/p>\n\n\n\n<p>Entre as <strong>vantagens do FI-Infra<\/strong>, Gabriel, da Bocaina Capital, comenta que esses fundos possibilitam a captura de ganhos de capital com<strong> isen\u00e7\u00e3o fiscal para <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/pessoa-fisica\/\" target=\"_blank\" rel=\"noopener\">pessoa f\u00edsica<\/a><\/strong>.<\/p>\n\n\n\n<p>\u201cA \u00faltima aloca\u00e7\u00e3o que realizamos no fundo Bocaina Infra, o BODB11, que \u00e9 nosso FI-Infra listado na B3, foi em uma deb\u00eanture incentivada com taxa de IPCA+9.83%. No momento que os juros reais estiverem em n\u00edveis mais baixos, \u00e9 poss\u00edvel capturar ganhos de capital relevantes nesses ativos, e esse ganho se reflete em retorno ao cotista do FI-Infra com isen\u00e7\u00e3o de imposto de renda\u201d, complementa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-taxa-de-retorno-dos-fi-infra\">A taxa de retorno dos FI-Infra<\/h2>\n\n\n\n<p>Diogo, do FI F\u00e1cil Investimentos, afirma que o FI-Infra pode ter retorno superior a 18%. Segundo o especialista, geralmente, s\u00e3o atrelados a \u00edndices como o <a href=\"https:\/\/www.suno.com.br\/artigos\/ima-b\/\">IMA-B<\/a>.<\/p>\n\n\n\n<p>\u201cO FI-Infra tem uma liberdade maior de trabalhar como se fosse um <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/fundo-de-credito\/\" target=\"_blank\" rel=\"noopener\">fundo de cr\u00e9dito<\/a>. Ent\u00e3o, ele \u00e9 um fundo que compra deb\u00eantures incentivadas, mas tem a liberdade e pode comprar, inclusive, deb\u00eantures n\u00e3o incentivadas\u201d, afirma.<\/p>\n\n\n\n<p>\u201cEm compensa\u00e7\u00e3o, a m\u00e9dia de infla\u00e7\u00e3o foi alta no ano. Ent\u00e3o, eles conseguiram entregar, em termos de dividendo, taxa acima de 16%. Alguns desvalorizaram, ent\u00e3o voc\u00ea ver\u00e1 um retorno menor. Outros n\u00e3o desvalorizaram e, inclusive, ganharam pre\u00e7o. Por isso, temos retornos acima de 18%. Isso vai depender do estilo que o fundo adaptou\u201d, explica.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-os-proventos-dos-fi-infra-em-relacao-a-renda-fixa-tradicional\">Os proventos dos FI-Infra em rela\u00e7\u00e3o \u00e0 renda fixa tradicional<\/h2>\n\n\n\n<p>De acordo com Gabriel, de modo geral, as deb\u00eantures incentivadas de infraestrutura contam com uma remunera\u00e7\u00e3o de IPCA+cupom.<\/p>\n\n\n\n<p>Ele comenta que \u201cos <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/titulos-de-credito\/\" target=\"_blank\" rel=\"noopener\">t\u00edtulos de cr\u00e9dito<\/a> privado tamb\u00e9m apresentam um pr\u00eamio &nbsp;\u2014 o chamado spread de cr\u00e9dito \u2014, que representa uma remunera\u00e7\u00e3o acima do t\u00edtulo p\u00fablico\u201d.<\/p>\n\n\n\n<p>Outro ponto a se considerar \u00e9 a isen\u00e7\u00e3o fiscal. Ao fazer uma compara\u00e7\u00e3o da mesma rentabilidade em fundos n\u00e3o-incentivados, o especialista destaca que a isen\u00e7\u00e3o de Imposto de Renda para pessoas f\u00edsicas aumenta o retorno l\u00edquido para o cotista do FI-Infra.<\/p>\n\n\n\n<p>Al\u00e9m disso, ele comenta que alguns fundos t\u00eam a capacidade de procurar ativos \u201cfora do radar do mercado, capturando valor em emiss\u00f5es o que tendem a ter uma rela\u00e7\u00e3o de retorno sobre risco superior ao dispon\u00edvel no <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/mercado-secundario\/\" target=\"_blank\" rel=\"noopener\">mercado secund\u00e1rio<\/a> de deb\u00eantures\u201d.<\/p>\n\n\n\n<p>Diogo comenta que, apesar do FI-Infra comprar um t\u00edtulo de <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/guias\/investimento-renda-fixa\/\" target=\"_blank\" rel=\"noopener\">renda fixa<\/a> tradicional, a diferen\u00e7a em rela\u00e7\u00e3o aos ativos dessa classe \u00e9 que \u201cquando o cheque \u00e9 maior, por n\u00e3o ter custo de distribui\u00e7\u00e3o de corretora e nem distribuidora, as taxas que esses fundos pegam s\u00e3o muito maiores\u201d.<\/p>\n\n\n\n<p>Muitas dessas taxas, explica Diogo, n\u00e3o est\u00e3o dispon\u00edveis para pessoas f\u00edsicas: s\u00e3o deb\u00eantures negociadas apenas no mercado <a href=\"https:\/\/www.suno.com.br\/artigos\/cetip\/\">CETIP<\/a>, no <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/mercado-balcao\/\" target=\"_blank\" rel=\"noopener\">mercado de balc\u00e3o<\/a>, entre eles.<\/p>\n\n\n\n<p>\u201cO resultado dessas deb\u00eantures vem da mesma forma. Os Fi-Infra s\u00e3o, na verdade, fundos que compram essas deb\u00eantures. Alguns conseguem originar de forma muito melhor [&#8230;] e outros fundos  basicamente utilizam deb\u00eantures incentivadas e operam cr\u00e9dito \u2014  e podem fazer dinheiro com isso\u201d, acrescenta.<\/p>\n\n\n\n<p>O especialista comenta que os FI-Infra s\u00e3o fundos que, potencialmente, t\u00eam uma carteira com um yield maior do que se compraria no mercado de renda fixa normal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-escolher-os-melhores-fundos-dessa-categoria\">Como escolher os melhores fundos dessa categoria?<\/h2>\n\n\n\n<p>Segundo Diogo, a sele\u00e7\u00e3o dos melhores FI-Infra \u201cparte muito da escolha de segmentos\u201d.<\/p>\n\n\n\n<p>O especialista explica que cada segmento tem um tipo de contrato, e \u201cisso d\u00e1 uma seguran\u00e7a maior ou menor para suas pr\u00f3prias deb\u00eantures, saber se a deb\u00eanture \u00e9 corporativa ou n\u00e3o, qual \u00e9 o grau de risco dela, qual \u00e9 o grau de garantia. Assim, voc\u00ea consegue categorizar as deb\u00eantures e definir\u201d.<\/p>\n\n\n\n<p>Diogo tamb\u00e9m afirma que se pode ter uma rela\u00e7\u00e3o risco e retorno. \u201cVoc\u00ea pode definir os que t\u00eam as maiores taxas, os que t\u00eam os maiores riscos e, a\u00ed, voc\u00ea faz uma verifica\u00e7\u00e3o\u201d.<\/p>\n\n\n\n<p>Gabriel, por sua vez, entende que a escolha de um bom FI-Infra \u201cpassa por observar a ader\u00eancia do <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/perfil-de-risco\/\" target=\"_blank\" rel=\"noopener\">perfil de risco<\/a> e retorno do fundo aos objetivos de investimento do investidor, principalmente em termos de volatilidade, liquidez e perfil de risco do portf\u00f3lio\u201d.<\/p>\n\n\n\n<p>O especialista tamb\u00e9m considera essencial conhecer a gest\u00e3o, \u201csaber quem \u00e9 o gestor, qual sua capacidade e principalmente qual a sua experi\u00eancia em infraestrutura e gest\u00e3o, entre outros fatores\u201d.<\/p>\n\n\n\n<p>\u201c<strong>FI-Infra<\/strong> \u00e9 uma classe emergente de ativos que tem um potencial muito interessante para os investidores no Brasil, mas \u00e9 fundamental ter uma gest\u00e3o profissional experiente atuando via Fi-Infras para que se tenha uma boa curadoria de ativos de qualidade\u201d, finaliza Gabriel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-fi-infra-com-melhores-proventos\">FI-Infra com melhores proventos <\/h2>\n\n\n\n<p>Segundo dados do site Status Invest, o FI-Infra que apresentou o maior <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/artigos\/dividend-yield-como-calcular\/\" rel=\"noopener\">dividend yield<\/a> (retorno em dividendos) em dezembro foi o Bocaina Infra (BODB11), com DY de 1,61%.<\/p>\n\n\n\n<p>O dividend yield \u00e9 um indicador que mostra quanto algum ativo pagou em proventos durante certo per\u00edodo, em rela\u00e7\u00e3o \u00e0 sua cota\u00e7\u00e3o.<\/p>\n\n\n\n<p>Outro FI-Infra que se destacou em dezembro foi o XP FIC FI-Infra (XPID11), que ofereceu proventos com dividend yield de 0,85% e 0,51% no per\u00edodo.<\/p>\n\n\n\n<p>Estes foram os pagamentos realizados em dezembro:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"405\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-dezembro-1024x405.jpg\" alt=\"FI-Infra dividend yield dezembro\" class=\"wp-image-350481\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-dezembro-1024x405.jpg 1024w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-dezembro-300x119.jpg 300w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-dezembro-768x303.jpg 768w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-dezembro-150x59.jpg 150w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-dezembro.jpg 1101w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Reprodu\u00e7\u00e3o\/Status Invest<\/figcaption><\/figure>\n\n\n\n<p>J\u00e1 em novembro, o <strong>FI-Infra com o maior dividend yield <\/strong>foi o BTG Pactual D\u00edvida Infra (BDIF11), com DY de 1,36%.<\/p>\n\n\n\n<p>Confira os demais resultados do m\u00eas:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"404\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-novembro-1024x404.jpg\" alt=\"FI-Infra dividend yield novembro\" class=\"wp-image-350489\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-novembro-1024x404.jpg 1024w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-novembro-300x118.jpg 300w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-novembro-768x303.jpg 768w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-novembro-150x59.jpg 150w, https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/FI-Infra-dividend-yield-novembro.jpg 1100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Reprodu\u00e7\u00e3o\/Status Invest<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"FI-infra: Tudo sobre o fundo BODB11 | com Miguel Ferreira\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/0pz_15g-QxY?start=798&#038;feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/www.suno.com.br\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Por meio da aplica\u00e7\u00e3o em Fundo Incentivado de Investimento em Infraestrutura (FI-Infra), os investidores podem ter acesso a um setor com grande demanda no pa\u00eds. Al\u00e9m da diversifica\u00e7\u00e3o da carteira, os essas pessoas ainda t\u00eam a possibilidade de obter rendimentos isentos de impostos. &nbsp; Em entrevista ao Suno Not\u00edcias, Gabriel Esteca, cofundador e Head de [&hellip;]<\/p>\n","protected":false},"author":224,"featured_media":206836,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[313],"suno_strategy":[],"class_list":["post-350472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-fundos-de-investimento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FI-Infra e dividendos: quanto rendem os principais fundos?<\/title>\n<meta name=\"description\" content=\"Os Fi-Infra possibilita que os investidores obtenham rendimentos isentos de impostos. Veja quanto rendem os principais fundos. \u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FI-Infra e dividendos: quanto rendem os principais fundos?\" \/>\n<meta property=\"og:description\" content=\"Os Fi-Infra possibilita que os investidores obtenham rendimentos isentos de impostos. Veja quanto rendem os principais fundos. \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/dinheiro-pixabay.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1088\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Silvio Suehiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Silvio Suehiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/\"},\"author\":{\"name\":\"Silvio Suehiro\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c94f387eeb0598ad381eac3e47a8686c\"},\"headline\":\"FI-Infra e dividendos: quanto rendem os principais fundos?\",\"datePublished\":\"2023-01-20T19:52:58+00:00\",\"dateModified\":\"2023-01-20T21:06:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/\"},\"wordCount\":1292,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/dinheiro-pixabay.jpg\",\"keywords\":[\"Fundos de investimento\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/\",\"name\":\"FI-Infra e dividendos: quanto rendem os principais fundos?\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/dinheiro-pixabay.jpg\",\"datePublished\":\"2023-01-20T19:52:58+00:00\",\"dateModified\":\"2023-01-20T21:06:30+00:00\",\"description\":\"Os Fi-Infra possibilita que os investidores obtenham rendimentos isentos de impostos. Veja quanto rendem os principais fundos. \u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/dinheiro-pixabay.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/dinheiro-pixabay.jpg\",\"width\":1920,\"height\":1088,\"caption\":\"Fi-Infra: Foto: Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FI-Infra e dividendos: quanto rendem os principais fundos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c94f387eeb0598ad381eac3e47a8686c\",\"name\":\"Silvio Suehiro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/06585eb21140975c6be6bb79a07edac1?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/06585eb21140975c6be6bb79a07edac1?s=96&r=g\",\"caption\":\"Silvio Suehiro\"},\"description\":\"Redator freelancer, com experi\u00eancia na produ\u00e7\u00e3o de not\u00edcias e artigos para as \u00e1reas de economia, finan\u00e7as e investimentos. Graduado em Comunica\u00e7\u00e3o Social - Jornalismo pela Universidade de Mogi das Cruzes (UMC), e p\u00f3s-graduado em Produ\u00e7\u00e3o Audiovisual Multiplataforma pela Universidade Anhembi Morumbi (UAM).\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/silvio-suehiro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FI-Infra e dividendos: quanto rendem os principais fundos?","description":"Os Fi-Infra possibilita que os investidores obtenham rendimentos isentos de impostos. Veja quanto rendem os principais fundos. \u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/","og_locale":"pt_BR","og_type":"article","og_title":"FI-Infra e dividendos: quanto rendem os principais fundos?","og_description":"Os Fi-Infra possibilita que os investidores obtenham rendimentos isentos de impostos. Veja quanto rendem os principais fundos. \u00a0","og_url":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1920,"height":1088,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/dinheiro-pixabay.jpg","type":"image\/jpeg"}],"author":"Silvio Suehiro","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Silvio Suehiro","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/"},"author":{"name":"Silvio Suehiro","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c94f387eeb0598ad381eac3e47a8686c"},"headline":"FI-Infra e dividendos: quanto rendem os principais fundos?","datePublished":"2023-01-20T19:52:58+00:00","dateModified":"2023-01-20T21:06:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/"},"wordCount":1292,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/dinheiro-pixabay.jpg","keywords":["Fundos de investimento"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/","url":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/","name":"FI-Infra e dividendos: quanto rendem os principais fundos?","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/dinheiro-pixabay.jpg","datePublished":"2023-01-20T19:52:58+00:00","dateModified":"2023-01-20T21:06:30+00:00","description":"Os Fi-Infra possibilita que os investidores obtenham rendimentos isentos de impostos. Veja quanto rendem os principais fundos. \u00a0","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/dinheiro-pixabay.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/dinheiro-pixabay.jpg","width":1920,"height":1088,"caption":"Fi-Infra: Foto: Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"FI-Infra e dividendos: quanto rendem os principais fundos?"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c94f387eeb0598ad381eac3e47a8686c","name":"Silvio Suehiro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/06585eb21140975c6be6bb79a07edac1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06585eb21140975c6be6bb79a07edac1?s=96&r=g","caption":"Silvio Suehiro"},"description":"Redator freelancer, com experi\u00eancia na produ\u00e7\u00e3o de not\u00edcias e artigos para as \u00e1reas de economia, finan\u00e7as e investimentos. Graduado em Comunica\u00e7\u00e3o Social - Jornalismo pela Universidade de Mogi das Cruzes (UMC), e p\u00f3s-graduado em Produ\u00e7\u00e3o Audiovisual Multiplataforma pela Universidade Anhembi Morumbi (UAM).","url":"https:\/\/www.suno.com.br\/noticias\/author\/silvio-suehiro\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/dinheiro-pixabay-400x200.jpg\" alt=\"FI-Infra e dividendos: quanto rendem os principais fundos?\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/fi-infra-quanto-rendem-fundos-dividendos\/\"><h2 class=\"content__title\">FI-Infra e dividendos: quanto rendem os principais fundos?<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/silvio-suehiro\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/06585eb21140975c6be6bb79a07edac1?s=96&#038;r=g\" alt=\"Silvio Suehiro\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/silvio-suehiro\/\"><span itemprop=\"author\">Silvio Suehiro<\/span><\/a><\/span><time datetime=\"2023-01-20T16:52:58-03:00\" itemprop=\"datePublished\">20\/01\/2023 16:52<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/350472"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/224"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=350472"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/350472\/revisions"}],"predecessor-version":[{"id":350709,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/350472\/revisions\/350709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/206836"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=350472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=350472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=350472"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=350472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}