{"id":34451,"date":"2019-08-17T09:11:20","date_gmt":"2019-08-17T12:11:20","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=34451"},"modified":"2021-02-17T22:47:57","modified_gmt":"2021-02-18T01:47:57","slug":"banco-central-china-reforma-taxa-de-juros","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/","title":{"rendered":"Banco central da China anuncia nova reforma da taxa de juros"},"content":{"rendered":"<p>O <strong>banco central<\/strong> da China anunciou neste s\u00e1bado (17) o novo projeto de reforma da <strong>taxa de juros<\/strong>.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china-jpg.webp\" width=\"800\" height=\"450\" alt=\"Banco central da China anuncia nova reforma da taxa de juros\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">O Banco Central da China vai continuar mantendo uma pol\u00edtica monet\u00e1ria prudente por causa do surto de coronav\u00edrus<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<p>O intuito da reforma \u00e9 diminuir os custos de financiamento para companhias chinesas que est\u00e3o apresentando resultados ruins. A medida j\u00e1 era esperada por conta dos reflexos da <strong>guerra comercial<\/strong> na economia da <strong>China<\/strong>.<\/p>\n\n<p>As pequenas empresas s\u00e3o o alvo do Banco do Povo da China, pois foram as mais afetadas com as complica\u00e7\u00f5es econ\u00f4micas do pa\u00eds. Para essas empresas, o acesso ao financiamento \u00e9 limitado, o que n\u00e3o ocorre nas estatais, por exemplo.<\/p>\n<p>Os empr\u00e9stimos banc\u00e1rios que j\u00e1 est\u00e3o em vigor n\u00e3o ser\u00e3o afetados pelas novas taxas.<\/p>\n<h2>Reforma na taxa de juros<\/h2>\n<p>O BC chin\u00eas explicou que as <a href=\"https:\/\/www.suno.com.br\/artigos\/taxa-referencial\/\">taxas de juros de refer\u00eancia<\/a> ser\u00e3o substitu\u00eddas pelas taxas de empr\u00e9stimos oferecidos pelos bancos comerciais do pa\u00eds aos seus clientes.<\/p>\n<p>O custo de empr\u00e9stimo dos bancos \u00e9 chamado de &#8220;taxa de empr\u00e9stimo prime (LPR, da sigla em ingl\u00eas)&#8221;.<\/p>\n<p>As institui\u00e7\u00f5es financeiras dever\u00e3o enviar suas taxas de empr\u00e9stimo para o banco central chin\u00eas todos os meses. Assim, o BC poder\u00e1 estabelecer uma m\u00e9dia entre os custos e obter o valor do LPR.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp2.suno.com.br\/pv\/curso-zero-ao-primeiro-rendimento\/?utm_source=suno-noticias&#038;utm_medium=banner&#038;utm_campaign=_SNC4CCF8112_\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/Artigos-e-Noticias-Banner-Materias-02-Mobile_-400x300-1-png.webp\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/Artigos-e-Noticias-Banner-Materias-01-Desktop_-1420x240-1-png.webp\"\n\t\t\t\t\tdata-promo-id=\"635313\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/12\/Artigos-e-Noticias-Banner-Materias-01-Desktop_-1420x240-1-png.webp\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Para obter a m\u00e9dia, o banco central considerar\u00e1 18 institui\u00e7\u00f5es financeiras do pa\u00eds.<\/p>\n<p>Al\u00e9m disso, haver\u00e1 uma taxa m\u00e9dia de juros de cinco anos para ser utilizada em casos de empr\u00e9stimos a longo prazo dos bancos.<\/p>\n<h2>Resultados ruins para a economia da China<\/h2>\n<p>Como consequ\u00eancia da <a href=\"https:\/\/www.suno.com.br\/artigos\/a-guerra-comercial\/\">guerra comercial<\/a> com os Estados Unidos, o crescimento da produ\u00e7\u00e3o industrial chinesa desacelerou para 4,8% em julho ante o mesmo per\u00edodo de 2018.<\/p>\n<p>A disputa comercial com os norte-americanos impacta sobre as empresas e consumidores da China. Mesmo ap\u00f3s uma s\u00e9rie de medidas do governo no \u00faltimo ano, a atividade industrial do pa\u00eds asi\u00e1tico continua a esfriar.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/china-crescimento-da-industria-tem-pior-resultado-em-17-anos\/\">Saiba mais: China: crescimento da ind\u00fastria tem pior resultado em 17 anos<\/a><\/p>\n<p>Larry Hu, diretor do Macquarie Group, um banco de investimentos da Austr\u00e1lia, disse que &#8220;a economia da <strong>China<\/strong> precisa de mais est\u00edmulo porque os obst\u00e1culos s\u00e3o bastante fortes e os dados de hoje s\u00e3o muito mais fracos do que o consenso&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O banco central da China anunciou neste s\u00e1bado (17) o novo projeto de reforma da taxa de juros. O Banco Central da China vai continuar mantendo uma pol\u00edtica monet\u00e1ria prudente por causa do surto de coronav\u00edrus O intuito da reforma \u00e9 diminuir os custos de financiamento para companhias chinesas que est\u00e3o apresentando resultados ruins. A [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":34454,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[1842,711,980,1752],"suno_strategy":[],"class_list":["post-34451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-banco-central-bc","tag-china","tag-guerra-comercial","tag-taxa-de-juros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Banco central da China anuncia plano de reforma da taxa de juros<\/title>\n<meta name=\"description\" content=\"O BC da China anunciou o novo projeto de reforma da taxa de juros. A medida j\u00e1 era esperada ap\u00f3s a guerra comercial. Clique para saber mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banco central da China anuncia plano de reforma da taxa de juros\" \/>\n<meta property=\"og:description\" content=\"O BC da China anunciou o novo projeto de reforma da taxa de juros. A medida j\u00e1 era esperada ap\u00f3s a guerra comercial. Clique para saber mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanna Oliveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanna Oliveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/\"},\"author\":{\"name\":\"Giovanna Oliveira\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120\"},\"headline\":\"Banco central da China anuncia nova reforma da taxa de juros\",\"datePublished\":\"2019-08-17T12:11:20+00:00\",\"dateModified\":\"2021-02-18T01:47:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/\"},\"wordCount\":397,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china-jpg.webp\",\"keywords\":[\"Banco Central (BC)\",\"China\",\"guerra comercial\",\"taxa de juros\"],\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/\",\"name\":\"Banco central da China anuncia plano de reforma da taxa de juros\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china-jpg.webp\",\"datePublished\":\"2019-08-17T12:11:20+00:00\",\"dateModified\":\"2021-02-18T01:47:57+00:00\",\"description\":\"O BC da China anunciou o novo projeto de reforma da taxa de juros. A medida j\u00e1 era esperada ap\u00f3s a guerra comercial. Clique para saber mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china-jpg.webp\",\"width\":680,\"height\":340,\"caption\":\"O Banco Central da China vai continuar mantendo uma pol\u00edtica monet\u00e1ria prudente por causa do surto de coronav\u00edrus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Banco central da China anuncia nova reforma da taxa de juros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120\",\"name\":\"Giovanna Oliveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g\",\"caption\":\"Giovanna Oliveira\"},\"description\":\"Giovanna Oliveira escreve sobre economia e pol\u00edtica. Foi rep\u00f3rter do portal de jornalismo da ESPM-SP e produziu conte\u00fado para a Corinthians TV. \u00c9 estudante da ESPM.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Banco central da China anuncia plano de reforma da taxa de juros","description":"O BC da China anunciou o novo projeto de reforma da taxa de juros. A medida j\u00e1 era esperada ap\u00f3s a guerra comercial. Clique para saber mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/","og_locale":"pt_BR","og_type":"article","og_title":"Banco central da China anuncia plano de reforma da taxa de juros","og_description":"O BC da China anunciou o novo projeto de reforma da taxa de juros. A medida j\u00e1 era esperada ap\u00f3s a guerra comercial. Clique para saber mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":680,"height":340,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china.jpg","type":"image\/jpeg"}],"author":"Giovanna Oliveira","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Giovanna Oliveira","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/"},"author":{"name":"Giovanna Oliveira","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120"},"headline":"Banco central da China anuncia nova reforma da taxa de juros","datePublished":"2019-08-17T12:11:20+00:00","dateModified":"2021-02-18T01:47:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/"},"wordCount":397,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china-jpg.webp","keywords":["Banco Central (BC)","China","guerra comercial","taxa de juros"],"articleSection":["Internacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/","url":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/","name":"Banco central da China anuncia plano de reforma da taxa de juros","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china-jpg.webp","datePublished":"2019-08-17T12:11:20+00:00","dateModified":"2021-02-18T01:47:57+00:00","description":"O BC da China anunciou o novo projeto de reforma da taxa de juros. A medida j\u00e1 era esperada ap\u00f3s a guerra comercial. Clique para saber mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china-jpg.webp","width":680,"height":340,"caption":"O Banco Central da China vai continuar mantendo uma pol\u00edtica monet\u00e1ria prudente por causa do surto de coronav\u00edrus"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Internacional","item":"https:\/\/www.suno.com.br\/noticias\/internacional\/"},{"@type":"ListItem","position":3,"name":"Banco central da China anuncia nova reforma da taxa de juros"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120","name":"Giovanna Oliveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g","caption":"Giovanna Oliveira"},"description":"Giovanna Oliveira escreve sobre economia e pol\u00edtica. Foi rep\u00f3rter do portal de jornalismo da ESPM-SP e produziu conte\u00fado para a Corinthians TV. \u00c9 estudante da ESPM.","url":"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/4a41c9ec-bc-china-400x200.webp\" alt=\"Banco central da China anuncia nova reforma da taxa de juros\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/internacional\/\">Internacional<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/banco-central-china-reforma-taxa-de-juros\/\"><h2 class=\"content__title\">Banco central da China anuncia nova reforma da taxa de juros<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/952a89ca-screenshot_20190608-171507-150x150.webp\" alt=\"Giovanna Oliveira\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/\"><span itemprop=\"author\">Giovanna Oliveira<\/span><\/a><\/span><time datetime=\"2019-08-17T09:11:20-03:00\" itemprop=\"datePublished\">17\/08\/2019 09:11<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/34451"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=34451"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/34451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/34454"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=34451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=34451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=34451"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=34451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}