{"id":340548,"date":"2023-01-04T14:25:33","date_gmt":"2023-01-04T17:25:33","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=340548"},"modified":"2023-01-04T16:54:37","modified_gmt":"2023-01-04T19:54:37","slug":"revisao-reforma-da-previdencia-lula-rui-costa","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/","title":{"rendered":"Rui Costa desmente Lupi e nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula"},"content":{"rendered":"<p>O ministro da Casa Civil, Rui Costa, afirmou nesta quarta-feira (4) que o presidente Luiz In\u00e1cio Lula da Silva (PT) n\u00e3o deu aval a nenhum estudo de revis\u00e3o da <strong>reforma da Previd\u00eancia<\/strong>. \u201cN\u00e3o h\u00e1 nenhuma proposta de revis\u00e3o da reforma da Previd\u00eancia em curso\u201d, disse.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Rui Costa desmente Lupi e nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Rui Costa anuncia expans\u00e3o do Minha Casa, Minha Vida e novos programas sociais. Foto: Jos\u00e9 Cruz\/Ag\u00eancia Brasil<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"89005\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>A fala de Rui Costa tenta conter as rea\u00e7\u00f5es negativas \u00e0 declara\u00e7\u00e3o do novo ministro da Previd\u00eancia, Carlos Lupi, de que ser\u00e1 institu\u00edda uma comiss\u00e3o para estudar a revis\u00e3o da reforma.<\/p>\n\n\n\n<p>Costa se reuniu com Lula na manh\u00e3 desta quarta-feira e afirmou que o presidente delegou \u00e0 Casa Civil a tarefa de analisar as propostas de revis\u00e3o sugeridas por ministros.<\/p>\n\n\n\n\t<div data-element=\"shortcode-read-more\" class=\"readToo\">\n\t\t\t\t<span class=\"readToo__title\">Leia mais<\/span>\n\t\t\t\t<ul class=\"readToo__list\">\n\t\t\t<li><a href=\"https:\/\/www.suno.com.br\/noticias\/fgts-saque-aniversario-sera-encerrado-marinho\/\">FGTS: saque-anivers\u00e1rio ser\u00e1 encerrado, diz ministro Luiz Marinho<\/a><\/li><li><a href=\"https:\/\/www.suno.com.br\/noticias\/geraldo-alckmin-assume-mdic\/\">Geraldo Alckmin assume MDIC e promete retomar pol\u00edtica de &#8216;reindustrializa\u00e7\u00e3o\u2019<\/a><\/li>\t\t<\/ul>\n\t<\/div>\n\n\n\n\n<p>Lupi havia dito na ter\u00e7a-feira (3) que a <strong>reforma da Previd\u00eancia<\/strong> foi uma \u201cantirreforma\u201d feita apenas para retirar direitos dos trabalhadores. O ministro declarou que pretendia rediscutir as mudan\u00e7as no sistema previdenci\u00e1rio. <\/p>\n\n\n\n<p>As declara\u00e7\u00f5es derrubaram o Ibovespa e provocaram a <a class=\"suno-keyword\" target=\"_blank\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/alta-do-dolar\/\" rel=\"noopener\">alta do d\u00f3lar<\/a> na ter\u00e7a-feira, que chegou ao maior valor em seis meses, negociado a R$ 5,45.<\/p>\n\n\n\n<p>Costa afirmou que o presidente Lula \u00e9 quem deve bater o martelo sobre qualquer mudan\u00e7a ou revis\u00e3o da <strong>reforma da Previd\u00eancia<\/strong>. Segundo o ministro, neste momento n\u00e3o h\u00e1 nada sendo elaborado. &#8220;[Uma eventual reforma] vai passar pela Casa Civil e \u00e9 evidente que quem teve mais de 60 milh\u00f5es de votos \u00e9 quem decide&#8221;, comentou. \u201cTodo mundo tem direito a opini\u00e3o, mas nesse momento n\u00e3o h\u00e1 nenhuma proposta. As energias est\u00e3o l\u00e1 em cima, \u00e9 um momento de posse, de alegria e de entusiasmo.&#8221;<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O ministro da Casa Civil, Rui Costa, afirmou nesta quarta-feira (4) que o presidente Luiz In\u00e1cio Lula da Silva (PT) n\u00e3o deu aval a nenhum estudo de revis\u00e3o da reforma da Previd\u00eancia. \u201cN\u00e3o h\u00e1 nenhuma proposta de revis\u00e3o da reforma da Previd\u00eancia em curso\u201d, disse. Rui Costa anuncia expans\u00e3o do Minha Casa, Minha Vida e [&hellip;]<\/p>\n","protected":false},"author":70,"featured_media":340549,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[61],"tags":[106895,940],"suno_strategy":[],"class_list":["post-340548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-previdencia","tag-reforma-da-previdencia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rui Costa nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula<\/title>\n<meta name=\"description\" content=\"A fala de Rui Costa tenta conter as rea\u00e7\u00f5es negativas \u00e0 declara\u00e7\u00e3o de Carlos Lupi sobre revis\u00e3o da reforma da Previd\u00eancia. Entenda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rui Costa nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula\" \/>\n<meta property=\"og:description\" content=\"A fala de Rui Costa tenta conter as rea\u00e7\u00f5es negativas \u00e0 declara\u00e7\u00e3o de Carlos Lupi sobre revis\u00e3o da reforma da Previd\u00eancia. Entenda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"717\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Beatriz Boyadjian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beatriz Boyadjian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/\"},\"author\":{\"name\":\"Beatriz Boyadjian\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c9d40f227e4ffee8114b1299c28902b0\"},\"headline\":\"Rui Costa desmente Lupi e nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula\",\"datePublished\":\"2023-01-04T17:25:33+00:00\",\"dateModified\":\"2023-01-04T19:54:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/\"},\"wordCount\":287,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao.jpg\",\"keywords\":[\"Previd\u00eancia\",\"Reforma da Previd\u00eancia\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/\",\"name\":\"Rui Costa nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao.jpg\",\"datePublished\":\"2023-01-04T17:25:33+00:00\",\"dateModified\":\"2023-01-04T19:54:37+00:00\",\"description\":\"A fala de Rui Costa tenta conter as rea\u00e7\u00f5es negativas \u00e0 declara\u00e7\u00e3o de Carlos Lupi sobre revis\u00e3o da reforma da Previd\u00eancia. Entenda.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao.jpg\",\"width\":1200,\"height\":717,\"caption\":\"Rui Costa anuncia expans\u00e3o do Minha Casa, Minha Vida e novos programas sociais. Foto: Jos\u00e9 Cruz\/Ag\u00eancia Brasil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/politica\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rui Costa desmente Lupi e nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c9d40f227e4ffee8114b1299c28902b0\",\"name\":\"Beatriz Boyadjian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4c3c59f4030e268f950437c4f36e38b7?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4c3c59f4030e268f950437c4f36e38b7?s=96&r=g\",\"caption\":\"Beatriz Boyadjian\"},\"description\":\"Rep\u00f3rter multim\u00eddia no Suno Not\u00edcias. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero, foi rep\u00f3rter da Forbes Brasil e atuou na cobertura de hard news, economia, neg\u00f3cios e lifestyle. Gerenciou as redes sociais da edi\u00e7\u00e3o brasileira da tradicional revista de neg\u00f3cios. Na M\u00e1quina Cohn&amp;Wolfe, atuou como rela\u00e7\u00f5es p\u00fablicas de clientes do N\u00facleo de Sa\u00fade da empresa. Produziu releases, notas, relat\u00f3rios, entre outros, para empresas como Biomm, Hypera, FIDI. Anteriormente, respons\u00e1vel pelas redes sociais do Suno Not\u00edcias.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/beatriz-boyadjian\/\"],\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/beatriz-boyadjian\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rui Costa nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula","description":"A fala de Rui Costa tenta conter as rea\u00e7\u00f5es negativas \u00e0 declara\u00e7\u00e3o de Carlos Lupi sobre revis\u00e3o da reforma da Previd\u00eancia. Entenda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/","og_locale":"pt_BR","og_type":"article","og_title":"Rui Costa nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula","og_description":"A fala de Rui Costa tenta conter as rea\u00e7\u00f5es negativas \u00e0 declara\u00e7\u00e3o de Carlos Lupi sobre revis\u00e3o da reforma da Previd\u00eancia. Entenda.","og_url":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1200,"height":717,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao.jpg","type":"image\/jpeg"}],"author":"Beatriz Boyadjian","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Beatriz Boyadjian","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/"},"author":{"name":"Beatriz Boyadjian","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c9d40f227e4ffee8114b1299c28902b0"},"headline":"Rui Costa desmente Lupi e nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula","datePublished":"2023-01-04T17:25:33+00:00","dateModified":"2023-01-04T19:54:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/"},"wordCount":287,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao.jpg","keywords":["Previd\u00eancia","Reforma da Previd\u00eancia"],"articleSection":["Pol\u00edtica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/","url":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/","name":"Rui Costa nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao.jpg","datePublished":"2023-01-04T17:25:33+00:00","dateModified":"2023-01-04T19:54:37+00:00","description":"A fala de Rui Costa tenta conter as rea\u00e7\u00f5es negativas \u00e0 declara\u00e7\u00e3o de Carlos Lupi sobre revis\u00e3o da reforma da Previd\u00eancia. Entenda.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao.jpg","width":1200,"height":717,"caption":"Rui Costa anuncia expans\u00e3o do Minha Casa, Minha Vida e novos programas sociais. Foto: Jos\u00e9 Cruz\/Ag\u00eancia Brasil"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica","item":"https:\/\/www.suno.com.br\/noticias\/politica\/"},{"@type":"ListItem","position":3,"name":"Rui Costa desmente Lupi e nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c9d40f227e4ffee8114b1299c28902b0","name":"Beatriz Boyadjian","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4c3c59f4030e268f950437c4f36e38b7?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c3c59f4030e268f950437c4f36e38b7?s=96&r=g","caption":"Beatriz Boyadjian"},"description":"Rep\u00f3rter multim\u00eddia no Suno Not\u00edcias. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero, foi rep\u00f3rter da Forbes Brasil e atuou na cobertura de hard news, economia, neg\u00f3cios e lifestyle. Gerenciou as redes sociais da edi\u00e7\u00e3o brasileira da tradicional revista de neg\u00f3cios. Na M\u00e1quina Cohn&amp;Wolfe, atuou como rela\u00e7\u00f5es p\u00fablicas de clientes do N\u00facleo de Sa\u00fade da empresa. Produziu releases, notas, relat\u00f3rios, entre outros, para empresas como Biomm, Hypera, FIDI. Anteriormente, respons\u00e1vel pelas redes sociais do Suno Not\u00edcias.","sameAs":["https:\/\/www.linkedin.com\/in\/beatriz-boyadjian\/"],"url":"https:\/\/www.suno.com.br\/noticias\/author\/beatriz-boyadjian\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/01\/rui-costa-casa-civil-previdencia-agencia-brasil-reproducao-400x200.jpg\" alt=\"Rui Costa desmente Lupi e nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/politica\/\">Pol\u00edtica<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/revisao-reforma-da-previdencia-lula-rui-costa\/\"><h2 class=\"content__title\">Rui Costa desmente Lupi e nega revis\u00e3o de reforma da Previd\u00eancia no governo Lula<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/janize-colaco\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/11\/20221120_111807-1-150x150.jpg\" alt=\"Janize Cola\u00e7o\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/janize-colaco\/\"><span itemprop=\"author\">Janize Cola\u00e7o<\/span><\/a><\/span><time datetime=\"2023-01-04T14:25:33-03:00\" itemprop=\"datePublished\">04\/01\/2023 14:25<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/340548"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=340548"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/340548\/revisions"}],"predecessor-version":[{"id":340705,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/340548\/revisions\/340705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/340549"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=340548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=340548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=340548"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=340548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}