{"id":33877,"date":"2019-08-13T12:22:52","date_gmt":"2019-08-13T15:22:52","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=33877"},"modified":"2021-05-30T21:15:11","modified_gmt":"2021-05-31T00:15:11","slug":"estacio-lucro-r-2018-milhoes-segundo-trimestre","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/","title":{"rendered":"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre"},"content":{"rendered":"<p>A companhia de educa\u00e7\u00e3o Est\u00e1cio <strong>(YDUQ3)<\/strong> registrou um lucro l\u00edquido de R$ 201,8 milh\u00f5es na base pro-forma, levando em conta o per\u00edodo compreendido entre o in\u00edcio de abril e o final de junho deste ano. O lucro mostra uma baixa de 14,8% ante o mesmo per\u00edodo do ano passado.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead-800x450.webp\" width=\"800\" height=\"450\" alt=\"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\"><\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n<p>De acordo com a <strong>Est\u00e1cio<\/strong>, em 2018 o lucro foi maior por conta da revers\u00e3o de Imposto de Renda e ao aux\u00edlio social em rela\u00e7\u00e3o ao benef\u00edcio do POEB. O POEB significa a &#8216;Propor\u00e7\u00e3o de Ocupa\u00e7\u00e3o Efetiva de Bolsas&#8217;. Se esses efeitos n\u00e3o fossem levados em conta, o <a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\"><strong>lucro<\/strong> <strong>l\u00edquido<\/strong><\/a> teria atingido R$ 179,9 milh\u00f5es. Dessa forma, o lucro l\u00edquido do segundo trimestre deste ano seria 12% maior do que o do ano passado.<\/p>\n<p>Com as normas cont\u00e1beis do <a href=\"https:\/\/www.suno.com.br\/artigos\/contabilidade-internacional\/\">IFRS <\/a>16, o lucro da empresa de educa\u00e7\u00e3o no trimestre foi de R$ 194,8 milh\u00f5es. O resultado operacional da Est\u00e1cio atingiu o valor de R$ 288 milh\u00f5es, uma alta de 1,6% em compara\u00e7\u00e3o com o ano anterior. O resultado \u00e9 medido pelo <a href=\"https:\/\/www.suno.com.br\/artigos\/ebitda\/\">Ebitda<\/a> (lucro antes de juros, impostos, deprecia\u00e7\u00e3o e amortiza\u00e7\u00e3o).<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/minicurso-contabilidade\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Minicurso-Contabilidade.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Minicurso-Contabilidade.png\"\n\t\t\t\t\tdata-promo-id=\"383158\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Minicurso-Contabilidade.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Considerando o IFRS 16, o <strong>Ebitda<\/strong> chegou a R$ 342 milh\u00f5es no per\u00edodo. Entretanto, especialista esperavam o valor de R$ 348,2 milh\u00f5es.<\/p>\n<p>A receita l\u00edquida da Est\u00e1cio somou R$ 957,2 milh\u00f5es no segundo trimestre deste ano, uma baixa de 0,7 ante ao igual per\u00edodo de 2018.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/magazine-luiza-lucro-liquido-acao\/\">Veja tamb\u00e9m: Magazine Luiza tem avan\u00e7o de 174,7% no lucro l\u00edquido do 2T19\u00a0<\/a><\/p>\n<h2>Companhia explica baixa nos resultados<\/h2>\n<p>A baixa \u00e9 explicada pela empresa por conta da desacelera\u00e7\u00e3o na economia nacional e, consequentemente, a queda de alunos em salas de aula. Al\u00e9m disso, houve uma diminui\u00e7\u00e3o de alunos do <strong>Fies<\/strong>. O programa estudantil foi reduzido pelo governo de <strong>Jair<\/strong> <strong>Bolsonaro<\/strong>.<\/p>\n<p>As despesas gerais da <strong>Est\u00e1cio<\/strong> tiveram uma queda de 9% no comparativo anual. O valor no trimestre ficou em R$ 137,6 milh\u00f5es.<\/p>\n<h2>A\u00e7\u00f5es da Est\u00e1cio<\/h2>\n<p>Por volta das 12h15 desta ter\u00e7a-feira (13), a <strong>Est\u00e1cio (YDUQ3)<\/strong> registrava alta de\u00a0<span class=\"ng-binding\">0,33<\/span>\u00a0<label class=\"percent\">% com as a\u00e7\u00f5es sendo negociadas a R$ 33,63.<\/label><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A companhia de educa\u00e7\u00e3o Est\u00e1cio (YDUQ3) registrou um lucro l\u00edquido de R$ 201,8 milh\u00f5es na base pro-forma, levando em conta o per\u00edodo compreendido entre o in\u00edcio de abril e o final de junho deste ano. O lucro mostra uma baixa de 14,8% ante o mesmo per\u00edodo do ano passado. De acordo com a Est\u00e1cio, em [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":33881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[1029,2363],"suno_strategy":[],"class_list":["post-33877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-balancos-trimestrais","tag-yduqs-yduq3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre<\/title>\n<meta name=\"description\" content=\"A companhia de educa\u00e7\u00e3o Est\u00e1cio (YDUQ3) registrou um l\u00edquido de R$ 201,8 milh\u00f5es na base pro-forma do segundo trimestre. Clique e saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre\" \/>\n<meta property=\"og:description\" content=\"A companhia de educa\u00e7\u00e3o Est\u00e1cio (YDUQ3) registrou um l\u00edquido de R$ 201,8 milh\u00f5es na base pro-forma do segundo trimestre. Clique e saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1089\" \/>\n\t<meta property=\"og:image:height\" content=\"637\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juliano Passaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juliano Passaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/\"},\"author\":{\"name\":\"Juliano Passaro\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3\"},\"headline\":\"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre\",\"datePublished\":\"2019-08-13T15:22:52+00:00\",\"dateModified\":\"2021-05-31T00:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/\"},\"wordCount\":371,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead-jpg.webp\",\"keywords\":[\"balan\u00e7os trimestrais\",\"Yduqs (YDUQ3)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/\",\"name\":\"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead-jpg.webp\",\"datePublished\":\"2019-08-13T15:22:52+00:00\",\"dateModified\":\"2021-05-31T00:15:11+00:00\",\"description\":\"A companhia de educa\u00e7\u00e3o Est\u00e1cio (YDUQ3) registrou um l\u00edquido de R$ 201,8 milh\u00f5es na base pro-forma do segundo trimestre. Clique e saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead-jpg.webp\",\"width\":1089,\"height\":637,\"caption\":\"Yduqs - Est\u00e1cio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3\",\"name\":\"Juliano Passaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g\",\"caption\":\"Juliano Passaro\"},\"description\":\"Juliano Passaro escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal da Suno Research. Antes da Suno, trabalhou no Portal da Band. \u00c9 formado em jornalismo pela Universidade Presbiteriana Mackenzie.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre","description":"A companhia de educa\u00e7\u00e3o Est\u00e1cio (YDUQ3) registrou um l\u00edquido de R$ 201,8 milh\u00f5es na base pro-forma do segundo trimestre. Clique e saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/","og_locale":"pt_BR","og_type":"article","og_title":"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre","og_description":"A companhia de educa\u00e7\u00e3o Est\u00e1cio (YDUQ3) registrou um l\u00edquido de R$ 201,8 milh\u00f5es na base pro-forma do segundo trimestre. Clique e saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1089,"height":637,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead.jpg","type":"image\/jpeg"}],"author":"Juliano Passaro","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Juliano Passaro","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/"},"author":{"name":"Juliano Passaro","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3"},"headline":"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre","datePublished":"2019-08-13T15:22:52+00:00","dateModified":"2021-05-31T00:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/"},"wordCount":371,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead-jpg.webp","keywords":["balan\u00e7os trimestrais","Yduqs (YDUQ3)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/","url":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/","name":"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead-jpg.webp","datePublished":"2019-08-13T15:22:52+00:00","dateModified":"2021-05-31T00:15:11+00:00","description":"A companhia de educa\u00e7\u00e3o Est\u00e1cio (YDUQ3) registrou um l\u00edquido de R$ 201,8 milh\u00f5es na base pro-forma do segundo trimestre. Clique e saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead-jpg.webp","width":1089,"height":637,"caption":"Yduqs - Est\u00e1cio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3","name":"Juliano Passaro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g","caption":"Juliano Passaro"},"description":"Juliano Passaro escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal da Suno Research. Antes da Suno, trabalhou no Portal da Band. \u00c9 formado em jornalismo pela Universidade Presbiteriana Mackenzie.","url":"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/08\/34feca2f-unidade-da-esta\u0301cio-em-vic\u0327osa-mg-instituic\u0327a\u0303o-carioca-chegou-a-600-polos-de-ead-400x200.webp\" alt=\"Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/estacio-lucro-r-2018-milhoes-segundo-trimestre\/\"><h2 class=\"content__title\">Est\u00e1cio tem lucro de R$ 201,8 milh\u00f5es no segundo trimestre<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/7cc3efea-whatsapp-image-2019-07-18-at-21.59.33-e1563499821209-150x150.webp\" alt=\"Juliano Passaro\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\"><span itemprop=\"author\">Juliano Passaro<\/span><\/a><\/span><time datetime=\"2019-08-13T12:22:52-03:00\" itemprop=\"datePublished\">13\/08\/2019 12:22<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/33877"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=33877"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/33877\/revisions"}],"predecessor-version":[{"id":152632,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/33877\/revisions\/152632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/33881"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=33877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=33877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=33877"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=33877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}