{"id":33193,"date":"2019-08-06T18:58:45","date_gmt":"2019-08-06T21:58:45","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=33193"},"modified":"2021-06-13T23:42:24","modified_gmt":"2021-06-14T02:42:24","slug":"ibovespa-alta-06082019","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/","title":{"rendered":"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China"},"content":{"rendered":"<p>O Ibovespa encerrou em alta de 2,06% nesta ter\u00e7a-feira (06), acompanhando as bolsas norte-americanas que atingiram seus maiores ganhos di\u00e1rios das \u00faltimas oito semanas. O \u00edndice acion\u00e1rio fechou o preg\u00e3o com 102.163,688 pontos, aumentando cerca de 2000 pontos em rela\u00e7\u00e3o ao valor registrado ontem (05).<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa-800x450.webp\" width=\"800\" height=\"450\" alt=\"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">O Ibovespa hoje encerrou em alta acompanhando as bolas internacionais<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\n<p>A alta de hoje do <strong>Ibovespa<\/strong> \u00e9 a maior registrada desde 21 de maio, com o volume financeiro negociado chegando a R$ 17,79 bilh\u00f5es.<\/p>\n<h2>Uma tr\u00e9gua na guerra<\/h2>\n<p>O crescimento externo se deu por conta da sinaliza\u00e7\u00e3o de que os <strong>Estados Unidos<\/strong> seguir\u00e3o negociando com a <strong>China.<\/strong> Segundo o assessor econ\u00f4mico da Casa Branca, Larry Kudlow, o presidente Donald Trump quer continuar as tratativas para encerrar a <strong>guerra comercial<\/strong> entre os dois pa\u00edses.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/asset\/fundos\/suno-fic-fia\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/SUNO-FIC-FIA-400x300-Mobile-Artigos-5.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/SUNO-FIC-FIA-1420x240-Banner-Artigos-1-_-Banner-Materias-4.png\"\n\t\t\t\t\tdata-promo-id=\"478742\"\t\t\t\t\t\t\t\t\t\twidth='2840' height='480'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/SUNO-FIC-FIA-1420x240-Banner-Artigos-1-_-Banner-Materias-4.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>O Banco Popular da China (PBoC) definiu hoje a corre\u00e7\u00e3o cambial di\u00e1ria em n\u00edvel mais alto do que o esperado por analistas, o que resultou na melhora entre as duas grandes pot\u00eancias. Tal corre\u00e7\u00e3o ajudou a aliviar a tens\u00e3o entre investidores.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/china-novas-medidas-diminuir-desvalorizacao-yuan\/\">Entenda mais sobre as novas medidas econ\u00f4micas chinesas<\/a><\/p>\n<p>Na \u00faltima segunda (05), a moeda chinesa ficou cotada em 7 yuans por d\u00f3lar.\u00a0 A queda brusca pode deixar o mercado completamente inst\u00e1vel. Como consequ\u00eancia, a economia mundial seria abalada e isso geraria uma fuga de capitais.<\/p>\n<h2>Possibilidade de um novo corte na Selic<\/h2>\n<p>O Banco Central (BC) divulgou nesta ter\u00e7a-feira (6) a ata da reuni\u00e3o do Comit\u00ea de Pol\u00edtica Monet\u00e1ria (Copom) que decidiu na \u00faltima quarta-feira (31) reduzir a <strong>taxa b\u00e1sica de juros (Selic)<\/strong> de 6,5% para 6% ao ano.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/banco-central-taxa-selic-basica-de-juros\/\">Saiba mais sobre este comunicado do Banco Central<\/a><\/p>\n<p>Nesta ata o Banco Central indica a possibilidade de novo corte na taxa Selic. De acordo com o documento, a desacelera\u00e7\u00e3o da economia global permanece, dessa forma, o cen\u00e1rio pressup\u00f5e que a taxa b\u00e1sica de juros encerre o ano em 5,50%.<\/p>\n<h2>\u00daltima cota\u00e7\u00e3o do Ibovespa<\/h2>\n<p>Na \u00faltima sess\u00e3o, na segunda-feira (5), o <strong><a href=\"https:\/\/www.youtube.com\/watch?v=Lgr57xxtHYg\">Ibovespa<\/a><\/strong> encerrou em queda de -2,51% alcan\u00e7ando 100.097,75 pontos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Ibovespa encerrou em alta de 2,06% nesta ter\u00e7a-feira (06), acompanhando as bolsas norte-americanas que atingiram seus maiores ganhos di\u00e1rios das \u00faltimas oito semanas. O \u00edndice acion\u00e1rio fechou o preg\u00e3o com 102.163,688 pontos, aumentando cerca de 2000 pontos em rela\u00e7\u00e3o ao valor registrado ontem (05). O Ibovespa hoje encerrou em alta acompanhando as bolas internacionais [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":29631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[711,793,980,721,290],"suno_strategy":[],"class_list":["post-33193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-china","tag-estados-unidos-eua","tag-guerra-comercial","tag-ibovespa","tag-taxa-selic"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China<\/title>\n<meta name=\"description\" content=\"O Ibovespa encerrou em alta de 2,06% nesta ter\u00e7a-feira (06), com 102.163,688 pontos. Clique para saber mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China\" \/>\n<meta property=\"og:description\" content=\"O Ibovespa encerrou em alta de 2,06% nesta ter\u00e7a-feira (06), com 102.163,688 pontos. Clique para saber mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafael Lara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafael Lara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/\"},\"author\":{\"name\":\"Rafael Lara\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/098743caeed97b37f51315c9576c4078\"},\"headline\":\"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China\",\"datePublished\":\"2019-08-06T21:58:45+00:00\",\"dateModified\":\"2021-06-14T02:42:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/\"},\"wordCount\":351,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa-jpg.webp\",\"keywords\":[\"China\",\"Estados Unidos (EUA)\",\"guerra comercial\",\"Ibovespa\",\"Taxa Selic\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/\",\"name\":\"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa-jpg.webp\",\"datePublished\":\"2019-08-06T21:58:45+00:00\",\"dateModified\":\"2021-06-14T02:42:24+00:00\",\"description\":\"O Ibovespa encerrou em alta de 2,06% nesta ter\u00e7a-feira (06), com 102.163,688 pontos. Clique para saber mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa-jpg.webp\",\"width\":1200,\"height\":630,\"caption\":\"O Ibovespa hoje encerrou em alta acompanhando as bolas internacionais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/mercado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/098743caeed97b37f51315c9576c4078\",\"name\":\"Rafael Lara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dfc254ab9bb2ea1895d98b9e9dae4bdd?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dfc254ab9bb2ea1895d98b9e9dae4bdd?s=96&r=g\",\"caption\":\"Rafael Lara\"},\"description\":\"Rafael Lara cursa jornalismo na Faculdade C\u00e1sper L\u00edbero. Escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal Suno Not\u00edcias. Antes, colaborou na TV Gazeta na produ\u00e7\u00e3o do programa Edi\u00e7\u00e3o Extra.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/rafael\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China","description":"O Ibovespa encerrou em alta de 2,06% nesta ter\u00e7a-feira (06), com 102.163,688 pontos. Clique para saber mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/","og_locale":"pt_BR","og_type":"article","og_title":"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China","og_description":"O Ibovespa encerrou em alta de 2,06% nesta ter\u00e7a-feira (06), com 102.163,688 pontos. Clique para saber mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1200,"height":630,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa.jpg","type":"image\/jpeg"}],"author":"Rafael Lara","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Rafael Lara","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/"},"author":{"name":"Rafael Lara","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/098743caeed97b37f51315c9576c4078"},"headline":"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China","datePublished":"2019-08-06T21:58:45+00:00","dateModified":"2021-06-14T02:42:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/"},"wordCount":351,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa-jpg.webp","keywords":["China","Estados Unidos (EUA)","guerra comercial","Ibovespa","Taxa Selic"],"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/","url":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/","name":"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa-jpg.webp","datePublished":"2019-08-06T21:58:45+00:00","dateModified":"2021-06-14T02:42:24+00:00","description":"O Ibovespa encerrou em alta de 2,06% nesta ter\u00e7a-feira (06), com 102.163,688 pontos. Clique para saber mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa-jpg.webp","width":1200,"height":630,"caption":"O Ibovespa hoje encerrou em alta acompanhando as bolas internacionais"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/www.suno.com.br\/noticias\/mercado\/"},{"@type":"ListItem","position":3,"name":"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/098743caeed97b37f51315c9576c4078","name":"Rafael Lara","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dfc254ab9bb2ea1895d98b9e9dae4bdd?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dfc254ab9bb2ea1895d98b9e9dae4bdd?s=96&r=g","caption":"Rafael Lara"},"description":"Rafael Lara cursa jornalismo na Faculdade C\u00e1sper L\u00edbero. Escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal Suno Not\u00edcias. Antes, colaborou na TV Gazeta na produ\u00e7\u00e3o do programa Edi\u00e7\u00e3o Extra.","url":"https:\/\/www.suno.com.br\/noticias\/author\/rafael\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/0bff64a7-ibovespa-400x200.webp\" alt=\"Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mercado\/\">Mercado<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-alta-06082019\/\"><h2 class=\"content__title\">Ibovespa sobe com redu\u00e7\u00e3o da tens\u00e3o comercial entre EUA e China<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/rafael\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/dfc254ab9bb2ea1895d98b9e9dae4bdd?s=96&#038;r=g\" alt=\"Rafael Lara\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/rafael\/\"><span itemprop=\"author\">Rafael Lara<\/span><\/a><\/span><time datetime=\"2019-08-06T18:58:45-03:00\" itemprop=\"datePublished\">06\/08\/2019 18:58<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/33193"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=33193"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/33193\/revisions"}],"predecessor-version":[{"id":157295,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/33193\/revisions\/157295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/29631"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=33193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=33193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=33193"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=33193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}