{"id":326061,"date":"2022-11-30T08:06:40","date_gmt":"2022-11-30T11:06:40","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=326061"},"modified":"2022-11-30T08:08:35","modified_gmt":"2022-11-30T11:08:35","slug":"banco-do-brasil-bbas3-eztec-eztc3-dividendos","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/","title":{"rendered":"Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta-feira; veja valores"},"content":{"rendered":"<p>Esta quarta-feira (30) \u00e9 um dos dias aguardados pelos investidores que seguem uma estrat\u00e9gia de investimentos focada em <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" target=\"_blank\" rel=\"noopener\">dividendos<\/a>: o <strong>Banco do Brasil<\/strong> (BBAS3) e a <a class=\"suno-keyword\" data-force=\"yes\" data-priority=\"2\" href=\"https:\/\/www.suno.com.br\/acoes\/EZTC3\/\" target=\"_blank\" rel=\"noopener\">Eztec (EZTC3)<\/a> v\u00e3o pagar rendimentos aos seus acionistas.<\/p><div class=\"videoFull \">\n\t\t\t<div class=\"videoWrapper yt-lazyload center\"\n\t\t\t\tdata-width=\"960\"\n\t\t\t\tdata-height=\"540\"\n\t\t\t\tdata-id=\"ouAKksaBIX0\"\n\t\t\t\tdata-alt=\"V\u00eddeo do YouTube - clique para reproduzir\"\n\t\t\t\tdata-logo=\"3\"\n\t\t\t\tdata-imagequality=\"maxres\">\n\t\t\t<\/div>\n\t\t<\/div><script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"VideoObject\",\"name\":\"MERCADO APOSTA EM DESIDRATA\u00c7\u00c3O DA PEC | Alckmin na Fazenda? | 'Efeito China' ajuda Ibovespa\",\"description\":\"#pecdatransi\u00e7\u00e3o #lula #alckmin #china #mercadofinanceiro #livedas19h #gest\u00e3oativa #investimentos #mercadofinanceiro #pol\u00edtica #ibovespa #d\u00f3lar O Ibovespa hoje encerrou o preg\u00e3o de ter\u00e7a-feira (29) em alta de 1,96%, aos 110.909,61 pontos. A m\u00e1xima do dia foram 112.187,11 pontos, enquanto a m\u00ednima foi de 108.783,98 pontos. O volume financeiro chegou a R$ 27,9 bilh\u00f5es. O Ibovespa hoje se descolou\u2026\",\"duration\":\"PT40M11S\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/ouAKksaBIX0\",\"regionsAllowed\":\"pt-BR\",\"interactionStatistic\":{\"@type\":\"InteractionCounter\",\"interactionType\":{\"@type\":\"WatchAction\"},\"userInteractionCount\":3996},\"thumbnailUrl\":\"https:\/\/i.ytimg.com\/vi\/ouAKksaBIX0\/default.jpg\",\"uploadDate\":\"2022-11-29T22:43:44Z\"}<\/script>\n\n\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p>Contando com os<strong> dividendos da Banco do Brasil<\/strong> e da Eztec, um total 5 empresas pagar\u00e3o proventos hoje, 30\/11. <\/p>\n\n\n\n<p>Os acionistas da Banco do Brasil v\u00e3o receber R$ 0,1702 por a\u00e7\u00e3o, enquanto os da Eztec receber\u00e3o R$ 0,1147 por a\u00e7\u00e3o.<\/p>\n\n\n\n<p>T\u00eam direito aos proventos da Banco do Brasil os investidores que detinham a\u00e7\u00f5es <strong><a href=\"https:\/\/statusinvest.com.br\/acoes\/bbas3\" target=\"_blank\" rel=\"noreferrer noopener\">BBAS3 <\/a><\/strong>no preg\u00e3o dia 21 de novembro.<\/p>\n\n\n\n<p>J\u00e1 para receber os dividendos da Eztec, os acionistas tinham que deter pap\u00e9is da empresa em 17 de novembro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-agenda-de-dividendos-do-dia\">Agenda de dividendos do dia<\/h2>\n\n\n\n<p><strong>Banco do Brasil (BBAS3)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tipo: Dividendo e JCP<\/li><li>Valor por a\u00e7\u00e3o: R$ 0,1702 e R$ 0,6344<\/li><li>Data de corte: 21\/11\/2022<\/li><li>Rendimento: 0,49% e 1,81%<\/li><\/ul>\n\n\n\n<p><strong>Eztec (EZTC3)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tipo: Dividendo<\/li><li>Valor por a\u00e7\u00e3o: R$ 0,1147<\/li><li>Data de corte: 17\/11\/2022<\/li><li>Rendimento: 0,77%<\/li><\/ul>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"311945\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n\n\n\n<p><strong>Boa Safra (SOJA3)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tipo: JCP e Dividendo<\/li><li>Valor por a\u00e7\u00e3o: R$ 0,0691 e R$ 0,0401<\/li><li>Data de corte: 21\/11\/2022 e 29\/04\/2022<\/li><li>Rendimento: 0,67% e 0,31%<\/li><\/ul>\n\n\n\n<p><strong>Alupar (ALUP11)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tipo: Dividendo<\/li><li>Valor por a\u00e7\u00e3o: R$ 0,33<\/li><li>Data de corte: 11\/04\/2022<\/li><li>Rendimento: 1,23%<\/li><\/ul>\n\n\n\n<p><strong>CCR (CCRO3)<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tipo: Dividendo<\/li><li>Valor por a\u00e7\u00e3o: R$ 0,2928<\/li><li>Data de corte: 01\/11\/2022<\/li><li>Rendimento: 2,28%<\/li><\/ul>\n\n\n\n<p>Uma das vantagens dos <a class=\"suno-keyword\" data-force=\"no\" data-priority=\"1\" href=\"https:\/\/www.suno.com.br\/artigos\/dividendos-de-acoes\/\" target=\"_blank\" rel=\"noopener\">dividendos de a\u00e7\u00f5es<\/a>,, como os pagos aos acionistas do Banco do Brasil, \u00e9 a isen\u00e7\u00e3o do Imposto de Renda, da mesma forma que ocorre com os rendimentos dos fundos imobili\u00e1rios. <\/p>\n\n\n\n<p>J\u00e1 os JCP t\u00eam 15% de IR. Todos eles devem ser informados na declara\u00e7\u00e3o anual de imposto de renda do investidor.<\/p>\n\n\n\n<p>Vale destacar que esta mat\u00e9ria de agenda de dividendos do <strong>Banco do Brasil<\/strong> e da Eztec n\u00e3o \u00e9 uma recomenda\u00e7\u00e3o de compra ou venda de ativos.<\/p>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"311946\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Esta quarta-feira (30) \u00e9 um dos dias aguardados pelos investidores que seguem uma estrat\u00e9gia de investimentos focada em dividendos: o Banco do Brasil (BBAS3) e a Eztec (EZTC3) v\u00e3o pagar rendimentos aos seus acionistas. Contando com os dividendos da Banco do Brasil e da Eztec, um total 5 empresas pagar\u00e3o proventos hoje, 30\/11. Os acionistas [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":209637,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[286,732,295,473,1957],"suno_strategy":[],"class_list":["post-326061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-acoes","tag-banco-do-brasil-bbas3","tag-dividendos","tag-eztec-eztc3","tag-juros-sobre-capital-proprio-jcp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta; veja valores<\/title>\n<meta name=\"description\" content=\"Banco do Brasil \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta; veja valores\" \/>\n<meta property=\"og:description\" content=\"Banco do Brasil \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/banco-do-brasil_mcamgo_abr_280620211818-2-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Vargas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Vargas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/\"},\"author\":{\"name\":\"Eduardo Vargas\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5\"},\"headline\":\"Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta-feira; veja valores\",\"datePublished\":\"2022-11-30T11:06:40+00:00\",\"dateModified\":\"2022-11-30T11:08:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/\"},\"wordCount\":308,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/banco-do-brasil_mcamgo_abr_280620211818-2-1-scaled.jpg\",\"keywords\":[\"A\u00e7\u00f5es\",\"Banco do Brasil (BBAS3)\",\"dividendos\",\"Eztec (EZTC3)\",\"juros sobre capital pr\u00f3prio (JCP)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/\",\"name\":\"Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta; veja valores\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/banco-do-brasil_mcamgo_abr_280620211818-2-1-scaled.jpg\",\"datePublished\":\"2022-11-30T11:06:40+00:00\",\"dateModified\":\"2022-11-30T11:08:35+00:00\",\"description\":\"Banco do Brasil \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/banco-do-brasil_mcamgo_abr_280620211818-2-1-scaled.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/banco-do-brasil_mcamgo_abr_280620211818-2-1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Edif\u00edcio sede do Banco do Brasil (BBAS3), em Bras\u00edlia. Foto: Marcelo Camargo\/Ag\u00eancia Brasil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta-feira; veja valores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5\",\"name\":\"Eduardo Vargas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g\",\"caption\":\"Eduardo Vargas\"},\"description\":\"Jornalista formado pela UFSC, cobre macroeconomia, neg\u00f3cios e startups para o Suno Not\u00edcias, escrevendo principalmente not\u00edcias sobre o mercado financeiro e a bolsa de valores. No YouTube e no Instagram, \u00e9 respons\u00e1vel pela produ\u00e7\u00e3o de Reels e Shorts do Suno Not\u00edcias. Anteriormente, trabalhou cobrindo economia e cotidiano no ND+ e para o ND, maior jornal impresso de Santa Catarina. Cursou um semestre letivo de Estudos de M\u00eddia na Universidad de Buenos Aires.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta; veja valores","description":"Banco do Brasil \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/","og_locale":"pt_BR","og_type":"article","og_title":"Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta; veja valores","og_description":"Banco do Brasil \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!","og_url":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":2560,"height":1707,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/banco-do-brasil_mcamgo_abr_280620211818-2-1-scaled.jpg","type":"image\/jpeg"}],"author":"Eduardo Vargas","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Eduardo Vargas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/"},"author":{"name":"Eduardo Vargas","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5"},"headline":"Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta-feira; veja valores","datePublished":"2022-11-30T11:06:40+00:00","dateModified":"2022-11-30T11:08:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/"},"wordCount":308,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/banco-do-brasil_mcamgo_abr_280620211818-2-1-scaled.jpg","keywords":["A\u00e7\u00f5es","Banco do Brasil (BBAS3)","dividendos","Eztec (EZTC3)","juros sobre capital pr\u00f3prio (JCP)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/","url":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/","name":"Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta; veja valores","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/banco-do-brasil_mcamgo_abr_280620211818-2-1-scaled.jpg","datePublished":"2022-11-30T11:06:40+00:00","dateModified":"2022-11-30T11:08:35+00:00","description":"Banco do Brasil \u00e9 o destaque do dia na agenda de dividendos. Veja mais detalhes do pagamento de proventos de hoje!","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/banco-do-brasil_mcamgo_abr_280620211818-2-1-scaled.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/banco-do-brasil_mcamgo_abr_280620211818-2-1-scaled.jpg","width":2560,"height":1707,"caption":"Edif\u00edcio sede do Banco do Brasil (BBAS3), em Bras\u00edlia. Foto: Marcelo Camargo\/Ag\u00eancia Brasil"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta-feira; veja valores"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/7f4d362bf3518e76090143ae77bb49a5","name":"Eduardo Vargas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&r=g","caption":"Eduardo Vargas"},"description":"Jornalista formado pela UFSC, cobre macroeconomia, neg\u00f3cios e startups para o Suno Not\u00edcias, escrevendo principalmente not\u00edcias sobre o mercado financeiro e a bolsa de valores. No YouTube e no Instagram, \u00e9 respons\u00e1vel pela produ\u00e7\u00e3o de Reels e Shorts do Suno Not\u00edcias. Anteriormente, trabalhou cobrindo economia e cotidiano no ND+ e para o ND, maior jornal impresso de Santa Catarina. Cursou um semestre letivo de Estudos de M\u00eddia na Universidad de Buenos Aires.","url":"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/banco-do-brasil_mcamgo_abr_280620211818-2-1-400x200.jpg\" alt=\"Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta-feira; veja valores\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/banco-do-brasil-bbas3-eztec-eztc3-dividendos\/\"><h2 class=\"content__title\">Banco do Brasil (BBAS3) e Eztec (EZTC3) pagam dividendos nesta quarta-feira; veja valores<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/dac340933427a22924c9f99d1eb2e3f2?s=96&#038;r=g\" alt=\"Eduardo Vargas\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/eduardo-vargas\/\"><span itemprop=\"author\">Eduardo Vargas<\/span><\/a><\/span><time datetime=\"2022-11-30T08:06:40-03:00\" itemprop=\"datePublished\">30\/11\/2022 08:06<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/326061"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=326061"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/326061\/revisions"}],"predecessor-version":[{"id":326079,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/326061\/revisions\/326079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/209637"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=326061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=326061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=326061"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=326061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}