{"id":31137,"date":"2019-07-16T15:39:32","date_gmt":"2019-07-16T18:39:32","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=31137"},"modified":"2021-02-18T19:48:27","modified_gmt":"2021-02-18T22:48:27","slug":"reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/","title":{"rendered":"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra"},"content":{"rendered":"<p>O secret\u00e1rio especial da <strong>Receita Federal<\/strong>, Marcos Cintra, declarou\u00a0nesta ter\u00e7a-feira (16) que a <a href=\"https:\/\/www.suno.com.br\/artigos\/reforma-tributaria\/\">reforma tribut\u00e1ria<\/a> poder\u00e1 ser enviada ao<strong> Congresso<\/strong> ainda neste m\u00eas.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra-jpg.webp\" width=\"800\" height=\"450\" alt=\"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<p>O economista ressaltou que a\u00a0<strong>reforma tribut\u00e1ria\u00a0<\/strong>n\u00e3o depende mais da reforma da Previd\u00eancia para que seja aprovada. Assim, a proposta tribut\u00e1ria deve ser encaminhada ao Congresso nos pr\u00f3ximos dias.<\/p>\n<p>&#8220;Agora \u00e9 s\u00f3 uma quest\u00e3o de uma semana ou 10 dias para mais ou para menos. Antes do fim do recesso j\u00e1 deveremos [apresentar a proposta], mas o ministro que vai resolver&#8221;, afirmou Cintra.<\/p>\n<p><iframe loading=\"lazy\" title=\"?Reforma tribut\u00e1ria na C\u00e2mara esse m\u00eas; BNDES quer vender 100 bi e Oi vai desinvestir 7,5 bi\" width=\"200\" height=\"113\" src=\"https:\/\/www.youtube.com\/embed\/6YJbcr7Hyzo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>O ministro da Economia, Paulo Guedes, deve ser respons\u00e1vel por apresentar o texto da reforma para a imprensa. Al\u00e9m disso, Guedes\u00a0poder\u00e1 iniciar os debates sobre o pacto federativo.<\/p>\n<p>O governo pode enviar a reforma tribut\u00e1ria atrav\u00e9s de um projeto do Executivo para a C\u00e2mara. Assim, o texto seria analisado na comiss\u00e3o especial criada na \u00faltima semana para analisar a PEC da reforma.\u00a0A outra op\u00e7\u00e3o \u00e9 apresentar o texto ao Senado.<\/p>\n<h2>Imposto sobre transa\u00e7\u00f5es<\/h2>\n<p>Conforme Cintra,\u00a0o texto da reforma tribut\u00e1ria incluir\u00e1 um imposto sobre transa\u00e7\u00f5es. No entanto, o governo desenvolveu uma segunda op\u00e7\u00e3o caso o imposto n\u00e3o seja aprovado. Neste caso, a\u00a0al\u00edquota no imposto \u00fanico sofrer\u00e1 aumento.<\/p>\n<p>&#8220;Vamos deixar uma alternativa. Se acharem que n\u00e3o querem esse imposto, n\u00e3o tem problema. Pega e joga a al\u00edquota no <a href=\"https:\/\/www.suno.com.br\/artigos\/iva-imposto-sobre-valor-agregado\/\">IVA (imposto sobre valor agregado)<\/a>&#8220;, explicou o secret\u00e1rio.<\/p>\n<p>Segundo ele, o Congresso deve resistir ao tributo. Contudo, Cintra ressaltou a pot\u00eancia de um imposto sobre as transa\u00e7\u00f5es, principalmente por conta da capacidade de arrecada\u00e7\u00e3o e com o baixo custo para a fiscaliza\u00e7\u00e3o.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/minicurso-contabilidade\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Minicurso-Contabilidade.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Minicurso-Contabilidade.png\"\n\t\t\t\t\tdata-promo-id=\"383158\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Minicurso-Contabilidade.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>As propostas do Congresso devem encontrar complica\u00e7\u00f5es no debate pois envolvem tributos de Estados e munic\u00edpios. A proposta desenvolvida pelo minist\u00e9rio da Economia conta somente com altera\u00e7\u00f5es federais.<\/p>\n<h2>Reforma tribut\u00e1ria na C\u00e2mara<\/h2>\n<p>Na \u00faltima quarta-feira (10), a comiss\u00e3o especial para analisar a PEC da reforma tribut\u00e1ria foi instalada na C\u00e2mara dos Deputados. O presidente do colegiado \u00e9 o deputado Hildo Rocha, que tem como vice Sidney Leite (PSD-AM).<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-unificacao-impostos\/\">Saiba mais: Reforma tribut\u00e1ria ter\u00e1 unifica\u00e7\u00e3o de impostos, diz secret\u00e1rio de Fazenda<\/a><\/p>\n<p>O relator da reforma \u00e9 o deputado\u00a0Aguinaldo Ribeiro (PP-PB). Al\u00e9m disso, o texto ser\u00e1 apresentado por\u00a0Baleia Rossi (MDB-SP) e elaborado pelo economista\u00a0Bernard Appy.<\/p>\n<p>Al\u00e9m disso, na \u00faltima semana o\u00a0secret\u00e1rio de Fazenda do Minist\u00e9rio da Economia,\u00a0Waldery Rodrigues J\u00fanior, abordou tamb\u00e9m algumas poss\u00edveis medidas da reforma.<\/p>\n<p>Segundo Rodrigues, a unifica\u00e7\u00e3o de impostos federais e a contribui\u00e7\u00e3o sobre pagamento ser\u00e3o pontos da <strong>reforma tribut\u00e1ria<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio especial da Receita Federal, Marcos Cintra, declarou\u00a0nesta ter\u00e7a-feira (16) que a reforma tribut\u00e1ria poder\u00e1 ser enviada ao Congresso ainda neste m\u00eas. Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra O economista ressaltou que a\u00a0reforma tribut\u00e1ria\u00a0n\u00e3o depende mais da reforma da Previd\u00eancia para que seja aprovada. Assim, a proposta tribut\u00e1ria deve ser [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":31148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[62],"tags":[1849,901,847,1286],"suno_strategy":[],"class_list":["post-31137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-bernard-appy","tag-congresso-nacional","tag-receita-federal","tag-reforma-tributaria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra<\/title>\n<meta name=\"description\" content=\"O secret\u00e1rio Marcos Cintra declarou\u00a0que a reforma tribut\u00e1ria poder\u00e1 ser enviada ao Congresso neste m\u00eas.\u00a0Clique para saber mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra\" \/>\n<meta property=\"og:description\" content=\"O secret\u00e1rio Marcos Cintra declarou\u00a0que a reforma tribut\u00e1ria poder\u00e1 ser enviada ao Congresso neste m\u00eas.\u00a0Clique para saber mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanna Oliveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanna Oliveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/\"},\"author\":{\"name\":\"Giovanna Oliveira\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120\"},\"headline\":\"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra\",\"datePublished\":\"2019-07-16T18:39:32+00:00\",\"dateModified\":\"2021-02-18T22:48:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/\"},\"wordCount\":479,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra-jpg.webp\",\"keywords\":[\"Bernard Appy\",\"Congresso Nacional\",\"Receita Federal\",\"reforma tribut\u00e1ria\"],\"articleSection\":[\"Economia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/\",\"name\":\"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra-jpg.webp\",\"datePublished\":\"2019-07-16T18:39:32+00:00\",\"dateModified\":\"2021-02-18T22:48:27+00:00\",\"description\":\"O secret\u00e1rio Marcos Cintra declarou\u00a0que a reforma tribut\u00e1ria poder\u00e1 ser enviada ao Congresso neste m\u00eas.\u00a0Clique para saber mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra-jpg.webp\",\"width\":730,\"height\":425,\"caption\":\"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Economia\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/economia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120\",\"name\":\"Giovanna Oliveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g\",\"caption\":\"Giovanna Oliveira\"},\"description\":\"Giovanna Oliveira escreve sobre economia e pol\u00edtica. Foi rep\u00f3rter do portal de jornalismo da ESPM-SP e produziu conte\u00fado para a Corinthians TV. \u00c9 estudante da ESPM.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra","description":"O secret\u00e1rio Marcos Cintra declarou\u00a0que a reforma tribut\u00e1ria poder\u00e1 ser enviada ao Congresso neste m\u00eas.\u00a0Clique para saber mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/","og_locale":"pt_BR","og_type":"article","og_title":"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra","og_description":"O secret\u00e1rio Marcos Cintra declarou\u00a0que a reforma tribut\u00e1ria poder\u00e1 ser enviada ao Congresso neste m\u00eas.\u00a0Clique para saber mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":730,"height":425,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra.jpg","type":"image\/jpeg"}],"author":"Giovanna Oliveira","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Giovanna Oliveira","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/"},"author":{"name":"Giovanna Oliveira","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120"},"headline":"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra","datePublished":"2019-07-16T18:39:32+00:00","dateModified":"2021-02-18T22:48:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/"},"wordCount":479,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra-jpg.webp","keywords":["Bernard Appy","Congresso Nacional","Receita Federal","reforma tribut\u00e1ria"],"articleSection":["Economia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/","url":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/","name":"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra-jpg.webp","datePublished":"2019-07-16T18:39:32+00:00","dateModified":"2021-02-18T22:48:27+00:00","description":"O secret\u00e1rio Marcos Cintra declarou\u00a0que a reforma tribut\u00e1ria poder\u00e1 ser enviada ao Congresso neste m\u00eas.\u00a0Clique para saber mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra-jpg.webp","width":730,"height":425,"caption":"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Economia","item":"https:\/\/www.suno.com.br\/noticias\/economia\/"},{"@type":"ListItem","position":3,"name":"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120","name":"Giovanna Oliveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g","caption":"Giovanna Oliveira"},"description":"Giovanna Oliveira escreve sobre economia e pol\u00edtica. Foi rep\u00f3rter do portal de jornalismo da ESPM-SP e produziu conte\u00fado para a Corinthians TV. \u00c9 estudante da ESPM.","url":"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/c66d640d-marcos-cintra-400x200.webp\" alt=\"Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/economia\/\">Economia<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/reforma-tributaria-sera-apresentada-ao-congresso-neste-mes-diz-cintra\/\"><h2 class=\"content__title\">Reforma tribut\u00e1ria ser\u00e1 apresentada ao Congresso neste m\u00eas, diz Cintra<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/952a89ca-screenshot_20190608-171507-150x150.webp\" alt=\"Giovanna Oliveira\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/\"><span itemprop=\"author\">Giovanna Oliveira<\/span><\/a><\/span><time datetime=\"2019-07-16T15:39:32-03:00\" itemprop=\"datePublished\">16\/07\/2019 15:39<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/31137"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=31137"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/31137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/31148"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=31137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=31137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=31137"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=31137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}