{"id":30688,"date":"2019-07-11T09:20:19","date_gmt":"2019-07-11T12:20:19","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=30688"},"modified":"2019-07-11T09:20:19","modified_gmt":"2019-07-11T12:20:19","slug":"dolar-queda-reforma-da-previdencia","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/","title":{"rendered":"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia"},"content":{"rendered":"<p>O d\u00f3lar abre em queda nesta quinta-feira (11) com a reforma da Previd\u00eancia no radar.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr-jpg.webp\" width=\"800\" height=\"450\" alt=\"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">No dia anterior, o d\u00f3lar encerrou em alta de 1,43%, a R$ 5,7630<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<p>Por volta das 9h15, o <strong>d\u00f3lar<\/strong> registrava queda de 0,357% sendo negociado a R$ 3,7444. O mercado segue atento a an\u00e1lise dos destaques do texto da reforma da Previd\u00eancia que acontecer\u00e1 nesta quinta-feira.<\/p>\n<p>Al\u00e9m disso, segue no radar dos investidores a ata do Federal Reserve divulgada na \u00faltima quarta-feira (10).<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/4-emissao-snel11\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/400x300-Mobile-Artigos-7.webp\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/1420x240-Banner-Artigos-1-_-Banner-Materias-5.webp\"\n\t\t\t\t\tdata-promo-id=\"364417\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/1420x240-Banner-Artigos-1-_-Banner-Materias-5.webp\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<h2>Reforma da Previd\u00eancia aprovada no plen\u00e1rio<\/h2>\n<p>Na \u00faltima quarta-feira (10), a reforma da Previd\u00eancia foi aprovada no plen\u00e1rio da C\u00e2mara dos Deputados. A vota\u00e7\u00e3o foi conclu\u00edda com 379 votos favor\u00e1veis contra 131 votos contr\u00e1rios a aprova\u00e7\u00e3o dependia de no m\u00ednimo 308 votos favor\u00e1veis.\u00a0Dos 513 deputados, 510 registraram presen\u00e7a no plen\u00e1rio da C\u00e2mara.<\/p>\n<p>Nesta quinta-feira, a partir das 9h os deputados seguem com a vota\u00e7\u00e3o, em primeiro turno, avaliando os destaques. O texto passar\u00e1 por uma vota\u00e7\u00e3o na C\u00e2mara e por duas vota\u00e7\u00f5es no Senado.\u00a0Ap\u00f3s a sess\u00e3o o presidente da C\u00e2mara, Rodrigo Maia, fez um discurso defendendo a reforma.<\/p>\n<p><a href=\"\/\/www.suno.com.br\/noticias\/dolar-queda-10072019\/\">Saiba Mais:\u00a0D\u00f3lar cai para menor valor em 4 meses com otimismo sobre a Previd\u00eancia<\/a><\/p>\n<p>&#8220;As solu\u00e7\u00f5es dos problemas da pobreza, dos problemas dos brasileiros que vivem abaixo da linha da pobreza, dos problemas de milh\u00f5es de desempregados passa pela pol\u00edtica. E n\u00e3o haver\u00e1 investimento privado, mesmo com reforma tribut\u00e1ria, mesmo com reforma previdenci\u00e1ria, se n\u00f3s n\u00e3o tivermos uma democracia forte. Investidor de longo prazo n\u00e3o investe em pa\u00eds que ataca as institui\u00e7\u00f5es&#8221;, disse o presidente.<\/p>\n<h2>C\u00e2mara analisa destaques<\/h2>\n<p>Nesta quinta-feira, a C\u00e2mara ir\u00e1 analisar 14 proposta de altera\u00e7\u00e3o no texto base da reforma da Previd\u00eancia. A sess\u00e3o est\u00e1 marcada para iniciar \u00e0s 9h.<\/p>\n<p>Para a conclus\u00e3o do primeiro turno \u00e9 necess\u00e1rio a an\u00e1lise dos destaques apresentados pelos partidos que desejam alterar pontos espec\u00edficos da proposta.\u00a0 Ap\u00f3s a avalia\u00e7\u00e3o, o texto poder\u00e1 ser encaminhado para o segundo turno de vota\u00e7\u00e3o.\u00a0 A an\u00e1lise do Senado s\u00f3 ocorrer\u00e1 depois da aprova\u00e7\u00e3o nos dois turnos.<\/p>\n<h2>Ata do Fed<\/h2>\n<p>Na \u00faltima quarta-feira (10) foi divulgada pelo Banco Central dos Estados Unidos a ata do <a href=\"https:\/\/www.federalreserve.gov\/\">Federal Reserve<\/a> (FED).\u00a0Varias autoridades do Fed afirmaram que novos incentivos ter\u00e3o que ser implantados \u00e0 economia global. Sendo assim, os Estados Unidos temem que, caso n\u00e3o corte as taxas de juros, sua economia fique estagnada.<\/p>\n<p><a href=\"\/\/www.suno.com.br\/noticias\/ata-fed-diz-autoridades-bc-corte-juros-curto-prazo\/\">Saiba Mais:\u00a0Ata do Fed diz que autoridades do BC viram corte de juros no curto prazo<\/a><\/p>\n<p>No dia 19 do m\u00eas passado, o Fed resolveu manter as taxas de juros inalteradas. O intervalo ficou entre 2,25% a 2,50%. Dessa forma, a economia global ficou empolgada com uma poss\u00edvel baixa nos juros dos EUA, em um curto prazo.<\/p>\n<h2>\u00daltima cota\u00e7\u00e3o<\/h2>\n<p>Na \u00faltima sess\u00e3o, na quarta-feira (10), o <strong>d\u00f3lar<\/strong> encerrou em queda de -1,274% negociado a R$ 3,7585 na venda. Essa foi a menor cota\u00e7\u00e3o da moeda em 4 meses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O d\u00f3lar abre em queda nesta quinta-feira (11) com a reforma da Previd\u00eancia no radar. No dia anterior, o d\u00f3lar encerrou em alta de 1,43%, a R$ 5,7630 Por volta das 9h15, o d\u00f3lar registrava queda de 0,357% sendo negociado a R$ 3,7444. O mercado segue atento a an\u00e1lise dos destaques do texto da reforma [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":28097,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[326,776,940],"suno_strategy":[],"class_list":["post-30688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-dolar","tag-federal-reseve-fed","tag-reforma-da-previdencia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia<\/title>\n<meta name=\"description\" content=\"Por volta das 9h15, o d\u00f3lar registra queda de 0,357% sendo negociado a R$ 3,7444. O mercado segue atento a an\u00e1lise dos destaques. Clique aqui\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia\" \/>\n<meta property=\"og:description\" content=\"Por volta das 9h15, o d\u00f3lar registra queda de 0,357% sendo negociado a R$ 3,7444. O mercado segue atento a an\u00e1lise dos destaques. Clique aqui\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Poliana Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Poliana Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/\"},\"author\":{\"name\":\"Poliana Santos\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\"},\"headline\":\"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia\",\"datePublished\":\"2019-07-11T12:20:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/\"},\"wordCount\":519,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr-jpg.webp\",\"keywords\":[\"d\u00f3lar\",\"Federal Reserve (FED)\",\"Reforma da Previd\u00eancia\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/\",\"name\":\"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr-jpg.webp\",\"datePublished\":\"2019-07-11T12:20:19+00:00\",\"description\":\"Por volta das 9h15, o d\u00f3lar registra queda de 0,357% sendo negociado a R$ 3,7444. O mercado segue atento a an\u00e1lise dos destaques. Clique aqui\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr-jpg.webp\",\"width\":640,\"height\":370,\"caption\":\"No dia anterior, o d\u00f3lar encerrou em alta de 1,43%, a R$ 5,7630\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/mercado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\",\"name\":\"Poliana Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"caption\":\"Poliana Santos\"},\"description\":\"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia","description":"Por volta das 9h15, o d\u00f3lar registra queda de 0,357% sendo negociado a R$ 3,7444. O mercado segue atento a an\u00e1lise dos destaques. Clique aqui","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/","og_locale":"pt_BR","og_type":"article","og_title":"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia","og_description":"Por volta das 9h15, o d\u00f3lar registra queda de 0,357% sendo negociado a R$ 3,7444. O mercado segue atento a an\u00e1lise dos destaques. Clique aqui","og_url":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":640,"height":370,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr.jpg","type":"image\/jpeg"}],"author":"Poliana Santos","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Poliana Santos","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/"},"author":{"name":"Poliana Santos","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda"},"headline":"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia","datePublished":"2019-07-11T12:20:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/"},"wordCount":519,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr-jpg.webp","keywords":["d\u00f3lar","Federal Reserve (FED)","Reforma da Previd\u00eancia"],"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/","url":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/","name":"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr-jpg.webp","datePublished":"2019-07-11T12:20:19+00:00","description":"Por volta das 9h15, o d\u00f3lar registra queda de 0,357% sendo negociado a R$ 3,7444. O mercado segue atento a an\u00e1lise dos destaques. Clique aqui","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr-jpg.webp","width":640,"height":370,"caption":"No dia anterior, o d\u00f3lar encerrou em alta de 1,43%, a R$ 5,7630"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/www.suno.com.br\/noticias\/mercado\/"},{"@type":"ListItem","position":3,"name":"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda","name":"Poliana Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","caption":"Poliana Santos"},"description":"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.","url":"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/5da068bf-dolarr-400x200.webp\" alt=\"D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mercado\/\">Mercado<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/dolar-queda-reforma-da-previdencia\/\"><h2 class=\"content__title\">D\u00f3lar opera em queda ap\u00f3s aprova\u00e7\u00e3o da reforma da Previd\u00eancia<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2019-07-11T09:20:19-03:00\" itemprop=\"datePublished\">11\/07\/2019 09:20<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/30688"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=30688"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/30688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/28097"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=30688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=30688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=30688"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=30688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}