{"id":29879,"date":"2019-07-02T20:24:06","date_gmt":"2019-07-02T23:24:06","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=29879"},"modified":"2021-02-17T22:30:10","modified_gmt":"2021-02-18T01:30:10","slug":"casino-vende-170-milhoes","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/","title":{"rendered":"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi"},"content":{"rendered":"<p>O grupo franc\u00eas Casino Guichard-Perrachon anunciou nesta ter\u00e7a-feira (02) a venda de uma s\u00e9rie de suas lojas por\u00a0US$ 44,2 milh\u00f5es. O valor equivale a cerca de R$ 170 milh\u00f5es.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino-jpg.webp\" width=\"800\" height=\"450\" alt=\"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">Grupo Casino conclui plano de refinanciamento e levanta 1,8 bi de euros<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<p>O varejista vendeu tr\u00eas hipermercados, sendo eles o\u00a0Cholet, o Roubaix e o Rennes. Al\u00e9m disso, foram vendidos quatro supermercados da rede <strong>Casino<\/strong> e uma loja da\u00a0Leader Price.<\/p>\n<p>O grupo declarou ainda que a negocia\u00e7\u00e3o dos mercados n\u00e3o est\u00e1 relacionada ao plano de venda de\u00a0<a href=\"https:\/\/www.suno.com.br\/artigos\/alocacao-de-ativos\/\">ativos<\/a> n\u00e3o estrat\u00e9gicos anunciado em 11 de junho de 2018.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/cl\/impacto-tarifas-trump\/?utm_source=sunoresearch&#038;utm_medium=banner.noticias&#038;utm_campaign=_SNC903E88AA_\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/trump-mobile.webp\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/trump-banner-desktop.webp\"\n\t\t\t\t\tdata-promo-id=\"613126\"\t\t\t\t\t\t\t\t\t\twidth='1000' height='325'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/trump-banner-desktop.webp\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>O Casino obteve lucro de aproximadamente R$\u00a0104 milh\u00f5es atrav\u00e9s da venda de\u00a0unidades deficit\u00e1rias. No total, o grupo j\u00e1 recebeu um montante de R$\u00a0581 milh\u00f5es por conta destas vendas.<\/p>\n<p>As a\u00e7\u00f5es do Casino subiram 3,39% nesta ter\u00e7a-feira.\u00a0Assim, negociando a\u00a031,76 euros por volta das 17h40.<\/p>\n<h2>Recupera\u00e7\u00e3o judicial<\/h2>\n<p>A venda dos supermercados do grupo est\u00e1 relacionada com plano de prote\u00e7\u00e3o contra credores solicitado pela holding <strong>Rallye<\/strong>, que controla o grupo Casino, e aprovado pela Justi\u00e7a da Fran\u00e7a no m\u00eas de maio.<\/p>\n<p>A medida solicitada pelo grupo \u00e9 parecida com a <a href=\"https:\/\/www.suno.com.br\/artigos\/recuperacao-judicial\/\">recupera\u00e7\u00e3o judicial<\/a> no Brasil. Assim, o objetivo \u00e9 conseguir montar um plano para reestruturar as d\u00edvidas.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/acoes-casino-caem-paris\/\">Saibe mais: A\u00e7\u00f5es do grupo Casino, controlador do GPA, caem em Paris<\/a><\/p>\n<p>Enquanto a Raylle controla o Casino, o grupo \u00e9 dono do <strong>Grupo P\u00e3o de A\u00e7\u00facar\u00a0<\/strong>(<strong>GPA<\/strong>), que, por sua vez tem a <strong>Via Varejo<\/strong> como subsidi\u00e1ria. Al\u00e9m disso, est\u00e3o entre as marcas do GPA:<\/p>\n<ul>\n<li>P\u00e3o de A\u00e7\u00facar;<\/li>\n<li>Extra;<\/li>\n<li>Casas Bahia;<\/li>\n<li>Ponto Frio;<\/li>\n<li>Assa\u00ed.<\/li>\n<\/ul>\n<p>Nesta ter\u00e7a-feira, as a\u00e7\u00f5es da Raylle apresentaram queda de 4,99% na <a href=\"https:\/\/www.suno.com.br\/artigos\/cac-40\/\">bolsa de Paris<\/a>. Dessa forma, negociaram a 6,70 euros \u00e0s 17h30.<\/p>\n<p>Al\u00e9m disso, os pap\u00e9is do GPA ca\u00edram\u00a02.35%, negociando a R$ 91,51 por volta das 17h.<\/p>\n<h2>Venda de parte da Via Varejo<\/h2>\n<p>Ainda no processo de vendas, o\u00a0Grupo P\u00e3o de A\u00e7\u00facar informou no \u00faltimo m\u00eas que vender\u00e1 sua participa\u00e7\u00e3o na Via Varejo para Michael Klein.\u00a0O Conselho de Administra\u00e7\u00e3o do GPA aprovou um pre\u00e7o de venda de R$ 4,75 por a\u00e7\u00e3o.<\/p>\n<p>A venda da Via Varejo,\u00a0dona das marcas Casas Bahia e Ponto Frio, ocorrer\u00e1 em leil\u00e3o na Bolsa de Valores de S\u00e3o Paulo. O GPA possui atualmente 36,27% do capital da Via Varejo.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.statusinvest.com.br\/ao\/assessoria-status-invest\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/400x300-Mobile.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/1420x240-Desktop.png\"\n\t\t\t\t\tdata-promo-id=\"537248\"\t\t\t\t\t\t\t\t\t\twidth='1400' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2024\/03\/1420x240-Desktop.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>A negocia\u00e7\u00e3o est\u00e1 relacionada com a venda dos supermercados anunciada nesta ter\u00e7a-feira pelo Grupo\u00a0<strong>Casino<\/strong>. Afinal, tanto o GPA quanto a Via Varejo s\u00e3o empresas do grupo. Assim, como o varejista \u00e9 da holding\u00a0Raylle, o valor deve ser direcionado ao pagamento da recupera\u00e7\u00e3o judicial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O grupo franc\u00eas Casino Guichard-Perrachon anunciou nesta ter\u00e7a-feira (02) a venda de uma s\u00e9rie de suas lojas por\u00a0US$ 44,2 milh\u00f5es. O valor equivale a cerca de R$ 170 milh\u00f5es. Grupo Casino conclui plano de refinanciamento e levanta 1,8 bi de euros O varejista vendeu tr\u00eas hipermercados, sendo eles o\u00a0Cholet, o Roubaix e o Rennes. Al\u00e9m [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":29881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[1531,1964,106935],"suno_strategy":[],"class_list":["post-29879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-grupo-casino","tag-grupo-pao-de-acucar-pcar3-pcar4","tag-via-viia3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi<\/title>\n<meta name=\"description\" content=\"O grupo franc\u00eas Casino Guichard-Perrachon anunciou a venda de uma s\u00e9rie de suas lojas por\u00a0US$ 44,2 milh\u00f5es. Clique para saber mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi\" \/>\n<meta property=\"og:description\" content=\"O grupo franc\u00eas Casino Guichard-Perrachon anunciou a venda de uma s\u00e9rie de suas lojas por\u00a0US$ 44,2 milh\u00f5es. Clique para saber mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanna Oliveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanna Oliveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/\"},\"author\":{\"name\":\"Giovanna Oliveira\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120\"},\"headline\":\"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi\",\"datePublished\":\"2019-07-02T23:24:06+00:00\",\"dateModified\":\"2021-02-18T01:30:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/\"},\"wordCount\":460,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino-jpg.webp\",\"keywords\":[\"Grupo Casino\",\"Grupo P\u00e3o de A\u00e7\u00facar (PCAR3\/PCAR4)\",\"Via (VIIA3)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/\",\"name\":\"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino-jpg.webp\",\"datePublished\":\"2019-07-02T23:24:06+00:00\",\"dateModified\":\"2021-02-18T01:30:10+00:00\",\"description\":\"O grupo franc\u00eas Casino Guichard-Perrachon anunciou a venda de uma s\u00e9rie de suas lojas por\u00a0US$ 44,2 milh\u00f5es. Clique para saber mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino-jpg.webp\",\"width\":620,\"height\":430,\"caption\":\"Grupo Casino conclui plano de refinanciamento e levanta 1,8 bi de euros\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120\",\"name\":\"Giovanna Oliveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g\",\"caption\":\"Giovanna Oliveira\"},\"description\":\"Giovanna Oliveira escreve sobre economia e pol\u00edtica. Foi rep\u00f3rter do portal de jornalismo da ESPM-SP e produziu conte\u00fado para a Corinthians TV. \u00c9 estudante da ESPM.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi","description":"O grupo franc\u00eas Casino Guichard-Perrachon anunciou a venda de uma s\u00e9rie de suas lojas por\u00a0US$ 44,2 milh\u00f5es. Clique para saber mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi","og_description":"O grupo franc\u00eas Casino Guichard-Perrachon anunciou a venda de uma s\u00e9rie de suas lojas por\u00a0US$ 44,2 milh\u00f5es. Clique para saber mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":620,"height":430,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino.jpg","type":"image\/jpeg"}],"author":"Giovanna Oliveira","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Giovanna Oliveira","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/"},"author":{"name":"Giovanna Oliveira","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120"},"headline":"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi","datePublished":"2019-07-02T23:24:06+00:00","dateModified":"2021-02-18T01:30:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/"},"wordCount":460,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino-jpg.webp","keywords":["Grupo Casino","Grupo P\u00e3o de A\u00e7\u00facar (PCAR3\/PCAR4)","Via (VIIA3)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/","url":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/","name":"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino-jpg.webp","datePublished":"2019-07-02T23:24:06+00:00","dateModified":"2021-02-18T01:30:10+00:00","description":"O grupo franc\u00eas Casino Guichard-Perrachon anunciou a venda de uma s\u00e9rie de suas lojas por\u00a0US$ 44,2 milh\u00f5es. Clique para saber mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino-jpg.webp","width":620,"height":430,"caption":"Grupo Casino conclui plano de refinanciamento e levanta 1,8 bi de euros"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/4e19e3d2575736e5283d58eb3199d120","name":"Giovanna Oliveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a37b3ae208962ac568992d0ffdbc2eb?s=96&r=g","caption":"Giovanna Oliveira"},"description":"Giovanna Oliveira escreve sobre economia e pol\u00edtica. Foi rep\u00f3rter do portal de jornalismo da ESPM-SP e produziu conte\u00fado para a Corinthians TV. \u00c9 estudante da ESPM.","url":"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/07\/25f1de61-casino-400x200.webp\" alt=\"Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/casino-vende-170-milhoes\/\"><h2 class=\"content__title\">Grupo Casino vende alguns de seus mercados por cerca de R$ 170 mi<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/952a89ca-screenshot_20190608-171507-150x150.webp\" alt=\"Giovanna Oliveira\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/giovanna\/\"><span itemprop=\"author\">Giovanna Oliveira<\/span><\/a><\/span><time datetime=\"2019-07-02T20:24:06-03:00\" itemprop=\"datePublished\">02\/07\/2019 20:24<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/29879"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=29879"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/29879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/29881"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=29879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=29879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=29879"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=29879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}