{"id":29603,"date":"2019-06-30T18:42:02","date_gmt":"2019-06-30T21:42:02","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=29603"},"modified":"2019-06-30T18:49:10","modified_gmt":"2019-06-30T21:49:10","slug":"fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/","title":{"rendered":"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas"},"content":{"rendered":"<p>O Fundo Monet\u00e1rio Internacional (FMI) mostrou que \u00e9 um grande defensor das <strong>moedas<\/strong> <strong>digitais<\/strong>. Desta forma, executivos da companhia deram alguns depoimentos sobre as vantagens de usar estas moedas.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294-800x450.webp\" width=\"800\" height=\"450\" alt=\"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">Christine Lagarde, presidente do Banco Central Europeu<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<p>O <strong>FMI<\/strong> afirmou que no futuro os bancos centrais ir\u00e3o criar suas pr\u00f3prias moedas digitais. Sendo assim, a previs\u00e3o foi feita por meia de um estudo publicado no blog da institui\u00e7\u00e3o.<\/p>\n<div>Vale ressaltar que no documento do <strong>FMI<\/strong>, h\u00e1 alguns bancos centrais que fizeram pesquisas ampliadas sobre as poss\u00edveis consequ\u00eancias que um <strong>CBDC<\/strong> pode ter sobre o sistema banc\u00e1rio central. Desta forma, afetando, tamb\u00e9m, o sistema financeiro global.<\/div>\n<div><\/div>\n<div>\n<div>O <strong>FMI<\/strong> chegou a conclus\u00e3o de que as <strong>Fintechs<\/strong> est\u00e3o sendo aderidas de maneira r\u00e1pida em diversos pa\u00edses. Portanto, est\u00e3o abrindo a possibilidade de ades\u00e3o de tecnologias disruptivas, como s\u00e3o o caso das <strong>criptomoedas<\/strong>.<\/div>\n<div><\/div>\n<div><span style=\"font-size: 1.21429rem;\">A diretora do <\/span><strong style=\"font-size: 1.21429rem;\">FMI<\/strong><span style=\"font-size: 1.21429rem;\">, <\/span><strong style=\"font-size: 1.21429rem;\">Christine<\/strong> <strong style=\"font-size: 1.21429rem;\">Lagarde<\/strong><span style=\"font-size: 1.21429rem;\">, j\u00e1 chegou a dizer publicamente que as <\/span><strong style=\"font-size: 1.21429rem;\">criptomoedas<\/strong><span style=\"font-size: 1.21429rem;\"> estavam balan\u00e7ando o sistema e precisavam de regulamenta\u00e7\u00e3o. A declara\u00e7\u00e3o foi dada em abril deste ano.<\/span><\/div>\n<div><\/div>\n<div><span style=\"font-size: 1.21429rem;\">\u201cEu acho que o papel dos disruptores e qualquer coisa que esteja usando a tecnologia de contabilidade distribu\u00edda, quer voc\u00ea chame isso de criptomoeda, ativos, moedas, ou qualquer outra coisa que seja&#8230; est\u00e1 claramente agitando o sistema\u201d, disse Christine Lagarde.<\/span><\/div>\n<\/div>\n<div>\n<p>Para a diretora,\u00a0muita inova\u00e7\u00e3o pode deixar o sistema fr\u00e1gil\u00a0e inst\u00e1vel.<\/p>\n<h2>O que s\u00e3o as fintechs<\/h2>\n<div>\n<p>As fintechs s\u00e3o startups financeiras que buscam redesenhar a \u00e1rea de servi\u00e7os com procedimentos totalmente baseados em tecnologia. A palavra \u00e9 a jun\u00e7\u00e3o de &#8220;financial&#8221; e &#8220;technology&#8221;, termos em ingl\u00eas que correspondem a: financeiro e tecnologia.<\/p>\n<div>Entretanto, esses servi\u00e7os revolucion\u00e1rios n\u00e3o se abreviam a bancos digitais. Portanto, apesar de estarem sob um mesmo nome, essas companhias podem proporcionar servi\u00e7os e produtos diferentes entre si.<\/div>\n<div><\/div>\n<div>Confira as \u00e1reas de atua\u00e7\u00e3o das fintechs:<\/div>\n<ul>\n<li>Fintechs de Bitcoins<\/li>\n<li>Fintechs de pagamento<\/li>\n<li>Fintechs de investimento<\/li>\n<li>Fintechs de crowdfunding<\/li>\n<li>Fintechs de cr\u00e9dito ou empr\u00e9stimo<\/li>\n<li>Fintechs de controle financeiro<\/li>\n<\/ul>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<div><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Fundo Monet\u00e1rio Internacional (FMI) mostrou que \u00e9 um grande defensor das moedas digitais. Desta forma, executivos da companhia deram alguns depoimentos sobre as vantagens de usar estas moedas. Christine Lagarde, presidente do Banco Central Europeu O FMI afirmou que no futuro os bancos centrais ir\u00e3o criar suas pr\u00f3prias moedas digitais. Sendo assim, a previs\u00e3o [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":4667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[62],"tags":[693,806],"suno_strategy":[],"class_list":["post-29603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-criptomoedas","tag-fundo-monetario-internacional-fmi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas<\/title>\n<meta name=\"description\" content=\"O Fundo Monet\u00e1rio Internacional (FMI) mostrou que \u00e9 um grande defensor das moedas digitais. Clique aqui e saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas\" \/>\n<meta property=\"og:description\" content=\"O Fundo Monet\u00e1rio Internacional (FMI) mostrou que \u00e9 um grande defensor das moedas digitais. Clique aqui e saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"546\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juliano Passaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juliano Passaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/\"},\"author\":{\"name\":\"Juliano Passaro\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3\"},\"headline\":\"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas\",\"datePublished\":\"2019-06-30T21:42:02+00:00\",\"dateModified\":\"2019-06-30T21:49:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/\"},\"wordCount\":358,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294-jpg.webp\",\"keywords\":[\"criptomoedas\",\"Fundo Monet\u00e1rio Internacional (FMI)\"],\"articleSection\":[\"Economia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/\",\"name\":\"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294-jpg.webp\",\"datePublished\":\"2019-06-30T21:42:02+00:00\",\"dateModified\":\"2019-06-30T21:49:10+00:00\",\"description\":\"O Fundo Monet\u00e1rio Internacional (FMI) mostrou que \u00e9 um grande defensor das moedas digitais. Clique aqui e saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294-jpg.webp\",\"width\":800,\"height\":546,\"caption\":\"Christine Lagarde, presidente do Banco Central Europeu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Economia\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/economia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3\",\"name\":\"Juliano Passaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g\",\"caption\":\"Juliano Passaro\"},\"description\":\"Juliano Passaro escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal da Suno Research. Antes da Suno, trabalhou no Portal da Band. \u00c9 formado em jornalismo pela Universidade Presbiteriana Mackenzie.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas","description":"O Fundo Monet\u00e1rio Internacional (FMI) mostrou que \u00e9 um grande defensor das moedas digitais. Clique aqui e saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/","og_locale":"pt_BR","og_type":"article","og_title":"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas","og_description":"O Fundo Monet\u00e1rio Internacional (FMI) mostrou que \u00e9 um grande defensor das moedas digitais. Clique aqui e saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":800,"height":546,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294.jpg","type":"image\/jpeg"}],"author":"Juliano Passaro","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Juliano Passaro","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/"},"author":{"name":"Juliano Passaro","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3"},"headline":"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas","datePublished":"2019-06-30T21:42:02+00:00","dateModified":"2019-06-30T21:49:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/"},"wordCount":358,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294-jpg.webp","keywords":["criptomoedas","Fundo Monet\u00e1rio Internacional (FMI)"],"articleSection":["Economia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/","url":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/","name":"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294-jpg.webp","datePublished":"2019-06-30T21:42:02+00:00","dateModified":"2019-06-30T21:49:10+00:00","description":"O Fundo Monet\u00e1rio Internacional (FMI) mostrou que \u00e9 um grande defensor das moedas digitais. Clique aqui e saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294-jpg.webp","width":800,"height":546,"caption":"Christine Lagarde, presidente do Banco Central Europeu"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Economia","item":"https:\/\/www.suno.com.br\/noticias\/economia\/"},{"@type":"ListItem","position":3,"name":"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1db762f78ffd8919a648a63e425953e3","name":"Juliano Passaro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/743d4df28eebf6dcc46b4ad03c319e92?s=96&r=g","caption":"Juliano Passaro"},"description":"Juliano Passaro escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal da Suno Research. Antes da Suno, trabalhou no Portal da Band. \u00c9 formado em jornalismo pela Universidade Presbiteriana Mackenzie.","url":"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/7398dd32-800px-women_in_economic_decision-making_christine_lagarde_8414041294-400x200.webp\" alt=\"FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/economia\/\">Economia<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/fmi-diz-bancos-centrais-lancarao-proprias-criptomoedas\/\"><h2 class=\"content__title\">FMI diz que bancos centrais lan\u00e7ar\u00e3o suas pr\u00f3prias criptomoedas<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/06\/7cc3efea-whatsapp-image-2019-07-18-at-21.59.33-e1563499821209-150x150.webp\" alt=\"Juliano Passaro\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/juliano\/\"><span itemprop=\"author\">Juliano Passaro<\/span><\/a><\/span><time datetime=\"2019-06-30T18:42:02-03:00\" itemprop=\"datePublished\">30\/06\/2019 18:42<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/29603"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=29603"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/29603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/4667"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=29603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=29603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=29603"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=29603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}