{"id":275587,"date":"2022-07-13T11:18:35","date_gmt":"2022-07-13T14:18:35","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=275587"},"modified":"2022-07-13T11:18:35","modified_gmt":"2022-07-13T14:18:35","slug":"ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/","title":{"rendered":"Ibovespa cai ap\u00f3s infla\u00e7\u00e3o mais forte nos EUA; Ambev (ABEV3) \u00e9 destaque de alta"},"content":{"rendered":"<p>O <strong>Ibovespa<\/strong> opera em baixa de 0,20%, aos 98.075 pontos, por volta das 10h43, ap\u00f3s a divulga\u00e7\u00e3o de dados de infla\u00e7\u00e3o mais fortes nos Estados Unidos, alcan\u00e7ando a maior taxa anual em 40 anos e meio.<\/p><div class=\"videoFull videoFull--noRadius\">\n\t\t\t<div class=\"videoWrapper yt-lazyload center\"\n\t\t\t\tdata-width=\"960\"\n\t\t\t\tdata-height=\"540\"\n\t\t\t\tdata-id=\"0_aBHN0NlzQ\"\n\t\t\t\tdata-alt=\"INFLA\u00c7\u00c3O NOS EUA (CPI) VAI A 9,1% EM 12 MESES, A MAIOR DESDE 1981\"\n\t\t\t\tdata-logo=\"3\"\n\t\t\t\tdata-imagequality=\"maxres\">\n\t\t\t<\/div>\n\t\t<\/div><span class=\"videoFull__caption videoFull__caption--show\">INFLA\u00c7\u00c3O NOS EUA (CPI) VAI A 9,1% EM 12 MESES, A MAIOR DESDE 1981<p><\/p><\/span><script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"VideoObject\",\"name\":\"INFLA\u00c7\u00c3O NOS EUA (CPI) VAI A 9,1% EM 12 MESES, A MAIOR DESDE 1981 | Breaking News\",\"description\":\"#cpi #infla\u00e7\u00e3o #estadosunidos #breakingnews #Not\u00edciasdoDia #Not\u00edcias A infla\u00e7\u00e3o nos Estados Unidos foi a 9,1% no acumulado dos \u00faltimos 12 meses, segundo leitura do \u00cdndice de Pre\u00e7os ao Consumidor (CPI, do ingl\u00eas) divulgada na manh\u00e3 desta quarta-feira (13). A varia\u00e7\u00e3o da infla\u00e7\u00e3o dos EUA foi de 1,3% de alta em junho, acima das proje\u00e7\u00f5es, que miravam\u2026\",\"duration\":\"PT5M23S\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/0_aBHN0NlzQ\",\"regionsAllowed\":\"pt-BR\",\"interactionStatistic\":{\"@type\":\"InteractionCounter\",\"interactionType\":{\"@type\":\"WatchAction\"},\"userInteractionCount\":1845},\"thumbnailUrl\":\"https:\/\/i.ytimg.com\/vi\/0_aBHN0NlzQ\/default.jpg\",\"uploadDate\":\"2022-07-13T12:43:57Z\"}<\/script>\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"138420\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>A queda na <a href=\"https:\/\/www.suno.com.br\/artigos\/ibovespa\/\" target=\"_blank\" rel=\"noopener\"><strong>cota\u00e7\u00e3o do Ibovespa<\/strong><\/a> est\u00e1 em linha com os mercados internacionais, j\u00e1 que grande parte das bolsas europeias e norte-americanas se encontram em baixa. O S&amp;P 500 cai 1,25%, enquanto a Nasdaq recua 1,35%.<\/p>\n<p>Entre os destaques positivos do<strong> \u00cdndice Bovespa<\/strong> se encontra a <a href=\"https:\/\/www.suno.com.br\/acoes\/abev3\/\" target=\"_blank\" rel=\"noopener\">Ambev (ABEV3)<\/a>, com uma varia\u00e7\u00e3o de 4,13%. A <a href=\"https:\/\/www.suno.com.br\/acoes\/cyre3\/\" target=\"_blank\" rel=\"noopener\">Cyrela (CYRE3)<\/a> sobe 2,07%, enquanto a cota das <a href=\"https:\/\/www.suno.com.br\/acoes\/lren3\/\" target=\"_blank\" rel=\"noopener\">Lojas Renner (LREN3)<\/a> avan\u00e7a 1,70%.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia mais:<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/inflacao-eua-recorde-cpi-junho\/\">\n\t\t\tInfla\u00e7\u00e3o nos EUA chega a 9,1% e \u00e9 recorde para os \u00faltimos 40 anos\t\t<\/a>\n\t<\/div>\n\n\n<p>Os pap\u00e9is da <a href=\"https:\/\/www.suno.com.br\/acoes\/petr4\/\" target=\"_blank\" rel=\"noopener\">Petrobras (PETR4)<\/a> se valorizam 0,14% e os da <a href=\"https:\/\/www.suno.com.br\/acoes\/vale3\/\" target=\"_blank\" rel=\"noopener\">Vale (VALE3)<\/a> sobem 0,14%.<\/p>\n<p>Na ponta negativa, se destaca a <a href=\"https:\/\/www.suno.com.br\/acoes\/yduq3\/\" target=\"_blank\" rel=\"noopener\">YDUQS (YDUQ3)<\/a>, cuja queda \u00e9 de 3,89%. As a\u00e7\u00f5es da <a href=\"https:\/\/www.suno.com.br\/acoes\/ciel3\/\" target=\"_blank\" rel=\"noopener\">Cielo (CIEL3)<\/a> recuam 3,02%, enquanto a <a href=\"https:\/\/www.suno.com.br\/acoes\/suzb3\/\" target=\"_blank\" rel=\"noopener\">Suzano (SUZB3)<\/a> opera em baixa de 2,46%.<\/p>\n<h2>Not\u00edcias que movimentam o Ibovespa hoje<\/h2>\n<ul>\n<li><a href=\"https:\/\/www.suno.com.br\/acoes\/tims3\/\" target=\"_blank\" rel=\"noopener\">Tim (TIMS3)<\/a> e <a href=\"https:\/\/www.suno.com.br\/acoes\/vivt3\/\" target=\"_blank\" rel=\"noopener\">Vivo (VIVT3)<\/a> lan\u00e7am ofertas p\u00fablicas para a venda de metade das antenas herdadas da Oi (OIBR3)<\/li>\n<li>Conselho de administra\u00e7\u00e3o da <a href=\"https:\/\/www.suno.com.br\/acoes\/ligt3\/\" target=\"_blank\" rel=\"noopener\">Light (LIGT3)<\/a> aprova elei\u00e7\u00e3o de Oct\u00e1vio Cortes Pereira Lopes para o cargo de diretor presidente<\/li>\n<li><a href=\"https:\/\/www.suno.com.br\/acoes\/even3\/\" target=\"_blank\" rel=\"noopener\">Even (EVEN3)<\/a> tem alta de 35% nas vendas do 2T22 na compara\u00e7\u00e3o anual<\/li>\n<\/ul>\n<h2>Tim e Vivo lan\u00e7am ofertas p\u00fablicas para a venda de metade das antenas herdadas da Oi<\/h2>\n<p>Um dos assuntos que est\u00e1 no radar dos investidores do<strong> Ibovespa hoje<\/strong> \u00e9 o an\u00fancio da Tim e da Telef\u00f4nica, que anunciaram o lan\u00e7amento de ofertas p\u00fablicas para vender metade das antenas provenientes do processo de compra das redes m\u00f3veis da Oi.<\/p>\n<p>No caso da Tim, foram 3.610 antenas colocadas \u00e0 venda, por um total de R$ 368,8 milh\u00f5es. J\u00e1 a Vivo tem a pretens\u00e3o de vender 1.346 antenas, pelo valor de R$ 50,5 milh\u00f5es, segundo informa\u00e7\u00f5es colocadas em documentos enviados para o <a href=\"https:\/\/www.suno.com.br\/artigos\/cade\/\" target=\"_blank\" rel=\"noopener\">Cade (Conselho Administrativo de Defesa Econ\u00f4mica)<\/a>.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>O intuito da Tim e da Vivo \u00e9 de cumprir uma determina\u00e7\u00e3o do Cade para se desfazer de metade das esta\u00e7\u00f5es r\u00e1dio-base (ERBs) no per\u00edodo de seis meses, a fim de evitar a concentra\u00e7\u00e3o desses ativos sob o poder de apenas tr\u00eas operadoras.<\/p>\n<p>No caso da Claro, a exig\u00eancia do Cade \u00e9 que a empresa se desfa\u00e7a de 40% das ERBs, j\u00e1 que ela vai concentrar menos equipamentos.<\/p>\n<h2>Conselho de administra\u00e7\u00e3o da Light aprova elei\u00e7\u00e3o de Oct\u00e1vio Cortes Pereira Lopes para diretor presidente<\/h2>\n<p>Outro tema que pode influenciar na <strong>movimenta\u00e7\u00e3o do Ibovespa<\/strong> \u00e9 a aprova\u00e7\u00e3o do <a href=\"https:\/\/www.suno.com.br\/artigos\/conselho-administracao\/\" target=\"_blank\" rel=\"noopener\">conselho de administra\u00e7\u00e3o<\/a> da Light para a elei\u00e7\u00e3o de Oct\u00e1vio Cortes Pereira Lopes ao cargo de diretor presidente, passando a ter as novas fun\u00e7\u00f5es vigentes a partir de 15 de agosto.<\/p>\n<p>At\u00e9 esta data, Wilson Martins Poit vai continuar exercendo suas fun\u00e7\u00f5es como diretor presidente interino.<\/p>\n<p>Oct\u00e1vio \u00e9 formado em economia na Universidade de S\u00e3o Paulo e tem um MBA pela Wharton School na Universidade da Pensilv\u00e2nia, onde \u00e9 membro do Executive Board for Latin America desde o ano de 2008.<\/p>\n<p>Al\u00e9m disso, Oct\u00e1vio Cortes Pereira Lopes \u00e9 o atual CEO da Tok&amp;Stok, uma das maiores empresas do setor de Casa&amp;Decora\u00e7\u00e3o no Brasil.<\/p>\n<p>Com a efetiva posse de Oct\u00e1vio, Wilson Martins Poit vai deixar o cargo de diretor presidente interino e voltar\u00e1 a presidir o conselho de administra\u00e7\u00e3o da Light.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<h2>Even tem alta de 35% nas vendas do 2T22 na compara\u00e7\u00e3o anual<\/h2>\n<p>Um dos temas que tamb\u00e9m podem mexer com o <strong>valor do Ibovespa<\/strong> \u00e9 o an\u00fancio da pr\u00e9via operacional da Even para o segundo trimestre de 2022 (2T22).<\/p>\n<p>Segundo os dados reportados pela empresa, as vendas registraram R$ 479 milh\u00f5es, representando uma alta de 35% em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2021, quando o montante era de R$ 354 milh\u00f5es.<\/p>\n<p>A <a href=\"https:\/\/www.suno.com.br\/artigos\/vso\/\" target=\"_blank\" rel=\"noopener\">Venda Sobre Oferta (VSO)<\/a> trimestral da Even foi de 15%, apresentando uma baixa de um ponto percentual na compara\u00e7\u00e3o anual.<\/p>\n<p>A soma das vendas de estoque foi de R$ 335 milh\u00f5es, tendo uma VSO de 12%. A Even vendeu R$ 144 milh\u00f5es dos empreendimentos que foram lan\u00e7ados no trimestre, representando um VSO de 31%.<\/p>\n<p>A empresa entregou os quatro projetos, dois em S\u00e3o Paulo e dois no Rio Grande do Sul. Em SP o VGV total foi de R$ 176 milh\u00f5es, enquanto no RS foi de R$ 59 milh\u00f5es.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile-1.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop-1.jpg\"\n\t\t\t\t\tdata-promo-id=\"171998\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop-1.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<h2>Maiores altas do Ibovespa<\/h2>\n<p>Por volta das 10h42, as 5 maiores altas do Ibovespa eram:<\/p>\n<ul>\n<li>ABEV3: +4,13%<\/li>\n<li>CYRE3: +2,07%<\/li>\n<li>LREN3: +1,70%<\/li>\n<li>VBBR3: +1,29%<\/li>\n<li>EZTC3: +1,36%<\/li>\n<\/ul>\n<h2>Maiores baixas do Ibovespa<\/h2>\n<p>Por volta das 10h42, as maiores quedas do Ibovespa eram:<\/p>\n<ul>\n<li>YDUQ3: -3,89%<\/li>\n<li>CIEL3: -3,02%<\/li>\n<li>RDOR3: -2,85%<\/li>\n<li>SUZB3: -2,46%<\/li>\n<li>PRIO3: -2,38%<\/li>\n<\/ul>\n<h2>\u00daltima cota\u00e7\u00e3o do Ibovespa<\/h2>\n<p>O <strong>Ibovespa<\/strong> terminou a sess\u00e3o desta ter\u00e7a-feira (12) em leve alta de 0,06%, aos 98.271 pontos.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O Ibovespa opera em baixa de 0,20%, aos 98.075 pontos, por volta das 10h43, ap\u00f3s a divulga\u00e7\u00e3o de dados de infla\u00e7\u00e3o mais fortes nos Estados Unidos, alcan\u00e7ando a maior taxa anual em 40 anos e meio. INFLA\u00c7\u00c3O NOS EUA (CPI) VAI A 9,1% EM 12 MESES, A MAIOR DESDE 1981 A queda na cota\u00e7\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":173,"featured_media":264203,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[359,443,471,721,41531,595,648,663,676,2363],"suno_strategy":[],"class_list":["post-275587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-ambev-abev3","tag-cyrela-cyre3","tag-even-even3","tag-ibovespa","tag-light-ligt3","tag-petrobras-petr4","tag-suzano-suzb3","tag-tim-tims3","tag-vale-vale3","tag-yduqs-yduq3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ibovespa cai ap\u00f3s dados de infla\u00e7\u00e3o nos EUA; Ambev (ABEV3) lidera altas<\/title>\n<meta name=\"description\" content=\"O Ibovespa cai nesta quarta-feira (13) com dado de infla\u00e7\u00e3o nos EUA, enquanto Ambev (ABEV3) \u00e9 destaque de alta. Saiba mais sobre o Ibovespa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ibovespa cai ap\u00f3s dados de infla\u00e7\u00e3o nos EUA; Ambev (ABEV3) lidera altas\" \/>\n<meta property=\"og:description\" content=\"O Ibovespa cai nesta quarta-feira (13) com dado de infla\u00e7\u00e3o nos EUA, enquanto Ambev (ABEV3) \u00e9 destaque de alta. Saiba mais sobre o Ibovespa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/06\/ibovespa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jo\u00e3o Vitor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jo\u00e3o Vitor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/\"},\"author\":{\"name\":\"Jo\u00e3o Vitor\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/87fc6973867c52dd884811905c43afba\"},\"headline\":\"Ibovespa cai ap\u00f3s infla\u00e7\u00e3o mais forte nos EUA; Ambev (ABEV3) \u00e9 destaque de alta\",\"datePublished\":\"2022-07-13T14:18:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/\"},\"wordCount\":826,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/06\/ibovespa.jpg\",\"keywords\":[\"AMBEV (ABEV3)\",\"Cyrela (CYRE3)\",\"Even (EVEN3)\",\"Ibovespa\",\"Light (LIGT3)\",\"Petrobras (PETR4)\",\"Suzano (SUZB3)\",\"TIM (TIMS3)\",\"Vale (VALE3)\",\"Yduqs (YDUQ3)\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/\",\"name\":\"Ibovespa cai ap\u00f3s dados de infla\u00e7\u00e3o nos EUA; Ambev (ABEV3) lidera altas\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/06\/ibovespa.jpg\",\"datePublished\":\"2022-07-13T14:18:35+00:00\",\"description\":\"O Ibovespa cai nesta quarta-feira (13) com dado de infla\u00e7\u00e3o nos EUA, enquanto Ambev (ABEV3) \u00e9 destaque de alta. Saiba mais sobre o Ibovespa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/06\/ibovespa.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/06\/ibovespa.jpg\",\"width\":1280,\"height\":853,\"caption\":\"ibovespa hoje. Foto: Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/mercado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ibovespa cai ap\u00f3s infla\u00e7\u00e3o mais forte nos EUA; Ambev (ABEV3) \u00e9 destaque de alta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/87fc6973867c52dd884811905c43afba\",\"name\":\"Jo\u00e3o Vitor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2843227ca03ccf8cc7ccca45204c127e?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2843227ca03ccf8cc7ccca45204c127e?s=96&r=g\",\"caption\":\"Jo\u00e3o Vitor\"},\"description\":\"Redator profissional, com atua\u00e7\u00e3o no mercado editorial na produ\u00e7\u00e3o de not\u00edcias e conte\u00fados sobre o mercado de a\u00e7\u00f5es, fundos imobili\u00e1rios e economia popular. Graduando em Engenharia Qu\u00edmica pela Unesp, tamb\u00e9m j\u00e1 atuou como consultor financeiro.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/joao-vitor-jacintho\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ibovespa cai ap\u00f3s dados de infla\u00e7\u00e3o nos EUA; Ambev (ABEV3) lidera altas","description":"O Ibovespa cai nesta quarta-feira (13) com dado de infla\u00e7\u00e3o nos EUA, enquanto Ambev (ABEV3) \u00e9 destaque de alta. Saiba mais sobre o Ibovespa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/","og_locale":"pt_BR","og_type":"article","og_title":"Ibovespa cai ap\u00f3s dados de infla\u00e7\u00e3o nos EUA; Ambev (ABEV3) lidera altas","og_description":"O Ibovespa cai nesta quarta-feira (13) com dado de infla\u00e7\u00e3o nos EUA, enquanto Ambev (ABEV3) \u00e9 destaque de alta. Saiba mais sobre o Ibovespa.","og_url":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1280,"height":853,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/06\/ibovespa.jpg","type":"image\/jpeg"}],"author":"Jo\u00e3o Vitor","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Jo\u00e3o Vitor","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/"},"author":{"name":"Jo\u00e3o Vitor","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/87fc6973867c52dd884811905c43afba"},"headline":"Ibovespa cai ap\u00f3s infla\u00e7\u00e3o mais forte nos EUA; Ambev (ABEV3) \u00e9 destaque de alta","datePublished":"2022-07-13T14:18:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/"},"wordCount":826,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/06\/ibovespa.jpg","keywords":["AMBEV (ABEV3)","Cyrela (CYRE3)","Even (EVEN3)","Ibovespa","Light (LIGT3)","Petrobras (PETR4)","Suzano (SUZB3)","TIM (TIMS3)","Vale (VALE3)","Yduqs (YDUQ3)"],"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/","url":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/","name":"Ibovespa cai ap\u00f3s dados de infla\u00e7\u00e3o nos EUA; Ambev (ABEV3) lidera altas","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/06\/ibovespa.jpg","datePublished":"2022-07-13T14:18:35+00:00","description":"O Ibovespa cai nesta quarta-feira (13) com dado de infla\u00e7\u00e3o nos EUA, enquanto Ambev (ABEV3) \u00e9 destaque de alta. Saiba mais sobre o Ibovespa.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/06\/ibovespa.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/06\/ibovespa.jpg","width":1280,"height":853,"caption":"ibovespa hoje. Foto: Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/www.suno.com.br\/noticias\/mercado\/"},{"@type":"ListItem","position":3,"name":"Ibovespa cai ap\u00f3s infla\u00e7\u00e3o mais forte nos EUA; Ambev (ABEV3) \u00e9 destaque de alta"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/87fc6973867c52dd884811905c43afba","name":"Jo\u00e3o Vitor","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2843227ca03ccf8cc7ccca45204c127e?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2843227ca03ccf8cc7ccca45204c127e?s=96&r=g","caption":"Jo\u00e3o Vitor"},"description":"Redator profissional, com atua\u00e7\u00e3o no mercado editorial na produ\u00e7\u00e3o de not\u00edcias e conte\u00fados sobre o mercado de a\u00e7\u00f5es, fundos imobili\u00e1rios e economia popular. Graduando em Engenharia Qu\u00edmica pela Unesp, tamb\u00e9m j\u00e1 atuou como consultor financeiro.","url":"https:\/\/www.suno.com.br\/noticias\/author\/joao-vitor-jacintho\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/06\/ibovespa-400x200.jpg\" alt=\"Ibovespa cai ap\u00f3s infla\u00e7\u00e3o mais forte nos EUA; Ambev (ABEV3) \u00e9 destaque de alta\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mercado\/\">Mercado<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-hoje-cai-inflacao-eua-ambev-abev3-destaque-de-alta\/\"><h2 class=\"content__title\">Ibovespa cai ap\u00f3s infla\u00e7\u00e3o mais forte nos EUA; Ambev (ABEV3) \u00e9 destaque de alta<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/joao-vitor-jacintho\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/2843227ca03ccf8cc7ccca45204c127e?s=96&#038;r=g\" alt=\"Jo\u00e3o Vitor Jacintho\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/joao-vitor-jacintho\/\"><span itemprop=\"author\">Jo\u00e3o Vitor Jacintho<\/span><\/a><\/span><time datetime=\"2022-07-13T11:18:35-03:00\" itemprop=\"datePublished\">13\/07\/2022 11:18<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/275587"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/173"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=275587"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/275587\/revisions"}],"predecessor-version":[{"id":275618,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/275587\/revisions\/275618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/264203"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=275587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=275587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=275587"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=275587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}