{"id":27116,"date":"2019-06-04T08:23:09","date_gmt":"2019-06-04T11:23:09","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=27116"},"modified":"2019-06-04T13:40:15","modified_gmt":"2019-06-04T16:40:15","slug":"senado-mp-inss-governo-mudancas","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/","title":{"rendered":"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o"},"content":{"rendered":"<p>Na \u00faltima segunda-feira (3), o <strong>Senado<\/strong> aprovou a<strong> Medida Provis\u00f3ria\u00a0<\/strong>(MP) que diz a respeito ao pente-fino em <strong>benef\u00edcios previdenci\u00e1rios e assistenciais<\/strong>. Foram 55 votos dos parlamentares a favor e 12 contra.\u00a0 A MP precisava ser aprovada at\u00e9 a \u00faltima segunda, caso contr\u00e1rio perderia a validade.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal-800x450.webp\" width=\"800\" height=\"450\" alt=\"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<p>&#8220;Quero agradecer publicamente a todos os senadores e senadoras que vieram, em uma segunda-feira, exercer o seu<strong> mandato parlamentar<\/strong>, representando o <strong>povo brasileiro<\/strong>, sabendo da responsabilidade da vota\u00e7\u00e3o desta <strong>MP\u00a0<\/strong>que interessa ao Pa\u00eds&#8221;, disse o<strong> presidente do Senado<\/strong>, <strong>Davi Alcolumbre<\/strong>.\u00a0N\u00e3o \u00e9 comum ao Senado realizar sess\u00f5es de vota\u00e7\u00e3o \u00e0s segunda-feiras.<\/p>\n<p>O <strong>porta-voz do presidente da Rep\u00fablica<\/strong>, <strong>Ot\u00e1vio R\u00eago<\/strong>, afirmou que a medida provis\u00f3ria \u00e9 de &#8220;extrema import\u00e2ncia&#8221;.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/www.suno.com.br\/asset\/fundos\/suno-acoes-xp-seg-prev\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/SUNOPREV-400x300-Mobile-Artigos-3.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/SUNOPREV-1420x240-Banner-Artigos-1-_-Banner-Materias-1.png\"\n\t\t\t\t\tdata-promo-id=\"476310\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/10\/SUNOPREV-1420x240-Banner-Artigos-1-_-Banner-Materias-1.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<h2>MP 871\/2019<\/h2>\n<p>Conforme o texto aprovado, o<strong> Instituto Nacional do Seguro Social<\/strong> (<strong>INSS<\/strong>) ter\u00e1 acesso a dados das seguintes institui\u00e7\u00f5es:<\/p>\n<ul>\n<li><a href=\"https:\/\/receita.economia.gov.br\/\">Receita Federal<\/a>;<\/li>\n<li><a href=\"http:\/\/www.saude.gov.br\/sistema-unico-de-saude\">Sistema \u00danico de Sa\u00fade<\/a>;<\/li>\n<li><a href=\"http:\/\/www.caixa.gov.br\/beneficios-trabalhador\/fgts\/Paginas\/default.aspx\">Fundo de Garantia por Tempo de Servi\u00e7o (FGTS)<\/a>;<\/li>\n<\/ul>\n<p>Al\u00e9m disso, o texto pro\u00edbe a <strong>distribui\u00e7\u00e3o de dados<\/strong> com outras entidades privadas com as quais tenha conv\u00eanio. A previs\u00e3o de dura\u00e7\u00e3o \u00e9 de dois anos podendo ser prorrogada at\u00e9 2022.<\/p>\n<p>De acordo com o governo, cerca de tr\u00eas milh\u00f5es de benef\u00edcios s\u00e3o concedidos irregularmente. Com isso, t\u00e9cnicos e analistas do <strong>INSS<\/strong> examinar\u00e3o todos os \u00f3rg\u00e3os. Ademais, o texto prev\u00ea agilizar o cancelamento de benef\u00edcios ilegais.<\/p>\n<h2>Altera\u00e7\u00f5es<\/h2>\n<p>Com a <strong>aprova\u00e7\u00e3o da MP<\/strong>, o <strong>aux\u00edlio-reclus\u00e3o<\/strong> somente ser\u00e1 pago aos dependentes se o detento tiver feito 24 contribui\u00e7\u00f5es ao <strong>INSS<\/strong> antes de ser preso e \u00e9 necess\u00e1rio estar sob pena de<strong> regime fechado<\/strong>.<\/p>\n<p>A <strong>aposentadoria-rural<\/strong> ter\u00e1 que ter o certificado de trabalho por 15 anos pelo <strong>Cadastro Nacional de Informa\u00e7\u00f5es Sociais<\/strong> (CNIS). O benef\u00edcio n\u00e3o ser\u00e1 concedido atrav\u00e9s de <strong>sindicatos rurais.<\/strong><\/p>\n<p>J\u00e1 os que utilizam o <strong>aux\u00edlio-acidente<\/strong> ser\u00e1 necess\u00e1rio continuar com a <strong>contribui\u00e7\u00e3o ao INSS<\/strong> para ter direito \u00e0 <a href=\"https:\/\/www.suno.com.br\/artigos\/como-se-aposentar\/\"><strong>aposentadoria<\/strong><\/a>. Por sua vez, os filhos ou c\u00f4njuges que forem condenados por <strong>homic\u00eddio<\/strong> contra companheiros ou pais perder\u00e3o o direito a pens\u00e3o.<\/p>\n<p>As <strong>institui\u00e7\u00f5es financeiras<\/strong> n\u00e3o poder\u00e3o mais entrar em contato atrav\u00e9s de mensagens ou liga\u00e7\u00f5es para oferecer <a href=\"https:\/\/www.suno.com.br\/artigos\/cartao-de-credito-sem-anuidade\/\"><strong>cart\u00e3o de cr\u00e9dito<\/strong><\/a> a aposentados ou pensionistas do <strong>INSS<\/strong>.<\/p>\n<p>Em rela\u00e7\u00e3o \u00e0<strong>\u00a0viol\u00eancia dom\u00e9stica<\/strong>, com a aprova\u00e7\u00e3o do texto, passa a valer que as<strong> despesas<\/strong> com v\u00edtimas s\u00e3o de<strong>\u00a0responsabilidade do agressor<\/strong>.<\/p>\n<p>As empresas ser\u00e3o respons\u00e1veis juntamente com a <strong>Previd\u00eancia Social<\/strong> por trabalhadores acidentados ou doentes devido \u00e0 neglig\u00eancia das <strong>normas de seguran\u00e7a do trabalho<\/strong>.<\/p>\n<h2>Acordo<\/h2>\n<p>A <strong>Medida Provis\u00f3ria<\/strong> s\u00f3 foi aprovada devido ao acordo entre o governo e a oposi\u00e7\u00e3o.\u00a0Conforme o <strong>senador Randolfe Rodrigues da Rede<\/strong>, a oposi\u00e7\u00e3o havia se comprometido em n\u00e3o obstruir e solicitar verifica\u00e7\u00f5es de qu\u00f3rum durante a vota\u00e7\u00e3o.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/mp-antifraude-governo-oposicao-acordo-votacao\/\">Saiba Mais:\u00a0MP Antifraude: governo e oposi\u00e7\u00e3o fazem acordo para garantir vota\u00e7\u00e3o<\/a><\/p>\n<p>J\u00e1 os opositores pediram ao <strong>governo<\/strong> que inclu\u00edsse um gatilho na<strong> MP<\/strong> para que o prazo de cadastramento de <strong>trabalhadores rurais<\/strong> e <strong>pescadores<\/strong> seja renovado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima segunda-feira (3), o Senado aprovou a Medida Provis\u00f3ria\u00a0(MP) que diz a respeito ao pente-fino em benef\u00edcios previdenci\u00e1rios e assistenciais. Foram 55 votos dos parlamentares a favor e 12 contra.\u00a0 A MP precisava ser aprovada at\u00e9 a \u00faltima segunda, caso contr\u00e1rio perderia a validade. Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":13942,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[61],"tags":[1068],"suno_strategy":[],"class_list":["post-27116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-senado-federal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o<\/title>\n<meta name=\"description\" content=\"Na \u00faltima segunda (3), o Senado aprovou a MP que diz a respeito ao &quot;pente-fino em benef\u00edcios previdenci\u00e1rios. Clique aqui e saiba mais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Na \u00faltima segunda (3), o Senado aprovou a MP que diz a respeito ao &quot;pente-fino em benef\u00edcios previdenci\u00e1rios. Clique aqui e saiba mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Poliana Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Poliana Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/\"},\"author\":{\"name\":\"Poliana Santos\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\"},\"headline\":\"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o\",\"datePublished\":\"2019-06-04T11:23:09+00:00\",\"dateModified\":\"2019-06-04T16:40:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/\"},\"wordCount\":542,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal-jpg.webp\",\"keywords\":[\"Senado Federal\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/\",\"name\":\"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal-jpg.webp\",\"datePublished\":\"2019-06-04T11:23:09+00:00\",\"dateModified\":\"2019-06-04T16:40:15+00:00\",\"description\":\"Na \u00faltima segunda (3), o Senado aprovou a MP que diz a respeito ao \\\"pente-fino em benef\u00edcios previdenci\u00e1rios. Clique aqui e saiba mais\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal-jpg.webp\",\"width\":1140,\"height\":760,\"caption\":\"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/politica\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\",\"name\":\"Poliana Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"caption\":\"Poliana Santos\"},\"description\":\"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o","description":"Na \u00faltima segunda (3), o Senado aprovou a MP que diz a respeito ao \"pente-fino em benef\u00edcios previdenci\u00e1rios. Clique aqui e saiba mais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/","og_locale":"pt_BR","og_type":"article","og_title":"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o","og_description":"Na \u00faltima segunda (3), o Senado aprovou a MP que diz a respeito ao \"pente-fino em benef\u00edcios previdenci\u00e1rios. Clique aqui e saiba mais","og_url":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1140,"height":760,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal.jpg","type":"image\/jpeg"}],"author":"Poliana Santos","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Poliana Santos","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/"},"author":{"name":"Poliana Santos","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda"},"headline":"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o","datePublished":"2019-06-04T11:23:09+00:00","dateModified":"2019-06-04T16:40:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/"},"wordCount":542,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal-jpg.webp","keywords":["Senado Federal"],"articleSection":["Pol\u00edtica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/","url":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/","name":"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal-jpg.webp","datePublished":"2019-06-04T11:23:09+00:00","dateModified":"2019-06-04T16:40:15+00:00","description":"Na \u00faltima segunda (3), o Senado aprovou a MP que diz a respeito ao \"pente-fino em benef\u00edcios previdenci\u00e1rios. Clique aqui e saiba mais","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal-jpg.webp","width":1140,"height":760,"caption":"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica","item":"https:\/\/www.suno.com.br\/noticias\/politica\/"},{"@type":"ListItem","position":3,"name":"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda","name":"Poliana Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","caption":"Poliana Santos"},"description":"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.","url":"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/02\/24924863-novo-presidente-do-senado-federal-400x200.webp\" alt=\"Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/politica\/\">Pol\u00edtica<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/senado-mp-inss-governo-mudancas\/\"><h2 class=\"content__title\">Senado aprova MP Antifraude ap\u00f3s acordo entre governo e oposi\u00e7\u00e3o<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2019-06-04T08:23:09-03:00\" itemprop=\"datePublished\">04\/06\/2019 08:23<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/27116"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=27116"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/27116\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/13942"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=27116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=27116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=27116"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=27116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}