{"id":26805,"date":"2019-05-31T15:00:24","date_gmt":"2019-05-31T18:00:24","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=26805"},"modified":"2021-06-13T23:44:10","modified_gmt":"2021-06-14T02:44:10","slug":"inflacao-estados-unidos-avanca-abril","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/","title":{"rendered":"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril"},"content":{"rendered":"<p>O <strong>\u00edndice de pre\u00e7os ao consumidor<\/strong> dos Estados Unidos, o mesmo que a infla\u00e7\u00e3o, registrou uma alta de 0,3% em abril. O dado foi divulgado nesta sexta-feira (31) pelo <strong>Departamento de Com\u00e9rcio<\/strong><\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-800x450.webp\" width=\"800\" height=\"450\" alt=\"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">PIB dos EUA sobe 3,2% no 3T22, ap\u00f3s revis\u00e3o; Pedidos de aux\u00edlio-desemprego aumentam. Foto: divulga\u00e7\u00e3o<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<p>O resultado dos <strong>Estados Unidos<\/strong> d\u00e1 base para o posicionamento do <strong>Federal Reserve (Fed)<\/strong>\u00a0em manter a taxa de juros em 2,5%. Isso porque o banco central americano j\u00e1 recebeu diversos pedidos de aumento da taxa. Contudo, os representantes do \u00f3rg\u00e3o afirmam que a baixa <strong>infla\u00e7\u00e3o<\/strong> e a desacelera\u00e7\u00e3o do crescimento podem ser passageiros.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/4-emissao-snel11\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/400x300-Mobile-Artigos-7.webp\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/1420x240-Banner-Artigos-1-_-Banner-Materias-5.webp\"\n\t\t\t\t\tdata-promo-id=\"364417\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/07\/1420x240-Banner-Artigos-1-_-Banner-Materias-5.webp\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Dessa forma, a alta da <strong>infla\u00e7\u00e3o<\/strong> em abril sustenta a teoria do <strong>Fed<\/strong>. Com o crescimento de 0,3%, o aumento anual do \u00edndice de pre\u00e7os passa a ser de 1,5% e n\u00e3o mais 1,4%, como registrado em mar\u00e7o deste ano.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/pib-eua-donald-trump-economia\/\">Saiba Mais: PIB dos EUA \u00e9 revisado para baixo a 3,1% no 1\u00b0 trimestre de 2019<\/a><\/p>\n<p>Em contrapartida, os <strong>gastos<\/strong> dos consumidores desaceleraram a alta. Isso porque em abril, o \u00edndice subiu 0,3%, mas, em mar\u00e7o, o avan\u00e7o havia sido de 1,1%, o maior registrado desde agosto de 2009. Os servi\u00e7os em que os consumidores gastaram menos neste m\u00eas foram, principalmente, <strong>eletricidade<\/strong> e <strong>g\u00e1s dom\u00e9stico<\/strong>.<\/p>\n<h2>PIB do EUA<\/h2>\n<p>Al\u00e9m disso, a estimativa do <strong>PIB<\/strong> americano foi revisada nesta sexta-feira.\u00a0Assim, a previs\u00e3o ficou ent\u00e3o em 3,1%.\u00a0O resultado\u00a0<strong>PIB dos EUA<\/strong> demonstra que houve <strong>crescimento econ\u00f4mico<\/strong> no primeiro trimestre. No entanto, de acordo com especialistas, h\u00e1 sinais de que esse aumento \u00e9 tempor\u00e1rio.<\/p>\n<p>O que faz acreditar que esse aumento n\u00e3o prosseguir\u00e1 s\u00e3o as quedas nas<strong> exporta\u00e7\u00f5es<\/strong>, a diminui\u00e7\u00e3o no ac\u00famulo de <strong>estoques<\/strong> e a desacelera\u00e7\u00e3o<strong> da<\/strong> produ\u00e7\u00e3o das<strong> f\u00e1bricas<\/strong>.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/trump-medidas-conter-imigrantes-mexico\/\">Saiba Mais: Trump anuncia medidas para conter imigrantes ilegais vindos do M\u00e9xico<\/a><\/p>\n<p>&#8220;O aumento do <strong>PIB<\/strong> real no primeiro trimestre refletiu contribui\u00e7\u00f5es positivas dos gastos do consumidores, investimento em estoques privados, exporta\u00e7\u00f5es, gastos do governo estadual e municipal e investimentos fixos n\u00e3o-residenciais, que foram parcialmente compensados por uma contribui\u00e7\u00e3o negativa do investimento fixo residencial&#8221;, disse o <strong>Departamento de Com\u00e9rcio dos EUA<\/strong>.<\/p>\n<p>O \u00f3rg\u00e3o tamb\u00e9m divulgou que a <strong>economia norte-americana<\/strong>\u00a0acelerou 3,2% no primeiro trimestre. Superando as expectativas dos analistas, que estimavam um crescimento de apenas 2%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O \u00edndice de pre\u00e7os ao consumidor dos Estados Unidos, o mesmo que a infla\u00e7\u00e3o, registrou uma alta de 0,3% em abril. O dado foi divulgado nesta sexta-feira (31) pelo Departamento de Com\u00e9rcio PIB dos EUA sobe 3,2% no 3T22, ap\u00f3s revis\u00e3o; Pedidos de aux\u00edlio-desemprego aumentam. Foto: divulga\u00e7\u00e3o O resultado dos Estados Unidos d\u00e1 base para [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":26808,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[793,776,807],"suno_strategy":[],"class_list":["post-26805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-estados-unidos-eua","tag-federal-reseve-fed","tag-produto-interno-bruto-pib"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril<\/title>\n<meta name=\"description\" content=\"O resultado da infla\u00e7\u00e3o nos Estados Unidos sustenta o posicionamento do Federal Reserve (Fed) sobre as taxas de juros. Clique e entenda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril\" \/>\n<meta property=\"og:description\" content=\"O resultado da infla\u00e7\u00e3o nos Estados Unidos sustenta o posicionamento do Federal Reserve (Fed) sobre as taxas de juros. Clique e entenda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-1024x554.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Beatriz Oliveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beatriz Oliveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/\"},\"author\":{\"name\":\"Beatriz Oliveira\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e67f665add014bf99f644028de070cc3\"},\"headline\":\"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril\",\"datePublished\":\"2019-05-31T18:00:24+00:00\",\"dateModified\":\"2021-06-14T02:44:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/\"},\"wordCount\":384,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-scaled.webp\",\"keywords\":[\"Estados Unidos (EUA)\",\"Federal Reserve (FED)\",\"Produto Interno Bruto (PIB)\"],\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/\",\"name\":\"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-scaled.webp\",\"datePublished\":\"2019-05-31T18:00:24+00:00\",\"dateModified\":\"2021-06-14T02:44:10+00:00\",\"description\":\"O resultado da infla\u00e7\u00e3o nos Estados Unidos sustenta o posicionamento do Federal Reserve (Fed) sobre as taxas de juros. Clique e entenda.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-scaled.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-scaled.webp\",\"width\":2560,\"height\":1384,\"caption\":\"PIB dos EUA sobe 3,2% no 3T22, ap\u00f3s revis\u00e3o; Pedidos de aux\u00edlio-desemprego aumentam. Foto: divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e67f665add014bf99f644028de070cc3\",\"name\":\"Beatriz Oliveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c9aa6a0aaecc598d257d5d5bd349157d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c9aa6a0aaecc598d257d5d5bd349157d?s=96&r=g\",\"caption\":\"Beatriz Oliveira\"},\"description\":\"Formada em Jornalismo pela Faculdade Paulus de Tecnologia e Comunica\u00e7\u00e3o, Beatriz Oliveira escreve para o portal de not\u00edcias Suno Research. Antes, passou pelas reda\u00e7\u00f5es da Revista EXAME e da Rede Bandeirantes.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/beatriz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril","description":"O resultado da infla\u00e7\u00e3o nos Estados Unidos sustenta o posicionamento do Federal Reserve (Fed) sobre as taxas de juros. Clique e entenda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/","og_locale":"pt_BR","og_type":"article","og_title":"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril","og_description":"O resultado da infla\u00e7\u00e3o nos Estados Unidos sustenta o posicionamento do Federal Reserve (Fed) sobre as taxas de juros. Clique e entenda.","og_url":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1024,"height":554,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-1024x554.jpg","type":"image\/jpeg"}],"author":"Beatriz Oliveira","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Beatriz Oliveira","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/"},"author":{"name":"Beatriz Oliveira","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e67f665add014bf99f644028de070cc3"},"headline":"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril","datePublished":"2019-05-31T18:00:24+00:00","dateModified":"2021-06-14T02:44:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/"},"wordCount":384,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-scaled.webp","keywords":["Estados Unidos (EUA)","Federal Reserve (FED)","Produto Interno Bruto (PIB)"],"articleSection":["Internacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/","url":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/","name":"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-scaled.webp","datePublished":"2019-05-31T18:00:24+00:00","dateModified":"2021-06-14T02:44:10+00:00","description":"O resultado da infla\u00e7\u00e3o nos Estados Unidos sustenta o posicionamento do Federal Reserve (Fed) sobre as taxas de juros. Clique e entenda.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-scaled.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-scaled.webp","width":2560,"height":1384,"caption":"PIB dos EUA sobe 3,2% no 3T22, ap\u00f3s revis\u00e3o; Pedidos de aux\u00edlio-desemprego aumentam. Foto: divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Internacional","item":"https:\/\/www.suno.com.br\/noticias\/internacional\/"},{"@type":"ListItem","position":3,"name":"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e67f665add014bf99f644028de070cc3","name":"Beatriz Oliveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c9aa6a0aaecc598d257d5d5bd349157d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c9aa6a0aaecc598d257d5d5bd349157d?s=96&r=g","caption":"Beatriz Oliveira"},"description":"Formada em Jornalismo pela Faculdade Paulus de Tecnologia e Comunica\u00e7\u00e3o, Beatriz Oliveira escreve para o portal de not\u00edcias Suno Research. Antes, passou pelas reda\u00e7\u00f5es da Revista EXAME e da Rede Bandeirantes.","url":"https:\/\/www.suno.com.br\/noticias\/author\/beatriz\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2019\/05\/c042783e-pib-estados-unidos-400x200.webp\" alt=\"Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/internacional\/\">Internacional<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/inflacao-estados-unidos-avanca-abril\/\"><h2 class=\"content__title\">Infla\u00e7\u00e3o dos Estados Unidos avan\u00e7a 0,3% em abril<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/beatriz\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/c9aa6a0aaecc598d257d5d5bd349157d?s=96&#038;r=g\" alt=\"Beatriz Oliveira\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/beatriz\/\"><span itemprop=\"author\">Beatriz Oliveira<\/span><\/a><\/span><time datetime=\"2019-05-31T15:00:24-03:00\" itemprop=\"datePublished\">31\/05\/2019 15:00<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/26805"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=26805"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/26805\/revisions"}],"predecessor-version":[{"id":157347,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/26805\/revisions\/157347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/26808"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=26805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=26805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=26805"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=26805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}