{"id":267309,"date":"2022-06-13T22:43:15","date_gmt":"2022-06-14T01:43:15","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=267309"},"modified":"2022-06-13T23:31:09","modified_gmt":"2022-06-14T02:31:09","slug":"icms-aprovado-projeto-preco-combustiveis-senado","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/","title":{"rendered":"Senado aprova texto-base de projeto que fixa teto do ICMS para os combust\u00edveis"},"content":{"rendered":"<p>O Senado aprovou nesta segunda (13), por 65 votos a favor e 12 contra, o Projeto de Lei Complementar (PLP) 18\/2022 que fixa teto de 17% do <strong>ICMS<\/strong> sobre combust\u00edveis, energia el\u00e9trica e servi\u00e7os de telecomunica\u00e7\u00f5es e de transporte p\u00fablico. A proposta prev\u00ea uma compensa\u00e7\u00e3o aos estados com o abatimento de d\u00edvidas com a Uni\u00e3o, quando a perda de arrecada\u00e7\u00e3o passar de 5%. Os governos n\u00e3o endividados ter\u00e3o prioridade para fazer empr\u00e9stimos com o aval da Uni\u00e3o, e podem ter recursos adicionais em 2023. Os senadores ainda analisam emendas destacadas para vota\u00e7\u00e3o em separado.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Senado aprova texto-base de projeto que fixa teto do ICMS para os combust\u00edveis\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">PEC da Transi\u00e7\u00e3o. Foto: Ag\u00eancia Senado.<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"240038\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>O governo argumenta que a <strong>mudan\u00e7a do ICMS<\/strong> vai diminuir os <strong>pre\u00e7os dos combust\u00edveis<\/strong> para o consumidor final e ajudar\u00e1 no controle da infla\u00e7\u00e3o, ajudando a economia como um todo. J\u00e1 os cr\u00edticos do PLP afirmam que n\u00e3o haver\u00e1 redu\u00e7\u00e3o significativa de pre\u00e7os nas bombas, mas \u00e1reas como sa\u00fade e educa\u00e7\u00e3o podem ser afetadas.<\/p>\n<p>O relator Fernando Bezerra Coelho (MDB-PE) complementou seu relat\u00f3rio analisando todas as 77 emendas apresentadas por senadores. Ele acolheu quatro emendas de maneira integral e outras nove emendas parcialmente.<\/p>\n<p>Como o projeto considera que combust\u00edveis \u2014 assim como energia, transportes coletivos, g\u00e1s natural e comunica\u00e7\u00f5es \u2014 s\u00e3o bens essenciais e indispens\u00e1veis,\u00a0 os governos n\u00e3o poder\u00e3o <strong>cobrar ICMS<\/strong> acima do teto se o PLP virar lei.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Os governadores t\u00eam demonstrado resist\u00eancia \u00e0 proposta, visto que o ICMS \u00e9 a principal fonte de<strong> arrecada\u00e7\u00e3o dos estados<\/strong>. J\u00e1 os parlamentares de oposi\u00e7\u00e3o\u00a0 consideram a medida eleitoreira, que pode prejudicar os governos locais sem surtir o efeito desejado, que \u00e9 baixar os valores na bomba. A quest\u00e3o tamb\u00e9m \u00e9 objeto de processo que tramita no Supremo Tribunal Federal (STF).<\/p>\n<p>O texto aprovado reduz a zero as al\u00edquotas de Cide-Combust\u00edveis e <strong>PIS\/Cofins<\/strong> incidentes sobre a gasolina at\u00e9 31 de dezembro de 2022. Atualmente, tais <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/tributos-federais\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">tributos federais<\/a> j\u00e1 est\u00e3o zerados para diesel e g\u00e1s de cozinha. O relator optou tamb\u00e9m por derrubar a zero a PIS\/Cofins incidente sobre \u00e1lcool hidratado e sobre \u00e1lcool anidro adicionado \u00e0 gasolina.<\/p>\n<p>O objetivo do projeto \u00e9 provocar a redu\u00e7\u00e3o no valor dos combust\u00edveis na bomba, aliviando o gasto do consumidor com gasolina, que supera os R$ 7 o litro no pa\u00eds, e com o diesel, beneficiando tamb\u00e9m caminhoneiros e transportadores. O PLP tamb\u00e9m busca reduzir o valor do g\u00e1s de cozinha e da conta de luz.<\/p>\n<p>O projeto volta para a C\u00e2mara para nova an\u00e1lise ap\u00f3s as emendas inseridas no texto. Para o relator do projeto no Senado, Fernando Bezerra (MDB-PE), o PLP \u00e9 \u201cum passo important\u00edssimo para derrubar a infla\u00e7\u00e3o\u201d, al\u00e9m de segurar os pre\u00e7os nas contas de luz e nos postos de combust\u00edvel. Ele tamb\u00e9m afirmou que o Congresso \u201cfaz hist\u00f3ria\u201d ao incluir esses setores entre os considerados essenciais.<\/p>\n<p>\u201cParticipei da Constituinte de 1988, l\u00e1 a gente dizia que a essencialidade dos produtos tinha que ser definida por lei complementar. E se passaram mais de 30 anos e o Congresso, em nenhum momento, definiu a essencialidade dos produtos. Portanto, esse \u00e9 um passo importante, estamos fazendo hist\u00f3ria\u201d, disse o senador.<\/p>\n<p>Bezerra leu seu relat\u00f3rio em plen\u00e1rio na semana passada\u00a0e hoje se ateve \u00e0s emendas recebidas pelo projeto. Foram 77 no total e Bezerra acolheu quatro integralmente e nove parcialmente.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile-1.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop-1.jpg\"\n\t\t\t\t\tdata-promo-id=\"171998\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop-1.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<h2>Emendas<\/h2>\n<p>Uma das emendas acatadas rep\u00f5e perdas de arrecada\u00e7\u00e3o do Fundo de Manuten\u00e7\u00e3o da Educa\u00e7\u00e3o B\u00e1sica (Fundeb) e de a\u00e7\u00f5es de servi\u00e7os de sa\u00fade. Ambos setores t\u00eam receitas vinculadas \u00e0 arrecada\u00e7\u00e3o com o ICMS. O relator incluiu um trecho que prev\u00ea a manuten\u00e7\u00e3o das vincula\u00e7\u00f5es \u00e0 sa\u00fade e educa\u00e7\u00e3o b\u00e1sica, mas de forma proporcional \u00e0 dedu\u00e7\u00e3o dos contratos de d\u00edvida dos Estados com a Uni\u00e3o.<\/p>\n<p>Bezerra tamb\u00e9m incluiu no texto um dispositivo para conferir seguran\u00e7a jur\u00eddica aos gestores estaduais. Assim, eles poder\u00e3o reduzir a arrecada\u00e7\u00e3o do ICMS sem ferir a Lei de Responsabilidade Fiscal (LRF) e a <strong>Lei de Diretrizes Or\u00e7ament\u00e1rias<\/strong> (LDO). De acordo com o regramento, um ente federativo n\u00e3o pode abrir m\u00e3o de uma receita sem indicar uma nova fonte de arrecada\u00e7\u00e3o para compensar.<\/p>\n<h2>Senadores<\/h2>\n<p>O PLP n\u00e3o foi un\u00e2nime no plen\u00e1rio. Alguns senadores se colocaram contr\u00e1rios ao projeto. Para Zenaide Maia (Pros-RN), o projeto n\u00e3o ataca o principal causador do aumento dos combust\u00edveis, que \u00e9 a atual pol\u00edtica de pre\u00e7os da Petrobras, vinculada ao pre\u00e7o internacional do barril de petr\u00f3leo e o valor do d\u00f3lar.<\/p>\n<p>\u201cEsse PL n\u00e3o tem nada a ver. E, ainda, sem a garantia de que vai ter redu\u00e7\u00e3o dos pre\u00e7os na bomba de combust\u00edvel, a gente sabe que depende do d\u00f3lar, e a certeza de que a Petrobras, assim que for aprovado isso aqui, vai recompor os pre\u00e7os, porque j\u00e1 faz mais de 20 dias que n\u00e3o dava aumento\u201d.<\/p>\n<p>Carlos Portinho (PL-RJ), novo l\u00edder do governo no Senado, defendeu o projeto e pediu a participa\u00e7\u00e3o dos estados no esfor\u00e7o de reduzir o pre\u00e7o do combust\u00edvel para a popula\u00e7\u00e3o. Segundo ele, o governo tem contribu\u00eddo ao abrir m\u00e3o de impostos federais sobre o combust\u00edvel para reduzir o impacto da infla\u00e7\u00e3o explicada, segundo ele, pela guerra na Ucr\u00e2nia, dentre outras vari\u00e1veis internacionais.<\/p>\n<p>\u201cTemos que cortar os impostos, assim como diversas na\u00e7\u00f5es no mundo, neste momento de emerg\u00eancia internacional, est\u00e3o fazendo. \u00c9 o que temos para hoje\u201d, disse. \u201cAgora \u00e9 hora dos governos: \u00e9 hora do Governo Federal, que p\u00f5e na mesa, e \u00e9 hora desse sacrif\u00edcio dos governos estaduais\u201d.<\/p>\n<h2>Relat\u00f3rio<\/h2>\n<p>Na semana passada, ao apresentar o relat\u00f3rio \u00e0 imprensa, Bezerra afirmou que, se aprovado, o PLP poderia derrubar em R$ 1,65 o pre\u00e7o da gasolina e em R$ 0,76 o pre\u00e7o do diesel. No entanto, destacou que os pre\u00e7os poderiam apenas \u201cn\u00e3o subir muito mais\u201d, a depender do cen\u00e1rio internacional, que influencia no pre\u00e7o do barril de petr\u00f3leo e na valoriza\u00e7\u00e3o do d\u00f3lar frente ao real.<\/p>\n<p>\u201cN\u00e3o estamos tabelando pre\u00e7o. Tem uma guerra na Ucr\u00e2nia, a R\u00fassia \u00e9 respons\u00e1vel por 25% da produ\u00e7\u00e3o de diesel no mundo, os pre\u00e7os est\u00e3o tensionados. \u00c9 evidente que pode haver eleva\u00e7\u00e3o de pre\u00e7os. Mas, mesmo que haja, isso vai ajudar a n\u00e3o subir muito mais do que subiria\u201d, disse, na ocasi\u00e3o.<\/p>\n<p>J\u00e1 existe um projeto, aprovado no Senado em mar\u00e7o, que pretende reduzir o valor dos combust\u00edveis. O Projeto de Lei 1.472\/2021 prop\u00f5e a mudan\u00e7a a forma de c\u00e1lculo do pre\u00e7o dos combust\u00edveis, al\u00e9m de criar uma Conta de Estabiliza\u00e7\u00e3o, para garantir a previsibilidade nos pre\u00e7os ao consumidor. O projeto, considerado uma das prioridades do Senado no in\u00edcio deste ano, atualmente est\u00e1 parado na C\u00e2mara dos Deputados, sem previs\u00e3o de vota\u00e7\u00e3o.<\/p>\n<h2>ICMS: perdas de arrecada\u00e7\u00e3o de estados ter\u00e3o compensa\u00e7\u00e3o, diz relator do projeto<\/h2>\n<p>Nos c\u00e1lculos apresentados por Fernando Bezerra Coelho em plen\u00e1rio, as perdas arrecadat\u00f3rias de estados e munic\u00edpios representar\u00e3o pouco frente ao aumento das receitas dos \u00faltimos anos.<\/p>\n<p>&#8220;Os estados poder\u00e3o comportar e dar a sua contribui\u00e7\u00e3o para que a gente possa reduzir o pre\u00e7o da energia, o pre\u00e7o dos combust\u00edveis, o pre\u00e7o das telecomunica\u00e7\u00f5es (&#8230; ) estados e munic\u00edpios podem, sim, suportar o impacto deste projeto&#8221;, afirmou o relator.<\/p>\n<p>Para Fernando Bezerra Coelho seu relat\u00f3rio aperfei\u00e7oou os mecanismos de compensa\u00e7\u00e3o aos estados previstos no projeto original, de autoria do deputado Danilo Forte (Uni\u00e3o-CE).<\/p>\n<p>L\u00edder do PL no Senado, o senador Fl\u00e1vio Bolsonaro (RJ) defendeu a aprova\u00e7\u00e3o do projeto por entender que haver\u00e1 redu\u00e7\u00e3o nos <strong>pre\u00e7os do frete<\/strong> e dos alimentos, al\u00e9m do al\u00edvio inflacion\u00e1rio.<\/p>\n<p>&#8220;\u00c9 um passo importante e corajoso a favor dos mais pobres que o Congresso Nacional dar\u00e1, pois estamos tratando os combust\u00edveis como bens essenciais que s\u00e3o, conforme j\u00e1 o pr\u00f3prio Poder Judici\u00e1rio vem reiteradamente reconhecendo e formando um conceito majorit\u00e1rio&#8221;, disse Fl\u00e1vio Bolsonaro.<\/p>\n<p>Tamb\u00e9m apoiaram a aprova\u00e7\u00e3o do projeto os senadores Wellington Fagundes (PL-MT), Marcos Rog\u00e9rio (PL-RO), Carlos Portinho (PL-RJ), Jorginho Mello (PL-SC), Zequinha Marinho (PL-PA), Reguffe (Uni\u00e3o-DF), Lucas Barreto (PSD-AP), Angelo Coronel (PSD-BA), Esperidi\u00e3o Amin (PP-SC), Fabio Garcia (Uni\u00e3o-MT) e outros.<\/p>\n<h2>Mais cr\u00edticas ao propjeto<\/h2>\n<p>O senador Oriovisto Guimar\u00e3es (Podemos-PR) criticou duramente o PLP. Ele disse que h\u00e1 100 milh\u00f5es de brasileiros que vivem em inseguran\u00e7a alimentar e que as mudan\u00e7as v\u00e3o \u201csubsidiar o combust\u00edvel dos carros da classe m\u00e9dia\u201d<\/p>\n<p>&#8220;Enquanto uma crian\u00e7a passa fome e tem o desenvolvimento mental dos seus neur\u00f4nios comprometido pela aus\u00eancia de prote\u00ednas e de alimenta\u00e7\u00e3o b\u00e1sica, \u00e9 justo que se estabele\u00e7a uma pol\u00edtica p\u00fablica de usar dinheiro p\u00fablico para financiar combust\u00edvel de carro de passeio? Eu jamais colocarei minha impress\u00e3o digital sobre tamanho absurdo. Isso n\u00e3o faz nenhum sentido!&#8221; opinou Oriovisto.<\/p>\n<p>A senadora Zenaide Maia (Pros-RN) tamb\u00e9m foi contr\u00e1ria ao PLP. Ela disse que as altera\u00e7\u00f5es v\u00e3o prejudicar os caixas dos estados e diminuir investimentos em sa\u00fade e educa\u00e7\u00e3o. Ela acrescentou n\u00e3o haver garantias que o pre\u00e7o vai diminuir nos postos de combust\u00edvel.<\/p>\n<p>&#8220;Enquanto a Inglaterra est\u00e1 decidindo taxar os lucros das empresas petrol\u00edferas, aqui n\u00f3s estamos optando por retirar recursos da educa\u00e7\u00e3o e da sa\u00fade dos estados e dos munic\u00edpios para manter os lucros e os <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">dividendos<\/a> dos acionistas da Petrobras, que pagam zero de Imposto de Renda. Isso n\u00e3o se pode fazer&#8221;, afirmou Zenaide.<\/p>\n<p>Os senadores Jean Paul Prates (PT-RN), Alessandro Vieira (PSDB-SE) e Oriovisto Guimar\u00e3es tamb\u00e9m disseram duvidar que o projeto vai conseguir diminuir o <strong>pre\u00e7o dos combust\u00edveis<\/strong> nos postos. Eles chegaram a pedir o adiamento da vota\u00e7\u00e3o, mas n\u00e3o obtiveram sucesso.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>&#8220;A nossa posi\u00e7\u00e3o como l\u00edder da minoria \u00e9 de ceticismo absoluto em rela\u00e7\u00e3o a esse projeto do ICMS por saber que a solu\u00e7\u00e3o n\u00e3o reside em, mais uma vez, atacar a tributa\u00e7\u00e3o estadual e zerar impostos sobre combust\u00edveis f\u00f3sseis, sacrificando a capacidade de atendimento dos estados e munic\u00edpios ao p\u00fablico&#8221;, observou Jean Paul Prates.<\/p>\n<p><em>Com Ag\u00eancia Senado<\/em><\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O Senado aprovou nesta segunda (13), por 65 votos a favor e 12 contra, o Projeto de Lei Complementar (PLP) 18\/2022 que fixa teto de 17% do ICMS sobre combust\u00edveis, energia el\u00e9trica e servi\u00e7os de telecomunica\u00e7\u00f5es e de transporte p\u00fablico. A proposta prev\u00ea uma compensa\u00e7\u00e3o aos estados com o abatimento de d\u00edvidas com a Uni\u00e3o, [&hellip;]<\/p>\n","protected":false},"author":98,"featured_media":210160,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[61],"tags":[1068],"suno_strategy":[],"class_list":["post-267309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-senado-federal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Senado aprova projeto que fixa teto do ICMS para os combust\u00edveis<\/title>\n<meta name=\"description\" content=\"O Senado aprovou, por 65 votos a favor e 12 contra, o projeto que fixa teto de 17% do ICMS sobre combust\u00edveis e energia el\u00e9trica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senado aprova projeto que fixa teto do ICMS para os combust\u00edveis\" \/>\n<meta property=\"og:description\" content=\"O Senado aprovou, por 65 votos a favor e 12 contra, o projeto que fixa teto de 17% do ICMS sobre combust\u00edveis e energia el\u00e9trica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marco Ant\u00f4nio Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Ant\u00f4nio Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/\"},\"author\":{\"name\":\"Marco Ant\u00f4nio Lopes\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/829bbe8d57f84333b966b96229c6bf5f\"},\"headline\":\"Senado aprova texto-base de projeto que fixa teto do ICMS para os combust\u00edveis\",\"datePublished\":\"2022-06-14T01:43:15+00:00\",\"dateModified\":\"2022-06-14T02:31:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/\"},\"wordCount\":1806,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-scaled.jpg\",\"keywords\":[\"Senado Federal\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/\",\"name\":\"Senado aprova projeto que fixa teto do ICMS para os combust\u00edveis\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-scaled.jpg\",\"datePublished\":\"2022-06-14T01:43:15+00:00\",\"dateModified\":\"2022-06-14T02:31:09+00:00\",\"description\":\"O Senado aprovou, por 65 votos a favor e 12 contra, o projeto que fixa teto de 17% do ICMS sobre combust\u00edveis e energia el\u00e9trica\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-scaled.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"PEC da Transi\u00e7\u00e3o. Foto: Ag\u00eancia Senado.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/politica\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Senado aprova texto-base de projeto que fixa teto do ICMS para os combust\u00edveis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/829bbe8d57f84333b966b96229c6bf5f\",\"name\":\"Marco Ant\u00f4nio Lopes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/385167b012fbc1cde32c5446ee253313?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/385167b012fbc1cde32c5446ee253313?s=96&r=g\",\"caption\":\"Marco Ant\u00f4nio Lopes\"},\"description\":\"Jornalista, \u00e9 editor no Suno Not\u00edcias. Trabalhou nas revistas Playboy, Super, Veja Comer &amp; Beber, Homem Vogue e Universo Masculino, al\u00e9m dos portais Abril.com, R7, nas editorias de Home, Esportes, Hora 7, Entretenimento e Geral, e Eu Quero Investir. Autor do livro Bruce Lee: Definitivo (Editora Conrad). Colaborou nas revistas Nova, Veja SP, Grandes Guerras, Placar, Bizz, Casa Claudia e Quatro Rodas.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/marco-lopes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senado aprova projeto que fixa teto do ICMS para os combust\u00edveis","description":"O Senado aprovou, por 65 votos a favor e 12 contra, o projeto que fixa teto de 17% do ICMS sobre combust\u00edveis e energia el\u00e9trica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/","og_locale":"pt_BR","og_type":"article","og_title":"Senado aprova projeto que fixa teto do ICMS para os combust\u00edveis","og_description":"O Senado aprovou, por 65 votos a favor e 12 contra, o projeto que fixa teto de 17% do ICMS sobre combust\u00edveis e energia el\u00e9trica","og_url":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":2560,"height":1707,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-scaled.jpg","type":"image\/jpeg"}],"author":"Marco Ant\u00f4nio Lopes","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Marco Ant\u00f4nio Lopes","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/"},"author":{"name":"Marco Ant\u00f4nio Lopes","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/829bbe8d57f84333b966b96229c6bf5f"},"headline":"Senado aprova texto-base de projeto que fixa teto do ICMS para os combust\u00edveis","datePublished":"2022-06-14T01:43:15+00:00","dateModified":"2022-06-14T02:31:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/"},"wordCount":1806,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-scaled.jpg","keywords":["Senado Federal"],"articleSection":["Pol\u00edtica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/","url":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/","name":"Senado aprova projeto que fixa teto do ICMS para os combust\u00edveis","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-scaled.jpg","datePublished":"2022-06-14T01:43:15+00:00","dateModified":"2022-06-14T02:31:09+00:00","description":"O Senado aprovou, por 65 votos a favor e 12 contra, o projeto que fixa teto de 17% do ICMS sobre combust\u00edveis e energia el\u00e9trica","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-scaled.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-scaled.jpg","width":2560,"height":1707,"caption":"PEC da Transi\u00e7\u00e3o. Foto: Ag\u00eancia Senado."},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica","item":"https:\/\/www.suno.com.br\/noticias\/politica\/"},{"@type":"ListItem","position":3,"name":"Senado aprova texto-base de projeto que fixa teto do ICMS para os combust\u00edveis"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/829bbe8d57f84333b966b96229c6bf5f","name":"Marco Ant\u00f4nio Lopes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/385167b012fbc1cde32c5446ee253313?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/385167b012fbc1cde32c5446ee253313?s=96&r=g","caption":"Marco Ant\u00f4nio Lopes"},"description":"Jornalista, \u00e9 editor no Suno Not\u00edcias. Trabalhou nas revistas Playboy, Super, Veja Comer &amp; Beber, Homem Vogue e Universo Masculino, al\u00e9m dos portais Abril.com, R7, nas editorias de Home, Esportes, Hora 7, Entretenimento e Geral, e Eu Quero Investir. Autor do livro Bruce Lee: Definitivo (Editora Conrad). Colaborou nas revistas Nova, Veja SP, Grandes Guerras, Placar, Bizz, Casa Claudia e Quatro Rodas.","url":"https:\/\/www.suno.com.br\/noticias\/author\/marco-lopes\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/11\/senado-1-400x200.jpg\" alt=\"Senado aprova texto-base de projeto que fixa teto do ICMS para os combust\u00edveis\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/politica\/\">Pol\u00edtica<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/icms-aprovado-projeto-preco-combustiveis-senado\/\"><h2 class=\"content__title\">Senado aprova texto-base de projeto que fixa teto do ICMS para os combust\u00edveis<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/marco-lopes\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/385167b012fbc1cde32c5446ee253313?s=96&#038;r=g\" alt=\"Marco Ant\u00f4nio Lopes\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/marco-lopes\/\"><span itemprop=\"author\">Marco Ant\u00f4nio Lopes<\/span><\/a><\/span><time datetime=\"2022-06-13T22:43:15-03:00\" itemprop=\"datePublished\">13\/06\/2022 22:43<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/267309"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/98"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=267309"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/267309\/revisions"}],"predecessor-version":[{"id":267326,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/267309\/revisions\/267326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/210160"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=267309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=267309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=267309"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=267309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}