{"id":26717,"date":"2019-05-31T10:10:28","date_gmt":"2019-05-31T13:10:28","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=26717"},"modified":"2019-05-31T10:10:28","modified_gmt":"2019-05-31T13:10:28","slug":"ibovespa-queda-eua-mexico-trump","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/","title":{"rendered":"Ibovespa em queda refletindo as tens\u00f5es do mercado externo"},"content":{"rendered":"<p>Nesta sexta-feira (31), o <a href=\"https:\/\/www.suno.com.br\/artigos\/bovespa-precedente-b3\/\">Ibovespa<\/a> opera em queda devido as tens\u00f5es do mercado externo.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled newsContent__article__imgCapa--noCaption\" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3-800x450.webp\" width=\"800\" height=\"450\" alt=\"Ibovespa em queda refletindo as tens\u00f5es do mercado externo\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--hide\">China: BC injeta 500 bi de yuans e mercado encerra em alta<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<p>Por volta das 10h10, o<strong> Ibovespa<\/strong> registrava uma queda de -0,38% alcan\u00e7ando 97.088,67 pontos. O mercado est\u00e1 atento as amea\u00e7as do <strong>presidente americano<\/strong>, <strong><a href=\"https:\/\/www.suno.com.br\/tudo-sobre\/donald-trump\/\">Donald Trump<\/a>,<\/strong> em elevar as <strong>tarifas alfandeg\u00e1rias do M\u00e9xico<\/strong>.<\/p>\n<p>Al\u00e9m disso, a alta da<a href=\"https:\/\/www.suno.com.br\/artigos\/ibovespa\/\"> Bolsa de Valores de S\u00e3o Paulo<\/a> se deve tamb\u00e9m a retra\u00e7\u00e3o do <a href=\"https:\/\/www.suno.com.br\/artigos\/pib-produto-interno-bruto\/\">Produto Interno Bruto brasileiro<\/a>.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ao\/sessao-estrategica-consultoria-c\/?utm_source=suno-noticias&#038;utm_medium=banner&#038;utm_campaing=dolar-cair-juros\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/09\/300x400.webp\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/09\/SN-DT-1420x240-1.webp\"\n\t\t\t\t\tdata-promo-id=\"624946\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2025\/09\/SN-DT-1420x240-1.webp\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<h2>Trump x M\u00e9xico<\/h2>\n<p>Como medida para conter os <strong>imigrantes ilegais<\/strong> nos <strong>Estados Unidos<\/strong>, <strong>Trump<\/strong> anunciou taxa de 5% sobre produtos vindo do<strong> M\u00e9xico<\/strong>.<\/p>\n<p>A a\u00e7\u00e3o foi divulgada na \u00faltima quinta-feira (30) e entrar\u00e1 em vigor no dia 10 de junho deste ano. A medida foi tomada, ap\u00f3s um grande grupo de <strong>imigrantes ilegais mexicanos<\/strong> tentarem atravessar a fronteira.<\/p>\n<p>Em seu twitter, o presidente publicou: &#8220;Ontem, agentes da Patrulha da Fronteira prenderam o <strong>maior grupo de estrangeiros ilegais no pa\u00eds<\/strong>: 1.036 pessoas atravessaram ilegalmente por volta das 4h da manh\u00e3&#8221;.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/trump-medidas-conter-imigrantes-mexico\/\">Saiba Mais: Trump anuncia medidas para conter imigrantes ilegais vindos do M\u00e9xico<\/a><\/p>\n<p>&#8220;No dia 10 de junho, os EUA impor\u00e3o 5% de <strong>taxas<\/strong> sobre todos os <strong>produtos<\/strong> que vierem do <strong>M\u00e9xico<\/strong>, para que os imigrantes ilegais parem de vir para o nosso pa\u00eds. O aumento da <strong>tarifa<\/strong> ser\u00e1 gradual at\u00e9 que os problemas de <strong>imigra\u00e7\u00e3o<\/strong> sejam remediados&#8221;, disse o presidente americano.<\/p>\n<p>As tarifas tem feito o <strong>mercado internacional<\/strong> ficar atento. A <strong>primeira-ministra alem\u00e3<\/strong>, <strong>Angela Merkel<\/strong>, criticou a<strong> pol\u00edtica de tarifas de Trump<\/strong>. &#8220;O <a href=\"https:\/\/www.suno.com.br\/artigos\/protecionismo\/\"><strong>protecionismo<\/strong><\/a> e os<strong> conflitos comerciais<\/strong> colocam em perigo o <strong>livre com\u00e9rcio<\/strong> e as funda\u00e7\u00f5es b\u00e1sicas da nossa <strong>prosperidade<\/strong>&#8220;, disse a <strong>premi\u00ea<\/strong>.<\/p>\n<h2>PIB recua 0,2%<\/h2>\n<p>De acordo com os dados divulgados pelo<strong> Instituto Brasileiro de Geografia e Estat\u00edsticas<\/strong> (IBGE), o <strong>PIB<\/strong> registrou uma queda de 0,2% no primeiro trimestre de 2019.<\/p>\n<p><a href=\"https:\/\/www.suno.com.br\/noticias\/pib-primeiro-trimestre-vale-brumadinho\/\">Saiba Mais:\u00a0PIB negativo no 1\u00ba tri teve influ\u00eancia da Vale e Brumadinho, diz IBGE<\/a><\/p>\n<p>Esse registro demonstra uma <strong>estagna\u00e7\u00e3o da economia<\/strong> e uma <strong>piora das expectativas<\/strong> para este ano. Al\u00e9m disso, a <strong>retra\u00e7\u00e3o<\/strong> \u00e9 a primeira desde o \u00faltimo trimestre de 2016, quando registrou uma queda de 2,3%.<\/p>\n<p>A <strong>trag\u00e9dia em Brumadinho<\/strong> influenciou a retra\u00e7\u00e3o do <strong>PIB<\/strong>, pois as <strong>opera\u00e7\u00f5es da Vale<\/strong> tiveram a menor escala afetando todo o setor industrial.\u00a0&#8220;A ind\u00fastria extrativa foi respons\u00e1vel pela queda do PIB&#8221;, disse a <strong>coordenadora de Contas Nacionais do IBGE<\/strong>.<\/p>\n<h2>\u00daltima cota\u00e7\u00e3o<\/h2>\n<p>Na \u00faltima sess\u00e3o, que ocorreu na quinta-feira (30), o <strong>Ibovespa<\/strong> encerrou em alta de 0,92% com 97.457,36 pontos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta sexta-feira (31), o Ibovespa opera em queda devido as tens\u00f5es do mercado externo. China: BC injeta 500 bi de yuans e mercado encerra em alta Por volta das 10h10, o Ibovespa registrava uma queda de -0,38% alcan\u00e7ando 97.088,67 pontos. O mercado est\u00e1 atento as amea\u00e7as do presidente americano, Donald Trump, em elevar as tarifas [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":4818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[724,793,721,729],"suno_strategy":[],"class_list":["post-26717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-donald-trump","tag-estados-unidos-eua","tag-ibovespa","tag-mexico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ibovespa em queda refletindo as tens\u00f5es do mercado externo<\/title>\n<meta name=\"description\" content=\"Nesta sexta-feira (31), o Ibovespa opera em queda devido as tens\u00f5es entre o presidente Trump e M\u00e9xico. Clique aqui e saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ibovespa em queda refletindo as tens\u00f5es do mercado externo\" \/>\n<meta property=\"og:description\" content=\"Nesta sexta-feira (31), o Ibovespa opera em queda devido as tens\u00f5es entre o presidente Trump e M\u00e9xico. Clique aqui e saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Poliana Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Poliana Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/\"},\"author\":{\"name\":\"Poliana Santos\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\"},\"headline\":\"Ibovespa em queda refletindo as tens\u00f5es do mercado externo\",\"datePublished\":\"2019-05-31T13:10:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/\"},\"wordCount\":428,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3-jpg.webp\",\"keywords\":[\"Donald Trump\",\"Estados Unidos (EUA)\",\"Ibovespa\",\"M\u00e9xico\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/\",\"name\":\"Ibovespa em queda refletindo as tens\u00f5es do mercado externo\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3-jpg.webp\",\"datePublished\":\"2019-05-31T13:10:28+00:00\",\"description\":\"Nesta sexta-feira (31), o Ibovespa opera em queda devido as tens\u00f5es entre o presidente Trump e M\u00e9xico. Clique aqui e saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3-jpg.webp\",\"width\":1920,\"height\":800,\"caption\":\"China: BC injeta 500 bi de yuans e mercado encerra em alta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/mercado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ibovespa em queda refletindo as tens\u00f5es do mercado externo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\",\"name\":\"Poliana Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"caption\":\"Poliana Santos\"},\"description\":\"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ibovespa em queda refletindo as tens\u00f5es do mercado externo","description":"Nesta sexta-feira (31), o Ibovespa opera em queda devido as tens\u00f5es entre o presidente Trump e M\u00e9xico. Clique aqui e saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/","og_locale":"pt_BR","og_type":"article","og_title":"Ibovespa em queda refletindo as tens\u00f5es do mercado externo","og_description":"Nesta sexta-feira (31), o Ibovespa opera em queda devido as tens\u00f5es entre o presidente Trump e M\u00e9xico. Clique aqui e saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1920,"height":800,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3.jpg","type":"image\/jpeg"}],"author":"Poliana Santos","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Poliana Santos","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/"},"author":{"name":"Poliana Santos","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda"},"headline":"Ibovespa em queda refletindo as tens\u00f5es do mercado externo","datePublished":"2019-05-31T13:10:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/"},"wordCount":428,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3-jpg.webp","keywords":["Donald Trump","Estados Unidos (EUA)","Ibovespa","M\u00e9xico"],"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/","url":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/","name":"Ibovespa em queda refletindo as tens\u00f5es do mercado externo","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3-jpg.webp","datePublished":"2019-05-31T13:10:28+00:00","description":"Nesta sexta-feira (31), o Ibovespa opera em queda devido as tens\u00f5es entre o presidente Trump e M\u00e9xico. Clique aqui e saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3-jpg.webp","width":1920,"height":800,"caption":"China: BC injeta 500 bi de yuans e mercado encerra em alta"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/www.suno.com.br\/noticias\/mercado\/"},{"@type":"ListItem","position":3,"name":"Ibovespa em queda refletindo as tens\u00f5es do mercado externo"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda","name":"Poliana Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","caption":"Poliana Santos"},"description":"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.","url":"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2018\/10\/65264bb7-ibovespa-3-400x200.webp\" alt=\"Ibovespa em queda refletindo as tens\u00f5es do mercado externo\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mercado\/\">Mercado<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-queda-eua-mexico-trump\/\"><h2 class=\"content__title\">Ibovespa em queda refletindo as tens\u00f5es do mercado externo<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2019-05-31T10:10:28-03:00\" itemprop=\"datePublished\">31\/05\/2019 10:10<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/26717"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=26717"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/26717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/4818"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=26717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=26717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=26717"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=26717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}