{"id":231399,"date":"2022-02-14T21:23:36","date_gmt":"2022-02-15T00:23:36","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=231399"},"modified":"2022-02-14T21:23:36","modified_gmt":"2022-02-15T00:23:36","slug":"itausa-itsa4-pagamento-jcp","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/","title":{"rendered":"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o"},"content":{"rendered":"<p>A <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/acoes\/ITSA4\/\" target=\"_blank\" rel=\"noopener\" data-force=\"yes\" data-priority=\"2\"><strong>Ita\u00fasa<\/strong> (ITSA4)<\/a> anunciou nesta segunda-feira (14) o pagamento aos acionistas de <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/entenda-o-jcp\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">Juros sobre Capital Pr\u00f3prio<\/a> (JCP). A holding informou que ser\u00e3o duas emiss\u00f5es diferentes.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Ita\u00fasa (ITSA4). Foto: Divulga\u00e7\u00e3o<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Uma delas, no valor de R$ 0,15472 por a\u00e7\u00e3o, s\u00f3 ser\u00e1 realizada para os acionistas detentores de pap\u00e9is da companhia at\u00e9 o <strong>final do preg\u00e3o do dia 23 de novembro de 2021.<\/strong> Ter\u00e1 reten\u00e7\u00e3o de 15% de imposto de renda na fonte, resultando em juros l\u00edquidos de <strong>R$ 0,131512 por a\u00e7\u00e3o.<\/strong><\/p>\n<p>O outro <strong>JCP do Ita\u00fasa<\/strong> ter\u00e1 como data de corte o<strong> preg\u00e3o desta segunda<\/strong>. A partir de amanh\u00e3 (15), as a\u00e7\u00f5es ser\u00e3o negociadas sem conceder direito ao recebimento do pagamento. O valor bruto \u00e9 de R$ 0,13334 por a\u00e7\u00e3o. Como tamb\u00e9m haver\u00e1 reten\u00e7\u00e3o de imposto, o valor l\u00edquido passa para <strong>R$ 0,113339 por a\u00e7\u00e3o.<\/strong><\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Apesar das emiss\u00f5es diferentes, o pagamento de ambas ser\u00e1 efetuado no mesmo dia: <strong>11 de mar\u00e7o de 2022.\u00a0<\/strong><\/p>\n<p>As <strong>a\u00e7\u00f5es do Ita\u00fasa<\/strong> encerraram o preg\u00e3o desta segunda em baixa de 0,38%, cotadas a R$ 10,48. Mas a companhia apresenta bons resultados neste inicio de ano, e seus pap\u00e9is j\u00e1 acumulam valoriza\u00e7\u00e3o de 16,19%.<\/p>\n<h2>Ita\u00fasa teve alta de 72,9% no lucro de 2021<\/h2>\n<p>Ita\u00fasa tamb\u00e9m divulgou hoje o balan\u00e7o do quarto trimestre de 2021. A companhia obteve um lucro recorrente de R$ 4,185 bilh\u00f5es no per\u00edodo, valor 53,2% superior ao registrado um ano antes. J\u00e1 no total de 2021, registrou <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">lucro l\u00edquido<\/a> de <strong>R$ 12,2 bilh\u00f5es<\/strong>. O montante \u00e9 72,9% maior do que o registrada em 2020.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile-1.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop-1.jpg\"\n\t\t\t\t\tdata-promo-id=\"171998\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop-1.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>O resultado positivo da holding era esperado, uma vez que a empresa de maior participa\u00e7\u00e3o no portf\u00f3lio da companhia, o <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/acoes\/ITUB4\/\" target=\"_blank\" rel=\"noopener\" data-force=\"yes\" data-priority=\"2\">Ita\u00fa Unibanco (ITUB4)<\/a>, j\u00e1 havia divulgado seu balan\u00e7o com um resultado acima das expectativas. O banco lucrou R$ 26,9 bilh\u00f5es em 2021, alta de 45% na compara\u00e7\u00e3o anual.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Saiba mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/resultado-itau-itub4-4t21\/\">\n\t\t\tIta\u00fa (ITUB4) lucra R$ 7,16 bi no 4T21, alta de 32,87%; carteira de cr\u00e9dito cresce e chega a R$ 1,027 tri\t\t<\/a>\n\t<\/div>\n\n\n<p>Al\u00e9m do banco, a empresa possui participa\u00e7\u00f5es na <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/acoes\/ALPA3\/\" target=\"_blank\" rel=\"noopener\" data-force=\"yes\" data-priority=\"2\">Alpargatas (ALPA3)<\/a>, Dexco, Aegea, Copa Energia, NTS e XP, que tamb\u00e9m apresentaram resultados satisfat\u00f3rios. \u201cCabe destacar que este foi o melhor ano da hist\u00f3ria da Dexco em desempenho de EBITDA e rentabilidade e, tamb\u00e9m, o maior EBITDA hist\u00f3rico da Alpargatas&#8221;, disse o <strong>Ita\u00fasa<\/strong> em seu balan\u00e7o.<\/p>\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"184190\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>A Ita\u00fasa (ITSA4) anunciou nesta segunda-feira (14) o pagamento aos acionistas de Juros sobre Capital Pr\u00f3prio (JCP). A holding informou que ser\u00e3o duas emiss\u00f5es diferentes. Ita\u00fasa (ITSA4). Foto: Divulga\u00e7\u00e3o Uma delas, no valor de R$ 0,15472 por a\u00e7\u00e3o, s\u00f3 ser\u00e1 realizada para os acionistas detentores de pap\u00e9is da companhia at\u00e9 o final do preg\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":118,"featured_media":146561,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[356,519,517,1957],"suno_strategy":[],"class_list":["post-231399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-alpargatas-alpa3-alpa4","tag-itau-unibanco-itub3-itub4","tag-itausa-itsa3-itsa4","tag-juros-sobre-capital-proprio-jcp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o<\/title>\n<meta name=\"description\" content=\"O Ita\u00fasa (ITSA4) aprovou nesta segunda-feira (14) o pagamento aos acionistas de Juros sobre Capital Pr\u00f3prio (JCP). Veja os valores por a\u00e7\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"O Ita\u00fasa (ITSA4) aprovou nesta segunda-feira (14) o pagamento aos acionistas de Juros sobre Capital Pr\u00f3prio (JCP). Veja os valores por a\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-scaled-e1620681330950.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruno Galv\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno Galv\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/\"},\"author\":{\"name\":\"Bruno Galv\u00e3o\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/06f0d962a6b1c54852e4860f16935600\"},\"headline\":\"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o\",\"datePublished\":\"2022-02-15T00:23:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/\"},\"wordCount\":399,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-scaled-e1620681330950.jpg\",\"keywords\":[\"Alpargatas (ALPA3\/ALPA4)\",\"Ita\u00fa Unibanco (ITUB3\/ITUB4)\",\"Ita\u00fasa (ITSA3\/ITSA4)\",\"juros sobre capital pr\u00f3prio (JCP)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/\",\"name\":\"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-scaled-e1620681330950.jpg\",\"datePublished\":\"2022-02-15T00:23:36+00:00\",\"description\":\"O Ita\u00fasa (ITSA4) aprovou nesta segunda-feira (14) o pagamento aos acionistas de Juros sobre Capital Pr\u00f3prio (JCP). Veja os valores por a\u00e7\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-scaled-e1620681330950.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-scaled-e1620681330950.jpg\",\"width\":1280,\"height\":854,\"caption\":\"Ita\u00fasa (ITSA4). Foto: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/06f0d962a6b1c54852e4860f16935600\",\"name\":\"Bruno Galv\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53598df0b41c00f12f287a912d0e918e?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53598df0b41c00f12f287a912d0e918e?s=96&r=g\",\"caption\":\"Bruno Galv\u00e3o\"},\"description\":\"Escreve para o portal Suno Not\u00edcias. \u00c9 estudante de Jornalismo pela Faculdade C\u00e1sper L\u00edbero e Letras pela USP. Entusiasta de tecnologia e intelig\u00eancia artificial.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/bruno-garcia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o","description":"O Ita\u00fasa (ITSA4) aprovou nesta segunda-feira (14) o pagamento aos acionistas de Juros sobre Capital Pr\u00f3prio (JCP). Veja os valores por a\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/","og_locale":"pt_BR","og_type":"article","og_title":"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o","og_description":"O Ita\u00fasa (ITSA4) aprovou nesta segunda-feira (14) o pagamento aos acionistas de Juros sobre Capital Pr\u00f3prio (JCP). Veja os valores por a\u00e7\u00e3o.","og_url":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1280,"height":854,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-scaled-e1620681330950.jpg","type":"image\/jpeg"}],"author":"Bruno Galv\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Bruno Galv\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/"},"author":{"name":"Bruno Galv\u00e3o","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/06f0d962a6b1c54852e4860f16935600"},"headline":"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o","datePublished":"2022-02-15T00:23:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/"},"wordCount":399,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-scaled-e1620681330950.jpg","keywords":["Alpargatas (ALPA3\/ALPA4)","Ita\u00fa Unibanco (ITUB3\/ITUB4)","Ita\u00fasa (ITSA3\/ITSA4)","juros sobre capital pr\u00f3prio (JCP)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/","url":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/","name":"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-scaled-e1620681330950.jpg","datePublished":"2022-02-15T00:23:36+00:00","description":"O Ita\u00fasa (ITSA4) aprovou nesta segunda-feira (14) o pagamento aos acionistas de Juros sobre Capital Pr\u00f3prio (JCP). Veja os valores por a\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-scaled-e1620681330950.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-scaled-e1620681330950.jpg","width":1280,"height":854,"caption":"Ita\u00fasa (ITSA4). Foto: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/06f0d962a6b1c54852e4860f16935600","name":"Bruno Galv\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53598df0b41c00f12f287a912d0e918e?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53598df0b41c00f12f287a912d0e918e?s=96&r=g","caption":"Bruno Galv\u00e3o"},"description":"Escreve para o portal Suno Not\u00edcias. \u00c9 estudante de Jornalismo pela Faculdade C\u00e1sper L\u00edbero e Letras pela USP. Entusiasta de tecnologia e intelig\u00eancia artificial.","url":"https:\/\/www.suno.com.br\/noticias\/author\/bruno-garcia\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/9d93a88d-imprensa-foto-01-alta-400x200.jpg\" alt=\"Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/itausa-itsa4-pagamento-jcp\/\"><h2 class=\"content__title\">Ita\u00fasa (ITSA4) anuncia pagamento de JCP; confira valores por a\u00e7\u00e3o<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/bruno-garcia\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/53598df0b41c00f12f287a912d0e918e?s=96&#038;r=g\" alt=\"Bruno Galv\u00e3o\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/bruno-garcia\/\"><span itemprop=\"author\">Bruno Galv\u00e3o<\/span><\/a><\/span><time datetime=\"2022-02-14T21:23:36-03:00\" itemprop=\"datePublished\">14\/02\/2022 21:23<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/231399"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/118"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=231399"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/231399\/revisions"}],"predecessor-version":[{"id":231435,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/231399\/revisions\/231435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/146561"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=231399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=231399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=231399"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=231399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}