{"id":224352,"date":"2022-01-24T10:00:51","date_gmt":"2022-01-24T13:00:51","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=224352"},"modified":"2022-01-24T10:00:51","modified_gmt":"2022-01-24T13:00:51","slug":"dia-do-aposentado-aposentadoria-previdencia","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/","title":{"rendered":"Como construir uma aposentadoria sem depender do governo? Veja as dicas"},"content":{"rendered":"<p>Hoje comemora-se o dia do aposentado, mas nem todos os aposentados podem comemorar sua <strong>aposentadoria<\/strong> com alegria. Isso porque cerca de 46% dos idosos se mant\u00e9m na ativa com alguma tarefa profissional, aumento de 10 pontos percentuais em rela\u00e7\u00e3o a 2018, segundo levantamento do Servi\u00e7o de Prote\u00e7\u00e3o ao Cr\u00e9dito (SPC) em parceria com Offer Wise Pesquisas no ano passado.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Como construir uma aposentadoria sem depender do governo? Veja as dicas\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Confira como preparar seus investimentos para a aposentadoria. Foto: Pexels.<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Entre os <strong>idosos<\/strong> que continuam trabalhando e j\u00e1 est\u00e3o <strong>aposentados<\/strong>, 71% mencionaram a complementa\u00e7\u00e3o da renda como principal motivo. Al\u00e9m disso, cerca de 46% n\u00e3o sabem at\u00e9 que idade pretendem trabalhar. Isso \u00e9 resultado da insufici\u00eancia de renda proveniente dos benef\u00edcios da <strong>Previd\u00eancia Social<\/strong>.<\/p>\n<p>De acordo com Instituto Nacional do Seguro Social (INSS), do total de benefici\u00e1rios, mais de 50% ganham o <strong><a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/salario-minimo\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"3\">sal\u00e1rio m\u00ednimo<\/a> <\/strong>de<strong> aposentadoria do INSS<\/strong>, no valor de R$ 1.210,44. E, por esse motivo, alguns idosos acabam retornando para as atividades profissionais com o objetivo de complementar a renda.<\/p>\n<p>Para somar, com a<strong> reforma da Previd\u00eancia<\/strong> os brasileiros s\u00e3o obrigados a trabalhar por mais tempo e, com base nesse cen\u00e1rio, se torna cada vez mais necess\u00e1rio<strong> investir<\/strong>\u00a0para garantir o mesmo patamar de vida no momento da aposentadoria.<\/p>\n<p>Realizar investimentos pensando no <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/longo-prazo\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">longo prazo<\/a> garante n\u00e3o somente a<strong> independ\u00eancia financeira<\/strong> mas tamb\u00e9m seguran\u00e7a contra eventuais &#8211; e prov\u00e1veis &#8211; mudan\u00e7as nas <strong>regras do INSS<\/strong>. Portanto, os especialistas recomendam pensar hoje em investir para se ter uma<strong> aposentadoria tranquila<\/strong>. Mas ser\u00e1 que \u00e9 poss\u00edvel ter uma <strong>previd\u00eancia<\/strong> sem depender do governo?<\/p>\n<p>&#8220;Sim, \u00e9 muito poss\u00edvel!&#8221;, disse a educadora financeira da Ativa Investimentos, Beatriz Morais. &#8220;Existem investimentos que geram renda passiva e, portanto, renda em conta de forma autom\u00e1tica, assim como o INSS. Quanto antes come\u00e7ar a investir, mais cedo a <strong>liberdade financeira<\/strong> chega. Tempo \u00e9 um fator muito importante na vida do investidor&#8221;, avalia a especialista.<\/p>\n<h2>Como n\u00e3o depender do governo para construir uma boa aposentadoria?<\/h2>\n<p>Os especialistas recomendam que a melhor forma do brasileiro n\u00e3o depender do governo para se aposentar \u00e9 garantindo a liberdade financeira atrav\u00e9s de aplica\u00e7\u00f5es. Ou seja, poupar e investir mensalmente numa <strong><a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/guias\/carteira-de-investimentos\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">carteira de investimentos<\/a> <\/strong>visando objetivos de longo prazo.<\/p>\n<p>&#8220;O primeiro passo para n\u00e3o ficar ref\u00e9m da <strong>previd\u00eancia estatal<\/strong> \u00e9 construir um planejamento financeiro completo, que prepare a carteira de investimentos para todas as fases da vida financeira do investidor, projetando antecipadamente a<strong> renda de aposentadoria<\/strong> do cliente&#8221;, disse o head da mesa de aloca\u00e7\u00e3o alta renda e s\u00f3cio da BRA, Leandro Vasconcellos.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Portanto, segundo o especialista, o pontap\u00e9 inicial \u00e9 o pensamento no longo prazo, depois a disciplina de poupar dinheiro e tamb\u00e9m de investir. Com isso, a aposentadoria atrav\u00e9s do governo ser\u00e1 uma <strong><a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/fonte-de-renda\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">fonte de renda<\/a> secund\u00e1ria<\/strong> no futuro.<\/p>\n<p>&#8220;\u00c9 importante come\u00e7ar a pensar hoje no futuro para que use o tempo a seu favor e, com isso, consiga aproveitar o m\u00e1ximo da rentabilidade que os investimentos podem trazer&#8221;, disse o analista de Renda Fixa da Nexgen Capital, Heitor Martins.<\/p>\n<h2>Jornada do Investidor<\/h2>\n<p>Vasconcellos explica que para construir uma carteira de ativos focada na aposentadoria \u00e9 preciso ter em mente que todo o investidor passa por pelo menos tr\u00eas fases antes de se aposentar e cada uma delas precisam de uma configura\u00e7\u00e3o de carteira espec\u00edfica.<\/p>\n<h3>1\u00aa fase: Acumula\u00e7\u00e3o de patrim\u00f4nio<\/h3>\n<p>Na fase de acumula\u00e7\u00e3o de patrim\u00f4nio, o objetivo principal \u00e9 estabelecer uma regularidade nos aportes, construir uma <strong>reserva de emerg\u00eancia<\/strong> e escolher ativos que sirvam como um grande dep\u00f3sito onde se criar um estoque de capital que possa ser usado nas fases seguintes.<\/p>\n<p>&#8220;Nesta fase a const\u00e2ncia \u00e9 at\u00e9 mais importante do que a rentabilidade, uma vez que ainda h\u00e1 pouco dinheiro investido e os aportes mensais s\u00e3o substancialmente maiores do que os juros sobre a reserva financeira&#8221;, salienta Vasconcellos.<\/p>\n<h3>2\u00aa fase: Multiplica\u00e7\u00e3o de patrim\u00f4nio<\/h3>\n<p>Na fase de<strong> multiplica\u00e7\u00e3o de patrim\u00f4nio<\/strong>, o objetivo principal \u00e9 alavancar a rentabilidade dos ativos.<\/p>\n<p>Nesta fase, o especialista explica que j\u00e1 se tem uma <strong>reserva de emerg\u00eancia financeira<\/strong> maior e os juros sobre ela j\u00e1 n\u00e3o s\u00e3o t\u00e3o inferiores aos aportes mensais, e normalmente \u00e9 nesse per\u00edodo em que os prazos das aplica\u00e7\u00f5es s\u00e3o alongados em busca de melhores taxas e tamb\u00e9m se toma um pouco mais de risco visando retornos maiores.<\/p>\n<h3>3\u00aa fase: Preserva\u00e7\u00e3o<\/h3>\n<p>Na fase de preserva\u00e7\u00e3o o objetivo \u00e9 totalmente oposto ao da fase anterior. Aqui preservar o capital \u00e9 mais importante do que obter retornos acima da m\u00e9dia e o maior risco sempre ser\u00e1 a infla\u00e7\u00e3o, que pode corroer o <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/poder-de-compra\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">poder de compra<\/a> da reserva financeira e provocar uma redu\u00e7\u00e3o no padr\u00e3o de vida do investidor.<\/p>\n<p>&#8220;Nessa fase, os juros sobre as <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/aplicacoes-financeiras\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">aplica\u00e7\u00f5es financeiras<\/a> devem ser capazes de repor as perdas para infla\u00e7\u00e3o e ainda custear as despesas mensais do investidor.&#8221;<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile-1.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop-1.jpg\"\n\t\t\t\t\tdata-promo-id=\"171998\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop-1.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<h2>Quais melhores ativos para investir na aposentadoria?<\/h2>\n<p>Os especialistas apontam que o mais importante \u00e9 ter uma carteira diversificada e prestar aten\u00e7\u00e3o em como os ativos &#8220;conversam&#8221; com os elementos de prazo, retorno e <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/perfil-de-risco\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">perfil de risco<\/a>.<\/p>\n<p>&#8220;O melhor ativo depender\u00e1 do perfil de risco do investidor e prazo que tem dispon\u00edvel para come\u00e7ar a usufruir a aposentadoria. O mais importante, no entanto, \u00e9 garantir a aplica\u00e7\u00e3o nas diversas classes de maneira diversificada, sem concentrar os aportes em \u00fanico ativo&#8221;, disse Martins.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Veja Tamb\u00e9m<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/aposentadoria-como-montar-uma-carteira-de-renda-variavel-para-longo-prazo\/\">\n\t\t\tAposentadoria: como montar uma carteira de renda vari\u00e1vel para longo prazo?\t\t<\/a>\n\t<\/div>\n\n\n<p>Morais explica que pensando em<strong> investimentos de renda fixa<\/strong> para aposentadoria seriam ideais <strong>deb\u00eantures<\/strong> e <strong>t\u00edtulos do Tesouro Direto<\/strong> com pagamento de juros semestrais. J\u00e1 pensando em investimentos de renda vari\u00e1vel, a indica\u00e7\u00e3o s\u00e3o a\u00e7\u00f5es boas pagadoras de <strong><a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/guias\/dividendos\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">dividendos<\/a> <\/strong>e <strong>fundos imobili\u00e1rios<\/strong> (FIIs).<\/p>\n<p>Martins acrescenta ainda que, se a pessoa optar pela maior parte do portf\u00f3lio em renda vari\u00e1vel, \u00e9 ideal ter um prazo maior para o investimento.<\/p>\n<p>&#8220;A aposentadoria pode ser feita atrav\u00e9s de investimentos em diversas classes de ativos, como por exemplo renda fixa, a\u00e7\u00f5es e fundos. O melhor ativo depender\u00e1 do seu perfil de risco do investidor e prazo que tem dispon\u00edvel para come\u00e7ar a usufruir a <strong>aposentadoria<\/strong>.&#8221;<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Hoje comemora-se o dia do aposentado, mas nem todos os aposentados podem comemorar sua aposentadoria com alegria. Isso porque cerca de 46% dos idosos se mant\u00e9m na ativa com alguma tarefa profissional, aumento de 10 pontos percentuais em rela\u00e7\u00e3o a 2018, segundo levantamento do Servi\u00e7o de Prote\u00e7\u00e3o ao Cr\u00e9dito (SPC) em parceria com Offer Wise [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":224799,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[65],"tags":[286,105815,1545,315,997,308],"suno_strategy":[],"class_list":["post-224352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financas-pessoais","tag-acoes","tag-especial","tag-fundos-de-acoes","tag-fundos-imobiliarios-fiis","tag-inss","tag-renda-fixa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como construir uma aposentadoria sem depender do governo? Confira!<\/title>\n<meta name=\"description\" content=\"O primeiro passo para n\u00e3o ficar ref\u00e9m da previd\u00eancia estatal \u00e9 construir um planejamento financeiro completo de aposentadoria. Veja aqui\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como construir uma aposentadoria sem depender do governo? Confira!\" \/>\n<meta property=\"og:description\" content=\"O primeiro passo para n\u00e3o ficar ref\u00e9m da previd\u00eancia estatal \u00e9 construir um planejamento financeiro completo de aposentadoria. Veja aqui\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Poliana Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Poliana Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/\"},\"author\":{\"name\":\"Poliana Santos\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\"},\"headline\":\"Como construir uma aposentadoria sem depender do governo? Veja as dicas\",\"datePublished\":\"2022-01-24T13:00:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/\"},\"wordCount\":1058,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-scaled.jpg\",\"keywords\":[\"A\u00e7\u00f5es\",\"Especiais\",\"Fundos de a\u00e7\u00f5es\",\"Fundos Imobili\u00e1rios (FIIs)\",\"INSS\",\"Renda Fixa\"],\"articleSection\":[\"Finan\u00e7as Pessoais\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/\",\"name\":\"Como construir uma aposentadoria sem depender do governo? Confira!\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-scaled.jpg\",\"datePublished\":\"2022-01-24T13:00:51+00:00\",\"description\":\"O primeiro passo para n\u00e3o ficar ref\u00e9m da previd\u00eancia estatal \u00e9 construir um planejamento financeiro completo de aposentadoria. Veja aqui\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-scaled.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Confira como preparar seus investimentos para a aposentadoria. Foto: Pexels.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finan\u00e7as Pessoais\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/financas-pessoais\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como construir uma aposentadoria sem depender do governo? Veja as dicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\",\"name\":\"Poliana Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"caption\":\"Poliana Santos\"},\"description\":\"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como construir uma aposentadoria sem depender do governo? Confira!","description":"O primeiro passo para n\u00e3o ficar ref\u00e9m da previd\u00eancia estatal \u00e9 construir um planejamento financeiro completo de aposentadoria. Veja aqui","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/","og_locale":"pt_BR","og_type":"article","og_title":"Como construir uma aposentadoria sem depender do governo? Confira!","og_description":"O primeiro passo para n\u00e3o ficar ref\u00e9m da previd\u00eancia estatal \u00e9 construir um planejamento financeiro completo de aposentadoria. Veja aqui","og_url":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":2560,"height":1707,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-scaled.jpg","type":"image\/jpeg"}],"author":"Poliana Santos","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Poliana Santos","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/"},"author":{"name":"Poliana Santos","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda"},"headline":"Como construir uma aposentadoria sem depender do governo? Veja as dicas","datePublished":"2022-01-24T13:00:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/"},"wordCount":1058,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-scaled.jpg","keywords":["A\u00e7\u00f5es","Especiais","Fundos de a\u00e7\u00f5es","Fundos Imobili\u00e1rios (FIIs)","INSS","Renda Fixa"],"articleSection":["Finan\u00e7as Pessoais"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/","url":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/","name":"Como construir uma aposentadoria sem depender do governo? Confira!","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-scaled.jpg","datePublished":"2022-01-24T13:00:51+00:00","description":"O primeiro passo para n\u00e3o ficar ref\u00e9m da previd\u00eancia estatal \u00e9 construir um planejamento financeiro completo de aposentadoria. Veja aqui","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-scaled.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-scaled.jpg","width":2560,"height":1707,"caption":"Confira como preparar seus investimentos para a aposentadoria. Foto: Pexels."},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Finan\u00e7as Pessoais","item":"https:\/\/www.suno.com.br\/noticias\/financas-pessoais\/"},{"@type":"ListItem","position":3,"name":"Como construir uma aposentadoria sem depender do governo? Veja as dicas"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda","name":"Poliana Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","caption":"Poliana Santos"},"description":"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.","url":"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2022\/01\/pexels-andrea-piacquadio-3823493-400x200.jpg\" alt=\"Como construir uma aposentadoria sem depender do governo? Veja as dicas\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/financas-pessoais\/\">Finan\u00e7as Pessoais<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/dia-do-aposentado-aposentadoria-previdencia\/\"><h2 class=\"content__title\">Como construir uma aposentadoria sem depender do governo? Veja as dicas<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2022-01-24T10:00:51-03:00\" itemprop=\"datePublished\">24\/01\/2022 10:00<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/224352"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=224352"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/224352\/revisions"}],"predecessor-version":[{"id":442419,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/224352\/revisions\/442419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/224799"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=224352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=224352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=224352"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=224352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}