{"id":222360,"date":"2022-01-16T15:51:40","date_gmt":"2022-01-16T18:51:40","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=222360"},"modified":"2022-01-16T15:51:40","modified_gmt":"2022-01-16T18:51:40","slug":"diesel-encosta-r7-janeiro-anp","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/","title":{"rendered":"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP"},"content":{"rendered":"<p>Mesmo antes do impacto total do aumento de pre\u00e7os feito pela <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/acoes\/PETR4\/\" target=\"_blank\" rel=\"noopener\" data-force=\"yes\" data-priority=\"2\"><strong>Petrobras<\/strong> (PETR4)<\/a> e pela Acelen no <strong>diesel<\/strong> e na <strong>gasolina<\/strong> na \u00faltima semana, os dois combust\u00edveis registraram em m\u00e9dia alta de 1,4% e 0,2% nos pre\u00e7os na semana de 9 a 15 de janeiro, respectivamente. O G\u00e1s Natural Veicular (GNV) tamb\u00e9m subiu em m\u00e9dia 1,2%, enquanto o <strong>pre\u00e7o do g\u00e1s de cozinha<\/strong> caiu 0,3% e o etanol ficou est\u00e1vel.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920-400x200.jpg\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920-800x450.jpg\" width=\"800\" height=\"450\" alt=\"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Caminh\u00e3o. Foto: Pixabay<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Os dados s\u00e3o da Ag\u00eancia Nacional do Petr\u00f3leo, G\u00e1s Natural e Biocombust\u00edveis (ANP), que detectou o pre\u00e7o m\u00e1ximo do diesel na regi\u00e3o Sudeste, a R$ 6,905\/litro, 3% acima do maior pre\u00e7o da semana anterior (R$ 6,700\/l). O valor mais baixo do diesel foi encontrado no Nordeste, a R$ 4,070, 15% abaixo do pre\u00e7o mais baixo da semana de 2 a 8 de janeiro.<\/p>\n<p>Tanto a Petrobras como a <strong>Acelen<\/strong> (controladora da Refinaria de Mataripe, na Bahia, ex-Rlam) elevaram o <strong>pre\u00e7o do diesel e da gasolina<\/strong> na semana passada, seguindo a <a href=\"https:\/\/www.suno.com.br\/noticias\/gasolina-petrobras-petr4-petroleo-perspectivas-2022\/\"><strong>alta do petr\u00f3leo no mercado internacional<\/strong><\/a>, que este m\u00eas j\u00e1 valorizou 10,6% em rela\u00e7\u00e3o ao final de dezembro do ano passado. A Petrobras subiu o diesel em 8% e a gasolina em 4,8% no dia 12, enquanto a Acelen fez ajustes de at\u00e9 5,1% para a gasolina e de at\u00e9 8,4% para o diesel no s\u00e1bado, 15.<\/p>\n<p>Segundo a ANP, a gasolina continua com o pre\u00e7o m\u00e1ximo de R$ 7,899\/l, registrado nos postos de abastecimento na regi\u00e3o Sudeste, o mesmo valor da semana anterior. O pre\u00e7o m\u00ednimo foi de R$ 5,569\/l, queda de 1,9% contra o mesmo per\u00edodo, encontrado em postos da regi\u00e3o Sul.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>O <strong>g\u00e1s de cozinha<\/strong>, ou G\u00e1s Liquefeito de Petr\u00f3leo (GLP) botij\u00e3o 13 quilos, teve seu pre\u00e7o m\u00e1ximo elevado novamente para R$ 140, depois de ter ca\u00eddo para R$ 135 na primeira semana de janeiro. Mesmo assim, o <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/preco-medio\/\" target=\"_blank\" rel=\"noopener\" data-force=\"no\" data-priority=\"1\">pre\u00e7o m\u00e9dio<\/a> no Brasil \u00e9 de R$ 102,24 o botij\u00e3o, contra R$ 102,55 na semana anterior, queda de 0,3%.<\/p>\n<p>O G<strong>\u00e1s Natural Veicular (GNV) <\/strong>sente o impacto da alta do g\u00e1s natural no mercado internacional, impulsionado pelo inverno do hemisf\u00e9rio norte, que aumenta o uso de aquecimento. O produto teve alta de 1,2% na m\u00e9dia praticada no Pa\u00eds de 9 a 15 de janeiro, com pre\u00e7o m\u00e1ximo de R$ 6,199 o metro c\u00fabico (m3) no Sudeste e o m\u00ednimo, de R$ 3,179\/m3, no Centro-Oeste.<\/p>\n<p>O pre\u00e7o m\u00e9dio do <strong>etanol<\/strong> se manteve praticamente est\u00e1vel, em R$ 5,046\/l, queda de 0,09% em rela\u00e7\u00e3o \u00e0 m\u00e9dia da semana anterior, com o menor pre\u00e7o sendo encontrado no Sudeste, de R$ 4,329\/l, e o mais alto no Sul, de R$ 7,699\/l.<\/p>\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"184190\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Mesmo antes do impacto total do aumento de pre\u00e7os feito pela Petrobras (PETR4) e pela Acelen no diesel e na gasolina na \u00faltima semana, os dois combust\u00edveis registraram em m\u00e9dia alta de 1,4% e 0,2% nos pre\u00e7os na semana de 9 a 15 de janeiro, respectivamente. O G\u00e1s Natural Veicular (GNV) tamb\u00e9m subiu em m\u00e9dia [&hellip;]<\/p>\n","protected":false},"author":43,"featured_media":182383,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[1437,1192,879],"suno_strategy":[],"class_list":["post-222360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-combustiveis","tag-diesel","tag-gasolina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP\" \/>\n<meta property=\"og:description\" content=\"Mesmo antes do impacto total do aumento de pre\u00e7os feito pela Petrobras (PETR4) e pela Acelen no diesel e na gasolina na \u00faltima semana, os dois combust\u00edveis registraram em m\u00e9dia alta de 1,4% e 0,2% nos pre\u00e7os na semana de 9 a 15 de janeiro, respectivamente. O G\u00e1s Natural Veicular (GNV) tamb\u00e9m subiu em m\u00e9dia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sunonoticias\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1292\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Suno Not\u00edcias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Suno Not\u00edcias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Suno Not\u00edcias\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea\"},\"headline\":\"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP\",\"datePublished\":\"2022-01-16T18:51:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/\"},\"wordCount\":472,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920.jpg\",\"keywords\":[\"combust\u00edveis\",\"diesel\",\"Gasolina\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/\",\"name\":\"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920.jpg\",\"datePublished\":\"2022-01-16T18:51:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920.jpg\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920.jpg\",\"width\":1920,\"height\":1292,\"caption\":\"Caminh\u00e3o. Foto: Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea\",\"name\":\"Reda\u00e7\u00e3o Suno Not\u00edcias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g\",\"caption\":\"Reda\u00e7\u00e3o Suno Not\u00edcias\"},\"description\":\"O Suno Not\u00edcias \u00e9 um portal de informa\u00e7\u00f5es sobre Mercado Financeiro, Pol\u00edtica, Neg\u00f3cios, Economia e Finan\u00e7as Pessoais.\",\"sameAs\":[\"https:\/\/www.suno.com.br\/noticias\",\"https:\/\/www.facebook.com\/sunonoticias\/\",\"https:\/\/www.instagram.com\/sunonoticias\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/sunoresearch\",\"https:\/\/www.youtube.com\/sunonoticias\"],\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/","og_locale":"pt_BR","og_type":"article","og_title":"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP","og_description":"Mesmo antes do impacto total do aumento de pre\u00e7os feito pela Petrobras (PETR4) e pela Acelen no diesel e na gasolina na \u00faltima semana, os dois combust\u00edveis registraram em m\u00e9dia alta de 1,4% e 0,2% nos pre\u00e7os na semana de 9 a 15 de janeiro, respectivamente. O G\u00e1s Natural Veicular (GNV) tamb\u00e9m subiu em m\u00e9dia [&hellip;]","og_url":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","article_author":"https:\/\/www.facebook.com\/sunonoticias\/","og_image":[{"width":1920,"height":1292,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Suno Not\u00edcias","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Suno Not\u00edcias","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/"},"author":{"name":"Reda\u00e7\u00e3o Suno Not\u00edcias","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea"},"headline":"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP","datePublished":"2022-01-16T18:51:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/"},"wordCount":472,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920.jpg","keywords":["combust\u00edveis","diesel","Gasolina"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/","url":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/","name":"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920.jpg","datePublished":"2022-01-16T18:51:40+00:00","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920.jpg","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920.jpg","width":1920,"height":1292,"caption":"Caminh\u00e3o. Foto: Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/c1b1bd3727fa852bd045e9dbff3673ea","name":"Reda\u00e7\u00e3o Suno Not\u00edcias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8104b9b5a71985d5238ee59fbe418af?s=96&r=g","caption":"Reda\u00e7\u00e3o Suno Not\u00edcias"},"description":"O Suno Not\u00edcias \u00e9 um portal de informa\u00e7\u00f5es sobre Mercado Financeiro, Pol\u00edtica, Neg\u00f3cios, Economia e Finan\u00e7as Pessoais.","sameAs":["https:\/\/www.suno.com.br\/noticias","https:\/\/www.facebook.com\/sunonoticias\/","https:\/\/www.instagram.com\/sunonoticias\/","https:\/\/x.com\/https:\/\/twitter.com\/sunoresearch","https:\/\/www.youtube.com\/sunonoticias"],"url":"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/truck-2920533_1920-400x200.jpg\" alt=\"Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/diesel-encosta-r7-janeiro-anp\/\"><h2 class=\"content__title\">Diesel encosta nos R$ 7 na segunda semana de janeiro, diz ANP<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/0ace682d-redacao-1-150x150.webp\" alt=\"Reda\u00e7\u00e3o Suno Not\u00edcias\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/redacao-suno\/\"><span itemprop=\"author\">Reda\u00e7\u00e3o Suno Not\u00edcias<\/span><\/a><\/span><time datetime=\"2022-01-16T15:51:40-03:00\" itemprop=\"datePublished\">16\/01\/2022 15:51<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/222360"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=222360"}],"version-history":[{"count":2,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/222360\/revisions"}],"predecessor-version":[{"id":222367,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/222360\/revisions\/222367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/182383"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=222360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=222360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=222360"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=222360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}